{"id":15298,"date":"2015-01-20T13:21:48","date_gmt":"2015-01-20T11:21:48","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=15298"},"modified":"2015-01-20T13:21:48","modified_gmt":"2015-01-20T11:21:48","slug":"le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/","title":{"rendered":"Le vendite di Volvo Cars in Europa sono cresciute a un ritmo doppio rispetto alla concorrenza nel 2014"},"content":{"rendered":"<p><a href=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/82.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/82-300x199.jpg\" alt=\"\" title=\"???????????????????????\" width=\"300\" height=\"199\" class=\"alignleft size-medium wp-image-15299\" \/><\/a><br \/>\nSecondo i dati dell\u2019Associazione Costruttori Europei di Automobili (ACEA), le vendite di Volvo Cars in Europa sarebbero cresciute a un ritmo doppio rispetto a quello dei concorrenti pi\u00f9 prossimi nel 2014.<\/p>\n<p>Con una crescita del 10,6% registrata nel 2014, Volvo ha lasciato indietro i suoi principali concorrenti nel segmento di lusso. Sempre secondo ACEA, nello stesso periodo le vendite di Audi sarebbero infattiaumentate del 4,2%, quelle di BMW del 5,1% e quelle di Mercedes del 5,3%.<!--more--><\/p>\n<p>ACEA ha reso noto che le vendite complessive nei 15 Paesi dell\u2019Unione Europea e nei tre Paesi dell\u2019Associazione Europea di Libero Scambio (EFTA) \u2013 il mercato europeo nel pi\u00f9 ampio senso del termine \u2013sono aumentate del 4,2% nel 2014, il che significa che la crescita di Volvo \u00e8 stata di due volte pi\u00f9 veloce del mercato allargato.<\/p>\n<p> \u201cSiamo davvero soddisfatti del ritmo della nostra crescita, sebbene non sorpresi,\u201d ha commentato AlainVisser, Senior Vice President Vendite &#038; Marketing. \u201cVolvo costruisce alcune fra le automobili pi\u00f9 sicure, meno inquinanti e pi\u00f9 accattivanti sul mercato, quindi va da s\u00e9 che i clienti desiderino acquistarle.\u201d<\/p>\n<p>Volvo ha registrato un forte incremento delle vendite in tutto il continente europeo, ma i risultati sono statiparticolarmente buoni soprattutto in tre Paesi: Svezia, Regno Unito e Germania.<\/p>\n<p>Stando alle cifre di Volvo, le vendite in Svezia sarebbero cresciute del 17,4% grazie alla forte richiesta dei modelli crossover Volvo XC60 e XC70, mentre l\u2019incremento registrato nel Regno Unito e in Germania \u2013 rispettivamente del 25,5% e del 18,3% &#8211; sarebbe riconducibile alla Volvo V40 due volumi e alla XC60.<\/p>\n<p>Volvo Cars ha registrato vendite da record a livello globale nel 2014, per un totale di 465.866 unit\u00e0, e un incremento di fatturato per 18 mesi consecutivi, sottolineando la velocit\u00e0 e la profondit\u00e0 del suo programma di trasformazione globale, attualmente in corso. Tutti questi successi sono stati realizzati prima del lancio della nuova Volvo XC90, che arriver\u00e0 nelle concessionarie nella prima met\u00e0 del 2015. L\u2019intera gamma di modelli diVolvo Cars verr\u00e0 rinnovata nei prossimi cinque anni.<\/p>\n<p>Volvo Cars si trova a met\u00e0 di un percorso di trasformazione globale che prevede la realizzazione di una presenza industriale internazionale, il completo rinnovamento della gamma di prodotti Volvo nei prossimi cinque anni, l\u2019introduzione di una nuova tecnologia modulare per i telai delle vetture, il lancio di tecnologie di sicurezza in anteprima mondiale, lo sviluppo di un nuovo linguaggio stilistico, di una nuova architettura per il sistema di propulsione e di una gamma di servizi di connettivit\u00e0 d\u2019eccellenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo i dati dell\u2019Associazione Costruttori Europei di Automobili (ACEA), le vendite di Volvo Cars in Europa sarebbero cresciute a un ritmo doppio rispetto a quello dei concorrenti pi\u00f9 prossimi nel 2014. Con una crescita del 10,6% registrata nel 2014, Volvo ha lasciato indietro i suoi principali concorrenti nel segmento di lusso. Sempre secondo ACEA, nello [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[269,348],"tags":[],"class_list":["post-15298","post","type-post","status-publish","format-standard","category-marche-auto","category-volvo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le vendite di Volvo Cars in Europa sono cresciute a un ritmo doppio rispetto alla concorrenza nel 2014 - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le vendite di Volvo Cars in Europa sono cresciute a un ritmo doppio rispetto alla concorrenza nel 2014 - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Secondo i dati dell\u2019Associazione Costruttori Europei di Automobili (ACEA), le vendite di Volvo Cars in Europa sarebbero cresciute a un ritmo doppio rispetto a quello dei concorrenti pi\u00f9 prossimi nel 2014. Con una crescita del 10,6% registrata nel 2014, Volvo ha lasciato indietro i suoi principali concorrenti nel segmento di lusso. Sempre secondo ACEA, nello [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-20T11:21:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/82-300x199.jpg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Le vendite di Volvo Cars in Europa sono cresciute a un ritmo doppio rispetto alla concorrenza nel 2014\",\"datePublished\":\"2015-01-20T11:21:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\\\/\"},\"wordCount\":414,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/82-300x199.jpg\",\"articleSection\":[\"MARCHE AUTO\",\"Volvo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\\\/\",\"name\":\"Le vendite di Volvo Cars in Europa sono cresciute a un ritmo doppio rispetto alla concorrenza nel 2014 - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/82-300x199.jpg\",\"datePublished\":\"2015-01-20T11:21:48+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/82.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/82.jpg\",\"width\":560,\"height\":373},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le vendite di Volvo Cars in Europa sono cresciute a un ritmo doppio rispetto alla concorrenza nel 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le vendite di Volvo Cars in Europa sono cresciute a un ritmo doppio rispetto alla concorrenza nel 2014 - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/","og_locale":"it_IT","og_type":"article","og_title":"Le vendite di Volvo Cars in Europa sono cresciute a un ritmo doppio rispetto alla concorrenza nel 2014 - AbmNews","og_description":"Secondo i dati dell\u2019Associazione Costruttori Europei di Automobili (ACEA), le vendite di Volvo Cars in Europa sarebbero cresciute a un ritmo doppio rispetto a quello dei concorrenti pi\u00f9 prossimi nel 2014. Con una crescita del 10,6% registrata nel 2014, Volvo ha lasciato indietro i suoi principali concorrenti nel segmento di lusso. Sempre secondo ACEA, nello [&hellip;]","og_url":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2015-01-20T11:21:48+00:00","og_image":[{"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/82-300x199.jpg","type":"","width":"","height":""}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Le vendite di Volvo Cars in Europa sono cresciute a un ritmo doppio rispetto alla concorrenza nel 2014","datePublished":"2015-01-20T11:21:48+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/"},"wordCount":414,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/82-300x199.jpg","articleSection":["MARCHE AUTO","Volvo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/","url":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/","name":"Le vendite di Volvo Cars in Europa sono cresciute a un ritmo doppio rispetto alla concorrenza nel 2014 - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/82-300x199.jpg","datePublished":"2015-01-20T11:21:48+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/01\/82.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/01\/82.jpg","width":560,"height":373},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/le-vendite-di-volvo-cars-in-europa-sono-cresciute-a-un-ritmo-doppio-rispetto-alla-concorrenza-nel-2014\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Le vendite di Volvo Cars in Europa sono cresciute a un ritmo doppio rispetto alla concorrenza nel 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/15298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=15298"}],"version-history":[{"count":0,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/15298\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=15298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=15298"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=15298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}