{"id":19008,"date":"2015-06-12T16:34:48","date_gmt":"2015-06-12T14:34:48","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=19008"},"modified":"2015-06-12T16:34:48","modified_gmt":"2015-06-12T14:34:48","slug":"ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/","title":{"rendered":"Ancora pochi giorni all\u2019happening pi\u00f9 atteso dagli \u201cOpelisti storici\u201d"},"content":{"rendered":"<p>Fervono i preparativi per l\u2019ottava edizione del 8\u00b0Meeting Internazionale Opel Storiche, a calendario sabato 13 giugno 2015, che avr\u00e0 come splendida cornice Garda, cittadina in provincia di Verona che si specchia su uno dei laghi pi\u00f9 famosi al mondo. Promotori e organizzatori dell\u2019evento dedicato ai molti appassionati delle vetture con il simbolo del fulmine cerchiato, i Club \u201cOpel Manta Fans Italy\u201d e \u201cOpel Fans Italy\u201d con il patrocinio del Comune di Garda e della A.A.V.S. (Associazione Amatori Veicoli Storici).<\/p>\n<p>Ad oggi sono gi\u00e0 80 le auto iscritte che parteciperanno a questo attesissimo Incontro, aperto a tutte le Opel a trazione posteriore costruite prima del 1985 \u2013 con deroga per i modelli Manta, Rekord, Monza e Senator A, tutti ammessi al grande Raduno \u201cstatico espositivo\u201d.<\/p>\n<p>Il programma della giornata prevede:<\/p>\n<p>ore 09.00: registrazione dei partecipanti ed esposizione delle automobili.<br \/>\nOre 10.30: tour di Garda, affascinante centro turistico che si affaccia sulle sponde dell\u2019omonimo specchio d\u2019acqua.<br \/>\nOre 12.30: pausa pranzo presso un\u2019ampia selezione di ristoranti tipici.<br \/>\nOre 14.30: visita del Museo del Lago di Garda.<br \/>\nOre 16.10: cerimonia di premiazione, foto di gruppo e saluti.<br \/>\nUn appuntamento da non mancare, dunque, per tutti i possessori, ma anche semplicemente per i molti appassionati, delle Opel Storiche, che potranno ammirare da vicino vere e proprie pietre miliari del mondo delle quattro ruote come ad esempio la serie Kadett, Ascona e, naturalmente, la coup\u00e9 per eccellenza: Manta.<\/p>\n<p>Per maggiori informazioni e\/o iscrizioni: consultare la pagina Facebook dell\u2019Opel Manta Fans Italy cliccando qui&gt;&gt;&gt;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fervono i preparativi per l\u2019ottava edizione del 8\u00b0Meeting Internazionale Opel Storiche, a calendario sabato 13 giugno 2015, che avr\u00e0 come splendida cornice Garda, cittadina in provincia di Verona che si specchia su uno dei laghi pi\u00f9 famosi al mondo. Promotori e organizzatori dell\u2019evento dedicato ai molti appassionati delle vetture con il simbolo del fulmine cerchiato, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19009,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[295],"tags":[],"class_list":["post-19008","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ancora pochi giorni all\u2019happening pi\u00f9 atteso dagli \u201cOpelisti storici\u201d - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ancora pochi giorni all\u2019happening pi\u00f9 atteso dagli \u201cOpelisti storici\u201d - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Fervono i preparativi per l\u2019ottava edizione del 8\u00b0Meeting Internazionale Opel Storiche, a calendario sabato 13 giugno 2015, che avr\u00e0 come splendida cornice Garda, cittadina in provincia di Verona che si specchia su uno dei laghi pi\u00f9 famosi al mondo. Promotori e organizzatori dell\u2019evento dedicato ai molti appassionati delle vetture con il simbolo del fulmine cerchiato, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-12T14:34:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/1975-Opel-Manta-Advertisement-75573.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1669\" \/>\n\t<meta property=\"og:image:height\" content=\"2126\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Ancora pochi giorni all\u2019happening pi\u00f9 atteso dagli \u201cOpelisti storici\u201d\",\"datePublished\":\"2015-06-12T14:34:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\\\/\"},\"wordCount\":260,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/1975-Opel-Manta-Advertisement-75573.jpg\",\"articleSection\":[\"Opel\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\\\/\",\"name\":\"Ancora pochi giorni all\u2019happening pi\u00f9 atteso dagli \u201cOpelisti storici\u201d - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/1975-Opel-Manta-Advertisement-75573.jpg\",\"datePublished\":\"2015-06-12T14:34:48+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/1975-Opel-Manta-Advertisement-75573.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/1975-Opel-Manta-Advertisement-75573.jpg\",\"width\":1669,\"height\":2126},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ancora pochi giorni all\u2019happening pi\u00f9 atteso dagli \u201cOpelisti storici\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ancora pochi giorni all\u2019happening pi\u00f9 atteso dagli \u201cOpelisti storici\u201d - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/","og_locale":"it_IT","og_type":"article","og_title":"Ancora pochi giorni all\u2019happening pi\u00f9 atteso dagli \u201cOpelisti storici\u201d - AbmNews","og_description":"Fervono i preparativi per l\u2019ottava edizione del 8\u00b0Meeting Internazionale Opel Storiche, a calendario sabato 13 giugno 2015, che avr\u00e0 come splendida cornice Garda, cittadina in provincia di Verona che si specchia su uno dei laghi pi\u00f9 famosi al mondo. Promotori e organizzatori dell\u2019evento dedicato ai molti appassionati delle vetture con il simbolo del fulmine cerchiato, [&hellip;]","og_url":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2015-06-12T14:34:48+00:00","og_image":[{"width":1669,"height":2126,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/1975-Opel-Manta-Advertisement-75573.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Ancora pochi giorni all\u2019happening pi\u00f9 atteso dagli \u201cOpelisti storici\u201d","datePublished":"2015-06-12T14:34:48+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/"},"wordCount":260,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/1975-Opel-Manta-Advertisement-75573.jpg","articleSection":["Opel"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/","url":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/","name":"Ancora pochi giorni all\u2019happening pi\u00f9 atteso dagli \u201cOpelisti storici\u201d - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/1975-Opel-Manta-Advertisement-75573.jpg","datePublished":"2015-06-12T14:34:48+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/1975-Opel-Manta-Advertisement-75573.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/1975-Opel-Manta-Advertisement-75573.jpg","width":1669,"height":2126},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/ancora-pochi-giorni-allhappening-piu-atteso-dagli-opelisti-storici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Ancora pochi giorni all\u2019happening pi\u00f9 atteso dagli \u201cOpelisti storici\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/19008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=19008"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/19008\/revisions"}],"predecessor-version":[{"id":19010,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/19008\/revisions\/19010"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/19009"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=19008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=19008"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=19008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}