{"id":19019,"date":"2015-06-12T17:35:11","date_gmt":"2015-06-12T15:35:11","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=19019"},"modified":"2015-06-12T19:51:42","modified_gmt":"2015-06-12T17:51:42","slug":"ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/","title":{"rendered":"Ford torner\u00e0 a Le Mans nel 2016 con la nuova supercar GT"},"content":{"rendered":"<p>Ford ha annunciato oggi il ritorno a uno dei pi\u00f9 prestigiosi appuntamenti del motorsport mondiale, la 24 Ore di Le Mans. Ford torner\u00e0 a Le Mans a partire dal 2016 con la nuova supercar GT, che competer\u00e0 nella classe riservata a piloti e team professionisti (LM GTE Pro) della GT-Endurance Pro, a 50 anni della storica triplice vittoria della GT40 del 1966 alla quale seguirono 3 ulteriori vittorie consecutive Ford, nel 1967, nel 1968 e nel 1969.<\/p>\n<p>Ford ha svelato oggi, proprio a Le Mans, la versione da competizione della Ford GT, la nuova supercar dell\u2019Ovale Blu che sar\u00e0 in vendita il prossimo anno. La Ford GT \u00e8 un concentrato di innovazione che si avvale di materiali ultraleggeri come il carbonio. E\u2019 spinta da un motore EcoBoost V6 3.5, il pi\u00f9 potente EcoBoost di produzione di sempre.<\/p>\n<p>\u201cQuando le GT40 scesero in pista a Le Mans negli anni Sessanta, Henry Ford II intendeva dimostrare che Ford era in grado di battere nelle competizioni endurance i costruttori pi\u00f9 prestigiosi\u201d, ha dichiarato Bill Ford, Executive Chairman di Ford Motor Company. \u201cRicordiamo con orgoglio le nostre 4 vittorie consecutive, e quello spirito innovativo che accompagn\u00f2 lo sviluppo della prima Ford GT continua a guidarci ancora oggi\u201d.<\/p>\n<p>La versione da competizione della Ford GT garegger\u00e0 in tutti gli appuntamenti 2016 del Campionato del Mondo Endurance FIA e del Campionato TUDOR United SportsCar e far\u00e0 il suo debutto in pista il prossimo gennaio alla Rolex 24 di Daytona, in Florida. Il programma, che coinvolger\u00e0 2 team, ognuno dei quali correr\u00e0 con 2 vetture, sar\u00e0 portato avanti da Chip Ganassi Racing \u2013 Felix Sabates (CGRFS). Un team garegger\u00e0 nel Campionato del Mondo Endurance FIA, l\u2019altro nel Campionato TUDOR United SportsCar. Entrambi i team correranno a LeMans, dove scenderanno in pista tutte e 4 le Ford GT. I piloti saranno annunciati in futuro.<\/p>\n<p>La nuova Ford GT \u00e8 la declinazione pi\u00f9 estrema dei principi del nuovo team globale Ford Performance, una divisione creata per produrre innovazione attraverso le prestazioni: \u2018Innovation through performance\u2019. Tecnologie e soluzioni di ingegneria adottate a bordo della nuova gamma sportiva potranno infatti essere successivamente implementate a bordo di tutti i veicoli Ford. Ford Perfomance svilupper\u00e0 12 nuovi modelli globali ad alte prestazioni entro il 2020. La gamma, che comprende gi\u00e0 la Mustang, la Focus ST e la Fiesta ST, includer\u00e0 anche la Ford GT, la Focus RS, le Mustang Shelby GT350 e GT350R e l\u2019F-150 Raptor.<\/p>\n<p>Il segmento delle vetture ad alte prestazioni rappresenta per Ford un\u2019ulteriore opportunit\u00e0 di crescita, conseguita attraverso modelli che si distinguono nelle rispettive categorie per tecnologia, efficienza e piacere di guida senza compromessi.<\/p>\n<p>\u201cFord continua a essere focalizzata su 3 priorit\u00e0 globali: accelerare nel portare avanti la strategia One Ford, connotare di passione l\u2019eccellenza di prodotto e implementare l\u2019innovazione in ogni aspetto del nostro business\u201d, ha dichiarato Mark Fields, Presidente e CEO di Ford Motor Company. \u201cLa Ford GT \u00e8 uno straordinario esempio di come queste 3 direzioni convergano in un prodotto, e sappiamo, grazie al prestigioso heritage che vantiamo nel motorsport, che il mondo delle competizioni mondiali \u00e8 un eccellente incubatore per lo sviluppo di ulteriore innovazione\u201d.<\/p>\n<p>La versione da gara della Ford GT \u00e8 dotata di caratteristiche avanzate sviluppate per renderla competitiva nella LM GTE Pro, ma che possono essere implementate anche a bordo di tutti i veicoli Ford, come i materiali compositi ultraleggeri, che includono la fibra di carbonio, o il connubio tra potenza ed efficienza dell\u2019EcoBoost.<\/p>\n<p>\u201cNel corso dello sviluppo della Ford GT abbiamo avuto sin dall\u2019inizio un obiettivo importante: riportare in grande stile l\u2019Ovale Blu nel mondo delle corse endurance\u201d, ha dichiarato Raj Nair, Vice Presidente Sviluppo Prodotti Globali e Chief Technical Officer, di Ford. \u201cSiamo sicuri che la Ford GT sar\u00e0 un\u2019avversaria molto competitiva, grazie all\u2019aerodinamica avanzata, al peso ridotto e al motore EcoBoost\u201d.<\/p>\n<p>Per l\u2019operazione, Ford ha stabilito partnership anche con Multimatic Motorsports, Roush Yates Engines, Forza Motorsport, Sparco e Brembo. L\u2019auto \u00e8 stata sottoposta a un\u2019approfondita serie di test e di sessioni aggiuntive di progettazione in collaborazione con Multimatic e Ganassi, mentre CGRFS ha supportato lo sviluppo dell\u2019EcoBoost 3.5,<br \/>\nil pi\u00f9 potente motore EcoBoost di produzione di sempre.<\/p>\n<p>Il propulsore ha debuttato nel 2014 nel Campionato TUDOR United SportsCar su vetture dei team CGRFS e ha gi\u00e0 conquistato pi\u00f9 volte il gradino pi\u00f9 alto del podio in gare come la 12 Ore di Sebring e la Rolex 24 di Daytona. Il team Ganassi ha conquistato importanti vittorie agli appuntamenti di Daytona 500, Brickyard 400 e Indianapolis 500.<\/p>\n<p>\u201cAbbiamo vinto gare e campionati, ma Le Mans per noi sar\u00e0 una novit\u00e0\u201d, ha dichiarato Chip Ganassi. \u201cTrovarsi di fronte all\u2019opportunit\u00e0 di scendere in pista con la nuova Ford GT, nello scenario pi\u00f9 emozionante al mondo, celebrando il 50esimo anniversario di una delle pi\u00f9 straordinarie vittorie nella storia del motorsport: quale team non desidererebbe far parte di tutto ci\u00f2? Sar\u00e0 una sfida? Assolutamente s\u00ec. Ma per affrontarla non c\u2019\u00e8 partner migliore di Ford\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ford ha annunciato oggi il ritorno a uno dei pi\u00f9 prestigiosi appuntamenti del motorsport mondiale, la 24 Ore di Le Mans. Ford torner\u00e0 a Le Mans a partire dal 2016 con la nuova supercar GT, che competer\u00e0 nella classe riservata a piloti e team professionisti (LM GTE Pro) della GT-Endurance Pro, a 50 anni della [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19020,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[389,321],"tags":[],"class_list":["post-19019","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ford","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ford torner\u00e0 a Le Mans nel 2016 con la nuova supercar GT - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ford torner\u00e0 a Le Mans nel 2016 con la nuova supercar GT - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Ford ha annunciato oggi il ritorno a uno dei pi\u00f9 prestigiosi appuntamenti del motorsport mondiale, la 24 Ore di Le Mans. Ford torner\u00e0 a Le Mans a partire dal 2016 con la nuova supercar GT, che competer\u00e0 nella classe riservata a piloti e team professionisti (LM GTE Pro) della GT-Endurance Pro, a 50 anni della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-12T15:35:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-12T17:51:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/unnamed15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"665\" \/>\n\t<meta property=\"og:image:height\" content=\"498\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Ford torner\u00e0 a Le Mans nel 2016 con la nuova supercar GT\",\"datePublished\":\"2015-06-12T15:35:11+00:00\",\"dateModified\":\"2015-06-12T17:51:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\\\/\"},\"wordCount\":815,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/unnamed15.jpg\",\"articleSection\":[\"Ford\",\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\\\/\",\"name\":\"Ford torner\u00e0 a Le Mans nel 2016 con la nuova supercar GT - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/unnamed15.jpg\",\"datePublished\":\"2015-06-12T15:35:11+00:00\",\"dateModified\":\"2015-06-12T17:51:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/unnamed15.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/unnamed15.jpg\",\"width\":665,\"height\":498},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ford torner\u00e0 a Le Mans nel 2016 con la nuova supercar GT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ford torner\u00e0 a Le Mans nel 2016 con la nuova supercar GT - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/","og_locale":"it_IT","og_type":"article","og_title":"Ford torner\u00e0 a Le Mans nel 2016 con la nuova supercar GT - AbmNews","og_description":"Ford ha annunciato oggi il ritorno a uno dei pi\u00f9 prestigiosi appuntamenti del motorsport mondiale, la 24 Ore di Le Mans. Ford torner\u00e0 a Le Mans a partire dal 2016 con la nuova supercar GT, che competer\u00e0 nella classe riservata a piloti e team professionisti (LM GTE Pro) della GT-Endurance Pro, a 50 anni della [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2015-06-12T15:35:11+00:00","article_modified_time":"2015-06-12T17:51:42+00:00","og_image":[{"width":665,"height":498,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/unnamed15.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Ford torner\u00e0 a Le Mans nel 2016 con la nuova supercar GT","datePublished":"2015-06-12T15:35:11+00:00","dateModified":"2015-06-12T17:51:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/"},"wordCount":815,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/unnamed15.jpg","articleSection":["Ford","Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/","url":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/","name":"Ford torner\u00e0 a Le Mans nel 2016 con la nuova supercar GT - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/unnamed15.jpg","datePublished":"2015-06-12T15:35:11+00:00","dateModified":"2015-06-12T17:51:42+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/unnamed15.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/unnamed15.jpg","width":665,"height":498},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/ford-tornera-a-le-mans-nel-2016-con-la-nuova-supercar-gt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Ford torner\u00e0 a Le Mans nel 2016 con la nuova supercar GT"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/19019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=19019"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/19019\/revisions"}],"predecessor-version":[{"id":19021,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/19019\/revisions\/19021"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/19020"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=19019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=19019"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=19019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}