{"id":20685,"date":"2015-09-04T07:03:18","date_gmt":"2015-09-04T05:03:18","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=20685"},"modified":"2015-09-04T07:03:18","modified_gmt":"2015-09-04T05:03:18","slug":"ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/","title":{"rendered":"Ford: le tecnologie di assistenza alla guida fanno vendere le auto"},"content":{"rendered":"<p>Anche se le auto a guida completamente autonoma rappresentano ancora una tecnologia in fase di sperimentazione, le tecnologie di assistenza alla guida sono gi\u00e0 una realt\u00e0. E uno studio condotto da Ford rivela che un numero sempre maggiore di clienti europei sceglie di dotare la propria auto di sistemi di guida semi-autonoma in grado di frenare in caso di emergenza, regolare la velocit\u00e0 e la distanza di sicurezza o eseguire le manovre di parcheggio.<\/p>\n<p>Lo studio Car Buying Trends 2015 analizza le tendenze d\u2019acquisto dei clienti Ford in 22 paesi europei, evidenziando sia gli elementi comuni che quelli peculiari e caratterizzanti delle diverse aree geografiche.<\/p>\n<p>\u201cFord e altri costruttori sono al lavoro sui veicoli a guida automatica, ma molti sistemi di guida semi-autonoma sono gi\u00e0 disponibili oggi e sono sempre pi\u00f9 apprezzati dai clienti, che possono contare su soluzioni che incrementano la sicurezza e il comfort\u201d, ha dichiarato Roelant de Waard, Vice Presidente Marketing, Vendite e Assistenza, di Ford Europa. \u201cStiamo riscontrando un importante incremento della domanda di tutte quelle tecnologie che migliorano la qualit\u00e0 della vita a bordo e rendono sempre meno stressante il tempo passato in auto. Quando, per esempio, si ha la possibilit\u00e0 di lasciare eseguire all\u2019auto la manovra di parcheggio, ci si abitua molto presto alla comodit\u00e0\u201d.<\/p>\n<p>Lo studio Ford Car Buying Trends 2015 ha rivelato anche che la classifica dei colori pi\u00f9 apprezzati continua a vedere in testa il bianco, seguito da nero, grigio e blu.<\/p>\n<p>Tecnologie avanzate<\/p>\n<p>Ford sta portando avanti la ricerca nel campo della guida autonoma e ha gi\u00e0 mostrato il funzionamento di un prototipo basato sulla Fusion Hybrid (la gemella americana della Mondeo) in grado di muoversi autonomamente grazie a una mappa tridimensionale dell\u2019ambiente circostante generata in tempo reale tramite avanzati scanner 3d. L\u2019elenco delle tecnologie di guida semi-autonoma gi\u00e0 disponibili sulla gamma Ford include:<\/p>\n<p>\u00b7 l\u2019Active Park Assist, che aiuta il guidatore nella ricerca di uno spazio di parcheggio appropriato ed esegue semi-automaticamente il parcheggio, sia parallelo che perpendicolare, nel 2014 \u00e8 stato scelto, sulle auto sulle quali questa tecnologia \u00e8 disponibile, da 1 cliente europeo su 3 (34%), con una crescita del 28% sull\u2019anno precedente. Il paese in cui \u00e8 pi\u00f9 gradito \u00e8 la Svizzera (72%), mentre in Italia \u00e8 stato scelto dal 24% dei clienti<\/p>\n<p>\u00b7 l\u2019Adaptive Cruise Control, che permette di controllare la velocit\u00e0 di crociera e di mantenere la distanza di sicurezza dal veicolo che precede, \u00e8 stato scelto, sulle auto equipaggiabili con questa tecnologia, da 1 cliente europeo su 2 (52%), in crescita rispetto al 48% dell\u2019anno precedente, con punte in Turchia (86%), Finlandia (84%) e Svezia (80%), mentre in Italia \u00e8 stato scelto dal 37% dei clienti<\/p>\n<p>\u00b7 l\u2019Active City Stop, che a velocit\u00e0 cittadine frena automaticamente l\u2019auto in caso di rischio di impatto imminente evitando incidenti o riducendone in ogni caso l\u2019entit\u00e0, \u00e8 stato scelto da 1 cliente su 8 (13%), rivelandosi particolarmente apprezzato in Svezia (59%) e Norvegia (58%)<\/p>\n<p>il Lane Keeping Aid, che controlla la traiettoria dell\u2019auto rispetto alla corsia di marcia e aiuta il guidatore a riportarla nella posizione corretta in caso di deviazioni involontarie da quella ottimale, \u00e8 stato adottato dal 7% dei clienti europei, con punte in Svezia (51%), Norvegia (28%) e Svizzera (21%)<\/p>\n<p>Un continente hi-tech, ma in bianco e nero<br \/>\nIn Europa, il bianco continua a essere in testa alle preferenze (23%) seguito da nero (19%), grigio (16%) e blu (12%). Il blu \u00e8 anche il colore che ha mostrato il maggiore incremento rispetto all\u2019anno precedente (+63%). In Italia il bianco \u00e8 saldamente al vertice (27%), seguito dal grigio metallizzato (20%) e dal nero (16%).<\/p>\n<p>Il sistema di connettivit\u00e0 e comandi vocali Ford SYNC \u00e8 stato introdotto in Europa nel 2012 ed \u00e8 stato immediatamente recepito con grande entusiasmo dai clienti europei.<br \/>\nNel 2014 \u00e8 stato scelto, tra prima (SYNC) e seconda generazione (SYNC 2), dal 78% dei clienti Ford, il 10% in pi\u00f9 rispetto all\u2019anno precedente. In Italia, oltre 9 clienti su 10 hanno scelto di equipaggiare la propria Ford con il SYNC, tra prima e seconda generazione.<\/p>\n<p>La maggior parte dei clienti europei, il 52%, ha optato per configurazioni di carrozzeria a 5 porte (in Italia il 77%), contro il 37% delle wagon (in Italia il 16%) e l\u201911% delle 3 porte (in Italia il 7%).<\/p>\n<p>Le wagon sono invece particolarmente apprezzate in Danimarca e Germania, dove rispettivamente l\u201984% e l\u201981% dei clienti Focus e Mondeo hanno scelto questa configurazione, mentre all\u2019estremo opposto si trovano Grecia e Spagna, dove il 96% e l\u201987% dei clienti Focus e Mondeo hanno scelto la versione a 5 porte. In Italia, la carrozzeria pi\u00f9 scelta \u00e8 la 5 porte (77%).<\/p>\n<p>Tra le motorizzazioni, quelle a benzina sono state scelte dal 56% dei clienti europei, con punte in Russia (96%) e Olanda (87%). In Italia la tendenza \u00e8 inversa, con il 58% delle preferenze per il diesel, ma il paese in cui si vendono in assoluto pi\u00f9 auto Ford con motore diesel \u00e8 l\u2019Irlanda (70%). L\u2019Italia si distingue anche per la diffusione delle propulsioni alternative (ibrido, elettrico e soprattutto GPL), scelte dal 16% dei clienti contro il 2% della media europea.<\/p>\n<p>L\u2019Europa continua a preferire le trasmissioni manuali (83%), e in particolare in Grecia (97%), Irlanda (96%) e Italia (93%), mentre il 65% dei guidatori russi preferisce il cambio automatico.<\/p>\n<p>\u201cAnalizzando i trend, emerge chiaramente che alcuni elementi tendono a non cambiare nel tempo, mentre altre preferenze mutano e si evolvono\u201d, ha aggiunto de Waard. \u201cStudiamo e analizziamo le fluttuazioni dei gusti dei nostri clienti europei per fornire loro un\u2019offerta di prodotti che sia sempre allineati alla domanda da ogni punto di vista\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche se le auto a guida completamente autonoma rappresentano ancora una tecnologia in fase di sperimentazione, le tecnologie di assistenza alla guida sono gi\u00e0 una realt\u00e0. E uno studio condotto da Ford rivela che un numero sempre maggiore di clienti europei sceglie di dotare la propria auto di sistemi di guida semi-autonoma in grado di [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20686,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[389],"tags":[],"class_list":["post-20685","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ford"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ford: le tecnologie di assistenza alla guida fanno vendere le auto - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ford: le tecnologie di assistenza alla guida fanno vendere le auto - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Anche se le auto a guida completamente autonoma rappresentano ancora una tecnologia in fase di sperimentazione, le tecnologie di assistenza alla guida sono gi\u00e0 una realt\u00e0. E uno studio condotto da Ford rivela che un numero sempre maggiore di clienti europei sceglie di dotare la propria auto di sistemi di guida semi-autonoma in grado di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-04T05:03:18+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/unnamed4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"667\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Ford: le tecnologie di assistenza alla guida fanno vendere le auto\",\"datePublished\":\"2015-09-04T05:03:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\\\/\"},\"wordCount\":879,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/unnamed4.jpg\",\"articleSection\":[\"Ford\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\\\/\",\"name\":\"Ford: le tecnologie di assistenza alla guida fanno vendere le auto - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/unnamed4.jpg\",\"datePublished\":\"2015-09-04T05:03:18+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/unnamed4.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/unnamed4.jpg\",\"width\":667,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ford: le tecnologie di assistenza alla guida fanno vendere le auto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ford: le tecnologie di assistenza alla guida fanno vendere le auto - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/","og_locale":"it_IT","og_type":"article","og_title":"Ford: le tecnologie di assistenza alla guida fanno vendere le auto - AbmNews","og_description":"Anche se le auto a guida completamente autonoma rappresentano ancora una tecnologia in fase di sperimentazione, le tecnologie di assistenza alla guida sono gi\u00e0 una realt\u00e0. E uno studio condotto da Ford rivela che un numero sempre maggiore di clienti europei sceglie di dotare la propria auto di sistemi di guida semi-autonoma in grado di [&hellip;]","og_url":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2015-09-04T05:03:18+00:00","og_image":[{"width":667,"height":500,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/unnamed4.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Ford: le tecnologie di assistenza alla guida fanno vendere le auto","datePublished":"2015-09-04T05:03:18+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/"},"wordCount":879,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/unnamed4.jpg","articleSection":["Ford"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/","url":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/","name":"Ford: le tecnologie di assistenza alla guida fanno vendere le auto - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/unnamed4.jpg","datePublished":"2015-09-04T05:03:18+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/unnamed4.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/unnamed4.jpg","width":667,"height":500},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/ford-le-tecnologie-di-assistenza-alla-guida-fanno-vendere-le-auto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Ford: le tecnologie di assistenza alla guida fanno vendere le auto"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/20685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=20685"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/20685\/revisions"}],"predecessor-version":[{"id":20687,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/20685\/revisions\/20687"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/20686"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=20685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=20685"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=20685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}