{"id":20995,"date":"2015-09-18T19:23:53","date_gmt":"2015-09-18T17:23:53","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=20995"},"modified":"2015-09-18T19:23:53","modified_gmt":"2015-09-18T17:23:53","slug":"fiat-professional-al-lavoro-con-cuori-in-cammino","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/","title":{"rendered":"Fiat Professional al lavoro con &#8220;Cuori in cammino&#8221;"},"content":{"rendered":"<p>Fiat Professional \u00e8 accanto all&#8217;Associazione Nazionale Medici Cardiologi Ospedalieri per &#8220;Cuori in cammino&#8221;, l&#8217;iniziativa volta a sensibilizzare l&#8217;opinione pubblica circa la diffusione delle malattie cardiovascolari e l&#8217;importanza della prevenzione.<\/p>\n<p>Il progetto prevede un tour che avr\u00e0 il suo prologo a Pinerolo il 19 settembre e che da Aosta, attraversando altre sei citt\u00e0 sede di primarie strutture cardiologiche, arriver\u00e0 a Torino il sabato successivo promuovendo a ogni tappa uno stile di vita sano attraverso l&#8217;esempio della pratica del movimento come attivit\u00e0 di prevenzione. Il claim dell&#8217;operazione \u00e8, infatti, &#8220;Ci sta a cuore il tuo business e la tua salute&#8221;.<\/p>\n<p>Partner dell&#8217;iniziativa \u00e8 il Nuovo Ducato, il best seller del marchio giunto alla sesta generazione, che si conferma un mezzo in grado di offrire tecnologia, efficienza e valore in qualsiasi situazione di utilizzo. Dal punto di vista tecnologico, il Nuovo Ducato adotta soluzioni intelligenti per migliorare il lavoro e la vita a bordo come l&#8217;esclusivo supporto multifunzionale utilizzabile con tutti i dispositivi quali smartphone e tablet e la radio completa di tecnologia Bluetooth e lettore MP3.<br \/>\n\u00c8 possibile adottare anche l&#8217;esclusivo sistema UconnectTM con touchscreen a colori da 5&#8243;, telecamera posteriore per retromarcia, navigazione integrata e riproduzione radio digitale (DAB).<\/p>\n<p>Per quanto concerne la sicurezza, sull&#8217;intera gamma Ducato \u00e8 di serie il sistema di controllo elettronico della stabilit\u00e0 (ESC) che integra altre importanti funzioni di sicurezza come ad esempio il nuovo sistema anti-rollio ROM e il sistema di riconoscimento del baricentro (LAC &#8211; Load Adaptive Control) per adattare in tempo reale i parametri di funzionamento dell&#8217;ESC alle condizioni di carico.<br \/>\nInoltre sono disponibili contenuti di assistenza alla guida come il Traction + con Hill Descent Control e Lane Departure Warning System con Traffic Signal Recognition.<\/p>\n<p>Il Nuovo Ducato \u00e8 pi\u00f9 efficiente, grazie al miglior carico utile e portata sugli assi per i veicoli a ruota singola e alla riduzione del peso in ordine di marcia ottenuta lavorando anche sui materiali, come dimostrano le speciali sospensioni posteriori in materiale composito. Inoltre, la gamma motori Multijet di ultima generazione garantisce i pi\u00f9 bassi livelli di emissioni e consumi del segmento: fino a 5,8 l\/100 km e 158 g\/km di CO2 nel ciclo NEDC &#8211; grazie ai propulsori MultiJet II da 115 CV a 180 CV, disponibili anche con l&#8217;innovativo cambio Comfort Matic.<\/p>\n<p>Il valore, poi, \u00e8 garantito da una progettazione mirata alle esigenze dei clienti e degli allestitori, al miglioramento della qualit\u00e0, della durata e delle performance con la conseguente riduzione dei costi di manutenzione\/riparazione e aumento del valore residuo.<\/p>\n<p>Un suo altro grande punto di forza \u00e8 la versatilit\u00e0, che lo rende adatto a trasformazioni di varia natura: dalle officine mobili ai mezzi coibentati, dai camper per il tempo libero ai mezzi speciali per il soccorso. Insomma, non c&#8217;\u00e8 esigenza o attivit\u00e0 professionale che non possa essere soddisfatta dal Nuovo Ducato che si conferma il mezzo ideale nel settore delle attrezzature speciali per la mobilit\u00e0 assistita.<\/p>\n<p>Fino al 30 settembre sar\u00e0 possibile acquistare il Nuovo Ducato con la formula &#8220;Leasing Facile&#8221;, studiata in collaborazione con FCA Bank, che prevede un anticipo variabile(anche pari a 0%), durata fino a 60 mesi con canoni d&#8217;importo contenuto, valori di riscatto personalizzati e tasso agevolato. Alla scadenza del contratto, la possibilit\u00e0 di riscattare il veicolo o restituirlo senza costi aggiuntivi. Ad esempio, un Ducato 28 CH1 2.0 Multijet 16v da 115 CV &#8211; completo di climatizzatore, radio touchscreen con navigatore e Bluetooth, telecamera posteriore e cruise control &#8211; grazie a Leasing Facile \u00e8 offerto a 165 euro al mese, per cinque anni, con un anticipo del 21% e un TAN del 2,95%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fiat Professional \u00e8 accanto all&#8217;Associazione Nazionale Medici Cardiologi Ospedalieri per &#8220;Cuori in cammino&#8221;, l&#8217;iniziativa volta a sensibilizzare l&#8217;opinione pubblica circa la diffusione delle malattie cardiovascolari e l&#8217;importanza della prevenzione. Il progetto prevede un tour che avr\u00e0 il suo prologo a Pinerolo il 19 settembre e che da Aosta, attraversando altre sei citt\u00e0 sede di primarie [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20996,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[388],"tags":[],"class_list":["post-20995","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fiat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiat Professional al lavoro con &quot;Cuori in cammino&quot; - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiat Professional al lavoro con &quot;Cuori in cammino&quot; - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Fiat Professional \u00e8 accanto all&#8217;Associazione Nazionale Medici Cardiologi Ospedalieri per &#8220;Cuori in cammino&#8221;, l&#8217;iniziativa volta a sensibilizzare l&#8217;opinione pubblica circa la diffusione delle malattie cardiovascolari e l&#8217;importanza della prevenzione. Il progetto prevede un tour che avr\u00e0 il suo prologo a Pinerolo il 19 settembre e che da Aosta, attraversando altre sei citt\u00e0 sede di primarie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-18T17:23:53+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"413\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/fiat-professional-al-lavoro-con-cuori-in-cammino\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/fiat-professional-al-lavoro-con-cuori-in-cammino\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Fiat Professional al lavoro con &#8220;Cuori in cammino&#8221;\",\"datePublished\":\"2015-09-18T17:23:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/fiat-professional-al-lavoro-con-cuori-in-cammino\\\/\"},\"wordCount\":594,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/fiat-professional-al-lavoro-con-cuori-in-cammino\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/001.jpg\",\"articleSection\":[\"Fiat\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/fiat-professional-al-lavoro-con-cuori-in-cammino\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/fiat-professional-al-lavoro-con-cuori-in-cammino\\\/\",\"name\":\"Fiat Professional al lavoro con \\\"Cuori in cammino\\\" - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/fiat-professional-al-lavoro-con-cuori-in-cammino\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/fiat-professional-al-lavoro-con-cuori-in-cammino\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/001.jpg\",\"datePublished\":\"2015-09-18T17:23:53+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/fiat-professional-al-lavoro-con-cuori-in-cammino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/fiat-professional-al-lavoro-con-cuori-in-cammino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/fiat-professional-al-lavoro-con-cuori-in-cammino\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/001.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/001.jpg\",\"width\":620,\"height\":413},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/fiat-professional-al-lavoro-con-cuori-in-cammino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiat Professional al lavoro con &#8220;Cuori in cammino&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiat Professional al lavoro con \"Cuori in cammino\" - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/","og_locale":"it_IT","og_type":"article","og_title":"Fiat Professional al lavoro con \"Cuori in cammino\" - AbmNews","og_description":"Fiat Professional \u00e8 accanto all&#8217;Associazione Nazionale Medici Cardiologi Ospedalieri per &#8220;Cuori in cammino&#8221;, l&#8217;iniziativa volta a sensibilizzare l&#8217;opinione pubblica circa la diffusione delle malattie cardiovascolari e l&#8217;importanza della prevenzione. Il progetto prevede un tour che avr\u00e0 il suo prologo a Pinerolo il 19 settembre e che da Aosta, attraversando altre sei citt\u00e0 sede di primarie [&hellip;]","og_url":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2015-09-18T17:23:53+00:00","og_image":[{"width":620,"height":413,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/001.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Fiat Professional al lavoro con &#8220;Cuori in cammino&#8221;","datePublished":"2015-09-18T17:23:53+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/"},"wordCount":594,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/001.jpg","articleSection":["Fiat"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/","url":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/","name":"Fiat Professional al lavoro con \"Cuori in cammino\" - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/001.jpg","datePublished":"2015-09-18T17:23:53+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/001.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/001.jpg","width":620,"height":413},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/fiat-professional-al-lavoro-con-cuori-in-cammino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Fiat Professional al lavoro con &#8220;Cuori in cammino&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/20995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=20995"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/20995\/revisions"}],"predecessor-version":[{"id":20997,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/20995\/revisions\/20997"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/20996"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=20995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=20995"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=20995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}