{"id":21057,"date":"2015-09-22T06:32:48","date_gmt":"2015-09-22T04:32:48","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=21057"},"modified":"2015-09-22T06:32:48","modified_gmt":"2015-09-22T04:32:48","slug":"a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/","title":{"rendered":"A Barcellona, le PEUGEOT 208 WRX hanno permesso, per la decima volta sul podio"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Dopo una serie di quattro vittorie, di cui tre consecutive, il Team Peugeot Hansen affrontava la gara di Barcellona con grandi ambizioni. Il week-end \u00e8 iniziato con Timmy Hansen che ha dominato ancora una volta la prima giornata.<\/p>\n<p>La terza manche \u00e8 stata meno agevole, ma il giovane svedese ha ribadito subito la propria superiorit\u00e0 aggiudicandosi la quarta con l&#8217;eccellente tempo di 3\u201914\u2019\u2019366. Al termine delle qualifiche il pilota della PEUGEOT 208 WRX n\u00b021 era in testa alla classifica, con il compagno di squadra Davy Jeanney al quarto posto.<\/p>\n<p>Nella semifinale i due piloti delle PEUGEOT 208 WRX sono riusciti a guadagnarsi un posto in finale con un doppio piazzamento che nessun\u2019altra squadra \u00e8 riuscita ad ottenere.<\/p>\n<p>In finale, il poleman Timmy Hansen si \u00e8 fatto sorprendere in partenza da Petter Solberg, balzato in testa dalla seconda fila. Autore poi di un piccolo errore, ha concluso al terzo posto, subito davanti al compagno di squadra.<\/p>\n<p>I punti che i piloti hanno ottenuto permettono al Team Peugeot Hansen di consolidare il proprio vantaggio nel Campionato del Mondo Team, con ben 77 punti di vantaggio sul Team Ford Olsberg MSE, quando rimangono ancora tre gare da disputare.<\/p>\n<p>Nel campionato piloti, Timmy Hansen conferma il secondo posto guadagnando due punti su Petter Solberg. Davy Jeanney guadagna una posizione e ora \u00e8 quarto.<\/p>\n<p>Sempre a Barcellona, Kevin Hansen, il giovane pilota del Peugeot Red Bull Hansen Junior Team, ha consolidato ulteriormente il proprio vantaggio nel campionato RX Lites.<\/p>\n<p>Prossima tappa del Campionato del Mondo FIA Rallycross 2015 in Turchia, il 3 e 4 ottobre, sul circuito di Formula 1 di Istanbul.<\/p>\n<p>Kenneth Hansen, Team Principal<\/p>\n<p>\u00ab A Barcellona siamo stati ancora una volta velocissimi. Lo dimostra il fatto che abbiamo qualificato entrambe le vetture in finale. Tuttavia, non siamo riusciti a concretizzare completamente questo primato, ma cos\u00ec \u00e8 la vita. Talvolta la prima curva si dimostra molto insidiosa e quando non tutto va per il verso giusto, bisogna cercare di recuperare il terreno perduto. La finale non \u00e8 stata brillante come avevamo sperato, tuttavia abbiamo conquistato punti preziosi che ci danno un confortante vantaggio nel campionato team \u00bb.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Timmy Hansen, PEUGEOT 208 WRX #21, P3<\/p>\n<p>\u00ab Questo week-end \u00e8 iniziato benissimo per noi. Nonostante una penalit\u00e0, sono riuscito a partire in pole position nella semifinale! Ho cercato di risparmiare gli pneumatici. Partendo di nuovo dalla pole in finale, ero molto fiducioso. Quando \u00e8 scattato il semaforo verde, sono rimasto sorpreso nel vedere Petter Solberg che mi superava all\u2019interno della prima curva. Visto che la pista era stata appena bagnata, ho commesso un piccolo errore: ho toccato la pila degli pneumatici. Sono comunque riuscito a mantenere la seconda posizione. Avevo un piccolo distacco da Petter, ho cercato di colmarlo ma ho commesso due o tre errori che mi hanno allontanato da lui. Ho tentato il tutto per tutto negli ultimi giri ma non \u00e8 bastato. Il podio mi permette comunque di riconquistare due punti su Petter Solberg. \u00bb<\/p>\n<p>Davy Jeanney, PEUGEOT 208 WRX #17, P4<\/p>\n<p>\u00ab Conquisto dei punti nel campionato piloti e li porto alla squadra per la classifica Team. Sono importanti in vista della fine di stagione. Sono anche riuscito a risalire di un posto nel campionato ai danni di Andreas Bakkerud. E\u2019 il fatto positivo del week-end. Penso mi sia mancato qualcosa nella semifinale. Forse un po\u2019 pi\u00f9 di fiducia a un certo punto. Ho perso tempo, ma mi sono qualificato comunque per la finale in cui ho avuto la sensazione di avere guidato meglio \u00bb.<\/p>\n<p>Classifica decima prova (Spagna &#8211; Barcellona) &#8211; 19-20 settembre 2015<\/p>\n<p>1. Petter Solberg (SDRX, Citro\u00ebn DS3)<br \/>\n2. Johan Kristoffersson (Volkswagen Team Sweden, Volkswagen Polo) 3. Timmy Hansen (Team Peugeot Hansen, PEUGEOT 208 WRX)<br \/>\n4. Davy Jeanney (Team Peugeot Hansen, PEUGEOT 208 WRX),<br \/>\n5. Taner Foust (Marklund Motorsport, Volkswagen Polo)<br \/>\n6. Robin Larsson (Robin Larsson, Audi A1)<\/p>\n<p>Campionato del Mondo FIA di Rallycross, dopo 10 manche<br \/>\nPiloti<br \/>\n1. Petter Solberg (SDRX, Citro\u00ebn DS3), 243 pts<br \/>\n2. Timmy Hansen (Team Peugeot Hansen, PEUGEOT 208 WRX), 208 pts<br \/>\n3. Johan Kristoffersson (Volkswagen Team Sweden, Volkswagen Polo), 182 pts 4. Davy Jeanney (Team Peugeot Hansen, PEUGEOT 208 WRX), 166 pts<\/p>\n<p>5. Andreas Bakkerud (OlsbergMSE AB, Ford Fiesta ST), 163 pts<br \/>\n6. Mattias Ekstr\u00f6m (EKS, Audi S1), 155 pts<br \/>\n7. Reinis Nitiss (OlsbergMSE AB Ford Fiesta ST), 134 pts<br \/>\n8. Toomas Heikkinen, (Marklund Motorsport, Volkswagen Polo), 121 pt<\/p>\n<p>Team<br \/>\n1. Team Peugeot-Hansen, 374 pts 2. Ford Olsbergs MSE, 297 pts<br \/>\n3. SDR<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dopo una serie di quattro vittorie, di cui tre consecutive, il Team Peugeot Hansen affrontava la gara di Barcellona con grandi ambizioni. Il week-end \u00e8 iniziato con Timmy Hansen che ha dominato ancora una volta la prima giornata. La terza manche \u00e8 stata meno agevole, ma il giovane svedese ha ribadito subito la propria superiorit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21058,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[300],"tags":[],"class_list":["post-21057","post","type-post","status-publish","format-standard","has-post-thumbnail","category-peugeot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Barcellona, le PEUGEOT 208 WRX hanno permesso, per la decima volta sul podio - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Barcellona, le PEUGEOT 208 WRX hanno permesso, per la decima volta sul podio - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Dopo una serie di quattro vittorie, di cui tre consecutive, il Team Peugeot Hansen affrontava la gara di Barcellona con grandi ambizioni. Il week-end \u00e8 iniziato con Timmy Hansen che ha dominato ancora una volta la prima giornata. La terza manche \u00e8 stata meno agevole, ma il giovane svedese ha ribadito subito la propria superiorit\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-22T04:32:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/M_33d06fe4-8e14-4bf0-980b-ff21a42b67dc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"A Barcellona, le PEUGEOT 208 WRX hanno permesso, per la decima volta sul podio\",\"datePublished\":\"2015-09-22T04:32:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\\\/\"},\"wordCount\":699,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/M_33d06fe4-8e14-4bf0-980b-ff21a42b67dc.jpg\",\"articleSection\":[\"Peugeot\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\\\/\",\"name\":\"A Barcellona, le PEUGEOT 208 WRX hanno permesso, per la decima volta sul podio - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/M_33d06fe4-8e14-4bf0-980b-ff21a42b67dc.jpg\",\"datePublished\":\"2015-09-22T04:32:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/M_33d06fe4-8e14-4bf0-980b-ff21a42b67dc.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/M_33d06fe4-8e14-4bf0-980b-ff21a42b67dc.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Barcellona, le PEUGEOT 208 WRX hanno permesso, per la decima volta sul podio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Barcellona, le PEUGEOT 208 WRX hanno permesso, per la decima volta sul podio - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/","og_locale":"it_IT","og_type":"article","og_title":"A Barcellona, le PEUGEOT 208 WRX hanno permesso, per la decima volta sul podio - AbmNews","og_description":"Dopo una serie di quattro vittorie, di cui tre consecutive, il Team Peugeot Hansen affrontava la gara di Barcellona con grandi ambizioni. Il week-end \u00e8 iniziato con Timmy Hansen che ha dominato ancora una volta la prima giornata. La terza manche \u00e8 stata meno agevole, ma il giovane svedese ha ribadito subito la propria superiorit\u00e0 [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2015-09-22T04:32:48+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/M_33d06fe4-8e14-4bf0-980b-ff21a42b67dc.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"A Barcellona, le PEUGEOT 208 WRX hanno permesso, per la decima volta sul podio","datePublished":"2015-09-22T04:32:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/"},"wordCount":699,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/M_33d06fe4-8e14-4bf0-980b-ff21a42b67dc.jpg","articleSection":["Peugeot"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/","url":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/","name":"A Barcellona, le PEUGEOT 208 WRX hanno permesso, per la decima volta sul podio - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/M_33d06fe4-8e14-4bf0-980b-ff21a42b67dc.jpg","datePublished":"2015-09-22T04:32:48+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/M_33d06fe4-8e14-4bf0-980b-ff21a42b67dc.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/M_33d06fe4-8e14-4bf0-980b-ff21a42b67dc.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/a-barcellona-le-peugeot-208-wrx-hanno-permesso-per-la-decima-volta-sul-podio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"A Barcellona, le PEUGEOT 208 WRX hanno permesso, per la decima volta sul podio"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/21057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=21057"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/21057\/revisions"}],"predecessor-version":[{"id":21059,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/21057\/revisions\/21059"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/21058"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=21057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=21057"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=21057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}