{"id":21073,"date":"2015-09-23T12:21:31","date_gmt":"2015-09-23T10:21:31","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=21073"},"modified":"2015-09-23T12:21:31","modified_gmt":"2015-09-23T10:21:31","slug":"il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/","title":{"rendered":"Il Ministro Galletti scrive all&#8217; AD di Volkswagen Group Italia servono &#8216;elementi oggettivi&#8217; su vetture commercializzate nel nostro Paese"},"content":{"rendered":"<p>Con una lettera indirizzata all\u2019amministratore delegato e direttore generale di Volkswagen Group Italia Massimo Nordio, il ministro dell\u2019Ambiente Gian Luca Galletti chiede informazioni sulle vetture vendute nel mercato italiano dalla nota casa automobilistica, dopo le indagini condotte dall\u2019Agenzia federale Usa sulle difformit\u00e0 tra i valori emissivi dei veicoli diesel immessi sul mercato statunitense e quelli prodotti effettivamente su strada.<\/p>\n<p>\u201cHo appreso con preoccupazione le risultanze delle indagini \u2013 scrive Galletti \u2013 e le chiedo di volermi fornire elementi oggettivi che nelle autovetture commercializzate in Italia non siano stati installati accorgimenti tecnici analoghi volti ad alterare i dati emissivi da test rispetto alla realt\u00e0\u201d.<\/p>\n<p>Il ministro, che ricorda l\u2019incidenza di questi profili sulla qualit\u00e0 dell\u2019aria e sul clima, fa riferimento nella lettera alla decisione assunta dall\u2019azienda di bloccare le vendite delle auto sul mercato Usa e ritirare di quelle gi\u00e0 commercializzate, chiedendo al gruppo, \u201cqualora necessario, di assumere analoghe iniziative gi\u00e0 intraprese per il mercato americano anche a tutela dei consumatori italiani che hanno fatto affidamento sul marchio Volkswagen\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una lettera indirizzata all\u2019amministratore delegato e direttore generale di Volkswagen Group Italia Massimo Nordio, il ministro dell\u2019Ambiente Gian Luca Galletti chiede informazioni sulle vetture vendute nel mercato italiano dalla nota casa automobilistica, dopo le indagini condotte dall\u2019Agenzia federale Usa sulle difformit\u00e0 tra i valori emissivi dei veicoli diesel immessi sul mercato statunitense e quelli [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21074,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[347],"tags":[80],"class_list":["post-21073","post","type-post","status-publish","format-standard","has-post-thumbnail","category-volkswagen","tag-featured"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Ministro Galletti scrive all&#039; AD di Volkswagen Group Italia servono &#039;elementi oggettivi&#039; su vetture commercializzate nel nostro Paese - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Ministro Galletti scrive all&#039; AD di Volkswagen Group Italia servono &#039;elementi oggettivi&#039; su vetture commercializzate nel nostro Paese - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Con una lettera indirizzata all\u2019amministratore delegato e direttore generale di Volkswagen Group Italia Massimo Nordio, il ministro dell\u2019Ambiente Gian Luca Galletti chiede informazioni sulle vetture vendute nel mercato italiano dalla nota casa automobilistica, dopo le indagini condotte dall\u2019Agenzia federale Usa sulle difformit\u00e0 tra i valori emissivi dei veicoli diesel immessi sul mercato statunitense e quelli [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-23T10:21:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/ministro_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"341\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Il Ministro Galletti scrive all&#8217; AD di Volkswagen Group Italia servono &#8216;elementi oggettivi&#8217; su vetture commercializzate nel nostro Paese\",\"datePublished\":\"2015-09-23T10:21:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\\\/\"},\"wordCount\":192,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/ministro_3.jpg\",\"keywords\":[\"Featured\"],\"articleSection\":[\"Volkswagen\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\\\/\",\"name\":\"Il Ministro Galletti scrive all' AD di Volkswagen Group Italia servono 'elementi oggettivi' su vetture commercializzate nel nostro Paese - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/ministro_3.jpg\",\"datePublished\":\"2015-09-23T10:21:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/ministro_3.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/ministro_3.jpg\",\"width\":600,\"height\":341},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Ministro Galletti scrive all&#8217; AD di Volkswagen Group Italia servono &#8216;elementi oggettivi&#8217; su vetture commercializzate nel nostro Paese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Ministro Galletti scrive all' AD di Volkswagen Group Italia servono 'elementi oggettivi' su vetture commercializzate nel nostro Paese - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/","og_locale":"it_IT","og_type":"article","og_title":"Il Ministro Galletti scrive all' AD di Volkswagen Group Italia servono 'elementi oggettivi' su vetture commercializzate nel nostro Paese - AbmNews","og_description":"Con una lettera indirizzata all\u2019amministratore delegato e direttore generale di Volkswagen Group Italia Massimo Nordio, il ministro dell\u2019Ambiente Gian Luca Galletti chiede informazioni sulle vetture vendute nel mercato italiano dalla nota casa automobilistica, dopo le indagini condotte dall\u2019Agenzia federale Usa sulle difformit\u00e0 tra i valori emissivi dei veicoli diesel immessi sul mercato statunitense e quelli [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2015-09-23T10:21:31+00:00","og_image":[{"width":600,"height":341,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/ministro_3.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Il Ministro Galletti scrive all&#8217; AD di Volkswagen Group Italia servono &#8216;elementi oggettivi&#8217; su vetture commercializzate nel nostro Paese","datePublished":"2015-09-23T10:21:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/"},"wordCount":192,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/ministro_3.jpg","keywords":["Featured"],"articleSection":["Volkswagen"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/","url":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/","name":"Il Ministro Galletti scrive all' AD di Volkswagen Group Italia servono 'elementi oggettivi' su vetture commercializzate nel nostro Paese - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/ministro_3.jpg","datePublished":"2015-09-23T10:21:31+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/ministro_3.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/09\/ministro_3.jpg","width":600,"height":341},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/il-ministro-galletti-scrive-all-ad-di-volkswagen-group-italia-servono-elementi-oggettivi-su-vetture-commercializzate-nel-nostro-paese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Il Ministro Galletti scrive all&#8217; AD di Volkswagen Group Italia servono &#8216;elementi oggettivi&#8217; su vetture commercializzate nel nostro Paese"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/21073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=21073"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/21073\/revisions"}],"predecessor-version":[{"id":21075,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/21073\/revisions\/21075"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/21074"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=21073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=21073"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=21073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}