{"id":24846,"date":"2016-05-06T17:08:24","date_gmt":"2016-05-06T15:08:24","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=24846"},"modified":"2016-05-06T17:08:24","modified_gmt":"2016-05-06T15:08:24","slug":"alle-2000-si-accendono-i-motori-della-100th-targa-florio","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/","title":{"rendered":"ALLE 20,00 SI ACCENDONO I MOTORI DELLA 100TH TARGA FLORIO"},"content":{"rendered":"<p>La 100th Targa Florio ha acceso i motori della Classic e del Ferrari Tribute tra un mare di folla gioved\u00ec sera a Palermo e questa sera alle 20 si replica ancora in piazza Verdi e con l&#8217;imponente sfondo del Teatro Massimo quando a prendere il via saranno le attese vetture da rally, in totale 276 quelle verificate. Gi\u00e0 in giornata sono state protagoniste in parco assistenza a Campofelice di Roccella, preso d&#8217;assalto da appassionati e pubblico, e dello shakedown, il test in configurazione da gara, e a partire dalla prima prova di stasera si contenderanno i punti del Campionato Italiano Rally, del Trofeo Rally Asfalto, del Campionato Regionale e del Campionato Italiano Auto Storiche. Dalle ore 20 a Palermo la Targa torna alla competizione tra la sua gente e subito dopo anche sulle leggendarie strade delle Madonie. Un altro bagno di folla \u00e8 atteso in centro a Campofelice di Roccella e alla successiva prima sfida contro il cronometro, la PS1 &#8220;Citt\u00e0 di Collesano 1&#8221;, prova-notturna di 1,8 chilometri interna alla citt\u00e0 madonita con start alle 21.31 dalla quale scaturir\u00e0 la prima classifica della centesima edizione della corsa pi\u00f9 antica del mondo, che riprender\u00e0 l&#8217;indomani. Sabato 7 maggio il restart dal Targa Florio Village \u00e8 previsto alle 8.50. Il primo &#8220;giro&#8221; di prove, che toccher\u00e0 altre localit\u00e0 classiche della corsa, \u00e8 inaugurato dalla PS2 &#8220;Lascari 1&#8221; (9,2 km) alle 9.44, seguita dalle PS3 &#8220;Gratteri 1&#8221; (13,7 km) alle 10.08 e PS4 &#8220;Pollina&#8221; (13,9 km) alle 11.22. Alle 12.57 lungo riordino previsto sul Lungomare del Mediterraneo a Campofelice di Roccella e alle 15.07 si torna al vicino Targa Florio Village per la prima mezzora di assistenza. Alle 16.06 le auto saranno di nuovo a Lascari per inaugurare il secondo giro delle tre prove disputate al mattino, con successivi passaggi a Gratteri alle 16.25 e a Pollina alle 17.17. Alle 18.27 secondo riordino e alle 18.57 seconda assistenza di giornata a Campofelice di Roccella. In serata si riparte per ripetere la prova spettacolo &#8220;Citt\u00e0 di Collesano&#8221;, con start previsto alle 19.57, e a fine giornata si ritorna al Targa Florio Village per l&#8217;ultima assistenza e la sosta notturna con definite le classifiche di gara-1 per i protagonisti del Tricolore Rally e della prima tappa per i piloti del Tricolore storiche. L&#8217;unica competizione a concludersi sabato, con &#8220;smarcamento&#8221; finale per l&#8217;arrivo nella piazza centrale di Campofelice di Roccella sar\u00e0 quella che coinvolge le auto e i numerosi specialisti dell&#8217;isola che concorrono per il Campionato Regionale.<\/p>\n<p>Per il Tricolore Rally \u00e8 possibile seguire in diretta streaming su www.acisportitalia.it la Cerimonia di Partenza di Palermo stasera (venerd\u00ec) dalle 19.50. Sabato la diretta riguarder\u00e0 invece i due passaggi a Lascari, uno dalle 9.40 e il secondo dalle 15.50, e il rientro finale delle vetture al Targa Florio Village per la conclusione della prima giornata, con collegamento a partire dalle 19.50.<\/p>\n<p>Gli attesi protagonisti hanno &#8220;assaggiato&#8221; la Targa nello shakedown svolto in mattinata. Il toscano nove volte vincitore della corsa Paolo Andreucci, leader del CIR e in gara con il numero 1 sulla Peugeot 208 T16 R5 schierata da Peugeot Italia non si \u00e8 sbilanciato in vista del prestigioso &#8220;appuntamento con la storia&#8221; di questa centesima edizione: &#8220;Abbiamo provato la macchina, per ora tutto bene e siamo tranquilli. Le sensazioni? Ve le dico domenica dopo la gara&#8221;. Shakedown con pi\u00f9 passaggi anche per il veneto Giandomenico Basso, in classifica primo inseguitore del 9 volte campione italiano, al volante della Ford Fiesta R5 alimentata a GPL e preparata dalla BRC: &#8220;Abbiamo verificato le varie parti meccaniche pi\u00f9 che fare un test, tutto \u00e8 in ordine e siamo pronti a partire stasera.&#8221; Il lavoro del veronese Umberto Scandola, reduce da due podi consecutivi alla Targa e vincitore quest&#8217;anno di gara-1 al Sanremo, ha riguardato soprattutto l&#8217;affinamento del setup sulla sua Skoda Fabia R5 ufficiale: &#8220;Lo shakedown \u00e8 stato il primo assaggio, abbiamo apportato alcune modifiche e l&#8217;auto va bene. Siamo fiduciosi e rimaniamo concentrati&#8221;. A caccia di nuovi riferimenti \u00e8 andato il romagnolo Simone Campedelli sulla Peugeot 208 T16, iscritto anche per il Trofeo Asfalto: &#8220;Alla Targa \u00e8 sempre bellissimo correre, stiamo acquisendo sempre piu dati e il feeling con l&#8217;auto cresce, siamo pronti per stasera&#8221;. Per il Trofeo impegnati anche il toscano &#8220;Ciava&#8221; al volante della Citroen DS3 (&#8220;Emozionante la prima Targa! L&#8217;obiettivo \u00e8 fare esperienza e arrivare in fondo&#8221;) e il veneto Simone Tempestini sulla Ford Fiesta: &#8220;All&#8217;esordio qui dovevo utilizzare al meglio lo shakedown per partire al massimo stasera e dare il massimo domani&#8221;. Nel Tricolore Junior si presenta da leader nella gara di casa, dove per\u00f2 \u00e8 all&#8217;esordio, Marco Pollara sulla Peugeot 208 R2 in una livrea tutta particolare: &#8220;In stile carretto siciliano, decisa proprio in onore di questa centesima edizione e naturalmente della nostra isola. Qui mi aspetto una grande battaglia con i numerosi e agguerriti avversari, speriamo sia un debutto positivo&#8221;. Tra i rivali non si nasconde il molisano Giuseppe Testa, sempre su una 208 del Leone e vincitore della categoria alla Targa 2015: &#8220;Questa \u00e8 una delle mie gare preferite. Bisogna mettere in atto in gara quanto fatto nello shakedown. Pollara, Casella, Bernardi sono tutti piloti da non sottovalutare&#8221;. Salgono le aspettative anche per i piloti siciliani, tra i quali sulle vetture di classe R5 spiccano il messinese di Santa Teresa Riva due volte Campione italiano (Junior e Produzione) Andrea Nucita sulla Ford Fiesta, il cefaludese Marco Runfola sulla Peugeot 208 e il tre volte vincitore della corsa Tot\u00f2 Riolo, anche lui sulla 208 T16: &#8220;Le sensazioni sono positive &#8211; ha detto l&#8217;asso di Cerda -, vengo da un rally dell&#8217;Elba che \u00e8 andato davvero molto bene. La Targa \u00e8 &#8216;la&#8217; gara per noi, la pi\u00f9 importante, l&#8217;auto \u00e8 eccezionale e il team ha fatto un gran lavoro&#8221;. Con una gi\u00e0 molto ammirata Porsche 997 GT3 \u00e8 in gara tra le moderne anche il palermitano Domenico Guagliardo, vincitore tra le storiche nel 2015: &#8220;L&#8217;auto \u00e8 molto aggressiva e certamente dovremo gestire gli aspetti legati alla velocit\u00e0, percorrenza e guidabilit\u00e0 mi sono sembrate dei punti di forza&#8221;.<\/p>\n<p>Tornando al programma odierno degli altri eventi della 100th Targa Florio, \u00e8 in corso la prima tappa sulle Madonie per la Targa Florio Classic, l&#8217;evento riservato agli specialisti della regolarit\u00e0. La prestigiosa ed elegante carovana domani (sabato) visiter\u00e0 alcuni dei luoghi e delle localit\u00e0 pi\u00f9 suggestive della Sicilia spostandosi fino alla Valle dei Templi ad Agrigento e successivamente rientrer\u00e0 a Palermo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 100th Targa Florio ha acceso i motori della Classic e del Ferrari Tribute tra un mare di folla gioved\u00ec sera a Palermo e questa sera alle 20 si replica ancora in piazza Verdi e con l&#8217;imponente sfondo del Teatro Massimo quando a prendere il via saranno le attese vetture da rally, in totale 276 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6408,321],"tags":[],"class_list":["post-24846","post","type-post","status-publish","format-standard","has-post-thumbnail","category-100-targa-florio","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALLE 20,00 SI ACCENDONO I MOTORI DELLA 100TH TARGA FLORIO - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALLE 20,00 SI ACCENDONO I MOTORI DELLA 100TH TARGA FLORIO - AbmNews\" \/>\n<meta property=\"og:description\" content=\"La 100th Targa Florio ha acceso i motori della Classic e del Ferrari Tribute tra un mare di folla gioved\u00ec sera a Palermo e questa sera alle 20 si replica ancora in piazza Verdi e con l&#8217;imponente sfondo del Teatro Massimo quando a prendere il via saranno le attese vetture da rally, in totale 276 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-06T15:08:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/05\/unnamed3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"ALLE 20,00 SI ACCENDONO I MOTORI DELLA 100TH TARGA FLORIO\",\"datePublished\":\"2016-05-06T15:08:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\\\/\"},\"wordCount\":1037,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/unnamed3.jpg\",\"articleSection\":[\"100\u00b0 TARGA FLORIO\",\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\\\/\",\"name\":\"ALLE 20,00 SI ACCENDONO I MOTORI DELLA 100TH TARGA FLORIO - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/unnamed3.jpg\",\"datePublished\":\"2016-05-06T15:08:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/unnamed3.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/unnamed3.jpg\",\"width\":720,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALLE 20,00 SI ACCENDONO I MOTORI DELLA 100TH TARGA FLORIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALLE 20,00 SI ACCENDONO I MOTORI DELLA 100TH TARGA FLORIO - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/","og_locale":"it_IT","og_type":"article","og_title":"ALLE 20,00 SI ACCENDONO I MOTORI DELLA 100TH TARGA FLORIO - AbmNews","og_description":"La 100th Targa Florio ha acceso i motori della Classic e del Ferrari Tribute tra un mare di folla gioved\u00ec sera a Palermo e questa sera alle 20 si replica ancora in piazza Verdi e con l&#8217;imponente sfondo del Teatro Massimo quando a prendere il via saranno le attese vetture da rally, in totale 276 [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2016-05-06T15:08:24+00:00","og_image":[{"width":720,"height":479,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/05\/unnamed3.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"ALLE 20,00 SI ACCENDONO I MOTORI DELLA 100TH TARGA FLORIO","datePublished":"2016-05-06T15:08:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/"},"wordCount":1037,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/05\/unnamed3.jpg","articleSection":["100\u00b0 TARGA FLORIO","Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/","url":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/","name":"ALLE 20,00 SI ACCENDONO I MOTORI DELLA 100TH TARGA FLORIO - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/05\/unnamed3.jpg","datePublished":"2016-05-06T15:08:24+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/05\/unnamed3.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/05\/unnamed3.jpg","width":720,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/alle-2000-si-accendono-i-motori-della-100th-targa-florio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"ALLE 20,00 SI ACCENDONO I MOTORI DELLA 100TH TARGA FLORIO"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/24846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=24846"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/24846\/revisions"}],"predecessor-version":[{"id":24848,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/24846\/revisions\/24848"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/24847"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=24846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=24846"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=24846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}