{"id":25141,"date":"2016-05-21T06:19:24","date_gmt":"2016-05-21T04:19:24","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=25141"},"modified":"2016-05-21T06:19:24","modified_gmt":"2016-05-21T04:19:24","slug":"bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/","title":{"rendered":"BMW Motorrad R 5 Hommage. L\u2019Essenza della Bellezza e della Semplicit\u00e0al Concorso d\u2019Eleganza Villa d\u2019Este"},"content":{"rendered":"<p>80 anni or sono, BMW presentava al pubblico internazionale la BMW R 5 \u2013 un\u2019eccitante evoluzione tecnologica che avrebbe influenzato la produzione motociclistica attraverso tutti gli anni Cinquanta. Ispirata alla versione da corsa prodotta in fabbrica del 1935, era una straordinaria moto da corsa della fine anni Trenta con il suo innovativo telaio leggero. Per celebrare l\u201980\u00b0 anniversario della BMW R 5, BMW Motorrad rende omaggio a questo modello iconico al Concorso d\u2019Eleganza Villa d\u2019Este 2016 con un modello speciale: la BMW R 5 Hommage.<br \/>\nLa BMW R 5 Hommage interpreta l\u2019essenza del motociclismo in chiave moderna, sposando il mondo del design motociclistico storico con il mondo moderno delle moto custom.<\/p>\n<p>\u201cQuando debutt\u00f2, la R 5 non era soltanto un capolavoro ingegneristico, ma spiccava per la purezza delle sue linee e l\u2019eleganza delle sue proporzioni. A mio parere, la R 5 resta tutt\u2019oggi una delle moto pi\u00f9 attraenti della storia della BMW,\u201d sostiene Edgar Heinrich, Head of Design BMW Motorrad. \u201cIl suo fascino e la sua bellezza unica stanno tutti nella sua semplicit\u00e0\u201d, aggiunge Ola Stenegard, Head of Vehicle Design e Creative Director Heritage BMW Motorrad. \u201cNel mondo moderno \u00e8 molto semplice complicarsi la vita, ma molto complicato semplificarla. La BMW R 5 coglie la quintessenza della motocicletta. Il nostro intento era quello di cogliere la sua purezza e la sua elegante estetica e trasportala ai giorni nostri \u2013 creando una rispettosa combinazione di vecchia scuola e high-tech, con una \u2018spolverata\u2019 di alte prestazioni\u201d.<\/p>\n<p>Vintage e Custom<br \/>\nLa BMW R 5 Hommage mostra come il mondo delle moto d\u2019epoca si sposi armoniosamente con il mondo delle moto custom. Il cuore pulsante di questo progetto \u00e8 il motore bicilindrico di 500 cc fornito dall\u2019appassionato di moto Sebastian Gutsch. Questo motore boxer fu danneggiato in una gara e forn\u00ec il punto di partenza per la creazione della BMW R 5 Hommage.<\/p>\n<p>Come avviene per una moto custom, la BMW R 5 Hommage \u00e8 stata costruita a mano partendo dal foglio bianco. Ronny e Benny Noren sono stati incaricati di costruire le varie componenti sulla base dei progetti forniti dal BMW Motorrad Design Team: i due fratelli hanno costruito moto su misura per trent\u2019anni.<\/p>\n<p>Il cuore storico\u2026<br \/>\nIl motore bicilindrico boxer a quattro tempi della R 5 era stato disegnato ex novo all\u2019epoca e vantava una potenza massima di 24 CV a 5.500 giri\/min. La distribuzione era a catena con doppio albero a camme. Anche grazie l\u2019innovativo telaio in tubolari ovali saldati, la leggera R 5 raggiungeva la velocit\u00e0 massima di 135 km\/h, rendendola quasi veloce come la R 17 da 33 CV e 750 cc di cilindrata \u2013 motivo per cui veniva spesso scelta per le competizioni, cos\u00ec come il motore scelto per la BMW R 5 Hommage, danneggiato durante una gara. Diverse componenti della moto commemorativa, come il coperchio delle valvole e lo scudo anteriore del motore boxer sono state prodotte in alluminio partendo dai disegni originali: conferiscono al cuore storico un tocco di modernit\u00e0.<\/p>\n<p>\u2026 in un abito realizzato su misura<br \/>\nI due decani delle moto custom, Ronny e Benny Noren, erano i partner perfetti per il progetto BMW R 5 Hommage per vestire il cuore storico e produrre le componenti mancanti del motore e del cambio. Le altre parti hanno progressivamente preso forma nell\u2019officina dei fratelli Noren sulla base dei disegni del BMW Motorrad Design Team. Tutte le componenti come il telaio, il serbatoio ed il parafango posteriore sono pezzi unici \u2013 realizzati a mano \u2013 rendendo la BMW R 5 Hommage una vera moto custom. Soprattutto, le nuove componenti ridisegnate portano nel futuro l\u2019originale carattere purista della R 5.<\/p>\n<p>Eleganza senza tempo: le proporzioni<br \/>\nIl risultato \u00e8 sorprendente: anche da lontano le proporzioni rispecchiano la bellezza senza tempo del minimalismo essenziale \u2013 fedele allo spirito originale della R 5 \u2013 traducendo questa idea originale ai tempi moderni. Il telaio ed il serbatoio riprendono l\u2019elegante forma a goccia dell\u2019originale in un\u2019interpretazione pi\u00f9 aerodinamica e moderna. La forcella anteriore \u00e8 leggermente pi\u00f9 inclinata, ad esempio, per conferire alla R 5 Hommage una maggior presenza e maggiore carattere sottolineandone l\u2019appartenenza al mondo delle moto personalizzate. Per quanto riguarda il telaio, ci siamo concentrati sui tubolari a sezione ovale che rappresentavano una caratteristica peculiare dell\u2019originale. Il telaio ed il serbatoio descrivono una linea continua dal manubrio fino al mozzo della ruota posteriore, conferendo eleganza nella vista laterale. Il parafango posteriore in metallo realizzato a mano completa la configurazione minimalista.<\/p>\n<p>Interpretazione moderna di dettagli storici<br \/>\nUna delle caratteristiche che definiscono particolarmente l\u2019aspetto della R 5 originale erano le forcelle telescopiche \u2013 una novit\u00e0 per quei tempi \u2013 i cui steli erano coperti con profili aerodinamici all\u2019altezza del faro. La BMW R 5 Hommage rievoca questo elemento stilistico e lo interpreta in chiave moderna basandosi sulla forcella personalizzata. Il bordo superiore dei tappi delle forcelle richiamano le pieghe dello scudo anteriore e del coperchio delle valvole riprendendo l\u2019interpretazione suggerita dalle tipiche \u201ccostole\u201d della R 5. Allo stesso modo, le leve del freno e della frizione poste sul manubrio mescolano il passato con lo stato dell\u2019arte della tecnologia: queste componenti realizzate su misura abbinano l\u2019aspetto delle storiche leve rovesciate con le opzioni di regolazione dei moderni comandi.<\/p>\n<p>Straordinaria personalizzazione artigianale: compressore, scarichi<br \/>\ne sospensioni<br \/>\nIl cuore della BMW R 5 resta nelle proporzioni minimaliste della moto commemorativa. La specificit\u00e0 tecnica del motore \u00e8 costituita dal compressore che sulla BMW R 5 Homage incrementa a 26 CV la potenza del motore 500 cc originale, aggiornandola a livelli attuali.<br \/>\nUn sistema di scarico in acciaio di nuova realizzazione riflette attraverso il suono l\u2019aumento di potenza.<\/p>\n<p>Altri accenti contemporanei arrivano dalla sospensione posteriore, dal moderno impianto frenante con pinze a pistoncino e dal design elaborato per gli alloggiamenti delle ruote anteriore e posteriore. Quest\u2019ultimo combina il sistema frenante e l\u2019ancoraggio dei raggi ruota in un unico elemento estetico \u2013 frutto di una dettagliata riflessione del concetto minimalista incarnato dalla BMW R 5 Hommage.<\/p>\n<p>Il colore: stile classico BMW eppure da vera moto custom<br \/>\nLa BMW R 5 Hommage viene presentata in modo classico per quanto riguarda la colorazione. Il tema base \u00e8 tipicamente BMW \u2013 nero con righe bianche, ovviamente reinterpretate in stile moderno. Oltre alle finiture opache delle superfici, i cosiddetti dettagli \u201cfum\u00e9\u201d sul serbatoio e sul parafango posteriore lasciano trasparire parzialmente l\u2019acciaio sottostante. Oltre alle strisce bianche, la verniciatura nera del serbatoio e del parafango posteriore acquisiscono ulteriore personalit\u00e0, in perfetto stile custom, grazie alla finitura metallizzata con un leggero effetto \u201ccristallo\u201d. Il basamento del motore e la scatola del cambio in alluminio satinato fanno il paio con le componenti in alluminio lucidato come il coperchio delle valvole e lo scudo anteriore. La lucentezza dell\u2019alluminio lucidato \u00e8 una particolare reminiscenza della BMW R 5 originale. L\u2019immagine d\u2019insieme \u00e8 completata dal sellino in pelle lavorato a mano con goffratura di alta qualit\u00e0 artigianale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>80 anni or sono, BMW presentava al pubblico internazionale la BMW R 5 \u2013 un\u2019eccitante evoluzione tecnologica che avrebbe influenzato la produzione motociclistica attraverso tutti gli anni Cinquanta. Ispirata alla versione da corsa prodotta in fabbrica del 1935, era una straordinaria moto da corsa della fine anni Trenta con il suo innovativo telaio leggero. Per [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25142,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[363],"tags":[],"class_list":["post-25141","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bmw"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BMW Motorrad R 5 Hommage. L\u2019Essenza della Bellezza e della Semplicit\u00e0al Concorso d\u2019Eleganza Villa d\u2019Este - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BMW Motorrad R 5 Hommage. L\u2019Essenza della Bellezza e della Semplicit\u00e0al Concorso d\u2019Eleganza Villa d\u2019Este - AbmNews\" \/>\n<meta property=\"og:description\" content=\"80 anni or sono, BMW presentava al pubblico internazionale la BMW R 5 \u2013 un\u2019eccitante evoluzione tecnologica che avrebbe influenzato la produzione motociclistica attraverso tutti gli anni Cinquanta. Ispirata alla versione da corsa prodotta in fabbrica del 1935, era una straordinaria moto da corsa della fine anni Trenta con il suo innovativo telaio leggero. Per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-21T04:19:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/05\/P90219646_lowRes_bmw-motorrad-r5-homa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"BMW Motorrad R 5 Hommage. L\u2019Essenza della Bellezza e della Semplicit\u00e0al Concorso d\u2019Eleganza Villa d\u2019Este\",\"datePublished\":\"2016-05-21T04:19:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\\\/\"},\"wordCount\":1127,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/P90219646_lowRes_bmw-motorrad-r5-homa.jpg\",\"articleSection\":[\"BMW\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\\\/\",\"name\":\"BMW Motorrad R 5 Hommage. L\u2019Essenza della Bellezza e della Semplicit\u00e0al Concorso d\u2019Eleganza Villa d\u2019Este - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/P90219646_lowRes_bmw-motorrad-r5-homa.jpg\",\"datePublished\":\"2016-05-21T04:19:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/P90219646_lowRes_bmw-motorrad-r5-homa.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/P90219646_lowRes_bmw-motorrad-r5-homa.jpg\",\"width\":600,\"height\":399},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BMW Motorrad R 5 Hommage. L\u2019Essenza della Bellezza e della Semplicit\u00e0al Concorso d\u2019Eleganza Villa d\u2019Este\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BMW Motorrad R 5 Hommage. L\u2019Essenza della Bellezza e della Semplicit\u00e0al Concorso d\u2019Eleganza Villa d\u2019Este - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/","og_locale":"it_IT","og_type":"article","og_title":"BMW Motorrad R 5 Hommage. L\u2019Essenza della Bellezza e della Semplicit\u00e0al Concorso d\u2019Eleganza Villa d\u2019Este - AbmNews","og_description":"80 anni or sono, BMW presentava al pubblico internazionale la BMW R 5 \u2013 un\u2019eccitante evoluzione tecnologica che avrebbe influenzato la produzione motociclistica attraverso tutti gli anni Cinquanta. Ispirata alla versione da corsa prodotta in fabbrica del 1935, era una straordinaria moto da corsa della fine anni Trenta con il suo innovativo telaio leggero. Per [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2016-05-21T04:19:24+00:00","og_image":[{"width":600,"height":399,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/05\/P90219646_lowRes_bmw-motorrad-r5-homa.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"BMW Motorrad R 5 Hommage. L\u2019Essenza della Bellezza e della Semplicit\u00e0al Concorso d\u2019Eleganza Villa d\u2019Este","datePublished":"2016-05-21T04:19:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/"},"wordCount":1127,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/05\/P90219646_lowRes_bmw-motorrad-r5-homa.jpg","articleSection":["BMW"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/","url":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/","name":"BMW Motorrad R 5 Hommage. L\u2019Essenza della Bellezza e della Semplicit\u00e0al Concorso d\u2019Eleganza Villa d\u2019Este - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/05\/P90219646_lowRes_bmw-motorrad-r5-homa.jpg","datePublished":"2016-05-21T04:19:24+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/05\/P90219646_lowRes_bmw-motorrad-r5-homa.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/05\/P90219646_lowRes_bmw-motorrad-r5-homa.jpg","width":600,"height":399},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/bmw-motorrad-r-5-hommage-lessenza-della-bellezza-e-della-semplicitaal-concorso-deleganza-villa-deste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"BMW Motorrad R 5 Hommage. L\u2019Essenza della Bellezza e della Semplicit\u00e0al Concorso d\u2019Eleganza Villa d\u2019Este"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=25141"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25141\/revisions"}],"predecessor-version":[{"id":25143,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25141\/revisions\/25143"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/25142"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=25141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=25141"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=25141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}