{"id":25426,"date":"2016-06-02T05:42:36","date_gmt":"2016-06-02T03:42:36","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=25426"},"modified":"2016-06-02T05:42:36","modified_gmt":"2016-06-02T03:42:36","slug":"nuovo-citroen-jumpy-debutta-sul-mercato-italiano","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/","title":{"rendered":"Nuovo Citro\u00ebn Jumpy, debutta sul mercato italiano"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Dopo essere stato presentato al recente Salone di Birmingham, Nuovo Citro\u00ebn Jumpy debutta sul nostro mercato, accompagnato dalla versione Atlante, per il trasporto persone.<\/p>\n<p>Nuovo Jumpy arriva in un momento particolarmente interessante per Citro\u00ebn nel mercato dei veicoli commerciali. Il Marchio, infatti, ha chiuso il 2015 con un incremento delle vendite pari al 21,8% rispetto al 2014 e il primo quadrimestre 2016 con un +23,7% rispetto all\u2019analogo periodo dello scorso anno.<\/p>\n<p>In Italia viene proposto in tre configurazioni: furgone, pianale cabinato e doppia cabina. Le versioni doppia cabina saranno disponibili prossimamente.<\/p>\n<p>I punti di forza di Nuovo Jumpy, \u201cThe magic box\u201d del Double Chevron, consentiranno di rafforzare la presenza di Citro\u00ebn nel segmento K1 del mercato dei commerciali:<\/p>\n<p>+ design, moderno e al servizio di ogni esigenza;<\/p>\n<p>+ modularit\u00e0, per una massima facilit\u00e0 di carico grazie a:<br \/>\n&#8211; tre lunghezze: XS 4,60 m, inedita nel segmento, M 4,95 m e XL 5,30 m;<br \/>\n&#8211; Moduwork, che permette di ottenere una lunghezza utile fino a 4 m nella versione XL;<br \/>\n&#8211; maggiori volumi a disposizione: da 5,1 m3 per la versione XS fino a 6,6 m3 per la versione XL (grazie al Moduwork);<br \/>\n&#8211; carico utile maggiorato, fino a 1.400 kg;<br \/>\n&#8211; altezza contenuta di soli 1,90 m che gli permette di accedere ai parcheggi sotterranei di abitazioni, centri commerciali e aeroporti, non sempre accessibili per veicoli di questa categoria.<\/p>\n<p>+ equipaggiamenti high-tech come il Touch Pad da 7\u201d, per una connettivit\u00e0 immediata e intuitiva e l\u2019apertura delle porte laterali senza chiavi.<\/p>\n<p>+ motorizzazioni efficienti, che assicurano costi d\u2019utilizzo \u201cbest in class\u201d (BlueHDi 95, BlueHDi 95 S&amp;S ETG6, BlueHDi 115 S&amp;S, BlueHDi 120, BlueHDi 120 S&amp;S, BlueHDi 150 S&amp;S, BlueHDi 180 S&amp;S EAT6).<\/p>\n<p>I prezzi partono da \u20ac 20.250 IVA esclusa per il furgone lamierato in taglia XS e allestimento Comfort e 21.450 euro per il pianale cabinato.<\/p>\n<p>Nuovo Citro\u00ebn Jumpy Atlante, omologato per il trasporto di persone, ripropone molte delle soluzioni innovative della versione commerciale.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Alto 1,90 m e anch\u2019esso disponibile in tre \u201ctaglie\u201d (XS 4,60 m, M 4,95 m e XL 5,30 m), \u00e8 stato pensato per i professionisti del trasporto di persone, mettendo a disposizione fino a 10 combinazioni di sedute, per un massimo di 9 passeggeri.<\/p>\n<p>Robusto e funzionale, Nuovo Citro\u00ebn Jumpy Atlante si caratterizza per la sua grande modularit\u00e0. Ad esempio, per facilitare l\u2019accesso alla terza fila, nella configurazione a 8\/9 posti (in opzione) i sedili della seconda fila possono essere ripiegati con un semplice gesto, liberando cos\u00ec il passaggio.<\/p>\n<p>In Italia \u00e8 commercializzato in un unico livello di allestimento, con due tipologie di rivestimento per i sedili.<\/p>\n<p>Cinque i motori a disposizione: BlueHDi 95, BlueHDi 95 ETG6, BlueHDi 115 S&amp;S, BlueHDi 150 S&amp;S, BlueHDi 180 S&amp;S EAT6, con prezzi a partire da \u20ac 26.900 chiavi in mano.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dopo essere stato presentato al recente Salone di Birmingham, Nuovo Citro\u00ebn Jumpy debutta sul nostro mercato, accompagnato dalla versione Atlante, per il trasporto persone. Nuovo Jumpy arriva in un momento particolarmente interessante per Citro\u00ebn nel mercato dei veicoli commerciali. Il Marchio, infatti, ha chiuso il 2015 con un incremento delle vendite pari al 21,8% rispetto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25427,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-25426","post","type-post","status-publish","format-standard","has-post-thumbnail","category-senza-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuovo Citro\u00ebn Jumpy, debutta sul mercato italiano - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuovo Citro\u00ebn Jumpy, debutta sul mercato italiano - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Dopo essere stato presentato al recente Salone di Birmingham, Nuovo Citro\u00ebn Jumpy debutta sul nostro mercato, accompagnato dalla versione Atlante, per il trasporto persone. Nuovo Jumpy arriva in un momento particolarmente interessante per Citro\u00ebn nel mercato dei veicoli commerciali. Il Marchio, infatti, ha chiuso il 2015 con un incremento delle vendite pari al 21,8% rispetto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-02T03:42:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/CL_16.033.022_04.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"634\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Nuovo Citro\u00ebn Jumpy, debutta sul mercato italiano\",\"datePublished\":\"2016-06-02T03:42:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\\\/\"},\"wordCount\":452,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/CL_16.033.022_04.jpg\",\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\\\/\",\"name\":\"Nuovo Citro\u00ebn Jumpy, debutta sul mercato italiano - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/CL_16.033.022_04.jpg\",\"datePublished\":\"2016-06-02T03:42:36+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/CL_16.033.022_04.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/CL_16.033.022_04.jpg\",\"width\":1024,\"height\":634},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuovo Citro\u00ebn Jumpy, debutta sul mercato italiano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuovo Citro\u00ebn Jumpy, debutta sul mercato italiano - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/","og_locale":"it_IT","og_type":"article","og_title":"Nuovo Citro\u00ebn Jumpy, debutta sul mercato italiano - AbmNews","og_description":"Dopo essere stato presentato al recente Salone di Birmingham, Nuovo Citro\u00ebn Jumpy debutta sul nostro mercato, accompagnato dalla versione Atlante, per il trasporto persone. Nuovo Jumpy arriva in un momento particolarmente interessante per Citro\u00ebn nel mercato dei veicoli commerciali. Il Marchio, infatti, ha chiuso il 2015 con un incremento delle vendite pari al 21,8% rispetto [&hellip;]","og_url":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2016-06-02T03:42:36+00:00","og_image":[{"width":1024,"height":634,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/CL_16.033.022_04.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Nuovo Citro\u00ebn Jumpy, debutta sul mercato italiano","datePublished":"2016-06-02T03:42:36+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/"},"wordCount":452,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/CL_16.033.022_04.jpg","inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/","url":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/","name":"Nuovo Citro\u00ebn Jumpy, debutta sul mercato italiano - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/CL_16.033.022_04.jpg","datePublished":"2016-06-02T03:42:36+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/CL_16.033.022_04.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/CL_16.033.022_04.jpg","width":1024,"height":634},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/nuovo-citroen-jumpy-debutta-sul-mercato-italiano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuovo Citro\u00ebn Jumpy, debutta sul mercato italiano"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=25426"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25426\/revisions"}],"predecessor-version":[{"id":25428,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25426\/revisions\/25428"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/25427"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=25426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=25426"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=25426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}