{"id":25487,"date":"2016-06-06T15:47:39","date_gmt":"2016-06-06T13:47:39","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=25487"},"modified":"2016-06-06T15:48:02","modified_gmt":"2016-06-06T13:48:02","slug":"nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/","title":{"rendered":"Nilox DOC+: il nuovo modello Bluetooth per volare a suon di musica"},"content":{"rendered":"<p>Per chi sogna di volare sulle due ruote elettriche di DOC ma non pu\u00f2 vivere senza musica, ecco Nilox DOC+. Tutto il divertimento di DOC con in pi\u00f9 un potente speaker Bluetooth per ascoltare le proprie playlist anche in movimento.<\/p>\n<p>&nbsp;<\/p>\n<p>Come gli altri modelli della gamma Nilox, anche DOC+ \u00e8 un concentrato di hi-tech, design e divertimento. E\u2019 davvero semplicissimo da usare, perch\u00e9 &#8211; per muoversi &#8211; basta pensare al movimento e il gioco \u00e8 fatto. E\u2019 sufficiente salire sulle due ruote da 6 pollici e mezzo di DOC, e dopo pochi minuti, prendere dimestichezza e guidarlo bilanciando il proprio peso per andare avanti indietro, a destra e sinistra. Il motore elettrico vi far\u00e0 sfrecciare fino a un massimo di 10 km\/h, salire su leggere pendenze e muoversi sulle pi\u00f9 diverse superfici. Il tutto ascoltando la propria musica preferita, semplicemente collegando la cassa Bluetooth posizionata sotto la pedana di Nilox DOC+ al proprio smartphone o lettore musicale.<\/p>\n<p>&nbsp;<\/p>\n<p>La marca italiana di tecnologia per lo sport \u00e8 stata la prima a portare in Italia lo skateboard del futuro, il prodotto che ha fatto impazzire gli Stati Uniti tanto da essere uno dei regali di Natale pi\u00f9 richiesti. La DOC-mania grazie a Nilox \u00e8 arrivata anche nel nostro Paese e ha contagiato perfino le nostre celebrity, sempre a caccia dei prodotti pi\u00f9 trendy e alla moda, che hanno fatto a gara per provarlo e postare dei video sui loro profili Facebook e Instagram.\u00a0\u00a0Questo perch\u00e9 salire su un DOC \u00e8 un\u2019esperienza unica e super-divertente, oggi ancora pi\u00f9 entusiasmante con il modello DOC+.<\/p>\n<p>&nbsp;<\/p>\n<p>Con la linea DOC, Nilox vuole replicare il successo ottenuto nel segmento action cam dove risulta essere il brand italiano pi\u00f9 venduto al mondo, utilizzando le stesse carte vincenti: attenzione e controllo di tutti i componenti per garantire un prodotto sicuro e di qualit\u00e0, un servizio di assistenza serio ed affidabile e una campagna di comunicazione dedicata.<\/p>\n<p>&nbsp;<\/p>\n<p>DOC+ \u00e8 disponibile in tre varianti di colore (nero, bianco e nero-oro) con borsa, adesivi e protezione in gomma\u00a0gi\u00e0 inclusi nel packaging. Prezzo consigliato al pubblico: 499,99 euro.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per chi sogna di volare sulle due ruote elettriche di DOC ma non pu\u00f2 vivere senza musica, ecco Nilox DOC+. Tutto il divertimento di DOC con in pi\u00f9 un potente speaker Bluetooth per ascoltare le proprie playlist anche in movimento. &nbsp; Come gli altri modelli della gamma Nilox, anche DOC+ \u00e8 un concentrato di hi-tech, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25488,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-25487","post","type-post","status-publish","format-standard","has-post-thumbnail","category-senza-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nilox DOC+: il nuovo modello Bluetooth per volare a suon di musica - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nilox DOC+: il nuovo modello Bluetooth per volare a suon di musica - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Per chi sogna di volare sulle due ruote elettriche di DOC ma non pu\u00f2 vivere senza musica, ecco Nilox DOC+. Tutto il divertimento di DOC con in pi\u00f9 un potente speaker Bluetooth per ascoltare le proprie playlist anche in movimento. &nbsp; Come gli altri modelli della gamma Nilox, anche DOC+ \u00e8 un concentrato di hi-tech, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-06T13:47:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-06T13:48:02+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/unnamed12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"515\" \/>\n\t<meta property=\"og:image:height\" content=\"515\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Nilox DOC+: il nuovo modello Bluetooth per volare a suon di musica\",\"datePublished\":\"2016-06-06T13:47:39+00:00\",\"dateModified\":\"2016-06-06T13:48:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\\\/\"},\"wordCount\":357,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/unnamed12.jpg\",\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\\\/\",\"name\":\"Nilox DOC+: il nuovo modello Bluetooth per volare a suon di musica - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/unnamed12.jpg\",\"datePublished\":\"2016-06-06T13:47:39+00:00\",\"dateModified\":\"2016-06-06T13:48:02+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/unnamed12.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/unnamed12.jpg\",\"width\":515,\"height\":515},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nilox DOC+: il nuovo modello Bluetooth per volare a suon di musica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nilox DOC+: il nuovo modello Bluetooth per volare a suon di musica - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/","og_locale":"it_IT","og_type":"article","og_title":"Nilox DOC+: il nuovo modello Bluetooth per volare a suon di musica - AbmNews","og_description":"Per chi sogna di volare sulle due ruote elettriche di DOC ma non pu\u00f2 vivere senza musica, ecco Nilox DOC+. Tutto il divertimento di DOC con in pi\u00f9 un potente speaker Bluetooth per ascoltare le proprie playlist anche in movimento. &nbsp; Come gli altri modelli della gamma Nilox, anche DOC+ \u00e8 un concentrato di hi-tech, [&hellip;]","og_url":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2016-06-06T13:47:39+00:00","article_modified_time":"2016-06-06T13:48:02+00:00","og_image":[{"width":515,"height":515,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/unnamed12.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Nilox DOC+: il nuovo modello Bluetooth per volare a suon di musica","datePublished":"2016-06-06T13:47:39+00:00","dateModified":"2016-06-06T13:48:02+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/"},"wordCount":357,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/unnamed12.jpg","inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/","url":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/","name":"Nilox DOC+: il nuovo modello Bluetooth per volare a suon di musica - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/unnamed12.jpg","datePublished":"2016-06-06T13:47:39+00:00","dateModified":"2016-06-06T13:48:02+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/unnamed12.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/unnamed12.jpg","width":515,"height":515},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/nilox-doc-il-nuovo-modello-bluetooth-per-volare-a-suon-di-musica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nilox DOC+: il nuovo modello Bluetooth per volare a suon di musica"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=25487"}],"version-history":[{"count":2,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25487\/revisions"}],"predecessor-version":[{"id":25490,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25487\/revisions\/25490"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/25488"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=25487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=25487"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=25487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}