{"id":26555,"date":"2016-09-02T04:08:29","date_gmt":"2016-09-02T02:08:29","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=26555"},"modified":"2016-09-02T04:08:29","modified_gmt":"2016-09-02T02:08:29","slug":"mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/","title":{"rendered":"Mercato Auto: le ferie fanno bene al mercato dell\u2019auto agosto + 20,1%"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>La pausa estiva fa bene al mercato dell\u2019auto che, dopo il rallentamento registrato nel mese di luglio, sembra riprendersi con un tonico +20,1%, figlio anche di un giorno lavorativo in pi\u00f9. Riprende di conseguenza, la crescita del cumulato, senza alibi sulle giornate lavorative che nei due anni coincidono.<\/p>\n<p>Secondo i dati diffusi oggi dal Ministero delle Infrastrutture e dei Trasporti, agosto si chiude con un immatricolato di 71.576 auto, in crescita del 20,1% rispetto alle 59.587 unit\u00e0 dello stesso mese dello scorso anno, con circa 12.000 immatricolazioni in pi\u00f9. Gli otto mesi cumulati segnano una crescita del 17,4% e 1.251.806 auto vendute rispetto alle 1.066.454 dello stesso periodo del 2015.<\/p>\n<p>\u201cSe guardiamo ai prossimi mesi &#8211; ha detto Massimo Nordio, Presidente dell\u2019UNRAE, l\u2019Associazione delle Case automobilistiche estere &#8211; dobbiamo ricordare che l\u2019avvicinarsi del periodo autunnale porter\u00e0 ancora irrisolti molti temi della mobilit\u00e0, tradizionalmente affrontati con estemporaneit\u00e0, urgenza ed in assenza di coordinamento come i piani antismog, i blocchi del traffico, le targhe alterne e le restrizioni a livelli di Direttiva.<\/p>\n<p>\u201cRibadiamo quindi la necessit\u00e0 &#8211; conclude Nordio &#8211; di una cabina di regia, coordinata da un Mobility Champion &#8211; come abbiamo gi\u00e0 proposto nel nostro recente incontro con la Stampa alla presenza del Ministro delle Infrastrutture e dei Trasporti, Graziano Delrio &#8211; che sappia guidarla per armonizzare, impostare e implementare gli interventi necessari a garantire una mobilit\u00e0 fruibile alle famiglie.\u201d<\/p>\n<p>Intanto, dall\u2019analisi delle vendite emerge un buon incremento a doppia cifra in agosto per tutti i canali di vendita. I privati crescono del 18,5%, fermandosi al 67,4% del totale e portando il cumulato ad un +17,7%, con una quota che si conferma al 62% del mercato. Pi\u00f9 dinamico il noleggio che continua a crescere, segnando nel mese un +24% (13,1% di quota), in particolare grazie all\u2019andamento del breve termine con un sostanzioso +58,7%. Buono anche il trend del lungo temine, al +18% in volume. Negli 8 mesi cumulati il noleggio si mantiene in crescita del 14,2%, al 21,5% del totale. Anche le societ\u00e0 segnano un incremento in volume del 23,5% in agosto, raggiungendo il 19,5% di quota e crescendo nel cumulato del 22%, al 16,5% del totale.<\/p>\n<p>Prosegue la crescita di benzina e diesel, con tassi di incremento in volume superiori al 20% per entrambi, sfiorando rispettivamente il 59% di quota per il diesel e il 30,7% per la benzina, oltre alle ibride che in agosto hanno segnato un +80,2%. L\u2019andamento di flessione, invece, caratterizza anche il mese di agosto per il GPL (-4,8%) e per il metano, in forte calo (-43,4%).<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Dall\u2019analisi per segmento si conferma un trend di crescita per tutti in agosto, ma va rilevato come, mentre per i segmenti medi e superiori l\u2019aumento \u00e8 molto forte per C ed E e addirittura superiore al 50% per il D, i segmenti di ingresso registrano incrementi pi\u00f9 contenuti: +6% per le utilitarie e +14,4% per le city car. Ottimo andamento nel mese anche per tutte le carrozzerie, in particolare per i crossover ed i fuoristrada, ad eccezione dei monovolume.<\/p>\n<p>Anche le aree geografiche del Paese registrano tutte incrementi dei volumi a doppia cifra, con rappresentativit\u00e0 pi\u00f9 o meno stabili, ad eccezione della riduzione di quasi mezzo punto di quota per l\u2019Italia meridionale.<\/p>\n<p>Per concludere l\u2019analisi del mercato, in agosto i trasferimenti di propriet\u00e0 al lordo delle minivolture (i trasferimenti temporanei a nome del concessionario in attesa della rivendita al cliente finale) hanno segnato anch\u2019essi un buon incremento pari al 16,4%, grazie alle 271.586 vetture trasferite, rispetto alle 233.338 del 2015. Nel cumulato la crescita \u00e8 del 6,4% con 3.110.542 unit\u00e0, che si confrontano con le 2.924.144 del gennaio-agosto 2015.<\/p>\n<p><a href=\"http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2016\/09\/Senza-titolo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-26556\" src=\"http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2016\/09\/Senza-titolo-248x300.jpg\" alt=\"Senza titolo\" width=\"248\" height=\"300\" srcset=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/09\/Senza-titolo-248x300.jpg 248w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/09\/Senza-titolo.jpg 471w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La pausa estiva fa bene al mercato dell\u2019auto che, dopo il rallentamento registrato nel mese di luglio, sembra riprendersi con un tonico +20,1%, figlio anche di un giorno lavorativo in pi\u00f9. Riprende di conseguenza, la crescita del cumulato, senza alibi sulle giornate lavorative che nei due anni coincidono. Secondo i dati diffusi oggi dal Ministero [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26557,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6422],"tags":[80],"class_list":["post-26555","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mercato-auto","tag-featured"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercato Auto: le ferie fanno bene al mercato dell\u2019auto agosto + 20,1% - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercato Auto: le ferie fanno bene al mercato dell\u2019auto agosto + 20,1% - AbmNews\" \/>\n<meta property=\"og:description\" content=\"La pausa estiva fa bene al mercato dell\u2019auto che, dopo il rallentamento registrato nel mese di luglio, sembra riprendersi con un tonico +20,1%, figlio anche di un giorno lavorativo in pi\u00f9. Riprende di conseguenza, la crescita del cumulato, senza alibi sulle giornate lavorative che nei due anni coincidono. Secondo i dati diffusi oggi dal Ministero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-02T02:08:29+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/09\/autotrade-and-logistics_il-faldo_superficie-di-parcheggio_260x146.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"260\" \/>\n\t<meta property=\"og:image:height\" content=\"146\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Mercato Auto: le ferie fanno bene al mercato dell\u2019auto agosto + 20,1%\",\"datePublished\":\"2016-09-02T02:08:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\\\/\"},\"wordCount\":583,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/autotrade-and-logistics_il-faldo_superficie-di-parcheggio_260x146.jpg\",\"keywords\":[\"Featured\"],\"articleSection\":[\"Mercato Auto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\\\/\",\"name\":\"Mercato Auto: le ferie fanno bene al mercato dell\u2019auto agosto + 20,1% - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/autotrade-and-logistics_il-faldo_superficie-di-parcheggio_260x146.jpg\",\"datePublished\":\"2016-09-02T02:08:29+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/autotrade-and-logistics_il-faldo_superficie-di-parcheggio_260x146.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/autotrade-and-logistics_il-faldo_superficie-di-parcheggio_260x146.jpg\",\"width\":260,\"height\":146},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercato Auto: le ferie fanno bene al mercato dell\u2019auto agosto + 20,1%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercato Auto: le ferie fanno bene al mercato dell\u2019auto agosto + 20,1% - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/","og_locale":"it_IT","og_type":"article","og_title":"Mercato Auto: le ferie fanno bene al mercato dell\u2019auto agosto + 20,1% - AbmNews","og_description":"La pausa estiva fa bene al mercato dell\u2019auto che, dopo il rallentamento registrato nel mese di luglio, sembra riprendersi con un tonico +20,1%, figlio anche di un giorno lavorativo in pi\u00f9. Riprende di conseguenza, la crescita del cumulato, senza alibi sulle giornate lavorative che nei due anni coincidono. Secondo i dati diffusi oggi dal Ministero [&hellip;]","og_url":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2016-09-02T02:08:29+00:00","og_image":[{"width":260,"height":146,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/09\/autotrade-and-logistics_il-faldo_superficie-di-parcheggio_260x146.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Mercato Auto: le ferie fanno bene al mercato dell\u2019auto agosto + 20,1%","datePublished":"2016-09-02T02:08:29+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/"},"wordCount":583,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/09\/autotrade-and-logistics_il-faldo_superficie-di-parcheggio_260x146.jpg","keywords":["Featured"],"articleSection":["Mercato Auto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/","url":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/","name":"Mercato Auto: le ferie fanno bene al mercato dell\u2019auto agosto + 20,1% - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/09\/autotrade-and-logistics_il-faldo_superficie-di-parcheggio_260x146.jpg","datePublished":"2016-09-02T02:08:29+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/09\/autotrade-and-logistics_il-faldo_superficie-di-parcheggio_260x146.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/09\/autotrade-and-logistics_il-faldo_superficie-di-parcheggio_260x146.jpg","width":260,"height":146},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/mercato-auto-le-ferie-fanno-bene-al-mercato-dellauto-agosto-201\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Mercato Auto: le ferie fanno bene al mercato dell\u2019auto agosto + 20,1%"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/26555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=26555"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/26555\/revisions"}],"predecessor-version":[{"id":26558,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/26555\/revisions\/26558"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/26557"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=26555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=26555"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=26555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}