{"id":27753,"date":"2016-10-15T05:53:50","date_gmt":"2016-10-15T03:53:50","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=27753"},"modified":"2016-10-15T05:53:50","modified_gmt":"2016-10-15T03:53:50","slug":"peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/","title":{"rendered":"Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Se Peugeot 108 si trova a suo agio nelle scatenate e giovani gare musicali di X-Factor, Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d la rassegna milanese, ormai arrivata alla trentaduesima edizione, da cinque anni in collaborazione con Peugeot Italia.<\/p>\n<p>La manifestazione riserva parte della sua programmazione al jazz, un genere che mantiene intatto il suo legame con la propria tradizione cos\u00ec lontana, lasciando spazio anche a linguaggi musicali pi\u00f9 moderni che da esso hanno tratto ispirazione.<\/p>\n<p>Proprio la capacit\u00e0 di valorizzare la tradizione per creare nuovi stimoli per il futuro \u00e8 probabilmente l\u2019 \u201canello di congiunzione\u201d che lega Peugeot alla manifestazione del Teatro Manzoni di Milano.<\/p>\n<p>Automobiles Peugeot, azienda con pi\u00f9 di 200 anni di storia e uno dei pi\u00f9 antichi marchi automobilistici in attivit\u00e0, celebra costantemente il proprio heritage per ritrovare nel proprio passato nuove chiavi di lettura, fonti di ispirazione per un costante rinnovamento e una continua ricerca.<\/p>\n<p>Ne \u00e8 un esempio Peugeot 308, il modello che sar\u00e0 esposto nella hall del Teatro Manzoni per tutta la durata della manifestazione, che continua la tradizione delle \u201cmedie\u201d del Leone e nelle versioni berlina e Station Wagon continua a riscontrare l\u2019apprezzamento dei clienti grazie alle sue prerogative: eleganza e design, funzionalit\u00e0 e innovazione, dinamismo e sportivit\u00e0.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se Peugeot 108 si trova a suo agio nelle scatenate e giovani gare musicali di X-Factor, Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d la rassegna milanese, ormai arrivata alla trentaduesima edizione, da cinque anni in collaborazione con Peugeot Italia. La manifestazione riserva parte della sua [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27754,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[300],"tags":[],"class_list":["post-27753","post","type-post","status-publish","format-standard","has-post-thumbnail","category-peugeot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Se Peugeot 108 si trova a suo agio nelle scatenate e giovani gare musicali di X-Factor, Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d la rassegna milanese, ormai arrivata alla trentaduesima edizione, da cinque anni in collaborazione con Peugeot Italia. La manifestazione riserva parte della sua [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-15T03:53:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/10\/308SW_1312STYP013.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"312\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d\",\"datePublished\":\"2016-10-15T03:53:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\\\/\"},\"wordCount\":225,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/308SW_1312STYP013.jpg\",\"articleSection\":[\"Peugeot\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\\\/\",\"name\":\"Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/308SW_1312STYP013.jpg\",\"datePublished\":\"2016-10-15T03:53:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/308SW_1312STYP013.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/308SW_1312STYP013.jpg\",\"width\":500,\"height\":312},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/","og_locale":"it_IT","og_type":"article","og_title":"Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d - AbmNews","og_description":"Se Peugeot 108 si trova a suo agio nelle scatenate e giovani gare musicali di X-Factor, Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d la rassegna milanese, ormai arrivata alla trentaduesima edizione, da cinque anni in collaborazione con Peugeot Italia. La manifestazione riserva parte della sua [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2016-10-15T03:53:50+00:00","og_image":[{"width":500,"height":312,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/10\/308SW_1312STYP013.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d","datePublished":"2016-10-15T03:53:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/"},"wordCount":225,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/10\/308SW_1312STYP013.jpg","articleSection":["Peugeot"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/","url":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/","name":"Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/10\/308SW_1312STYP013.jpg","datePublished":"2016-10-15T03:53:50+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/10\/308SW_1312STYP013.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/10\/308SW_1312STYP013.jpg","width":500,"height":312},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/peugeot-308-si-immerge-nelle-atmosfere-piu-raffinate-di-aperitivo-in-concerto-ritmi-del-nostro-tempo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Peugeot 308 si immerge nelle atmosfere pi\u00f9 raffinate di \u201cAperitivo in Concerto \u2013 ritmi del nostro tempo\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/27753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=27753"}],"version-history":[{"count":2,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/27753\/revisions"}],"predecessor-version":[{"id":27756,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/27753\/revisions\/27756"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/27754"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=27753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=27753"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=27753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}