{"id":29705,"date":"2017-05-11T18:24:13","date_gmt":"2017-05-11T16:24:13","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=29705"},"modified":"2017-05-11T18:25:40","modified_gmt":"2017-05-11T16:25:40","slug":"24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/","title":{"rendered":"24\u00b0 RALLY ADRIATICO: tutto pronto in casa Peugeot per la prima gara su terra 2017"},"content":{"rendered":"<p>&amp;nbsp;<\/p>\n<p>Rally Adriatico: quarto appuntamento del Campionato Italiano Rally e primo contatto con il fondo sterrato.<\/p>\n<p>Per il Team Peugeot Sport Italia sar\u00e0 un\u2019occasione importante per verificare il lavoro di sviluppo fatto finora sulla vettura. Paolo Andreucci e la 208 T16 saranno chiamati a confermare le prestazioni segnate su asfalto in questa prima parte del Tricolore.<\/p>\n<p>Il team junior Pollara-Princiotto, alla sua terza esperienza su terra, dovr\u00e0 dare continuit\u00e0 all\u2019ottimo esordio di campionato e portare punti pesanti per la conquista del Tricolore.<\/p>\n<p>L\u2019Adriatico, assieme al San Marino, \u00e8 una delle due uniche tappe su terra di quest\u2019anno e mette a dura prova i team ed i piloti, obbligandoli a cambiare quasi completamente il setup delle auto.<\/p>\n<p>Gli equipaggi<\/p>\n<p>Paolo Andreucci (208 T16): \u00ab L\u2019Adriatico \u00e8 la prima gara su terra della stagione e, come ogni anno, da leader del campionato, dovremo partire per primi e pulire la strada. Non \u00e8 proprio il massimo su speciali con tanta ghiaia come queste. \u00c8 sicuramente un rally molto bello, abbastanza pianeggiante, per cui ammortizzatori e altezza da terra non sono esagerati come potrebbero essere in Sardegna o al San Marino. Il fondo stradale, che prevede terra veloce, prima con ghiaia e poi con terra molto compatta, sar\u00e0 sicuramente interessante da affrontare. Uno sterrato veloce, pi\u00f9 di quello di San Marino, ma generalmente bello. Gli avversari anche in questa occasione saranno determinatissimi e ci sar\u00e0 da sgomitare, ma ce la metteremo sicuramente tutta. La prima tappa sar\u00e0 difficile da prevedere, ma si lotter\u00e0 di certo. Nella seconda sar\u00e0 tutto pi\u00f9 chiaro, i leader verranno fuori. \u00c8 una gara per noi sempre abbastanza difficile, ma abbiamo la determinazione per fare un ottimo lavoro\u00bb.<\/p>\n<p>Marco Pollara (pilota 208 R2): \u00ab Il Rally Adriatico sar\u00e0 una tappa molto difficile ed impegnativa, vista anche la poca esperienza che ho sulla terra ed essendo alla terza gara su questo tipo di fondo. Ho cercato di pianificarla nei minimi dettagli, usando molto la testa e cercando di non commettere errori per portare punti a casa per il campionato junior e due ruote motrici. Posso fare affidamento su una squadra che ha tanta esperienza e raccoglier\u00f2 senz\u2019altro i preziosi suggerimenti di Paolo e Anna. Pirelli, dal canto suo, mi sta supportando non poco e potr\u00f2 fare affidamento anche sui preziosi consigli dei suoi tecnici. Voglio crescere ed essere competitivo. Gli avversari saranno molto agguerriti, lo so bene, ma di certo non mi risparmier\u00f2 per dare il massimo\u201d.<\/p>\n<p>&amp;amp;lt;\/div&amp;amp;gt;<br \/>\n&amp;amp;lt;\/div&amp;amp;gt;<br \/>\n&amp;amp;lt;\/div&amp;amp;gt;<br \/>\n&amp;amp;lt;div class=&#8221;page&#8221; title=&#8221;Page 2&#8243;&amp;amp;gt;<br \/>\n&amp;amp;lt;div class=&#8221;layoutArea&#8221;&amp;amp;gt;<br \/>\n&amp;amp;lt;div class=&#8221;column&#8221;&amp;amp;gt;<\/p>\n<p>PEUGEOT SPORT ITALIA COMUNICATO STAMPA<\/p>\n<p>&amp;amp;lt;\/div&amp;amp;gt;<br \/>\n&amp;amp;lt;\/div&amp;amp;gt;<br \/>\n&amp;amp;lt;div class=&#8221;layoutArea&#8221;&amp;amp;gt;<br \/>\n&amp;amp;lt;div class=&#8221;column&#8221;&amp;amp;gt;<\/p>\n<p>competizioni@peugeot.com<\/p>\n<p>Campionato Italiano Piloti (Assoluto)<br \/>\n1. Andreucci 25,5; 2. Perico 18 punti; 3. Campedelli 16,5 punti; 4. Scandola 15,0 Campionato Italiano Piloti (Junior)<br \/>\n1. Pollara 16,5; 2. Bottarelli 14,5 3. Mazzocchi 11 punti;<br \/>\nCostruttori Assoluto<br \/>\n1.Peugeot 28,5 punti; 2.Skoda 22 punti<\/p>\n<p>Come seguire la gara<\/p>\n<p>&amp;amp;lt;\/div&amp;amp;gt;<br \/>\n&amp;amp;lt;div class=&#8221;column&#8221;&amp;amp;gt;<\/p>\n<p>10 maggio 2017<\/p>\n<p>&amp;amp;lt;\/div&amp;amp;gt;<br \/>\n&amp;amp;lt;\/div&amp;amp;gt;<br \/>\n&amp;amp;lt;div class=&#8221;layoutArea&#8221;&amp;amp;gt;<br \/>\n&amp;amp;lt;div class=&#8221;column&#8221;&amp;amp;gt;<\/p>\n<p>Classifica<\/p>\n<p>&amp;amp;lt;\/div&amp;amp;gt;<br \/>\n&amp;amp;lt;\/div&amp;amp;gt;<br \/>\n&amp;amp;lt;div class=&#8221;layoutArea&#8221;&amp;amp;gt;<br \/>\n&amp;amp;lt;div class=&#8221;column&#8221;&amp;amp;gt;<\/p>\n<p>Sar\u00e0 possibile seguire l\u2019intera gara delle vetture ufficiali del Leone, con foto, video, dietro le quinte e interviste ai nostri equipaggi sui canali social di Peugeot:<\/p>\n<p>\u2022 https:\/\/www.facebook.com\/peugeotitalia<br \/>\n\u2022 www.youtube.com\/peugeotitalia<br \/>\n\u2022 www.twitter.com\/peugeotitalia (#peugeotsport)<\/p>\n<p>&amp;amp;lt;\/div&amp;amp;gt;<br \/>\n&amp;amp;lt;img class=&#8221;alignnone size-medium wp-image-29709&#8243; src=&#8221;http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2017\/05\/Pollara-010-300&#215;200.jpg&#8221; alt=&#8221;&#8221; width=&#8221;300&#8243; height=&#8221;200&#8243; \/&amp;amp;gt; &amp;amp;lt;img class=&#8221;alignnone size-medium wp-image-29708&#8243; src=&#8221;http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2017\/05\/Pollara-003-300&#215;200.jpg&#8221; alt=&#8221;&#8221; width=&#8221;300&#8243; height=&#8221;200&#8243; \/&amp;amp;gt; &amp;amp;lt;img class=&#8221;alignnone size-medium wp-image-29707&#8243; src=&#8221;http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2017\/05\/Andreucci-012-300&#215;200.jpg&#8221; alt=&#8221;&#8221; width=&#8221;300&#8243; height=&#8221;200&#8243; \/&amp;amp;gt; &amp;amp;lt;img class=&#8221;alignnone size-medium wp-image-29706&#8243; src=&#8221;http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2017\/05\/Andreucci-007-300&#215;200.jpg&#8221; alt=&#8221;&#8221; width=&#8221;300&#8243; height=&#8221;200&#8243; \/&amp;amp;gt;<\/p>\n<p>&amp;amp;lt;\/div&amp;amp;gt;<br \/>\n&amp;amp;lt;\/div&amp;amp;gt;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&amp;nbsp; Rally Adriatico: quarto appuntamento del Campionato Italiano Rally e primo contatto con il fondo sterrato. Per il Team Peugeot Sport Italia sar\u00e0 un\u2019occasione importante per verificare il lavoro di sviluppo fatto finora sulla vettura. Paolo Andreucci e la 208 T16 saranno chiamati a confermare le prestazioni segnate su asfalto in questa prima parte del [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29706,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6517,300],"tags":[80],"class_list":["post-29705","post","type-post","status-publish","format-standard","has-post-thumbnail","category-24-rally-adriatico","category-peugeot","tag-featured"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>24\u00b0 RALLY ADRIATICO: tutto pronto in casa Peugeot per la prima gara su terra 2017 - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"24\u00b0 RALLY ADRIATICO: tutto pronto in casa Peugeot per la prima gara su terra 2017 - AbmNews\" \/>\n<meta property=\"og:description\" content=\"&amp;nbsp; Rally Adriatico: quarto appuntamento del Campionato Italiano Rally e primo contatto con il fondo sterrato. Per il Team Peugeot Sport Italia sar\u00e0 un\u2019occasione importante per verificare il lavoro di sviluppo fatto finora sulla vettura. Paolo Andreucci e la 208 T16 saranno chiamati a confermare le prestazioni segnate su asfalto in questa prima parte del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-11T16:24:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-11T16:25:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/05\/Andreucci-007.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"24\u00b0 RALLY ADRIATICO: tutto pronto in casa Peugeot per la prima gara su terra 2017\",\"datePublished\":\"2017-05-11T16:24:13+00:00\",\"dateModified\":\"2017-05-11T16:25:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\\\/\"},\"wordCount\":778,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Andreucci-007.jpg\",\"keywords\":[\"Featured\"],\"articleSection\":[\"24\u00b0 RALLY ADRIATICO\",\"Peugeot\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\\\/\",\"name\":\"24\u00b0 RALLY ADRIATICO: tutto pronto in casa Peugeot per la prima gara su terra 2017 - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Andreucci-007.jpg\",\"datePublished\":\"2017-05-11T16:24:13+00:00\",\"dateModified\":\"2017-05-11T16:25:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Andreucci-007.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Andreucci-007.jpg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"24\u00b0 RALLY ADRIATICO: tutto pronto in casa Peugeot per la prima gara su terra 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"24\u00b0 RALLY ADRIATICO: tutto pronto in casa Peugeot per la prima gara su terra 2017 - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/","og_locale":"it_IT","og_type":"article","og_title":"24\u00b0 RALLY ADRIATICO: tutto pronto in casa Peugeot per la prima gara su terra 2017 - AbmNews","og_description":"&amp;nbsp; Rally Adriatico: quarto appuntamento del Campionato Italiano Rally e primo contatto con il fondo sterrato. Per il Team Peugeot Sport Italia sar\u00e0 un\u2019occasione importante per verificare il lavoro di sviluppo fatto finora sulla vettura. Paolo Andreucci e la 208 T16 saranno chiamati a confermare le prestazioni segnate su asfalto in questa prima parte del [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2017-05-11T16:24:13+00:00","article_modified_time":"2017-05-11T16:25:40+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/05\/Andreucci-007.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"24\u00b0 RALLY ADRIATICO: tutto pronto in casa Peugeot per la prima gara su terra 2017","datePublished":"2017-05-11T16:24:13+00:00","dateModified":"2017-05-11T16:25:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/"},"wordCount":778,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/05\/Andreucci-007.jpg","keywords":["Featured"],"articleSection":["24\u00b0 RALLY ADRIATICO","Peugeot"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/","url":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/","name":"24\u00b0 RALLY ADRIATICO: tutto pronto in casa Peugeot per la prima gara su terra 2017 - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/05\/Andreucci-007.jpg","datePublished":"2017-05-11T16:24:13+00:00","dateModified":"2017-05-11T16:25:40+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/05\/Andreucci-007.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/05\/Andreucci-007.jpg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/24-rally-adriatico-tutto-pronto-in-casa-peugeot-per-la-prima-gara-su-terra-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"24\u00b0 RALLY ADRIATICO: tutto pronto in casa Peugeot per la prima gara su terra 2017"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/29705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=29705"}],"version-history":[{"count":4,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/29705\/revisions"}],"predecessor-version":[{"id":29713,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/29705\/revisions\/29713"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/29706"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=29705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=29705"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=29705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}