{"id":30306,"date":"2017-10-13T01:35:56","date_gmt":"2017-10-12T23:35:56","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=30306"},"modified":"2017-10-13T01:35:56","modified_gmt":"2017-10-12T23:35:56","slug":"audi-golf-experience-2017-il-final-lap","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/","title":{"rendered":"Audi golf experience 2017: il final lap"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<ul style=\"list-style-type: square;\">\n<li>Da venerd\u00ec 13 a domenica 15 ottobre si terr\u00e0 la Finale Nazionale in Puglia presso il San Domenico Golf Club \u2013 Borgo Egnazia. I 30 finalisti trascorreranno due giorni all\u2019insegna del golf e dei paesaggi suggestivi della valle d\u2019Itria.\n<p>La presenza di Audi nel panorama golfistico italiano nel corso degli anni \u00e8 una costante che ha conquistato sempre pi\u00f9 rilevanza. Nel tempo, infatti, si \u00e8 registrato un sensibile aumento dei golfisti possessori Audi tanto che nel 2009 \u00e8 nata l&#8217;idea di creare una manifestazione riservata esclusivamente ai Clienti giocatori di golf, un torneo ad inviti: l\u2019Audi golf experience.<\/p>\n<p>Questa iniziativa consente agli appassionati del marchio Audi di incontrarsi sul green, in un contesto del tutto particolare, dove l&#8217;atmosfera rilassata e l\u2019entusiasmo di chi pratica il proprio sport preferito si possono tradurre in un\u2019alternativa piattaforma di comunicazione. I golf club che accolgono la manifestazione sono infatti situati in zone strategiche per il Brand che cos\u00ec pu\u00f2 essere ulteriormente presente sul territorio.<\/p>\n<p>Considerato il successo delle precedenti edizioni, la stagione 2017 si \u00e8 articolata nelle tradizionali 10 tappe del torneo, con un numero massimo di 60 giocatori per<br \/>\ngara. In alcuni casi per\u00f2 le richieste sono state cos\u00ec elevate che si sono superate le numeriche, tanto che sono stati oltre 800 gli appassionati partecipanti al circuito.<\/p>\n<p>In occasione della Finale Nazionale in Puglia, il 1\u00b0 lordo, il 1\u00b0 classificato netto di prima categoria e il 1\u00b0 classificato netto di seconda categoria si aggiudicheranno un entusiasmante corso di guida Audi su neve.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Da venerd\u00ec 13 a domenica 15 ottobre si terr\u00e0 la Finale Nazionale in Puglia presso il San Domenico Golf Club \u2013 Borgo Egnazia. I 30 finalisti trascorreranno due giorni all\u2019insegna del golf e dei paesaggi suggestivi della valle d\u2019Itria. La presenza di Audi nel panorama golfistico italiano nel corso degli anni \u00e8 una costante che [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30307,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[357],"tags":[],"class_list":["post-30306","post","type-post","status-publish","format-standard","has-post-thumbnail","category-audi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Audi golf experience 2017: il final lap - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Audi golf experience 2017: il final lap - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Da venerd\u00ec 13 a domenica 15 ottobre si terr\u00e0 la Finale Nazionale in Puglia presso il San Domenico Golf Club \u2013 Borgo Egnazia. I 30 finalisti trascorreranno due giorni all\u2019insegna del golf e dei paesaggi suggestivi della valle d\u2019Itria. La presenza di Audi nel panorama golfistico italiano nel corso degli anni \u00e8 una costante che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-12T23:35:56+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/10\/ShowPublicPhoto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/audi-golf-experience-2017-il-final-lap\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/audi-golf-experience-2017-il-final-lap\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Audi golf experience 2017: il final lap\",\"datePublished\":\"2017-10-12T23:35:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/audi-golf-experience-2017-il-final-lap\\\/\"},\"wordCount\":246,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/audi-golf-experience-2017-il-final-lap\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/ShowPublicPhoto.jpg\",\"articleSection\":[\"Audi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/audi-golf-experience-2017-il-final-lap\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/audi-golf-experience-2017-il-final-lap\\\/\",\"name\":\"Audi golf experience 2017: il final lap - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/audi-golf-experience-2017-il-final-lap\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/audi-golf-experience-2017-il-final-lap\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/ShowPublicPhoto.jpg\",\"datePublished\":\"2017-10-12T23:35:56+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/audi-golf-experience-2017-il-final-lap\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/audi-golf-experience-2017-il-final-lap\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/audi-golf-experience-2017-il-final-lap\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/ShowPublicPhoto.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/ShowPublicPhoto.jpg\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/audi-golf-experience-2017-il-final-lap\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Audi golf experience 2017: il final lap\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Audi golf experience 2017: il final lap - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/","og_locale":"it_IT","og_type":"article","og_title":"Audi golf experience 2017: il final lap - AbmNews","og_description":"Da venerd\u00ec 13 a domenica 15 ottobre si terr\u00e0 la Finale Nazionale in Puglia presso il San Domenico Golf Club \u2013 Borgo Egnazia. I 30 finalisti trascorreranno due giorni all\u2019insegna del golf e dei paesaggi suggestivi della valle d\u2019Itria. La presenza di Audi nel panorama golfistico italiano nel corso degli anni \u00e8 una costante che [&hellip;]","og_url":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2017-10-12T23:35:56+00:00","og_image":[{"width":1536,"height":1024,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/10\/ShowPublicPhoto.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Audi golf experience 2017: il final lap","datePublished":"2017-10-12T23:35:56+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/"},"wordCount":246,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/10\/ShowPublicPhoto.jpg","articleSection":["Audi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/","url":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/","name":"Audi golf experience 2017: il final lap - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/10\/ShowPublicPhoto.jpg","datePublished":"2017-10-12T23:35:56+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/10\/ShowPublicPhoto.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/10\/ShowPublicPhoto.jpg","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/audi-golf-experience-2017-il-final-lap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Audi golf experience 2017: il final lap"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/30306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=30306"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/30306\/revisions"}],"predecessor-version":[{"id":30308,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/30306\/revisions\/30308"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/30307"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=30306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=30306"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=30306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}