{"id":34548,"date":"2019-01-08T05:55:50","date_gmt":"2019-01-08T04:55:50","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=34548"},"modified":"2019-01-08T05:56:41","modified_gmt":"2019-01-08T04:56:41","slug":"dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/","title":{"rendered":"Dakar 2019, Tappa 1 \u2013 partenza tranquilla  per la coppia Loeb e Elena con la  Peugeot  3008 DKR"},"content":{"rendered":"<p>Al volante della sua\u00a0 <strong>Peugeot 3008 DKR<\/strong>del 2017 preparata dal team privato <strong>PH Sport S\u00e9bastien Loeb <\/strong>se l\u2019\u00e8 presa comoda nella prima tappa di una Dakar 2019 che per la prima volta nella sua storia si snoder\u00e0 in un unico Paese, in questo caso il Per\u00f9, per un totale di 10 giornate di gara.<\/p>\n<p>Al termine degli 84 km che hanno portato la carovana da Lima a Pisco, l\u2019Extraterrestre ha tagliato il traguardo in 13esima posizione con il tempo di 1h07\u201948\u201d, accumulando subito un ritardo notevole di 6\u201907\u201d dal vincitore Nasser Al-Attiyah \u00a0su Toyota della Gazoo Racing Sa.<\/p>\n<p>Interessato perlopi\u00f9 a non commettere errori visto quanto accaduto 12 mesi fa quando dovette abbandonare dopo soli 5 giorni di competizione proprio per uno sbaglio di navigazione, l\u2019alsaziano\u00a0 ha preferito evitare di spingere troppo.<\/p>\n<p>\u201c<em>Ho deciso di non partire a tutta<\/em>\u201d, ha dichiarato alla fine il pilota Peugeot, che comunque non ha riscontrato alcun problema sulla sua vettura. \u201c<em>Infatti il mio obiettivo non \u00e8 mai stato quello di segnare il miglior crono. Diciamo che abbiamo voluto adottare una modalit\u00e0 tranquilla<\/em>\u201d.<\/p>\n<p>\u201c<em>Soprattutto ci tenevo a non sbagliare<\/em>\u201d, ha precisato. <em>\u201cIl percorso era insidioso per la presenza di molte dune, che non amo particolarmente, per cui con la visibilit\u00e0 limitata sono stato sulla difensiva. Non riesco ancora a leggere il fondo come fa Al-Attiyah.Non \u00e8 il mio terreno e non volevo fare brutte figure\u201d, <\/em>ha concluso realista il 44enne.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34554\" src=\"http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20195.jpg\" alt=\"\" width=\"800\" height=\"533\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34555\" src=\"http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20196.jpg\" alt=\"\" width=\"800\" height=\"648\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34553\" src=\"http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20194.jpg\" alt=\"\" width=\"800\" height=\"533\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34552\" src=\"http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20193.jpg\" alt=\"\" width=\"800\" height=\"533\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34551\" src=\"http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20192.jpg\" alt=\"\" width=\"800\" height=\"533\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34550\" src=\"http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20191.jpg\" alt=\"\" width=\"800\" height=\"532\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34549\" src=\"http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20190.jpg\" alt=\"\" width=\"800\" height=\"533\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al volante della sua\u00a0 Peugeot 3008 DKRdel 2017 preparata dal team privato PH Sport S\u00e9bastien Loeb se l\u2019\u00e8 presa comoda nella prima tappa di una Dakar 2019 che per la prima volta nella sua storia si snoder\u00e0 in un unico Paese, in questo caso il Per\u00f9, per un totale di 10 giornate di gara. Al [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":34555,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[7812],"tags":[80],"class_list":["post-34548","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dakar-2019","tag-featured"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dakar 2019, Tappa 1 \u2013 partenza tranquilla per la coppia Loeb e Elena con la Peugeot 3008 DKR - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dakar 2019, Tappa 1 \u2013 partenza tranquilla per la coppia Loeb e Elena con la Peugeot 3008 DKR - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Al volante della sua\u00a0 Peugeot 3008 DKRdel 2017 preparata dal team privato PH Sport S\u00e9bastien Loeb se l\u2019\u00e8 presa comoda nella prima tappa di una Dakar 2019 che per la prima volta nella sua storia si snoder\u00e0 in un unico Paese, in questo caso il Per\u00f9, per un totale di 10 giornate di gara. Al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-08T04:55:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-08T04:56:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20196.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Dakar 2019, Tappa 1 \u2013 partenza tranquilla per la coppia Loeb e Elena con la Peugeot 3008 DKR\",\"datePublished\":\"2019-01-08T04:55:50+00:00\",\"dateModified\":\"2019-01-08T04:56:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\\\/\"},\"wordCount\":244,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/DAKAR20196.jpg\",\"keywords\":[\"Featured\"],\"articleSection\":[\"dakar 2019\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\\\/\",\"name\":\"Dakar 2019, Tappa 1 \u2013 partenza tranquilla per la coppia Loeb e Elena con la Peugeot 3008 DKR - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/DAKAR20196.jpg\",\"datePublished\":\"2019-01-08T04:55:50+00:00\",\"dateModified\":\"2019-01-08T04:56:41+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/DAKAR20196.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/DAKAR20196.jpg\",\"width\":800,\"height\":648},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dakar 2019, Tappa 1 \u2013 partenza tranquilla per la coppia Loeb e Elena con la Peugeot 3008 DKR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dakar 2019, Tappa 1 \u2013 partenza tranquilla per la coppia Loeb e Elena con la Peugeot 3008 DKR - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/","og_locale":"it_IT","og_type":"article","og_title":"Dakar 2019, Tappa 1 \u2013 partenza tranquilla per la coppia Loeb e Elena con la Peugeot 3008 DKR - AbmNews","og_description":"Al volante della sua\u00a0 Peugeot 3008 DKRdel 2017 preparata dal team privato PH Sport S\u00e9bastien Loeb se l\u2019\u00e8 presa comoda nella prima tappa di una Dakar 2019 che per la prima volta nella sua storia si snoder\u00e0 in un unico Paese, in questo caso il Per\u00f9, per un totale di 10 giornate di gara. Al [&hellip;]","og_url":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2019-01-08T04:55:50+00:00","article_modified_time":"2019-01-08T04:56:41+00:00","og_image":[{"width":800,"height":648,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20196.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Dakar 2019, Tappa 1 \u2013 partenza tranquilla per la coppia Loeb e Elena con la Peugeot 3008 DKR","datePublished":"2019-01-08T04:55:50+00:00","dateModified":"2019-01-08T04:56:41+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/"},"wordCount":244,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20196.jpg","keywords":["Featured"],"articleSection":["dakar 2019"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/","url":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/","name":"Dakar 2019, Tappa 1 \u2013 partenza tranquilla per la coppia Loeb e Elena con la Peugeot 3008 DKR - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20196.jpg","datePublished":"2019-01-08T04:55:50+00:00","dateModified":"2019-01-08T04:56:41+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20196.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/DAKAR20196.jpg","width":800,"height":648},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-1-partenza-tranquilla-per-loeb-e-la-peugeot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Dakar 2019, Tappa 1 \u2013 partenza tranquilla per la coppia Loeb e Elena con la Peugeot 3008 DKR"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/34548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=34548"}],"version-history":[{"count":2,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/34548\/revisions"}],"predecessor-version":[{"id":34558,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/34548\/revisions\/34558"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/34555"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=34548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=34548"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=34548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}