{"id":34663,"date":"2019-01-15T22:20:26","date_gmt":"2019-01-15T21:20:26","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=34663"},"modified":"2019-01-15T22:21:55","modified_gmt":"2019-01-15T21:21:55","slug":"dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/","title":{"rendered":"Dakar 2019, Tappa 8 \u2013 Loeb \u2013 Elena regalano la quarta vittoria a Peugeot"},"content":{"rendered":"<p>Dopo aver lasciato tre minuti al leader della classifica generale nella porzione iniziale dei 361 km di tappa che da San Juan de Marcona ha portato la carovana della Dakar a Pisco, S\u00e8bastien Loeb non solo ha recuperato terreno, ma ha addirittura superato la Toyota di Nasser Al-Attiyah di ben 7\u201927 firmando la quarta vittoria di tappa in questa edizione dell\u2019insidioso raid nel deserto.<\/p>\n<p>\u201c<em>E\u2019 stata una giornata positiva\u00a0 anche se al km 6 abbiamo patito una foratura e siamo stati costretti\u00a0 a sostituire la gomma subito<\/em>\u201d, ha dichiarato il pilota Peugeot, ora a 46\u201945 dal qatariano. \u00a0\u201c <em>E\u2019 stato frustrante, ma da quel momento abbiamo corso con il coltello tra i denti. Ho commesso soltanto un piccolo errore ad un way point, ma per il resto \u00e8 andato tutto bene. Considerati i minuti persi luned\u00ec essere terzi assoluti non \u00e8 affatto male. Ci restano 2 speciali e ci crederemo fino alla fine<\/em>\u201d.<\/p>\n<p>Alle spalle della Hilux del bronzo olimpico e quindi in terza piazza \u00e8 giunto il costante polacco Jakub Przygonski, staccato di 15\u201915 con la MINI. Quarta a 15\u201955 la Toyota di Giniel de Villers, davanti di\u00a0 appena 2\u201d alla MINI 4X4 dello spagnolo Nani Roma.<\/p>\n<p>Sesto sempre su MINI il saudita Yazeed Al-Rajhi a 22\u201951, a precedere la Ford RS Raptor del ceco Martin Prokop a 28\u201936 da Al-Attiyah.<\/p>\n<p>Ottavo a ben 31\u201941 Monsieur Dakar St\u00e9phane Peterhansel su MINI. Il francese, tornato in lizza per la vittoria finale nella settima speciale, dopo aver cominciato la giornata tenendo un passo aggressivo \u00e8 rimasto bloccato per ben due volte tra le dune perdendo parecchio tempo prezioso.<\/p>\n<p>Nono il buggy MINI di Cyril Despres addirittura ad 1h02\u201953. Peggio ancora \u00e8 andata al compagno di marca Carlos Sainz, ultimo della top 10 a1h34\u201d11.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Classifica tappa 8<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>1 SEBASTIEN LOEB (FRA)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 PEUGEOT\u00a0\u00a0\u00a0\u00a0 3h54m53s<\/p>\n<p>2\u00a0 NASSER AL-ATTIYAH (QAT)TOYOTA\u00a0\u00a0\u00a0\u00a0\u00a0 00:07:27<\/p>\n<p>3\u00a0 JAKUB PRZYGONSKI (POL)\u00a0\u00a0 MINI\u00a0 00:15:15<\/p>\n<p>4 GINIEL DE VILLIERS (ZAF)\u00a0\u00a0\u00a0\u00a0\u00a0 TOYOTA\u00a0\u00a0\u00a0\u00a0\u00a0 00:15:55<\/p>\n<p>5 NANI ROMA (ESP)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 MINI\u00a0 00:15:57<\/p>\n<p>6 YAZEED AL-RAJHI (SAU)\u00a0MINI\u00a0 00:22:51<\/p>\n<p>7\u00a0 MARTIN PROKOP (CZE)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 FORD00:28:36<\/p>\n<p>8 STEPHANE PETERHANSEL (FRA)\u00a0\u00a0\u00a0\u00a0\u00a0 MINI\u00a0 00:31:41<\/p>\n<p>9\u00a0 CYRIL DESPRES (FRA)\u00a0 MINI\u00a0 01:02:53<\/p>\n<p>10 CARLOS SAINZ (ESP)\u00a0\u00a0 MINI\u00a0 01:34:11<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34665\" src=\"http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/50669965_2472658146081607_5569773925153374208_n.jpg\" alt=\"\" width=\"720\" height=\"960\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34664\" src=\"http:\/\/abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/50076760_1276122635860427_7459191658559569920_n.jpg\" alt=\"\" width=\"960\" height=\"638\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo aver lasciato tre minuti al leader della classifica generale nella porzione iniziale dei 361 km di tappa che da San Juan de Marcona ha portato la carovana della Dakar a Pisco, S\u00e8bastien Loeb non solo ha recuperato terreno, ma ha addirittura superato la Toyota di Nasser Al-Attiyah di ben 7\u201927 firmando la quarta vittoria [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":34667,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[7812],"tags":[80],"class_list":["post-34663","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dakar-2019","tag-featured"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dakar 2019, Tappa 8 \u2013 Loeb \u2013 Elena regalano la quarta vittoria a Peugeot - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dakar 2019, Tappa 8 \u2013 Loeb \u2013 Elena regalano la quarta vittoria a Peugeot - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Dopo aver lasciato tre minuti al leader della classifica generale nella porzione iniziale dei 361 km di tappa che da San Juan de Marcona ha portato la carovana della Dakar a Pisco, S\u00e8bastien Loeb non solo ha recuperato terreno, ma ha addirittura superato la Toyota di Nasser Al-Attiyah di ben 7\u201927 firmando la quarta vittoria [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-15T21:20:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-15T21:21:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/50076760_1276122635860427_7459191658559569920_n-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"946\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Dakar 2019, Tappa 8 \u2013 Loeb \u2013 Elena regalano la quarta vittoria a Peugeot\",\"datePublished\":\"2019-01-15T21:20:26+00:00\",\"dateModified\":\"2019-01-15T21:21:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\\\/\"},\"wordCount\":337,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/50076760_1276122635860427_7459191658559569920_n-1.jpg\",\"keywords\":[\"Featured\"],\"articleSection\":[\"dakar 2019\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\\\/\",\"name\":\"Dakar 2019, Tappa 8 \u2013 Loeb \u2013 Elena regalano la quarta vittoria a Peugeot - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/50076760_1276122635860427_7459191658559569920_n-1.jpg\",\"datePublished\":\"2019-01-15T21:20:26+00:00\",\"dateModified\":\"2019-01-15T21:21:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/50076760_1276122635860427_7459191658559569920_n-1.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/50076760_1276122635860427_7459191658559569920_n-1.jpg\",\"width\":946,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dakar 2019, Tappa 8 \u2013 Loeb \u2013 Elena regalano la quarta vittoria a Peugeot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dakar 2019, Tappa 8 \u2013 Loeb \u2013 Elena regalano la quarta vittoria a Peugeot - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/","og_locale":"it_IT","og_type":"article","og_title":"Dakar 2019, Tappa 8 \u2013 Loeb \u2013 Elena regalano la quarta vittoria a Peugeot - AbmNews","og_description":"Dopo aver lasciato tre minuti al leader della classifica generale nella porzione iniziale dei 361 km di tappa che da San Juan de Marcona ha portato la carovana della Dakar a Pisco, S\u00e8bastien Loeb non solo ha recuperato terreno, ma ha addirittura superato la Toyota di Nasser Al-Attiyah di ben 7\u201927 firmando la quarta vittoria [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2019-01-15T21:20:26+00:00","article_modified_time":"2019-01-15T21:21:55+00:00","og_image":[{"width":946,"height":381,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/50076760_1276122635860427_7459191658559569920_n-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Dakar 2019, Tappa 8 \u2013 Loeb \u2013 Elena regalano la quarta vittoria a Peugeot","datePublished":"2019-01-15T21:20:26+00:00","dateModified":"2019-01-15T21:21:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/"},"wordCount":337,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/50076760_1276122635860427_7459191658559569920_n-1.jpg","keywords":["Featured"],"articleSection":["dakar 2019"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/","url":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/","name":"Dakar 2019, Tappa 8 \u2013 Loeb \u2013 Elena regalano la quarta vittoria a Peugeot - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/50076760_1276122635860427_7459191658559569920_n-1.jpg","datePublished":"2019-01-15T21:20:26+00:00","dateModified":"2019-01-15T21:21:55+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/50076760_1276122635860427_7459191658559569920_n-1.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/01\/50076760_1276122635860427_7459191658559569920_n-1.jpg","width":946,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/dakar-2019-tappa-8-loeb-elena-regalano-la-quarta-vittoria-a-peugeot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Dakar 2019, Tappa 8 \u2013 Loeb \u2013 Elena regalano la quarta vittoria a Peugeot"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/34663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=34663"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/34663\/revisions"}],"predecessor-version":[{"id":34666,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/34663\/revisions\/34666"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/34667"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=34663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=34663"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=34663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}