{"id":36573,"date":"2019-09-18T08:59:46","date_gmt":"2019-09-18T06:59:46","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=36573"},"modified":"2019-09-18T09:00:21","modified_gmt":"2019-09-18T07:00:21","slug":"effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/","title":{"rendered":"\u201cEFFETTO DIESELGATE\u201d: ECCO I SORPRENDENTI RISULTATI DEL TEST ALTROCONSUMO SULLE EMISSIONI AUTO"},"content":{"rendered":"\n<p>A <strong>quattro anni dallo scandalo Dieselgate<\/strong> &#8211; quando l\u2019Agenzia americana per la protezione ambientale aveva denunciato il gruppo Volkswagen per aver ingannato i suoi clienti, vendendo auto che emettevano pi\u00f9 ossido di azoto (NOx) di quanto dichiarato e aggirando le normative ambientali sulle emissioni dei diesel \u2013 <strong>Altroconsumo ha effettuato dei test sulle emissioni di inquinanti e CO2 delle auto<\/strong>. Le analisi sono state condotte insieme alle principali organizzazioni europee di consumatori e ad Adac &#8211; uno dei maggiori automobile club europei: i risultati sono stati sorprendenti.<\/p>\n<p><strong>Dieselgate \u2013 anche grazie al contributo delle azioni intraprese da Altroconsumo &#8211; ha portato alla luce l\u2019inadeguatezza dei sistemi di controllo delle emissioni<\/strong>, che sono risultati aggirabili dalle case automobilistiche: da allora gli standard di omologazione sono cambiati e proprio da poche settimane \u00e8 entrato in vigore lo standard <strong>Euro 6D Temp<\/strong> che <strong>non<\/strong> <strong>solo fissa limiti di emissioni<\/strong>, ma rende anche <strong>pi\u00f9 stringente ed efficace il modo in cui queste emissioni vengono misurate<\/strong>.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Scandalo Dieselgate: al IV anniversario l\u2019appello di Euroconsumers a Volkswagen e alla Commissione europea<\/strong><\/p>\n<p>Gi\u00e0 nel 2015, allo scoppio del caso Dieselgate &#8211; che ha visto coinvolte le auto Euro 5 di Volkswagen, Audi, Seat e Skoda \u2013 Altroconsumo e le organizzazioni di consumatori Test-Achats in Belgio, OCU in Spagna, DECO Proteste in Portogallo (riunite sotto la sigla Euroconsumers insieme ai brasiliani di Proteste) hanno avviato class action nei rispettivi Paesi per chiedere che i consumatori europei fossero risarciti proprio come quelli statunitensi. In Italia sono <strong>75mila le adesioni alla class action<\/strong>promossa da Altroconsumo davanti al Tribunale di Venezia. Si tratta di un processo lungo e complesso (la prossima udienza \u00e8 prevista per la fine di marzo 2020, salvo rinvii), che va avanti a colpi di udienze, atti e perizie tecniche con cui i legali di Altroconsumo stanno rispondendo ai tentativi del gruppo tedesco di contestare la legittima richiesta di risarcimento e il diritto a partecipare degli aderenti.<\/p>\n<p>In occasione del quarto anniversario di questa vicenda, <strong>Euroconsumers chiede al gruppo Volkswagen di voltare definitivamente pagina e mettere la parola fine<\/strong> allo scandalo delle emissioni, riconoscendo ai clienti il risarcimento che gli spetta.<\/p>\n<p>L\u2019appello di Euroconsumers \u00e8 stato esteso anche alle Istituzioni attraverso una lettera aperta al neo eletto presidente della Commissione europea, Ursula Von der Leyen, in cui si chiede di convincere Volkswagen ad andare incontro alle legittime richieste dei suoi clienti. Quattro anni fa, l\u2019allora Commissione europea era all\u2019inizio del suo mandato, le speranze erano molte ma purtroppo non sono state abbastanza forti da convincere <strong>Volkswagen<\/strong>.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>I sorprendenti risultati dei test sulle emissioni: lo scandalo Dieselgate \u00e8 servito<\/strong><\/p>\n<p>Rispetto ai test condotti due anni fa da Altroconsumo, sembra che i produttori abbiano subito una sorta di <strong>\u201ceffetto Dieselgate\u201d<\/strong>, le emissioni di inquinanti dei motori diesel infatti sono diminuite molto, proprio per consentire alle auto che hanno questo tipo di motore di superare le pi\u00f9 stringenti prove di omologazione.<\/p>\n<p>La <strong>situazione tra diesel e benzina<\/strong> \u00e8 quindi risultata quasi <strong>ribaltata<\/strong>. Oggi un buon motore diesel inquina meno di un equivalente a benzina.<\/p>\n<p>Le <strong>vetture ibride<\/strong>, invece, sono risultate migliori solo se usate in citt\u00e0 mentre sui percorsi extraurbani inquinano quanto un\u2019auto a benzina visto che l\u2019apporto del motore elettrico diventa trascurabile. Per quanto riguarda le <strong>auto elettriche<\/strong>, le cui emissioni sono pari a zero, dobbiamo fare riferimento all\u2019inquinamento legato alla produzione dell\u2019elettricit\u00e0 che le alimenta: se arriva da combustibili fossili non vi \u00e8 un vantaggio per l\u2019ambiente. Nel nostro Paese, la produzione di elettricit\u00e0 \u00e8 frutto di un mix energetico di fonti rinnovabili e fossili per cui le migliori vetture elettriche comportano emissioni di CO<sub>2<\/sub> al di sotto dei 50 g\/km, inferiori a quelle delle vetture tradizionali.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Il test sulle emissioni di Altroconsumo: metodologia e classifica<\/strong><\/p>\n<p>Il test sulle emissioni delle auto di Altroconsumo, comprende tre fasi:<\/p>\n<p>&#8211; controllo del ciclo di omologazione su rulli (Wltp) previsto dai test europei;<\/p>\n<p>&#8211; controllo del ciclo \u201cautostradale\u201d per rilevare emissioni e consumi delle auto ad alte velocit\u00e0, non previsto dai test europei;<\/p>\n<p>&#8211; solo per le auto che hanno superato le due prove precedenti: test su strada Rde (Real driving emissions), eseguito installando sulla vettura in marcia una apposita apparecchiatura che misura le emissioni lungo un tragitto predefinito, stabilito dalla regolamentazione europea.<\/p>\n<p>\u00a0<\/p>\n<p>Queste tre prove portano a un punteggio Ecotest totale, ottenuto per ogni auto dalla media dei punteggi sul consumo di carburante e sulle emissioni di inquinanti.<\/p>\n<p>\u00a0<\/p>\n<p>&#8221; src=&#8221;blob:http:\/\/abmnews.com\/cc24ec33-ad8b-43dd-ba3c-64f14bcb5951&#8243; alt=&#8221;image003.png&#8221; class=&#8221;Apple-web-attachment&#8221; style=&#8221;width: 6.6354in; height: 6.0312in; opacity: 1;&#8221;&gt;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":36574,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[285,293],"tags":[],"class_list":["post-36573","post","type-post","status-publish","format-standard","has-post-thumbnail","category-motori","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cEFFETTO DIESELGATE\u201d: ECCO I SORPRENDENTI RISULTATI DEL TEST ALTROCONSUMO SULLE EMISSIONI AUTO - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cEFFETTO DIESELGATE\u201d: ECCO I SORPRENDENTI RISULTATI DEL TEST ALTROCONSUMO SULLE EMISSIONI AUTO - AbmNews\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-18T06:59:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-18T07:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/09\/ShowPhoto-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1820\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"\u201cEFFETTO DIESELGATE\u201d: ECCO I SORPRENDENTI RISULTATI DEL TEST ALTROCONSUMO SULLE EMISSIONI AUTO\",\"datePublished\":\"2019-09-18T06:59:46+00:00\",\"dateModified\":\"2019-09-18T07:00:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\\\/\"},\"wordCount\":762,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ShowPhoto-1.jpg\",\"articleSection\":[\"Motori\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\\\/\",\"name\":\"\u201cEFFETTO DIESELGATE\u201d: ECCO I SORPRENDENTI RISULTATI DEL TEST ALTROCONSUMO SULLE EMISSIONI AUTO - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ShowPhoto-1.jpg\",\"datePublished\":\"2019-09-18T06:59:46+00:00\",\"dateModified\":\"2019-09-18T07:00:21+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ShowPhoto-1.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ShowPhoto-1.jpg\",\"width\":1820,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cEFFETTO DIESELGATE\u201d: ECCO I SORPRENDENTI RISULTATI DEL TEST ALTROCONSUMO SULLE EMISSIONI AUTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cEFFETTO DIESELGATE\u201d: ECCO I SORPRENDENTI RISULTATI DEL TEST ALTROCONSUMO SULLE EMISSIONI AUTO - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cEFFETTO DIESELGATE\u201d: ECCO I SORPRENDENTI RISULTATI DEL TEST ALTROCONSUMO SULLE EMISSIONI AUTO - AbmNews","og_url":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2019-09-18T06:59:46+00:00","article_modified_time":"2019-09-18T07:00:21+00:00","og_image":[{"width":1820,"height":1024,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/09\/ShowPhoto-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"\u201cEFFETTO DIESELGATE\u201d: ECCO I SORPRENDENTI RISULTATI DEL TEST ALTROCONSUMO SULLE EMISSIONI AUTO","datePublished":"2019-09-18T06:59:46+00:00","dateModified":"2019-09-18T07:00:21+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/"},"wordCount":762,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/09\/ShowPhoto-1.jpg","articleSection":["Motori","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/","url":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/","name":"\u201cEFFETTO DIESELGATE\u201d: ECCO I SORPRENDENTI RISULTATI DEL TEST ALTROCONSUMO SULLE EMISSIONI AUTO - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/09\/ShowPhoto-1.jpg","datePublished":"2019-09-18T06:59:46+00:00","dateModified":"2019-09-18T07:00:21+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/09\/ShowPhoto-1.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/09\/ShowPhoto-1.jpg","width":1820,"height":1024},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/effetto-dieselgate-ecco-i-sorprendenti-risultati-del-test-altroconsumo-sulle-emissioni-auto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u201cEFFETTO DIESELGATE\u201d: ECCO I SORPRENDENTI RISULTATI DEL TEST ALTROCONSUMO SULLE EMISSIONI AUTO"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/36573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=36573"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/36573\/revisions"}],"predecessor-version":[{"id":36575,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/36573\/revisions\/36575"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/36574"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=36573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=36573"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=36573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}