{"id":43741,"date":"2020-02-15T16:31:43","date_gmt":"2020-02-15T15:31:43","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=43741"},"modified":"2020-02-15T16:31:45","modified_gmt":"2020-02-15T15:31:45","slug":"wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/","title":{"rendered":"WRC, Rally Svezia,  La C3 R5 di Ostberg in leggera difficolt\u00e0 nella seconda giornata"},"content":{"rendered":"\n<p>Malgrado una catena di errori nella PS 7 li abbia fatti scivolare in dodicesima posizione assoluta, l\u2019equipaggio <strong>Citroen Racing<\/strong> formato da <strong>Mads Ostberg e Torstein Eriksen<\/strong> resta in vetta nella categoria cadetta in un Rally di Svezia martoriato dalla mancanza di neve e privato di un\u2019altra speciale.<\/p>\n<p>A guidare il gruppo, come venerd\u00ec, uno scatenato Elfyn Evans. In versione \u201cmartello\u201d il gallese della Toyota si \u00e8 aggiudicato le prime tre PS di giornata andando ad incrementare il proprio vantaggio sulla Hyundai dell\u2019iridato in carica Ott T\u00e4nak non completamente a suo agio. Terzo a 28\u201d8 S\u00e9bastien Ogier su Yaris, poco convinto dell\u2019assetto scelto e subito in crisi con le gomme chiodate messe a dura prova dagli ampi tratti in sterrato.\u00a0<\/p>\n<p>Appena sotto il podio virtuale un Kalle Rovanpera \u00a0su Toyota, deluso dalla propria prestazione e tra l\u2019altro rallentato da un cambio pneumatici obbligato per la totale mancanza di grip. A 34\u201d7 dalla vetta la Ford Fiesta di Esapekka Lappi, protagonista di qualche sbavatura, poi la i20 di Thierry Neuville in bagarre con il collega di marca Craig Breen e autore dello scratch nella PS 9.<\/p>\n<p>Ottavo posto per Teemu Suninen su Fiesta, a precedere Takamoto Katsuta su Yaris. Il giapponese ha ammesso di aver faticato molto a guidare a causa del fondo cangiante. Infine, a chiudere la top 10 il finlandese Jari Huttunen su i20 R5.<\/p>\n<p>Da registrare il mancato start di Jari \u2013 Matti Latvala a seguito dei problemi tecnici legati al motore accusati nella prima tappa. Il boss Toyota Tommi M\u00e4kinen ha fatto il mea culpa e assicurato che conceder\u00e0 un\u2019altra chance al suo ex pilota ufficiale ora privatissimo pi\u00f9 avanti nella stagione.<\/p>\n<p><strong>Classifica Rally di Svezia dopo la PS 9:<\/strong><\/p>\n<p>1\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Evans Elfyn\/ Martin Scott Toyota Yaris WRC<\/p>\n<p>2\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 T\u00e4nak Ott\/ J\u00e4rveoja M. Hyundai i20 Coupe WRC\u00a0\u00a0\u00a0 +00:17.2<\/p>\n<p>3\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Ogier S.\/ Ingrassia J. Toyota Yaris WRC\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 +00:28.8<\/p>\n<p>4\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Rovanper\u00e4 K.\/ Halttunen Jonne Toyota Yaris WRC +00:29.3<\/p>\n<p>5\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Lappi Esapekka\/ Ferm Janne Ford Fiesta WRC\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 +00:34.7<\/p>\n<p>6\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Neuville Thierry\/ Gilsoul Nicolas Hyundai i20 Coupe WRC\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 +00:39.2<\/p>\n<p>7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Breen Craig\/ Nagle Paul Hyundai i20 Coupe WRC\u00a0\u00a0 +00:49.7<\/p>\n<p>8\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Suninen Teemu\/ Lehtinen Jarmo Ford Fiesta WRC +01:14.8<\/p>\n<p>9\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Katsuta T.\/ Barritt Daniel Toyota Yaris WRC +01:37.4<\/p>\n<p>10\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Huttunen Jari\/ Lukka Mikko Hyundai i20 R5 +03:39.1<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":43742,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[373,7853,293],"tags":[],"class_list":["post-43741","post","type-post","status-publish","format-standard","has-post-thumbnail","category-citroen","category-motorsport","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WRC, Rally Svezia, La C3 R5 di Ostberg in leggera difficolt\u00e0 nella seconda giornata - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WRC, Rally Svezia, La C3 R5 di Ostberg in leggera difficolt\u00e0 nella seconda giornata - AbmNews\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-15T15:31:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-15T15:31:45+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/02\/464A884E-BA78-40F4-BF63-F2D858749526.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"913\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"WRC, Rally Svezia, La C3 R5 di Ostberg in leggera difficolt\u00e0 nella seconda giornata\",\"datePublished\":\"2020-02-15T15:31:43+00:00\",\"dateModified\":\"2020-02-15T15:31:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\\\/\"},\"wordCount\":372,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/464A884E-BA78-40F4-BF63-F2D858749526.jpeg\",\"articleSection\":[\"Citroen\",\"Motorsport\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\\\/\",\"name\":\"WRC, Rally Svezia, La C3 R5 di Ostberg in leggera difficolt\u00e0 nella seconda giornata - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/464A884E-BA78-40F4-BF63-F2D858749526.jpeg\",\"datePublished\":\"2020-02-15T15:31:43+00:00\",\"dateModified\":\"2020-02-15T15:31:45+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/464A884E-BA78-40F4-BF63-F2D858749526.jpeg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/464A884E-BA78-40F4-BF63-F2D858749526.jpeg\",\"width\":913,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WRC, Rally Svezia, La C3 R5 di Ostberg in leggera difficolt\u00e0 nella seconda giornata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WRC, Rally Svezia, La C3 R5 di Ostberg in leggera difficolt\u00e0 nella seconda giornata - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/","og_locale":"it_IT","og_type":"article","og_title":"WRC, Rally Svezia, La C3 R5 di Ostberg in leggera difficolt\u00e0 nella seconda giornata - AbmNews","og_url":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-02-15T15:31:43+00:00","article_modified_time":"2020-02-15T15:31:45+00:00","og_image":[{"width":913,"height":608,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/02\/464A884E-BA78-40F4-BF63-F2D858749526.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"WRC, Rally Svezia, La C3 R5 di Ostberg in leggera difficolt\u00e0 nella seconda giornata","datePublished":"2020-02-15T15:31:43+00:00","dateModified":"2020-02-15T15:31:45+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/"},"wordCount":372,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/02\/464A884E-BA78-40F4-BF63-F2D858749526.jpeg","articleSection":["Citroen","Motorsport","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/","url":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/","name":"WRC, Rally Svezia, La C3 R5 di Ostberg in leggera difficolt\u00e0 nella seconda giornata - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/02\/464A884E-BA78-40F4-BF63-F2D858749526.jpeg","datePublished":"2020-02-15T15:31:43+00:00","dateModified":"2020-02-15T15:31:45+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/02\/464A884E-BA78-40F4-BF63-F2D858749526.jpeg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/02\/464A884E-BA78-40F4-BF63-F2D858749526.jpeg","width":913,"height":608},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/wrc-rally-svezia-la-c3-r5-di-ostberg-in-leggera-difficolta-nella-seconda-giornata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"WRC, Rally Svezia, La C3 R5 di Ostberg in leggera difficolt\u00e0 nella seconda giornata"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/43741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=43741"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/43741\/revisions"}],"predecessor-version":[{"id":43743,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/43741\/revisions\/43743"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/43742"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=43741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=43741"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=43741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}