{"id":44725,"date":"2020-03-10T17:17:00","date_gmt":"2020-03-10T16:17:00","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=44725"},"modified":"2020-03-10T17:17:49","modified_gmt":"2020-03-10T16:17:49","slug":"il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/","title":{"rendered":"Il marchio Jeep\u00ae annuncia la partnership mondiale con il gruppo pop Now United"},"content":{"rendered":"\n<p>Il marchio Jeep\u00ae ha annunciato l\u2019innovativa partnership con Now United, il primo gruppo pop al mondo, per promuovere il SUV compatto Jeep\u00a0Renegade sui social e digital media attraverso clip musicali e performance dal vivo realizzati sulle note di \u201cCome Together\u201d.<br \/>\u00a0<br \/>Con questo annuncio il marchio Jeep sar\u00e0 partner automobilistico globale di Now United e la partnership contribuir\u00e0 ad avvicinare gli appassionati del brand automotive in tutto il mondo agli oltre 40 milioni di fan e follower di Now United presenti a livello globale. L\u2019iniziativa prosegue sulla scia del successo ottenuto dallo spot pubblicitario \u201cGroundhog Day\u201d, lanciato durante il Super Bowl che ha visto come protagonista l\u2019attore Bill Murray. Facendo seguito a una serie di teaser pubblicati sui canali social di Now United la scorsa settimana, sabato 7 marzo 2020 \u00e8 stata lanciata la nuova campagna contestualmente all\u2019uscita ufficiale del nuovo singolo di Now United \u201c<a href=\"https:\/\/youtu.be\/_tileyCRZlA\">Come Together<\/a>\u201d. Il nuovo video musicale ha avuto un impatto immediato con 1,8 milioni di visualizzazioni nelle prime 24 ore dalla pubblicazione.<br \/>\u00a0<br \/>La partnership con Now United si rivolge ai nuovi clienti attraverso una campagna digital e social che vedr\u00e0 i 15 membri del gruppo protagonisti di nuovi spettacoli musicali &#8211; sia quotidiani che settimanali &#8211; su YouTube e attivit\u00e0 di social engagement in tempo reale su Instagram, TikTok e Twitter. In ciascuna di queste performance i componenti del gruppo indosseranno uniformi brandizzate Jeep.<br \/>\u00a0<br \/>Now United \u00e8 il primo gruppo pop globale del mondo ed \u00e8 composto da 15 membri tra cantanti e ballerini provenienti da 15 paesi diversi: India, Brasile, Regno Unito, Messico, Filippine, Finlandia, Corea del Sud, Australia, Senegal, Cina, Giappone, Germania, Russia, Canada e Stati Uniti. Creato nel 2017 dall\u2019icona dell\u2019industria musicale Simon Fuller, il gruppo Now United ha rapidamente raggiunto i 40 milioni di fan in tutto il mondo.<br \/>\u00a0<br \/>\u201cJeep \u00e8 unico in quanto \u00e8 veramente un marchio automobilistico globale, immediatamente riconoscibile in tutti i continenti\u201d ha dichiarato Olivier Francois, Chief Marketing Officer, FCA. \u201cI nostri fan e follower in tutto il mondo sanno che sono la passione, l\u2019autenticit\u00e0 e la libert\u00e0 a guidare il marchio Jeep. Now United condivide con noi questi stessi valori. Mentre la band inizia il suo tour estivo con la prima tappa in Brasile, non vediamo l\u2019ora di stabilire una partnership con Simon Fuller che rappresenti e unisca i nostri fan in un modo che solo Jeep e Now United possono rendere possibile.\u201d<br \/>\u00a0<br \/>Simon Fuller ha affermato: \u201cSono entusiasta di collaborare con Olivier Francois, un genio del branding con una mente straordinariamente innovativa, e do il benvenuto a Jeep come partner globale di Now United.\u00a0Jeep \u00e8 un marchio iconico e noi ne condividiamo il forte spirito e il senso di avventura. Il coinvolgimento di Jeep nel video di Come Together \u00e8 il primo di molti altri progetti innovativi che abbiamo intenzione di portare avanti insieme, che apriranno la strada a nuove forme di collaborazione e di coinvolgimento dei nostri fan in tutto il mondo\u201d.<br \/>\u00a0<br \/>Video di \u201cCome Together&#8221; disponibile al link: <a href=\"https:\/\/youtu.be\/_tileyCRZlA\">https:\/\/youtu.be\/_tileyCRZlA<\/a><u><br \/><\/u>\u00a0<\/p>\n<p><strong>Now United e Simon Fuller<\/strong><br \/>Now United \u00e8 il primo gruppo pop globale al mondo ed \u00e8 composto da 15 cantanti e ballerini provenienti da 15 paesi diversi: India, Brasile, Regno Unito, Messico, Filippine, Finlandia, Corea del Sud, Australia, Senegal, Cina, Giappone, Germania, Russia, Canada e Stati Uniti. In breve tempo la band ha raggiunto i 40 milioni di fan in tutto il mondo.<br \/>\u00a0<br \/>Now United \u00e8 frutto dell\u2019intuizione di Simon Fuller, creatore di American Idol e celebre imprenditore musicale inglese. L\u2019elenco dei clienti di Fuller include, tra gli altri, artisti quali le Spice Girls, Amy Winehouse, Annie Lennox, Kelly Clarkson, Carrie Underwood.\u00a0<br \/><br \/>Now United \u00e8 disponibile sui social: <a href=\"http:\/\/www.youtube.com\/nowunited\">YouTube: NowUnited <\/a>| <a href=\"https:\/\/www.instagram.com\/nowunited\/\">Instagram: @nowunited<\/a> | <a href=\"http:\/\/www.twitter.com\/nowunitedmusic\">Twitter: @NowUnitedMusic<\/a><u><br \/><br \/><\/u><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":44726,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[406,262,1],"tags":[],"class_list":["post-44725","post","type-post","status-publish","format-standard","has-post-thumbnail","category-jeep","category-novita","category-senza-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il marchio Jeep\u00ae annuncia la partnership mondiale con il gruppo pop Now United - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il marchio Jeep\u00ae annuncia la partnership mondiale con il gruppo pop Now United - AbmNews\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-10T16:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-10T16:17:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/03\/HP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Il marchio Jeep\u00ae annuncia la partnership mondiale con il gruppo pop Now United\",\"datePublished\":\"2020-03-10T16:17:00+00:00\",\"dateModified\":\"2020-03-10T16:17:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\\\/\"},\"wordCount\":614,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/HP.jpg\",\"articleSection\":[\"Jeep\",\"Novit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\\\/\",\"name\":\"Il marchio Jeep\u00ae annuncia la partnership mondiale con il gruppo pop Now United - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/HP.jpg\",\"datePublished\":\"2020-03-10T16:17:00+00:00\",\"dateModified\":\"2020-03-10T16:17:49+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/HP.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/HP.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il marchio Jeep\u00ae annuncia la partnership mondiale con il gruppo pop Now United\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il marchio Jeep\u00ae annuncia la partnership mondiale con il gruppo pop Now United - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/","og_locale":"it_IT","og_type":"article","og_title":"Il marchio Jeep\u00ae annuncia la partnership mondiale con il gruppo pop Now United - AbmNews","og_url":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-03-10T16:17:00+00:00","article_modified_time":"2020-03-10T16:17:49+00:00","og_image":[{"width":800,"height":533,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/03\/HP.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Il marchio Jeep\u00ae annuncia la partnership mondiale con il gruppo pop Now United","datePublished":"2020-03-10T16:17:00+00:00","dateModified":"2020-03-10T16:17:49+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/"},"wordCount":614,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/03\/HP.jpg","articleSection":["Jeep","Novit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/","url":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/","name":"Il marchio Jeep\u00ae annuncia la partnership mondiale con il gruppo pop Now United - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/03\/HP.jpg","datePublished":"2020-03-10T16:17:00+00:00","dateModified":"2020-03-10T16:17:49+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/03\/HP.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/03\/HP.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/il-marchio-jeep-annuncia-la-partnership-mondiale-con-il-gruppo-pop-now-united\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Il marchio Jeep\u00ae annuncia la partnership mondiale con il gruppo pop Now United"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/44725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=44725"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/44725\/revisions"}],"predecessor-version":[{"id":44727,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/44725\/revisions\/44727"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/44726"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=44725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=44725"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=44725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}