{"id":44733,"date":"2020-03-11T07:26:41","date_gmt":"2020-03-11T06:26:41","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=44733"},"modified":"2020-03-11T07:26:45","modified_gmt":"2020-03-11T06:26:45","slug":"peugeot-508-bluehdi-160-eat8-larte-del-viaggiare","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/","title":{"rendered":"Peugeot 508 BlueHDi 160 EAT8  L\u2019arte del viaggiare"},"content":{"rendered":"\n<p>Non \u00e8 necessario attraversare un oceano per fare un viaggio coast-to-coast, a volte l\u2019avventura pu\u00f2 essere pi\u00f9 vicina. Il nostro Paese offre l\u2019opportunit\u00e0 di attraversare paesaggi incredibili, poco noti, senza percorrere migliaia di chilometri.<\/p>\n<p>Un\u2019occhiata alla cartina geografica e l\u2019idea di fare il coast-to-coast \u00e8 immediata, specie quando si ha a disposizione una grande stradista come l\u2019ammiraglia della Casa del Leone, la PEUGEOT 508.<\/p>\n<p><div id=\"fb-root\"><\/div><script async=\"1\" defer=\"1\" crossorigin=\"anonymous\" src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js#xfbml=1&amp;version=v6.0\"><\/script><div class=\"fb-video\" data-href=\"https:\/\/www.facebook.com\/ABMnews\/videos\/665907174183527\/\" data-width=\"696\"><blockquote cite=\"https:\/\/www.facebook.com\/ABMnews\/videos\/665907174183527\/\" class=\"fb-xfbml-parse-ignore\"><a href=\"https:\/\/www.facebook.com\/ABMnews\/videos\/665907174183527\/\"><\/a><p>Peugeot 508 BlueHDi 160 EAT8 L\u2019arte del viaggiare<\/p>Posted by <a href=\"https:\/\/www.facebook.com\/ABMnews\/\">ABMnews<\/a> on Tuesday, March 10, 2020<\/blockquote><\/div><\/p>\n<p>Dal Tirreno allo Jonio, o viceversa, nel punto pi\u00f9 stretto dell\u2019Italia. La costa calabrese tra Sant\u2019Eufemia\/Lamezia Terme e Catanzaro Lido \u00e8 il coast-to-coast italiano da percorrere nell\u2019arco di poco pi\u00f9 di un\u2019ora.<\/p>\n<p>Sono meno di cento chilometri con la E848, oppure in un paio di giorni volendo attardarsi in un viaggio senza fretta per ammirare i panorami della costa e dell\u2019entroterra, gustando con lentezza le comodit\u00e0 che la fastback PEUGEOT garantisce ai suoi occupanti, coccolandoli in un abitacolo da quale non si vorrebbe mai scendere.<\/p>\n<p>La scarsa densit\u00e0 abitativa rispetto ad altre regioni regala l\u2019esperienza di un viaggio non solo fisico, ma anche mentale, permettendo al viaggiatore di allontanarsi spiritualmente dal quotidiano. Un viaggio facilitato in questo dal grande confort e dalla dinamica di marcia di gran pregio dell\u2019ammiraglia transalpina, qui, nelle immagini in versione fastback e spinta dal motore 2 litri BlueHDi 160 che trasmette a terra potenza e coppia attraverso un efficiente e moderno cambio automatico ad 8 rapporti, chiamato EAT8. Una motorizzazione che fa dell\u2019equilibrio una delle sue migliori caratteristiche, bilanciando sapientemente prestazioni, consumi ed emisisoni, con un livello tecnologico che pu\u00f2 vantare anche la presenza dell\u2019innovativo sistema Night Vision per elevare lo standard di sicurezza alla guida.<\/p>\n<p>Grazie alle sue doti da grande viaggiatrice, rincorrere da una costa all\u2019altra i due principali oggetti astronomici del nostro sistema planetario \u00e8 un gioco da ragazzi\u2026 due albe e due tramonti su due coste diverse, Luna e Sole, Sole e Luna\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":44734,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[262,300,346],"tags":[],"class_list":["post-44733","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novita","category-peugeot","category-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Peugeot 508 BlueHDi 160 EAT8 L\u2019arte del viaggiare - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot 508 BlueHDi 160 EAT8 L\u2019arte del viaggiare - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-11T06:26:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-11T06:26:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/03\/PEUGEOT-508-BLUEHDI160-LARTE-DEL-VIAGGIARE-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Peugeot 508 BlueHDi 160 EAT8 L\u2019arte del viaggiare\",\"datePublished\":\"2020-03-11T06:26:41+00:00\",\"dateModified\":\"2020-03-11T06:26:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\\\/\"},\"wordCount\":329,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/PEUGEOT-508-BLUEHDI160-LARTE-DEL-VIAGGIARE-1.jpg\",\"articleSection\":[\"Novit\u00e0\",\"Peugeot\",\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\\\/\",\"name\":\"Peugeot 508 BlueHDi 160 EAT8 L\u2019arte del viaggiare - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/PEUGEOT-508-BLUEHDI160-LARTE-DEL-VIAGGIARE-1.jpg\",\"datePublished\":\"2020-03-11T06:26:41+00:00\",\"dateModified\":\"2020-03-11T06:26:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/PEUGEOT-508-BLUEHDI160-LARTE-DEL-VIAGGIARE-1.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/PEUGEOT-508-BLUEHDI160-LARTE-DEL-VIAGGIARE-1.jpg\",\"width\":2560,\"height\":1703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peugeot 508 BlueHDi 160 EAT8 L\u2019arte del viaggiare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot 508 BlueHDi 160 EAT8 L\u2019arte del viaggiare - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/","og_locale":"it_IT","og_type":"article","og_title":"Peugeot 508 BlueHDi 160 EAT8 L\u2019arte del viaggiare - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-03-11T06:26:41+00:00","article_modified_time":"2020-03-11T06:26:45+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/03\/PEUGEOT-508-BLUEHDI160-LARTE-DEL-VIAGGIARE-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Peugeot 508 BlueHDi 160 EAT8 L\u2019arte del viaggiare","datePublished":"2020-03-11T06:26:41+00:00","dateModified":"2020-03-11T06:26:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/"},"wordCount":329,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/03\/PEUGEOT-508-BLUEHDI160-LARTE-DEL-VIAGGIARE-1.jpg","articleSection":["Novit\u00e0","Peugeot","Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/","url":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/","name":"Peugeot 508 BlueHDi 160 EAT8 L\u2019arte del viaggiare - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/03\/PEUGEOT-508-BLUEHDI160-LARTE-DEL-VIAGGIARE-1.jpg","datePublished":"2020-03-11T06:26:41+00:00","dateModified":"2020-03-11T06:26:45+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/03\/PEUGEOT-508-BLUEHDI160-LARTE-DEL-VIAGGIARE-1.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/03\/PEUGEOT-508-BLUEHDI160-LARTE-DEL-VIAGGIARE-1.jpg","width":2560,"height":1703},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/peugeot-508-bluehdi-160-eat8-larte-del-viaggiare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Peugeot 508 BlueHDi 160 EAT8 L\u2019arte del viaggiare"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/44733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=44733"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/44733\/revisions"}],"predecessor-version":[{"id":44735,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/44733\/revisions\/44735"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/44734"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=44733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=44733"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=44733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}