{"id":45480,"date":"2020-04-09T15:10:41","date_gmt":"2020-04-09T13:10:41","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=45480"},"modified":"2020-04-09T15:10:43","modified_gmt":"2020-04-09T13:10:43","slug":"la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/","title":{"rendered":"LA NUOVA CAMPAGNA DI COMUNICAZIONE DEL GRUPPO TOYOTA E\u2019 UN MESSAGGIO DI SPERANZA PER L\u2019ITALIA"},"content":{"rendered":"\n<p>Prepariamoci a rinascere, pi\u00f9 preziosi e pi\u00f9 forti.<\/p>\n<p>Questo \u00e8 il messaggio della nuova campagna di comunicazione \u2018<strong>The Unbreakable<\/strong>\u2019, da oggi on air sui principali canali TV e social, nei formati da 30\u2019\u2019 e 60\u2019\u2019.<\/p>\n<p>Gli \u2018<strong>Unbreakable\u2019<\/strong> sono persone fuori dal comune, che hanno affrontato e superato con coraggio sfide difficilissime, fisiche o emotive. Tramite i loro messaggi, il gruppo Toyota vuole celebrare coloro che hanno il coraggio di \u201csfidare l\u2019impossibile\u201d. Di fronte a insuccessi o avversit\u00e0, gli \u2018Unbreakable\u2019 sono in grado di rinascere pi\u00f9 forti di prima e, per questo motivo, sono fonte d\u2019ispirazione per chiunque trovi ostacoli lungo il proprio percorso: niente \u00e8 impossibile se ci crediamo davvero!<\/p>\n<p>Protagonisti della campagna sono 7 atleti olimpici e paralimpici italiani, rappresentanti del Toyota Team <sup>(1)<\/sup> (Bebe Vio, Ivan Zaytsev, Simona Quadarella, Andrea Pusateri, Vanessa Ferrari, Ivan Federico, Gabriele Detti). Accompagnati dalle toccanti note\u00a0della\u00a0<a href=\"https:\/\/eur01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fit.wikipedia.org%2Fwiki%2FTurandot&amp;data=02%7C01%7Csabrina.caputi%40toyota-europe.com%7C46ffca4b0ffa4b7773ed08d7dbd74c75%7C52b742d13dc247acbf03609c83d9df9f%7C0%7C0%7C637219590053134579&amp;sdata=H82C4wzBr4i%2BVTKFyh5W5A%2FMvVAyNXvnpqxW88WHXNo%3D&amp;reserved=0\">Turandot<\/a>\u00a0di\u00a0<a href=\"https:\/\/eur01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fit.wikipedia.org%2Fwiki%2FGiacomo_Puccini&amp;data=02%7C01%7Csabrina.caputi%40toyota-europe.com%7C46ffca4b0ffa4b7773ed08d7dbd74c75%7C52b742d13dc247acbf03609c83d9df9f%7C0%7C0%7C637219590053134579&amp;sdata=srb9OkLxQkX39Bcb%2Foas78oG%2B0zDKt9qq2UqK0EDY9Y%3D&amp;reserved=0\">Giacomo Puccini<\/a>, gli atleti, che hanno dovuto rimandare uno degli appuntamenti pi\u00f9 importanti della loro vita, le Olimpiadi e Paralimpiadi di Tokyo, trasmettono il loro messaggio di perseveranza, determinazione e di fiducia per una rinascita.<\/p>\n<p>In questo momento, nel quale tutti siamo chiamati ad andare oltre il nostro quotidiano, lottando in una corsia di ospedale a fianco dei pi\u00f9 deboli, o pi\u00f9 semplicemente restando a casa, il gruppo Toyota vuole inviare all\u2019Italia un messaggio di speranza e di incoraggiamento, prendendo ispirazione dal \u201c<strong>Kintsugi\u201d,<\/strong> l\u2019antica arte della tradizione giapponese. Secondo la tecnica del Kintsugi, il Doroppu, un vaso a forma di goccia, viene ricomposto dopo essere stato rotto usando filamenti d\u2019oro per unire le fratture, diventando cos\u00ec unico e per questo ancora pi\u00f9 prezioso. E\u2019 una metafora della vita, nella quale superando i momenti di difficolt\u00e0 e le cadute, si cresce, si diventa migliori e pi\u00f9 preziosi.<\/p>\n<p><em>\u201cSiamo un popolo unico, abituato da sempre a scrivere storie impossibili e a superare incredibili difficolt\u00e0. E lo faremo anche questa volta! Le nostre cicatrici ci faranno diventare speciali e ripartiremo pi\u00f9 forti, pi\u00f9 uniti, pi\u00f9 grandi \u2013 ha commentato <strong>Mauro Caruccio, Amministratore Delegato di Toyota Motor Italia<\/strong> &#8211; La comunit\u00e0 di Toyota e Lexus in Italia vuole fortemente trasmettere questo messaggio di speranza, perch\u00e9 amiamo il nostro paese e, con semplicit\u00e0, vogliamo dare un piccolo contributo toccando il cuore di tutti gli italiani\u201d.<\/em><\/p>\n<p><em>\u201cLa Toyota si dimostra \u2013 una volta di pi\u00f9 \u2013 un compagno di squadra straordinario, promuovendo una campagna che mette ancora una volta al centro lo sport \u2013 ha sottolineato il <strong>Presidente del CONI, Giovanni Malag\u00f2<\/strong> -. Siamo orgogliosi che i valori del movimento, incarnati da atlete e atleti fantastici, diventino lo strumento per vivere questo momento di grande complessit\u00e0 per il nostro Paese, con la consapevolezza di poter superare ogni ostacolo e vincere anche la sfida pi\u00f9 difficile\u201d.<\/em><\/p>\n<p><em>&#8220;Questa fantastica campagna di comunicazione coglie in pieno lo spirito dello sport, in particolare del mondo paralimpico. Nei momenti difficili tutti noi dobbiamo ripartire da ci\u00f2 che siamo, dalle nostre abilit\u00e0 residue, trasformando ogni ostacolo in un&#8217;opportunit\u00e0, con pazienza, coraggio e impegno. Uno straordinario messaggio di speranza al nostro Paese che sta attraversando una grave emergenza ma che, come sempre, sapr\u00e0 rialzarsi con orgoglio e determinazione. Sono felice che siano stati scelti degli sportivi come testimonial di questa campagna. Lo sport rappresenta uno straordinario strumento di coesione sociale e fonte d&#8217;ispirazione per tante persone. Ancora una volta Toyota dimostra di essere un eccellente partner capace non solo di sostenere il momento sportivo italiano ma anche di saperne cogliere i suoi valori pi\u00f9 profondi&#8221;. E&#8217; quanto dichiara <strong>Luca Pancalli, Presidente del Comitato Italiano Paralimpico<\/strong>.<\/em><\/p>\n<p>Ripartiremo presto, e lo faremo insieme. <strong>#ripartiremoinsieme<\/strong><\/p>\n<p>La nuova campagna sar\u00e0 visibile nel sito al seguente indirizzo <a href=\"https:\/\/www.toyota.it\/startyourimpossible\/ripartiremo-insieme\">https:\/\/www.toyota.it\/startyourimpossible\/ripartiremo-insieme<\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":45481,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[293,335],"tags":[],"class_list":["post-45480","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news","category-toyota"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA NUOVA CAMPAGNA DI COMUNICAZIONE DEL GRUPPO TOYOTA E\u2019 UN MESSAGGIO DI SPERANZA PER L\u2019ITALIA - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA NUOVA CAMPAGNA DI COMUNICAZIONE DEL GRUPPO TOYOTA E\u2019 UN MESSAGGIO DI SPERANZA PER L\u2019ITALIA - AbmNews\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-09T13:10:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-09T13:10:43+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/04\/campagnaunbreakable.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"641\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"LA NUOVA CAMPAGNA DI COMUNICAZIONE DEL GRUPPO TOYOTA E\u2019 UN MESSAGGIO DI SPERANZA PER L\u2019ITALIA\",\"datePublished\":\"2020-04-09T13:10:41+00:00\",\"dateModified\":\"2020-04-09T13:10:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\\\/\"},\"wordCount\":624,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/campagnaunbreakable.png\",\"articleSection\":[\"News\",\"Toyota\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\\\/\",\"name\":\"LA NUOVA CAMPAGNA DI COMUNICAZIONE DEL GRUPPO TOYOTA E\u2019 UN MESSAGGIO DI SPERANZA PER L\u2019ITALIA - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/campagnaunbreakable.png\",\"datePublished\":\"2020-04-09T13:10:41+00:00\",\"dateModified\":\"2020-04-09T13:10:43+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/campagnaunbreakable.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/campagnaunbreakable.png\",\"width\":800,\"height\":641},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA NUOVA CAMPAGNA DI COMUNICAZIONE DEL GRUPPO TOYOTA E\u2019 UN MESSAGGIO DI SPERANZA PER L\u2019ITALIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA NUOVA CAMPAGNA DI COMUNICAZIONE DEL GRUPPO TOYOTA E\u2019 UN MESSAGGIO DI SPERANZA PER L\u2019ITALIA - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/","og_locale":"it_IT","og_type":"article","og_title":"LA NUOVA CAMPAGNA DI COMUNICAZIONE DEL GRUPPO TOYOTA E\u2019 UN MESSAGGIO DI SPERANZA PER L\u2019ITALIA - AbmNews","og_url":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-04-09T13:10:41+00:00","article_modified_time":"2020-04-09T13:10:43+00:00","og_image":[{"width":800,"height":641,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/04\/campagnaunbreakable.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"LA NUOVA CAMPAGNA DI COMUNICAZIONE DEL GRUPPO TOYOTA E\u2019 UN MESSAGGIO DI SPERANZA PER L\u2019ITALIA","datePublished":"2020-04-09T13:10:41+00:00","dateModified":"2020-04-09T13:10:43+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/"},"wordCount":624,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/04\/campagnaunbreakable.png","articleSection":["News","Toyota"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/","url":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/","name":"LA NUOVA CAMPAGNA DI COMUNICAZIONE DEL GRUPPO TOYOTA E\u2019 UN MESSAGGIO DI SPERANZA PER L\u2019ITALIA - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/04\/campagnaunbreakable.png","datePublished":"2020-04-09T13:10:41+00:00","dateModified":"2020-04-09T13:10:43+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/04\/campagnaunbreakable.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/04\/campagnaunbreakable.png","width":800,"height":641},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/la-nuova-campagna-di-comunicazione-del-gruppo-toyota-e-un-messaggio-di-speranza-per-litalia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"LA NUOVA CAMPAGNA DI COMUNICAZIONE DEL GRUPPO TOYOTA E\u2019 UN MESSAGGIO DI SPERANZA PER L\u2019ITALIA"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/45480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=45480"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/45480\/revisions"}],"predecessor-version":[{"id":45482,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/45480\/revisions\/45482"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/45481"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=45480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=45480"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=45480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}