{"id":47060,"date":"2020-06-06T04:17:32","date_gmt":"2020-06-06T02:17:32","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=47060"},"modified":"2020-06-06T04:17:35","modified_gmt":"2020-06-06T02:17:35","slug":"unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/","title":{"rendered":"Un&#8217;intervista con il pilota del Team Redline Kevin Siggy: &#8220;Mi sento onorato di gareggiare per BMW&#8221;."},"content":{"rendered":"\n<p><strong>In vista dell&#8217;ultimo fine settimana della stagione &#8220;ABB Formula E Race at Home Challenge&#8221; con una gara sabato e la Grand Final di domenica, il pilota del Team Redline Kevin Siggy (SLO) come rappresentante della BMW i Andretti Motorsport guida la classifica generale nella Challenge Grid, in cui si sfidano i professionisti delle gare sim. Se il 21enne sar\u00e0 in grado di vincere la Grand Final al volante della BMW iFE.20 virtuale, la sua ricompensa sar\u00e0 un test drive in una vera vettura di Formula E e un posto alla partenza della finale della BMW SIM M2 CS Racing Cup all&#8217;evento BMW SIM Live a Monaco (GER) alla fine dell&#8217;anno. In un&#8217;intervista, Siggy parla della Formula E virtuale, della sensazione di guidare per un produttore come BMW e della sua connessione con il pilota della BMW i Andretti Motorsport Maximilian G\u00fcnther (GER), che attualmente \u00e8 terzo nella classifica generale per i piloti di Formula E a due gare dal termine del campionato.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Kevin, stai rappresentando in modo eccellente i colori della BMW i Andretti Motorsport nella Challenge Grid. Come fai ad andare cos\u00ec forte nella &#8220;ABB Formula E Race at Home Challenge&#8221;?<\/strong><\/p>\n<p>Kevin Siggy: &#8220;Penso che dipenda principalmente dalla mia vasta esperienza sulla piattaforma rFactor 2. Ci ho corso da quando avevo 13 anni e recentemente ho superato il traguardo delle 1.000 ore. Tutta questa pratica mi ha dato un&#8217;ottima comprensione di come funzionano la simulazione, il set-up, il tipo di pneumatico, l&#8217;aderenza in pista e il meteo\u201d.<\/p>\n<p><strong>Quanto intensamente ti alleni prima di ogni gara di Formula E?<\/strong><\/p>\n<p>Siggy: \u201cScopriamo sempre su quale pista correremo solo qualche giorno prima della gara. Quindi dipende se ho gi\u00e0 corso in quella pista o se &#8211; come quelli di Berlino e New York di recente \u2013 si tratta di un circuito nuovo. Su una pista come Hong Kong, che conoscevo gi\u00e0, ho fatto solo pochi giri per ritrovare il mio ritmo. Naturalmente, per i nuovi circuiti mi prendo pi\u00f9 tempo. Prima di tutto, faccio fino a 50 giri per familiarizzare con la pista. Quindi il giorno della gara faccio altre 2-3 ore per testare i miei limiti e trovare il ritmo ottimale per le qualifiche, che \u00e8 il fattore pi\u00f9 importante secondo me. E poi aiuto anche Maximilian G\u00fcnther nei suoi preparativi &#8230; &#8220;<\/p>\n<p><strong>Quindi ti chiede consigli?<\/strong><\/p>\n<p>Siggy: &#8220;Esatto! Si \u00e8 accorto di me durante la gara di test e si \u00e8 messo in contatto con me. Gli ho dato principalmente alcuni suggerimenti dalla mia esperienza con rFactor 2, che lo ha aiutato a sviluppare un buon set-up e un modo di guidare adatto a lui. Poi mi ha detto che la gestione non \u00e8 la stessa della vera BMW iFE.20. Ha dovuto adattarsi e fare alcune cose nel simulatore che non avrebbe fatto con la vera macchina da corsa &#8220;.<\/p>\n<p><strong>In che misura questo tipo di collaborazione \u00e8 standard?<\/strong><\/p>\n<p>Siggy: \u201cIl modo in cui Maximilian e io stiamo collaborando \u00e8 molto standard in questo ambiente. Ci incontriamo online per una sessione di allenamento congiunta prima di una gara. Fa domande, gli do consigli ovunque posso. Tutto qui. Molti altri piloti di sim e piloti di corse reali stanno facendo la stessa cosa.&#8221;<\/p>\n<p><strong>Tu e Maximilian G\u00fcnther avete vinto diverse gare in questa stagione. Ma lui non \u00e8 costante quanto te. Come mai?<\/strong><\/p>\n<p>Siggy: &#8220;Penso che, poich\u00e9 non ha ancora molta esperienza con le corse sim, non ha molto tempo per prepararsi per le nuove piste. Tuttavia, sta facendo un lavoro fantastico e sta imparando molto rapidamente, che \u00e8 ci\u00f2 di cui c\u2019\u00e8 bisogno per avere successo nelle corse sim. In linea generale, bisogna tenere conto del fatto che come sim racer ci guadagniamo da vivere in questo modo e quindi abbiamo trascorso molto tempo aa allenarci per molti anni. Persino un pilota professionista come Maximilian non riesce a recuperare il ritardo in pochi mesi perch\u00e9 la gestione in un simulatore \u00e8 totalmente diversa da quella di una vera auto da corsa.&#8221;<\/p>\n<p><strong>Cosa significa per te iniziare per la BMW nella Formula E virtuale?<\/strong><\/p>\n<p>Siggy: \u201cCorrere per un produttore come BMW \u00e8 una delle cose pi\u00f9 grandi che puoi immaginare come pilota di sim. Mi sento onorato.&#8221;<\/p>\n<p><strong>Come \u00e8 nato il contatto?<\/strong><\/p>\n<p>Siggy: \u201cDevo ringraziare il Team Redline, per il quale corro come pilota professionista da marzo, per questo. Hanno aperto la comunicazione con BMW e hanno supportato il mio debutto nella Formula E virtuale fin dall&#8217;inizio.\u201d<\/p>\n<p><strong>Quindi gareggi per il Team Redline da poco?<\/strong><\/p>\n<p>Siggy: &#8220;Esatto. Sono un pilota professionista da circa due anni e sono felice di poter dire che ora posso guadagnarmi da vivere. Ho vinto alcune gare importanti quest&#8217;anno, che \u00e8 ovviamente ci\u00f2 che ha attirato l&#8217;attenzione di una grande squadra come Redline. Sono entrati in contatto con me a marzo e ho firmato il mio contratto. &#8220;<\/p>\n<p><strong>Cosa ne pensi del boom delle corse sim, provocato dall&#8217;attuale crisi globale?<\/strong><\/p>\n<p>Siggy: \u201cPrima di tutto, la situazione in cui ci troviamo attualmente non \u00e8 affatto piacevole e speriamo che presto finisca. Ma ad essere sincero, \u00e8 stata una grande spinta per le corse sim. Da un lato, \u00e8 bello che qualcuno come me sia in grado di competere con veri piloti da corsa e guadagnarsi il loro rispetto. D&#8217;altra parte, come piloti di sim, ora stiamo guadagnando molta pi\u00f9 visibilit\u00e0, il che ovviamente ci aiuta immensamente come professionisti. Un anno fa non avrei potuto immaginare di guadagnarmi da vivere solo con le agre sim. Adesso le cose stanno cambiando.&#8221;<\/p>\n<p><strong>Se sarai in grado di vincere la Grand Final della \u201cABB Formula E Race at Home Challenge\u201d, i premi che ti attendono sono un test drive in una vera vettura di Formula E e un posto nella finale della BMW SIM M2 CS Racing Cup.<\/strong><\/p>\n<p>Siggy: \u201cSono entrambi fantastici! Essere alla finale di Campionato dal vivo a Monaco e incontrare Maximilian e tutti gli altri piloti da corsa sarebbe bello. E mi piacerebbe davvero guidare la vera vettura di Formula E perch\u00e9 \u00e8 qualcosa che ho sempre sognato. Sfortunatamente, non ho avuto i fondi necessari per essere coinvolto nelle corse reali. Questo test drive sarebbe una fantastica opportunit\u00e0 per mostrare cosa posso fare. &#8220;<\/p>\n<p><strong>Live streaming della ABB Formula E Race at Home Challenge:<\/strong><\/p>\n<p><strong>Sabato 6 giugno, 16:30hrs CEST:<\/strong><\/p>\n<p>Facebook: <a href=\"https:\/\/b.mw\/RaceAtHomeChallenge7FB\">https:\/\/b.mw\/RaceAtHomeChallenge7FB<\/a><\/p>\n<p>YouTube: <a href=\"https:\/\/b.mw\/RaceAtHomeChallenge7YT\">https:\/\/b.mw\/RaceAtHomeChallenge7YT<\/a><\/p>\n<p><strong>Domenica 7 giugno, 16:30hrs CEST:<\/strong><\/p>\n<p>Facebook: <a href=\"https:\/\/b.mw\/RaHC_final_FB\">https:\/\/b.mw\/RaHC_final_FB<\/a>.<\/p>\n<p>YouTube: <a href=\"https:\/\/b.mw\/RaHC_final_YT\">https:\/\/b.mw\/RaHC_final_YT<\/a>.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":47061,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[363,7853,293],"tags":[],"class_list":["post-47060","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bmw","category-motorsport","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un&#039;intervista con il pilota del Team Redline Kevin Siggy: &quot;Mi sento onorato di gareggiare per BMW&quot;. - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un&#039;intervista con il pilota del Team Redline Kevin Siggy: &quot;Mi sento onorato di gareggiare per BMW&quot;. - AbmNews\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-06T02:17:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-06T02:17:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/P90388723_highRes_munich-ger-9th-may-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Un&#8217;intervista con il pilota del Team Redline Kevin Siggy: &#8220;Mi sento onorato di gareggiare per BMW&#8221;.\",\"datePublished\":\"2020-06-06T02:17:32+00:00\",\"dateModified\":\"2020-06-06T02:17:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\\\/\"},\"wordCount\":1072,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/P90388723_highRes_munich-ger-9th-may-2.jpg\",\"articleSection\":[\"BMW\",\"Motorsport\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\\\/\",\"name\":\"Un'intervista con il pilota del Team Redline Kevin Siggy: \\\"Mi sento onorato di gareggiare per BMW\\\". - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/P90388723_highRes_munich-ger-9th-may-2.jpg\",\"datePublished\":\"2020-06-06T02:17:32+00:00\",\"dateModified\":\"2020-06-06T02:17:35+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/P90388723_highRes_munich-ger-9th-may-2.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/P90388723_highRes_munich-ger-9th-may-2.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un&#8217;intervista con il pilota del Team Redline Kevin Siggy: &#8220;Mi sento onorato di gareggiare per BMW&#8221;.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un'intervista con il pilota del Team Redline Kevin Siggy: \"Mi sento onorato di gareggiare per BMW\". - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/","og_locale":"it_IT","og_type":"article","og_title":"Un'intervista con il pilota del Team Redline Kevin Siggy: \"Mi sento onorato di gareggiare per BMW\". - AbmNews","og_url":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-06-06T02:17:32+00:00","article_modified_time":"2020-06-06T02:17:35+00:00","og_image":[{"width":800,"height":450,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/P90388723_highRes_munich-ger-9th-may-2.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Un&#8217;intervista con il pilota del Team Redline Kevin Siggy: &#8220;Mi sento onorato di gareggiare per BMW&#8221;.","datePublished":"2020-06-06T02:17:32+00:00","dateModified":"2020-06-06T02:17:35+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/"},"wordCount":1072,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/P90388723_highRes_munich-ger-9th-may-2.jpg","articleSection":["BMW","Motorsport","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/","url":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/","name":"Un'intervista con il pilota del Team Redline Kevin Siggy: \"Mi sento onorato di gareggiare per BMW\". - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/P90388723_highRes_munich-ger-9th-may-2.jpg","datePublished":"2020-06-06T02:17:32+00:00","dateModified":"2020-06-06T02:17:35+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/P90388723_highRes_munich-ger-9th-may-2.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/P90388723_highRes_munich-ger-9th-may-2.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/unintervista-con-il-pilota-del-team-redline-kevin-siggy-mi-sento-onorato-di-gareggiare-per-bmw\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Un&#8217;intervista con il pilota del Team Redline Kevin Siggy: &#8220;Mi sento onorato di gareggiare per BMW&#8221;."}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/47060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=47060"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/47060\/revisions"}],"predecessor-version":[{"id":47062,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/47060\/revisions\/47062"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/47061"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=47060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=47060"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=47060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}