{"id":47389,"date":"2020-06-17T11:31:20","date_gmt":"2020-06-17T09:31:20","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=47389"},"modified":"2020-06-17T11:31:23","modified_gmt":"2020-06-17T09:31:23","slug":"obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/","title":{"rendered":"Obiettivo tricolore ha fatto tappa presso la sede di BMW Italia a San Donato Milanese."},"content":{"rendered":"\n<p>Obiettivo tricolore \u00e8 la grande staffetta di Obiettivo3, che da venerd\u00ec 12 a domenica 28 giugno vedr\u00e0 oltre cinquanta atleti paralimpici, tra i quali il campione Alex Zanardi, passarsi di mano in mano il testimone lungo l\u2019Italia per lanciare un messaggio di rinascita. Il viaggio a tappe verso il traguardo finale di Santa Maria di Leuca prevede tre partenze differenti (Luino il 12, Levico Terme il 13 e Saluzzo il 16) e una serie di tappe in localit\u00e0 significative per Obiettivo3, trasformando il viaggio in una festa itinerante che abbraccia decine di luoghi, eventi e manifestazioni. Gli atleti di Obiettivo 3 impegnati nella tappa Milano-Parma della staffetta tricolore, nella mattinata di luned\u00ec 15 si sono fermati presso la sede di BMW Italia di San Donato Milanese per un saluto.<\/p>\n<p>BMW Italia \u00e8 tra i partner che sostengono Obiettivo3 nel contesto di SpecialMente, il programma di Corporate Social Responsibility che la filiale italiana di BMW coltiva da quasi due decenni ed \u00e8 dedicato alle molteplici iniziative che danno forma all\u2019impegno di BMW verso la societ\u00e0 in cui l\u2019azienda opera.<\/p>\n<p>La collaborazione di Alex Zanardi con BMW comprende l\u2019attivit\u00e0 di Brand Ambassador e quella in pista come pilota e anche l\u2019impegno sociale a sostegno di alcune delle iniziative di SpecialMente. Durante l\u2019emergenza sanitaria per la pandemia Zanardi \u00e8 stato scelto come portavoce della campagna #InsiemePerRipartire per trasmettere il messaggio di resilienza e incoraggiamento che l\u2019azienda ha voluto lanciare ed \u00e8 stato preso a modello come per sottolineare l\u2019atteggiamento di chi non si arrende di fronte ad un cambiamento ma sa trasformarlo in un nuovo inizio. \u00ab\u00c8 un nuovo viaggio, possiamo affrontarlo\u00bb \u00e8 stato il motto lanciato da Alex nella fase della ripartenza delle attivit\u00e0.<\/p>\n<p>\u201cSiamo molto felici \u2013 ha dichiarato Roberto Olivi, Direttore Relazioni Istituzionali e Comunicazione di BMW Italia \u2013 che la staffetta di Obiettivo3 abbia fatto tappa presso la nostra sede di San Donato Milanese, perch\u00e9 questa breve sosta \u00e8 stata un segno simbolico, ma ricco di contenuti, che da un lato ha testimoniato la nostra partnership e dall\u2019altro ha interpretato al meglio il messaggio di comunicazione che come azienda abbiamo lanciato nelle settimane difficili che abbiamo vissuto per la crisi epidemiologica. Un messaggio di resilienza prima e di anti fragilit\u00e0 in una seconda fase. La staffetta \u00e8 il modo migliore per ricominciare il viaggio per poter guardare al futuro insieme e con rinnovata speranza\u201d.<\/p>\n<p><strong>SpecialMente: il progetto di CSR di BMW Italia.<\/strong><\/p>\n<p>BMW Italia, filiale italiana di BMW AG, ha sviluppato un programma integrato di Corporate Social Responsibility denominato SpecialMente che ha come pilastri fondamentali cultura, inclusione sociale, dialogo interculturale, sicurezza stradale. SpecialMente \u00e8 una piattaforma che include tantissime attivit\u00e0 e che testimonia come il tema sia radicato nella cultura aziendale di BMW Italia: in linea con la strategia del BMW Group, ma anche punto di riferimento all\u2019interno dell\u2019universo della Casa di Monaco, in termini di intensit\u00e0, integrazione e capacit\u00e0 di agire nel tessuto sociale nel quale si opera.<\/p>\n<p>Dal 2001 ad oggi, il progetto SpecialMente ha coinvolto 1.000.000 di persone attraverso iniziative \u201con-line\u201d e \u201con-land\u201d.<\/p>\n<p>Maggiori dettagli sulle attivit\u00e0 di Corporate Social Responsibility di BMW Italia si possono trovare sul sito <a href=\"http:\/\/www.specialmente.bmw.it\/\">www.specialmente.bmw.it<\/a>.<\/p>\n<p><strong>Obiettivo3<\/strong><\/p>\n<p>Obiettivo3 \u00e8 un progetto ideato da Alex Zanardi, che mira a reclutare, avviare e sostenere persone disabili all\u2019attivit\u00e0 sportiva. Gli atleti, ai quali viene affidata l\u2019attrezzatura in comodato d\u2019uso gratuito, entrando nella comunit\u00e0, oltre alla guida competente dei coach, trovano nei loro compagni punti di riferimento importanti per coltivare questa passione. Nei suoi primi tre anni di attivit\u00e0 Obiettivo3 ha reclutato pi\u00f9 di 70 atleti, che hanno gi\u00e0 partecipato a decine di manifestazioni nazionali e internazionali, raggiungendo risultati notevoli.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":47390,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[363,262],"tags":[],"class_list":["post-47389","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bmw","category-novita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obiettivo tricolore ha fatto tappa presso la sede di BMW Italia a San Donato Milanese. - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obiettivo tricolore ha fatto tappa presso la sede di BMW Italia a San Donato Milanese. - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-17T09:31:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-17T09:31:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/P90391347_highRes_-obiettivo-tricolore.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Obiettivo tricolore ha fatto tappa presso la sede di BMW Italia a San Donato Milanese.\",\"datePublished\":\"2020-06-17T09:31:20+00:00\",\"dateModified\":\"2020-06-17T09:31:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\\\/\"},\"wordCount\":613,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/P90391347_highRes_-obiettivo-tricolore.jpg\",\"articleSection\":[\"BMW\",\"Novit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\\\/\",\"name\":\"Obiettivo tricolore ha fatto tappa presso la sede di BMW Italia a San Donato Milanese. - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/P90391347_highRes_-obiettivo-tricolore.jpg\",\"datePublished\":\"2020-06-17T09:31:20+00:00\",\"dateModified\":\"2020-06-17T09:31:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/P90391347_highRes_-obiettivo-tricolore.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/P90391347_highRes_-obiettivo-tricolore.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obiettivo tricolore ha fatto tappa presso la sede di BMW Italia a San Donato Milanese.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obiettivo tricolore ha fatto tappa presso la sede di BMW Italia a San Donato Milanese. - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/","og_locale":"it_IT","og_type":"article","og_title":"Obiettivo tricolore ha fatto tappa presso la sede di BMW Italia a San Donato Milanese. - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-06-17T09:31:20+00:00","article_modified_time":"2020-06-17T09:31:23+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/P90391347_highRes_-obiettivo-tricolore.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Obiettivo tricolore ha fatto tappa presso la sede di BMW Italia a San Donato Milanese.","datePublished":"2020-06-17T09:31:20+00:00","dateModified":"2020-06-17T09:31:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/"},"wordCount":613,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/P90391347_highRes_-obiettivo-tricolore.jpg","articleSection":["BMW","Novit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/","url":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/","name":"Obiettivo tricolore ha fatto tappa presso la sede di BMW Italia a San Donato Milanese. - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/P90391347_highRes_-obiettivo-tricolore.jpg","datePublished":"2020-06-17T09:31:20+00:00","dateModified":"2020-06-17T09:31:23+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/P90391347_highRes_-obiettivo-tricolore.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/P90391347_highRes_-obiettivo-tricolore.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/obiettivo-tricolore-ha-fatto-tappa-presso-la-sede-di-bmw-italia-a-san-donato-milanese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Obiettivo tricolore ha fatto tappa presso la sede di BMW Italia a San Donato Milanese."}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/47389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=47389"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/47389\/revisions"}],"predecessor-version":[{"id":47391,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/47389\/revisions\/47391"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/47390"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=47389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=47389"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=47389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}