{"id":47853,"date":"2020-06-30T17:17:46","date_gmt":"2020-06-30T15:17:46","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=47853"},"modified":"2020-06-30T17:17:48","modified_gmt":"2020-06-30T15:17:48","slug":"opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/","title":{"rendered":"Opel Vivaro-e e l&#8217;offensiva per veicoli commerciali elettrificati"},"content":{"rendered":"\n<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Il mercato dei veicoli a basse emissioni sar\u00e0 10 volte pi\u00f9 grande entro il 2025, riguarder\u00e0 tutte le regioni del mondo e sar\u00e0 cos\u00ec sia per le vetture per trasporto passeggeri che per i veicoli commerciali.<br \/>La prima gamma di veicoli commerciali elettrici di Opel \u00e8 pronta per la strada: tre questi Opel Vivaro-e e Zafira-e Life saranno disponibili presto.<\/p>\n<p>La strategia di Opel sta nell\u2019elettrificare non solo un modello ma tutta la gamma di veicoli commerciali che sar\u00e0 completamente elettrificata entro il 2021 e sar\u00e0 cos\u00ec sia per i furgoni che per le vetture derivate.<\/p>\n<p>\u201cIl Vivaro-e \u00e8 il primo veicolo commerciale completamente elettrico di Opel e uno dei primi sul mercato. Come sapete l\u2019elettrificazione e il trasporto di beni e servizi diventer\u00e0 sempre pi\u00f9 importante in molte aree urbane e noi di Opel possiamo fornirlo. 100% elettrico e zero emissioni. Sar\u00e0 disponibile nell\u2019autunno di quest\u2019anno. Provatelo, lo amerete!&#8221;, ha dichiarato il CEO di Opel Michael Lohscheller.<\/p>\n<p>I van elettrificati e Vivaro-e sono la risposta di Opel alle crescenti limitazioni al traffico nei centri storici delle nostre citt\u00e0 e permettono di garantire continuit\u00e0 al proprio lavoro ben oltre il famoso ultimo miglio. A questo elemento bisogna aggiungere che i clienti dei veicoli commerciali sono professionisti che hanno un\u2019ampia gamma di necessit\u00e0, aspettative alte e vogliono mantenere le stesse prestazioni dei veicoli con motore termico usato finora. E\u2019 per questo che Opel offre una gamma di veicoli commerciali elettrificati con diverse dimensioni o carrozzerie, per adattarsi a tutte le esigenze dei clienti.<\/p>\n<p>Nessun cambiamento nelle caratteristiche tecniche di Opel Vivaro-e: la capacit\u00e0 di carico \u00e8 invariata con volume di carico fino a 6,6 metri cubi. Tre lunghezze disponibili con volume di carico crescente come per le versioni termiche. A partire dall\u2019offerta di un van compatto da 4,6 m di lunghezza con fino a 5 metri cubi di capacit\u00e0, che sono gli stessi nella versione elettrica. Il carico utile di Opel Vivaro-e \u00e8 sempre elevato, fino a 1275 kg; ugualmente elevata la capacit\u00e0 di traino, fino a 1000 kg.<\/p>\n<\/div>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\u00a0<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>\u00a0<\/p>\n<p>Nessun compromesso neppure sulle prestazioni: Opel Vivaro-e \u00e8 equipaggiato con un motore elettrico potente e confortevole da guidare: 100 kW\/136 CV di potenza massima, 260 Nm di coppia massima a partire da 0 giri al minuto e velocit\u00e0 massima di 130 km\/h. Opel offre anche due diversi tagli di batteria con una doppia autonomia fino a 230 km oppure fino a 330 km, semplicemente perch\u00e9 l\u201983% dei clienti guidano in media meno di 200 km al giorno e il 44% non guida mai pi\u00f9 di 300 km al giorno. Opel Vivaro-e Include anche la ricarica rapida: 80% della batteria in 30 minuti, per un veicolo elettrico a zero emissioni, zero rumore, zero vibrazioni.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":47854,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[262,295],"tags":[],"class_list":["post-47853","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novita","category-opel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Opel Vivaro-e e l&#039;offensiva per veicoli commerciali elettrificati - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opel Vivaro-e e l&#039;offensiva per veicoli commerciali elettrificati - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-30T15:17:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-30T15:17:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/Opel-Vivaro-e-511686_0-1024x659.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"659\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Opel Vivaro-e e l&#8217;offensiva per veicoli commerciali elettrificati\",\"datePublished\":\"2020-06-30T15:17:46+00:00\",\"dateModified\":\"2020-06-30T15:17:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\\\/\"},\"wordCount\":442,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Opel-Vivaro-e-511686_0.jpg\",\"articleSection\":[\"Novit\u00e0\",\"Opel\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\\\/\",\"name\":\"Opel Vivaro-e e l'offensiva per veicoli commerciali elettrificati - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Opel-Vivaro-e-511686_0.jpg\",\"datePublished\":\"2020-06-30T15:17:46+00:00\",\"dateModified\":\"2020-06-30T15:17:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Opel-Vivaro-e-511686_0.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Opel-Vivaro-e-511686_0.jpg\",\"width\":6024,\"height\":3877,\"caption\":\"Opel Vivaro-e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opel Vivaro-e e l&#8217;offensiva per veicoli commerciali elettrificati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Opel Vivaro-e e l'offensiva per veicoli commerciali elettrificati - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/","og_locale":"it_IT","og_type":"article","og_title":"Opel Vivaro-e e l'offensiva per veicoli commerciali elettrificati - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-06-30T15:17:46+00:00","article_modified_time":"2020-06-30T15:17:48+00:00","og_image":[{"width":1024,"height":659,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/Opel-Vivaro-e-511686_0-1024x659.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Opel Vivaro-e e l&#8217;offensiva per veicoli commerciali elettrificati","datePublished":"2020-06-30T15:17:46+00:00","dateModified":"2020-06-30T15:17:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/"},"wordCount":442,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/Opel-Vivaro-e-511686_0.jpg","articleSection":["Novit\u00e0","Opel"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/","url":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/","name":"Opel Vivaro-e e l'offensiva per veicoli commerciali elettrificati - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/Opel-Vivaro-e-511686_0.jpg","datePublished":"2020-06-30T15:17:46+00:00","dateModified":"2020-06-30T15:17:48+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/Opel-Vivaro-e-511686_0.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/Opel-Vivaro-e-511686_0.jpg","width":6024,"height":3877,"caption":"Opel Vivaro-e"},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/opel-vivaro-e-e-loffensiva-per-veicoli-commerciali-elettrificati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Opel Vivaro-e e l&#8217;offensiva per veicoli commerciali elettrificati"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/47853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=47853"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/47853\/revisions"}],"predecessor-version":[{"id":47855,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/47853\/revisions\/47855"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/47854"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=47853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=47853"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=47853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}