{"id":49035,"date":"2020-08-21T15:46:35","date_gmt":"2020-08-21T13:46:35","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=49035"},"modified":"2020-08-21T15:46:37","modified_gmt":"2020-08-21T13:46:37","slug":"nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/","title":{"rendered":"Nissan offre a 50 clienti LEAF una finale della UEFA Champions League indimenticabile"},"content":{"rendered":"\n<p>Nissan ha organizzato un esclusivo cinema drive-in per 50 clienti LEAF, nel rispetto del distanziamento sociale, per portare le emozioni della mobilit\u00e0 elettrificata alla Finale della UEFA Champions League.<\/p>\n<p>Domenica 23 agosto, giorno della partita che quest\u2019anno si svolger\u00e0 a porte chiuse, le auto dei 50 proprietari di LEAF saranno posizionate in formazione di squadra di fronte a un maxi-schermo, installato in un luogo segreto che sar\u00e0 comunicato solamente ai tifosi selezionati, ognuno dei quali potr\u00e0 portare con se un ospite.<\/p>\n<p>Tra i partecipanti, ci saranno anche il cliente numero 5.000 di LEAF in Portogallo e la leggenda della UEFA Champions League Nuno Gomes, protagonista anche di un esclusivo incontro. Inoltre, rispettando tutte le misure igieniche necessarie, i tifosi avranno la possibilit\u00e0 di vedere da vicino il trofeo della UEFA Champions League e scattare delle foto, prima che questo sia trasferito nello stadio.<\/p>\n<p>Nissan \u00e8 al sesto anno come <b>official automotive sponsor<\/b> della <u><a href=\"https:\/\/lulop.com\/proxy\/KcQtdNGlqFojHJuo0NQ21YRUAm4c2yIQMa8DDE3V\/aHR0cHM6Ly93d3cudWVmYS5jb20vdWVmYWNoYW1waW9uc2xlYWd1ZS8=\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/lulop.com\/proxy\/KcQtdNGlqFojHJuo0NQ21YRUAm4c2yIQMa8DDE3V\/aHR0cHM6Ly93d3cudWVmYS5jb20vdWVmYWNoYW1waW9uc2xlYWd1ZS8%3D&amp;source=gmail&amp;ust=1598098159897000&amp;usg=AFQjCNH64ezrNfNhdrTp9Zc6EBSbGG_Shg\">UEFA Champions League<\/a><\/u>, il pi\u00f9 grande evento sportivo annuale al mondo.<\/p>\n<p>\u201cDa sei stagioni elettrifichiamo la Finale della UEFA Champions League\u201d, ha dichiarato <b>Gareth Dunsmore, Vice President Marketing Communications, Connected Car Services and Customer Experience Nissan Europe<\/b>. \u201cQuest\u2019anno siamo ancora pi\u00f9 motivati nell\u2019aggiungere divertimento all\u2019evento.\u201d<\/p>\n<p>\u201cNulla pu\u00f2 ricreare l\u2019emozione di essere allo stadio, ma speriamo di dare ai clienti LEAF un\u2019esperienza memorabile.\u201d<\/p>\n<p>Inoltre, Nissan far\u00e0 sfilare a bordo di <b>LEAF NISMO RC<\/b> il trofeo della UEFA Champions League fino all\u2019Estadio Da Luz di Lisbona.<\/p>\n<p>La finale della Champions League sar\u00e0 anche il primo grande evento con il <b>nuovo logo Nissan<\/b>, svelato poche settimane fa insieme al nuovo crossover coup\u00e9 elettrico <b>Nissan Ariya<\/b>. Entrambi saranno protagonisti delle attivit\u00e0 organizzate da Nissan nel corso del fine settimana a Lisbona, nominata <u><a href=\"https:\/\/lulop.com\/proxy\/KcQtdNGlqFojHJuo0NQ21YRUAm4c2yIQMa8DDE3V\/aHR0cHM6Ly9lYy5ldXJvcGEuZXUvZW52aXJvbm1lbnQvZXVyb3BlYW5ncmVlbmNhcGl0YWwvbGlzYm9uLWlzLXRoZS0yMDIwLWV1cm9wZWFuLWdyZWVuLWNhcGl0YWwtYXdhcmQtd2lubmVyLw==\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/lulop.com\/proxy\/KcQtdNGlqFojHJuo0NQ21YRUAm4c2yIQMa8DDE3V\/aHR0cHM6Ly9lYy5ldXJvcGEuZXUvZW52aXJvbm1lbnQvZXVyb3BlYW5ncmVlbmNhcGl0YWwvbGlzYm9uLWlzLXRoZS0yMDIwLWV1cm9wZWFuLWdyZWVuLWNhcGl0YWwtYXdhcmQtd2lubmVyLw%3D%3D&amp;source=gmail&amp;ust=1598098159897000&amp;usg=AFQjCNGW4uMA-udhaXQkCsuCR46lX68lwA\">European Green Capital<\/a><\/u> per il 2020.<\/p>\n<p>Con pi\u00f9 di 5.000 LEAF sulle strade del Portogallo dal lancio nel 2010, i proprietari di veicoli elettrici Nissan hanno risparmiato oltre mezzo milione di tonnellate di CO<sub>2<\/sub> ogni anno.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":49036,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[294,262],"tags":[],"class_list":["post-49035","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nissan","category-novita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nissan offre a 50 clienti LEAF una finale della UEFA Champions League indimenticabile - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nissan offre a 50 clienti LEAF una finale della UEFA Champions League indimenticabile - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-21T13:46:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-21T13:46:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/08\/uefa-champions-league-final-source.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Nissan offre a 50 clienti LEAF una finale della UEFA Champions League indimenticabile\",\"datePublished\":\"2020-08-21T13:46:35+00:00\",\"dateModified\":\"2020-08-21T13:46:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\\\/\"},\"wordCount\":328,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/uefa-champions-league-final-source.png\",\"articleSection\":[\"Nissan\",\"Novit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\\\/\",\"name\":\"Nissan offre a 50 clienti LEAF una finale della UEFA Champions League indimenticabile - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/uefa-champions-league-final-source.png\",\"datePublished\":\"2020-08-21T13:46:35+00:00\",\"dateModified\":\"2020-08-21T13:46:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/uefa-champions-league-final-source.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/uefa-champions-league-final-source.png\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nissan offre a 50 clienti LEAF una finale della UEFA Champions League indimenticabile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nissan offre a 50 clienti LEAF una finale della UEFA Champions League indimenticabile - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/","og_locale":"it_IT","og_type":"article","og_title":"Nissan offre a 50 clienti LEAF una finale della UEFA Champions League indimenticabile - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-08-21T13:46:35+00:00","article_modified_time":"2020-08-21T13:46:37+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/08\/uefa-champions-league-final-source.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Nissan offre a 50 clienti LEAF una finale della UEFA Champions League indimenticabile","datePublished":"2020-08-21T13:46:35+00:00","dateModified":"2020-08-21T13:46:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/"},"wordCount":328,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/08\/uefa-champions-league-final-source.png","articleSection":["Nissan","Novit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/","url":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/","name":"Nissan offre a 50 clienti LEAF una finale della UEFA Champions League indimenticabile - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/08\/uefa-champions-league-final-source.png","datePublished":"2020-08-21T13:46:35+00:00","dateModified":"2020-08-21T13:46:37+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/08\/uefa-champions-league-final-source.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/08\/uefa-champions-league-final-source.png","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/nissan-offre-a-50-clienti-leaf-una-finale-della-uefa-champions-league-indimenticabile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nissan offre a 50 clienti LEAF una finale della UEFA Champions League indimenticabile"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/49035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=49035"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/49035\/revisions"}],"predecessor-version":[{"id":49037,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/49035\/revisions\/49037"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/49036"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=49035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=49035"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=49035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}