{"id":50474,"date":"2020-10-14T12:32:56","date_gmt":"2020-10-14T10:32:56","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=50474"},"modified":"2020-10-14T12:32:58","modified_gmt":"2020-10-14T10:32:58","slug":"alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/","title":{"rendered":"Alfa Romeo Stelvio Quadrifoglio nominato \u201cSUV dell&#8217;anno\u201d"},"content":{"rendered":"\n<p>Il Model Year 2020 del primo SUV che \u00e8 anche un\u2019Alfa Romeo, nella pi\u00f9 potente delle versioni contraddistinta dall\u2019iconico Quadrifoglio, si aggiudica un riconoscimento gi\u00e0 ottenuto due anni fa. La rivista automobilistica AUTO ZEITUNG ha infatti nuovamente nominato il modello top di gamma \u201cSUV dell&#8217;anno\u201d. Alfa Romeo Stelvio Quadrifoglio ha avuto la meglio su undici competitor, tra cui i pi\u00f9 potenti SUV dei principali brand tedeschi, italiani e inglesi.<\/p>\n<p>\u00a0<\/p>\n<p>Alfa Romeo Stelvio Quadrifoglio \u00e8 dotato di motore V6 bi-turbo a benzina da 510 CV, che consente di accelerare da 0 a 100 km\/h in 3,8 secondi e di raggiungere una velocit\u00e0 massima di 283 km\/h. La maneggevolezza e l\u2019agilit\u00e0 di questo SUV sono frutto delle sospensioni attive a controllo elettronico (Alfa<sup>TM<\/sup> Active Suspension), del selettore Alfa<sup>TM<\/sup> D.N.A. Pro Dynamic Driving Control, al quale \u00e8 stata aggiunta la modalit\u00e0 performante \u201cRace\u201d, dell&#8217;impianto frenante ad alte prestazioni Brembo\u00ae, della trazione integrale Alfa<sup>TM<\/sup> Q4, della distribuzione ideale del peso (50\/50) tra l&#8217;asse anteriore e posteriore e dello sterzo estremamente diretto. I sedili sportivi rivestiti in pelle e Alcantara\u00ae aumentano ulteriormente il piacere della guida, oltre al cambio automatico a otto velocit\u00e0 dotato di palette a volante. Poco dopo il suo debutto, Alfa Romeo Stelvio Quadrifoglio ha stabilito il record su giro nella categoria SUV di serie sul leggendario tracciato \u201cNordschleife\u201d del N\u00fcrburgring. Tra le principali novit\u00e0 del MY20, i sistemi elettronici avanzati di assistenza alla guida, che consentono di raggiungere la guida autonoma di livello 2, e un sistema di infotainment di nuova generazione dotato di un display da 8,8 pollici.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":50475,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[354,293],"tags":[],"class_list":["post-50474","post","type-post","status-publish","format-standard","has-post-thumbnail","category-alfa-romeo","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alfa Romeo Stelvio Quadrifoglio nominato \u201cSUV dell&#039;anno\u201d - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alfa Romeo Stelvio Quadrifoglio nominato \u201cSUV dell&#039;anno\u201d - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-14T10:32:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T10:32:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/Stelvio-Quadrifoglio-MY20_03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Alfa Romeo Stelvio Quadrifoglio nominato \u201cSUV dell&#8217;anno\u201d\",\"datePublished\":\"2020-10-14T10:32:56+00:00\",\"dateModified\":\"2020-10-14T10:32:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\\\/\"},\"wordCount\":265,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Stelvio-Quadrifoglio-MY20_03.jpg\",\"articleSection\":[\"Alfa Romeo\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\\\/\",\"name\":\"Alfa Romeo Stelvio Quadrifoglio nominato \u201cSUV dell'anno\u201d - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Stelvio-Quadrifoglio-MY20_03.jpg\",\"datePublished\":\"2020-10-14T10:32:56+00:00\",\"dateModified\":\"2020-10-14T10:32:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Stelvio-Quadrifoglio-MY20_03.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Stelvio-Quadrifoglio-MY20_03.jpg\",\"width\":800,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alfa Romeo Stelvio Quadrifoglio nominato \u201cSUV dell&#8217;anno\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alfa Romeo Stelvio Quadrifoglio nominato \u201cSUV dell'anno\u201d - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/","og_locale":"it_IT","og_type":"article","og_title":"Alfa Romeo Stelvio Quadrifoglio nominato \u201cSUV dell'anno\u201d - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-10-14T10:32:56+00:00","article_modified_time":"2020-10-14T10:32:58+00:00","og_image":[{"width":800,"height":534,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/Stelvio-Quadrifoglio-MY20_03.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Alfa Romeo Stelvio Quadrifoglio nominato \u201cSUV dell&#8217;anno\u201d","datePublished":"2020-10-14T10:32:56+00:00","dateModified":"2020-10-14T10:32:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/"},"wordCount":265,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/Stelvio-Quadrifoglio-MY20_03.jpg","articleSection":["Alfa Romeo","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/","url":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/","name":"Alfa Romeo Stelvio Quadrifoglio nominato \u201cSUV dell'anno\u201d - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/Stelvio-Quadrifoglio-MY20_03.jpg","datePublished":"2020-10-14T10:32:56+00:00","dateModified":"2020-10-14T10:32:58+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/Stelvio-Quadrifoglio-MY20_03.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/Stelvio-Quadrifoglio-MY20_03.jpg","width":800,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-stelvio-quadrifoglio-nominato-suv-dellanno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Alfa Romeo Stelvio Quadrifoglio nominato \u201cSUV dell&#8217;anno\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/50474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=50474"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/50474\/revisions"}],"predecessor-version":[{"id":50476,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/50474\/revisions\/50476"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/50475"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=50474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=50474"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=50474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}