{"id":50486,"date":"2020-10-14T18:15:12","date_gmt":"2020-10-14T16:15:12","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=50486"},"modified":"2020-10-14T18:15:16","modified_gmt":"2020-10-14T16:15:16","slug":"progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/","title":{"rendered":"Progresso e prestazioni targate Audi  al Milano- Monza Open Air Motorshow"},"content":{"rendered":"\n<p>Audi conferma la propria partecipazione al Milano Monza Open Air Motor Show, il salone dell\u2019auto che si svolger\u00e0 all\u2019aperto dal 29 ottobre al 1\u00b0 novembre 2020. Dopo aver dato vita, nell\u2019ambito degli eventi di Milano Design City, al talk <em>\u201cChange your view, change your way. L\u2019uomo al centro\u201d<\/em> per raccontare come per Audi il futuro sia un\u2019attitudine, la presenza del Brand nel capoluogo lombardo testimonia ulteriormente la vicinanza e l\u2019affinit\u00e0 con la citt\u00e0 con cui Audi condivide i valori di innovazione e progresso.<\/p>\n<p>\u00a0<\/p>\n<p>Porre l\u2019uomo al centro del proprio fare significa, infatti, per la Casa dei quattro anelli affrontare il tema della mobilit\u00e0 sostenibile mediante una tecnologia utile e un approccio neutrale volto allo sviluppo di tutti i sistemi di alimentazione. L\u2019elettrificazione della gamma si sviluppa cos\u00ec sul completamento della gamma ibrida plug-in, sull\u2019ampliamento dell\u2019offerta 100% elettrica e sull\u2019evoluzione nel segno dell\u2019efficienza della gamma Audi Sport.<\/p>\n<p>\u00a0<\/p>\n<p>Audi sar\u00e0 quindi presente per le strade della citt\u00e0 offrendo al pubblico la possibilit\u00e0 di conoscere da vicino alcuni modelli che esemplificano lo stato dell\u2019arte sportivo e tecnologico del Brand.<\/p>\n<p>\u00a0<\/p>\n<p>In Piazza Duomo sar\u00e0 esposta <strong>Audi e-tron S Sportback<\/strong>: l\u2019evoluzione della trazione integrale nell\u2019era dell\u2019elettrico a 40 anni dall\u2019introduzione del sistema quattro. Con il nuovo SUV sportivo, la Casa dei quattro anelli scrive un ulteriore capitolo di tecnica automobilistica grazie all\u2019introduzione della versione high performance del SUV a elettroni Audi e-tron Sportback. Al powertrain da oltre 500 CV composto da tre motori elettrici \u2013 un unicum tecnico \u2013 si accompagnano la trazione integrale quattro elettrica e l\u2019innovativa funzione torque vectoring elettrica con ripartizione attiva e variabile della coppia sull\u2019assale posteriore. Agilit\u00e0 e dinamismo sono quindi le parole chiave di Audi e-tron S Sportback. L\u2019elettrica dei quattro anelli scatta da 0 a 100 km\/h in 4,5 secondi. I tre motori elettrici erogano una potenza massima, in modalit\u00e0 boost, di 503 CV e una coppia di 973 Nm. La batteria ad alta tensione, posizionata sotto la cellula abitacolo, pu\u00f2 accumulare 95 kWh di energia elettrica. Audi e-tron S Sportback percorre sino a 369 km nel ciclo combinato WLTP e pu\u00f2 essere ricaricata in corrente continua (DC) con potenze fino a 150 kW: un valore di riferimento tra i SUV elettrici. In meno di mezz\u2019ora \u00e8 possibile disporre dell\u201980% dell\u2019energia.<\/p>\n<p>\u00a0<\/p>\n<p>Via Montenapoleone, invece, ospiter\u00e0 le pi\u00f9 recenti novit\u00e0 della gamma performante di Audi Sport, che quest\u2019anno festeggia l\u2019importante traguardo dei 25 anni della gamma RS.<\/p>\n<p>\u00a0<\/p>\n<p>Performance, esclusivit\u00e0 e fruibilit\u00e0 nell\u2019utilizzo quotidiano sono le peculiarit\u00e0 della gamma Audi Sport, che viene qui rappresentata da <strong>Audi RS Q8<\/strong>, il top di gamma della famiglia Q, in cui la straordinaria potenza di 600 CV si accompagna all\u2019elevata efficienza garantita dal sistema mild-hybrid a 48 Volt, da <strong>Audi RS 6<\/strong> <strong>Avant<\/strong>, quarta generazione dell\u2019icona RS dove alla potenza di 600 CV si accompagnano una capacit\u00e0 di carico sino a 1.680 litri e un\u2019elevata efficienza garantita dalla combinazione del sistema mild-hybrid a 48 Volt e della tecnologia cylinder on demand, e Audi <strong>RS Q3 Sportback<\/strong>, che ha inaugurato il segmento dei SUV coup\u00e9 compatti high performance da 400 CV e che \u00e8 equipaggiata con il pluri-premiato 5 cilindri 2.5 TFSI per una sonorit\u00e0 unica e inconfondibile.<\/p>\n<p>\u00a0<\/p>\n<p>La presenza Audi nel Quadrilatero della moda \u00e8 anche una conferma della partnership che da sette anni lega Audi all\u2019associazione MonteNapoleone District.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":50487,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[357,262,312],"tags":[],"class_list":["post-50486","post","type-post","status-publish","format-standard","has-post-thumbnail","category-audi","category-novita","category-saloni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Progresso e prestazioni targate Audi al Milano- Monza Open Air Motorshow - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Progresso e prestazioni targate Audi al Milano- Monza Open Air Motorshow - AbmNews\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-14T16:15:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T16:15:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/unnamed-14.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Progresso e prestazioni targate Audi al Milano- Monza Open Air Motorshow\",\"datePublished\":\"2020-10-14T16:15:12+00:00\",\"dateModified\":\"2020-10-14T16:15:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\\\/\"},\"wordCount\":559,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/unnamed-14.jpg\",\"articleSection\":[\"Audi\",\"Novit\u00e0\",\"Saloni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\\\/\",\"name\":\"Progresso e prestazioni targate Audi al Milano- Monza Open Air Motorshow - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/unnamed-14.jpg\",\"datePublished\":\"2020-10-14T16:15:12+00:00\",\"dateModified\":\"2020-10-14T16:15:16+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/unnamed-14.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/unnamed-14.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progresso e prestazioni targate Audi al Milano- Monza Open Air Motorshow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Progresso e prestazioni targate Audi al Milano- Monza Open Air Motorshow - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/","og_locale":"it_IT","og_type":"article","og_title":"Progresso e prestazioni targate Audi al Milano- Monza Open Air Motorshow - AbmNews","og_url":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-10-14T16:15:12+00:00","article_modified_time":"2020-10-14T16:15:16+00:00","og_image":[{"width":800,"height":533,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/unnamed-14.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Progresso e prestazioni targate Audi al Milano- Monza Open Air Motorshow","datePublished":"2020-10-14T16:15:12+00:00","dateModified":"2020-10-14T16:15:16+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/"},"wordCount":559,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/unnamed-14.jpg","articleSection":["Audi","Novit\u00e0","Saloni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/","url":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/","name":"Progresso e prestazioni targate Audi al Milano- Monza Open Air Motorshow - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/unnamed-14.jpg","datePublished":"2020-10-14T16:15:12+00:00","dateModified":"2020-10-14T16:15:16+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/unnamed-14.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/unnamed-14.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/progresso-e-prestazioni-targate-audi-al-milano-monza-open-air-motorshow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Progresso e prestazioni targate Audi al Milano- Monza Open Air Motorshow"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/50486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=50486"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/50486\/revisions"}],"predecessor-version":[{"id":50488,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/50486\/revisions\/50488"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/50487"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=50486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=50486"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=50486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}