{"id":51085,"date":"2020-11-05T16:14:17","date_gmt":"2020-11-05T15:14:17","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=51085"},"modified":"2020-11-05T16:14:19","modified_gmt":"2020-11-05T15:14:19","slug":"progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/","title":{"rendered":"PROGETTO TORNADO: SERVIZI DI MOBILIT\u00c0 AUTONOMA NELLE ZONE RURALI"},"content":{"rendered":"\n<p>La mobilit\u00e0 autonoma non \u00e8 una sfida riservata alle grandi metropoli.<\/p>\n<p>Le sperimentazioni dei veicoli autonomi devono, infatti, prendere in considerazione le specificit\u00e0 delle aree a scarsa densit\u00e0 di popolazione dove le soluzioni di trasporto spesso sono pi\u00f9 rare e numerose sono le sfide che riguardano specificatamente le zone rurali.<\/p>\n<p>Il progetto di ricerca <strong>TORNADO<\/strong>, che si conclude in data odierna, si prefiggeva lo scopo di individuare le tecnologie e le infrastrutture di comunicazione necessarie per lo sviluppo dei servizi di mobilit\u00e0 autonoma nelle zone rurali e periurbane, mediante due casi di utilizzo e grazie alla collaborazione tra vari partner industriali ed accademici, un territorio e le popolazioni locali.<\/p>\n<p>\u00c8 in quest\u2019ambito che sono stati sperimentati due servizi di mobilit\u00e0 elettrica ed autonoma, con periodi di validazione sul campo su scala e in ambienti reali:<\/p>\n<ul>\n<li>Un servizio di car sharing (Renault ZOE) on demand, con collegamento diretto tra la stazione rurale di Gazeran e la zona commerciale Bel Air &#8211; La For\u00eat a Rambouillet.<\/li>\n<li>Un servizio di navetta secondo una logica di collegamento delle fermate nella zona commerciale Bel Air.<\/li>\n<\/ul>\n<p><strong>Definire le tecnologie necessarie per lo sviluppo di soluzioni di trasporto autonomo nelle zone rurali e periurbane. <\/strong><\/p>\n<p>La parte tecnica del progetto TORNADO consisteva nel definire e sviluppare le soluzioni di guida autonoma, ma anche le tecnologie e le infrastrutture di comunicazione:<\/p>\n<ul>\n<li>Per garantire <strong>il massimo livello di sicurezza<\/strong>: soluzioni hardware, software, embedded e remote, comunicazione tra veicolo e infrastrutture, ecc.<\/li>\n<li>Adatte alle <strong>specificit\u00e0 delle zone rurali e periurbane<\/strong>: <em>stradine strette<\/em><em>, rotatorie, ostacoli che impediscono la visibilit\u00e0, mancanza di segnaletica orizzontale o di punti di riferimento, eterogeneit\u00e0 dei bordi stradali, gallerie strette ad un\u2019unica corsia, ecc. <\/em><\/li>\n<\/ul>\n<p>Per il Gruppo Renault, si trattava di far circolare un veicolo elettrico in modo assolutamente autonomo su un percorso di 13\u00a0km realizzando <strong>uno scenario di collegamento diretto tra la stazione di <\/strong><strong>Gazeran e la zona commerciale Bel Air di Rambouillet, <\/strong>rappresentativa di queste specificit\u00e0.<\/p>\n<p>La complessit\u00e0 e la diversit\u00e0 degli scenari di circolazione negli ambienti rurali e periurbani hanno, tra l\u2019altro, richiesto di:<\/p>\n<ul>\n<li>Aumentare le capacit\u00e0 di percezione dei veicoli autonomi che devono essere in grado di rilevare l\u2019ambiente circostante (tipo di oggetto, dimensione, distanza rispetto al veicolo) a 360\u00b0, in tempo reale.<\/li>\n<li>Essere in grado di localizzare e controllare il veicolo autonomo considerando una distanza di circa 20 centimetri per garantire il suo mantenimento in carreggiata, su strade che possono anche essere molto strette e con bordi eterogenei.<\/li>\n<li>Compensare le temporanee perdite di segnale GPS o la totale assenza di visibilit\u00e0, ad esempio, nell\u2019attraversare le gallerie ad un\u2019unica corsia.<\/li>\n<li>Raggiungere, in modalit\u00e0 autonoma, livelli di velocit\u00e0 \u201caccettabili\u201d e quanto pi\u00f9 possibile vicini alla realt\u00e0 per i passeggeri e gli altri utenti della strada, ossia fino a 70\u00a0km\/h.<\/li>\n<\/ul>\n<p>Su questo percorso, i partner del progetto hanno potuto sperimentare <strong>il ruolo svolto dagli elementi infrastrutturali connessi <\/strong>(semafori connessi e telecamere fisse che consentono ai veicoli di prendere in considerazione la presenza di oggetti, al di l\u00e0 della propria percezione).<\/p>\n<p>Per completare questo caso di utilizzo all\u2019interno della zona commerciale Bel Air e definire un servizio \u201cporta a porta\u201d <strong>\u00e8 stata testata una navetta elettrica ed autonoma in grado di trasportare 10 persone secondo una logica di collegamento delle fermate nell\u2019area interessata. <\/strong><\/p>\n<p>Per consentire di spostarsi da una parte all\u2019altra della zona commerciale in piena sicurezza, la navetta ha incorporato anche nuovi sistemi introdotti dai partner: percezione avanzata, percezione associata alle infrastrutture e perimetro di sicurezza automatizzato.<\/p>\n<p>I veicoli Renault ZOE e la navetta, comandati con la stessa applicazione mobile, erano coordinati tra di loro per garantire la continuit\u00e0 e la fluidit\u00e0 del servizio sperimentato.<\/p>\n<p><strong>Essere quanto pi\u00f9 possibile vicini agli abitanti.<\/strong><\/p>\n<p>Il secondo capitolo del progetto TORNADO consisteva nel <strong>capire quali fossero le abitudini di mobilit\u00e0 degli abitanti della zona oggetto di sperimentazione, comprendere la loro percezione dei veicoli autonomi <\/strong>e <strong>valutare il livello di adesione <\/strong>(attese e freni) ai potenziali futuri servizi di trasporto autonomo come complemento pertinente, sicuro, condiviso e rispettoso dell\u2019ambiente alle esigenze di mobilit\u00e0.<\/p>\n<p><strong>Nelle varie fasi del progetto sono state coinvolte un centinaio di persone<\/strong>, provenienti dalla comunit\u00e0 di utenti del <a href=\"https:\/\/www.rt78.fr\/mobilab\">MobiLab<\/a> di Rambouillet Territoires<strong>.<\/strong><\/p>\n<p>Le sessioni di prova dei veicoli autonomi Renault ZOE, integrate da workshop di co-creazione, hanno permesso di <strong>studiare come si familiarizza con il veicolo autonomo<\/strong>, di seguire l\u2019evoluzione del <strong>modo di rapportarsi a queste nuove tecnologie <\/strong>e di <strong>far evolvere il progetto<\/strong> apportando migliorie e\/o adattamenti tecnici per essere il pi\u00f9 possibile in linea con le attese della comunit\u00e0 di utenti, che si \u00e8 rivelata molto attiva per l\u2019intero progetto.<\/p>\n<p>A titolo esemplificativo, i veicoli Renault ZOE oggi circolano in modalit\u00e0 autonoma a 70\u00a0km\/h (contro i 50\u00a0km\/h del 2019). Questa performance risponde alla richiesta degli utenti che auspicavano che i veicoli autonomi potessero raggiungere la velocit\u00e0 massima autorizzata lungo il percorso, per avere una percezione quanto pi\u00f9 possibile realistica del servizio reso.<\/p>\n<p><strong>Rispondere alle esigenze dei territori. <\/strong><\/p>\n<p>La mobilit\u00e0 elettrica, autonoma e condivisa rappresenta un\u2019opportunit\u00e0 per i territori che desiderano favorire la mobilit\u00e0 del maggior numero di persone, soprattutto nelle aree a bassa densit\u00e0 di popolazione.<\/p>\n<p>Offre, infatti, una risposta alle esigenze di trasporto pubblico con veicoli sicuri e rispettosi dell\u2019ambiente.<\/p>\n<p>Rambouillet Territoires, per cui le problematiche di mobilit\u00e0 non sono solo un\u2019aspettativa degli abitanti, ma anche un modo per incrementare l\u2019attrattiva del territorio, ha partecipato attivamente al progetto con il sostegno di altri enti dell\u2019agglomerato e del dipartimento.<\/p>\n<p>Oltre a trattare le questioni normative, occuparsi della gestione della rete stradale interessata e dell\u2019implementazione concreta delle sperimentazioni del progetto TORNADO, per questo territorio \u00e8 stato importante coinvolgere gli utenti nelle riflessioni per la definizione del futuro servizio. \u00a0<\/p>\n<p><strong>Un progetto di cooperazione pubblico-privato <\/strong><\/p>\n<p>TORNADO \u00e8 un progetto FUI-R\u00e9gions finanziato da Bpifrance e dalle regioni \u00cele-de-France, Alvernia-Rodano-Alpi ed Occitania.<\/p>\n<p>Si tratta di un progetto multi-partner che riunisce attori complementari che hanno messo in comune le loro competenze, know-how e capacit\u00e0 di innovazione al servizio di un territorio.<\/p>\n<p><a><strong>I partner del progetto TORNADO sono:<\/strong><\/a><\/p>\n<ul>\n<li>Capoprogetto: Gruppo Renault<\/li>\n<li>Co-pilota: Rambouillet Territoires<\/li>\n<li>Partner industriali: LACROIX City, AVAIRX, Exoskills, 4D-Virtualiz ed EasyMile<\/li>\n<li>Partner accademici: Universit\u00e0 Gustave Eiffel, UT di Compi\u00e8gne-Laboratoire Heudiasyc, Institut Pascal, INRIA e UPPA (Universit\u00e9 de Pau et des Pays de l&#8217;Adour).<\/li>\n<li>Label associati: Mov\u2019eo, ViaM\u00e9ca ed Aerospace Valley<\/li>\n<\/ul>\n<p>Per maggiori informazioni sul progetto TORNADO, cliccare <a href=\"https:\/\/www.tornado-mobility.com\/index.php\/about\/\">qui<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":51087,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[7797,307],"tags":[],"class_list":["post-51085","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mobilita","category-renault"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PROGETTO TORNADO: SERVIZI DI MOBILIT\u00c0 AUTONOMA NELLE ZONE RURALI - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROGETTO TORNADO: SERVIZI DI MOBILIT\u00c0 AUTONOMA NELLE ZONE RURALI - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-05T15:14:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-05T15:14:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/11\/Progetto-Tornado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"PROGETTO TORNADO: SERVIZI DI MOBILIT\u00c0 AUTONOMA NELLE ZONE RURALI\",\"datePublished\":\"2020-11-05T15:14:17+00:00\",\"dateModified\":\"2020-11-05T15:14:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\\\/\"},\"wordCount\":1065,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Progetto-Tornado.jpg\",\"articleSection\":[\"Mobilit\u00e0\",\"Renault\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\\\/\",\"name\":\"PROGETTO TORNADO: SERVIZI DI MOBILIT\u00c0 AUTONOMA NELLE ZONE RURALI - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Progetto-Tornado.jpg\",\"datePublished\":\"2020-11-05T15:14:17+00:00\",\"dateModified\":\"2020-11-05T15:14:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Progetto-Tornado.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Progetto-Tornado.jpg\",\"width\":900,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROGETTO TORNADO: SERVIZI DI MOBILIT\u00c0 AUTONOMA NELLE ZONE RURALI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROGETTO TORNADO: SERVIZI DI MOBILIT\u00c0 AUTONOMA NELLE ZONE RURALI - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/","og_locale":"it_IT","og_type":"article","og_title":"PROGETTO TORNADO: SERVIZI DI MOBILIT\u00c0 AUTONOMA NELLE ZONE RURALI - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-11-05T15:14:17+00:00","article_modified_time":"2020-11-05T15:14:19+00:00","og_image":[{"width":900,"height":506,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/11\/Progetto-Tornado.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"PROGETTO TORNADO: SERVIZI DI MOBILIT\u00c0 AUTONOMA NELLE ZONE RURALI","datePublished":"2020-11-05T15:14:17+00:00","dateModified":"2020-11-05T15:14:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/"},"wordCount":1065,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/11\/Progetto-Tornado.jpg","articleSection":["Mobilit\u00e0","Renault"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/","url":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/","name":"PROGETTO TORNADO: SERVIZI DI MOBILIT\u00c0 AUTONOMA NELLE ZONE RURALI - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/11\/Progetto-Tornado.jpg","datePublished":"2020-11-05T15:14:17+00:00","dateModified":"2020-11-05T15:14:19+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/11\/Progetto-Tornado.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/11\/Progetto-Tornado.jpg","width":900,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/progetto-tornado-servizi-di-mobilita-autonoma-nelle-zone-rurali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"PROGETTO TORNADO: SERVIZI DI MOBILIT\u00c0 AUTONOMA NELLE ZONE RURALI"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/51085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=51085"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/51085\/revisions"}],"predecessor-version":[{"id":51088,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/51085\/revisions\/51088"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/51087"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=51085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=51085"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=51085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}