{"id":51350,"date":"2020-11-13T17:52:45","date_gmt":"2020-11-13T16:52:45","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=51350"},"modified":"2020-11-13T17:54:27","modified_gmt":"2020-11-13T16:54:27","slug":"la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/","title":{"rendered":"La Volkswagen avvia la costruzione di un laboratorio negli USA per lo sviluppo delle batterie"},"content":{"rendered":"\n<p><strong>\u2013 Il 10 novembre, la Volkswagen of America ha avviato la costruzione del Battery Engineering Lab presso il suo Engineering and Planning Center di Chattanooga, in Tennessee, negli Stati Uniti d\u2019America. La struttura, che sar\u00e0 realizzata con un investimento di circa 22 milioni di Dollari e completata nel corso del 2021, effettuer\u00e0 test e validazioni delle celle e dei pacchi batteria per auto elettriche. A Chattanooga, la Volkswagen sta investendo 800 milioni di Dollari per una nuova linea di produzione che dal 2022 costruir\u00e0 il SUV 100% elettrico ID.4.<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>Il nuovo laboratorio far\u00e0 parte del centro per la produzione e lo sviluppo di veicoli elettrici della regione nordamericana, insieme ad altre due strutture gi\u00e0 in costruzione: la nuova area di 52.000 metri quadri all\u2019interno dello stabilimento Volkswagen di Chattanooga, un\u2019espansione realizzata per ospitare le nuove linee di produzione di vetture elettriche, e la nuova fabbrica di 18.000 metri quadri per l\u2019assemblaggio dei pacchi batteria. Nel nuovo laboratorio, la Volkswagen effettuer\u00e0 test e ottimizzazioni su celle che vengono realizzate dalla SKI nello stato limitrofo della Georgia; queste attivit\u00e0 riguarderanno anche le batterie per il nuovo SUV 100% elettrico Volkswagen ID.4, il cui avvio di produzione negli Stati Uniti d\u2019America \u00e8 previsto nel 2022.<\/p>\n<p>\u00a0<\/p>\n<p>Questo laboratorio rientra all\u2019interno dell\u2019impegno della Volkswagen a localizzare maggiormente tutti gli aspetti fondamentali dello sviluppo e della produzione di nuove vetture; un approccio che migliora le competenze ingegneristiche della regione e permette, inoltre, di ridurre i costi e i tempi di sviluppo. Oggi, test e validazioni dei componenti delle batterie vengono effettuati in due laboratori tedeschi, a Braunschweig e Wolfsburg, e in due cinesi, a Shanghai e Changchun. Realizzare queste operazioni anche a Chattanooga permetter\u00e0 agli ingegneri di applicare pi\u00f9 rapidamente i progressi alla produzione locale e di offrire le soluzioni pi\u00f9 adatte al mercato nordamericano in termini di utilizzo, sicurezza e affidabilit\u00e0.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Gli ingegneri Volkswagen del nuovo laboratorio di Chattanooga effettueranno test sui componenti delle batterie, sull\u2019integrazione della batteria nella vettura e cercheranno di coinvolgere il pi\u00f9 possibile la filiera dei fornitori locali nel processo di produzione. <br \/><br \/><\/p>\n<p>Il laboratorio includer\u00e0 strumenti per prove di pressione e immersione, camere di corrosione, cinque camere climatiche e un banco multiassiale (multi-axis shaker table, MAST) da due tonnellate progettato appositamente per mettere alla prova la tenuta dei singoli componenti in condizioni estreme di utilizzo. Il MAST di Chattanooga sar\u00e0 tra i primi a essere appositamente realizzato per auto elettriche; la batteria, infatti, \u00e8 il componente preponderante di questo tipo di vetture, con le sue centinaia di kg di peso e le dimensioni che occupano gran parte della superficie a terra. Nel nuovo laboratorio statunitense della Volkswagen, le batterie saranno sottoposte a test di resistenza alle sollecitazioni in ambienti che simuleranno le condizioni pi\u00f9 disparate, dal gelo del Polo Sud al deserto del Sahara. Per soddisfare questi requisiti, invece di richiederlo a un fornitore, la Volkswagen ha realizzato il MAST di Chattanooga in autonomia. I suoi supporti, per esempio, sono stati interrati tre metri sotto il pavimento del laboratorio, rinforzati con cemento armato per contrastare meglio le forze in azione durante il suo funzionamento.<\/p>\n<p>\u00a0<\/p>\n<p>Per ridurre al minimo l\u2019impatto ambientale del laboratorio, in linea con l\u2019impegno della Volkswagen alla neutralit\u00e0 climatica entro il 2050, il sito sar\u00e0 dotato di ciclatori rigenerativi in grado di restituire l\u2019energia in eccesso allo stabilimento o alla rete, in un\u2019ottica di massima efficienza.<\/p>\n<p>\u00a0<\/p>\n<p>La costruzione del Battery Engineering Lab fa parte del piano di investimenti da <br \/>800 milioni di Dollari della Volkswagen dedicato allo stabilimento statunitense di Chattanooga. Nel novembre 2019, sono iniziati i lavori di espansione per realizzare una nuova linea produttiva che dal 2022 costruir\u00e0 il SUV 100% elettrico Volkswagen ID.4. Oggi, nello stabilimento Volkswagen di Chattanooga vengono costruiti la berlina Passat e i SUV Atlas e Atlas Cross Sport.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":51352,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[262,347],"tags":[],"class_list":["post-51350","post","type-post","status-publish","format-standard","has-post-thumbnail","category-novita","category-volkswagen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Volkswagen avvia la costruzione di un laboratorio negli USA per lo sviluppo delle batterie - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Volkswagen avvia la costruzione di un laboratorio negli USA per lo sviluppo delle batterie - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-13T16:52:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-13T16:54:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/11\/unnamed-17.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"449\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"La Volkswagen avvia la costruzione di un laboratorio negli USA per lo sviluppo delle batterie\",\"datePublished\":\"2020-11-13T16:52:45+00:00\",\"dateModified\":\"2020-11-13T16:54:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\\\/\"},\"wordCount\":635,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/unnamed-17.jpg\",\"articleSection\":[\"Novit\u00e0\",\"Volkswagen\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\\\/\",\"name\":\"La Volkswagen avvia la costruzione di un laboratorio negli USA per lo sviluppo delle batterie - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/unnamed-17.jpg\",\"datePublished\":\"2020-11-13T16:52:45+00:00\",\"dateModified\":\"2020-11-13T16:54:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/unnamed-17.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/unnamed-17.jpg\",\"width\":800,\"height\":449},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Volkswagen avvia la costruzione di un laboratorio negli USA per lo sviluppo delle batterie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Volkswagen avvia la costruzione di un laboratorio negli USA per lo sviluppo delle batterie - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/","og_locale":"it_IT","og_type":"article","og_title":"La Volkswagen avvia la costruzione di un laboratorio negli USA per lo sviluppo delle batterie - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-11-13T16:52:45+00:00","article_modified_time":"2020-11-13T16:54:27+00:00","og_image":[{"width":800,"height":449,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/11\/unnamed-17.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"La Volkswagen avvia la costruzione di un laboratorio negli USA per lo sviluppo delle batterie","datePublished":"2020-11-13T16:52:45+00:00","dateModified":"2020-11-13T16:54:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/"},"wordCount":635,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/11\/unnamed-17.jpg","articleSection":["Novit\u00e0","Volkswagen"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/","url":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/","name":"La Volkswagen avvia la costruzione di un laboratorio negli USA per lo sviluppo delle batterie - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/11\/unnamed-17.jpg","datePublished":"2020-11-13T16:52:45+00:00","dateModified":"2020-11-13T16:54:27+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/11\/unnamed-17.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/11\/unnamed-17.jpg","width":800,"height":449},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/la-volkswagen-avvia-la-costruzione-di-un-laboratorio-negli-usa-per-lo-sviluppo-delle-batterie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La Volkswagen avvia la costruzione di un laboratorio negli USA per lo sviluppo delle batterie"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/51350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=51350"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/51350\/revisions"}],"predecessor-version":[{"id":51351,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/51350\/revisions\/51351"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/51352"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=51350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=51350"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=51350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}