{"id":56763,"date":"2021-04-21T17:03:34","date_gmt":"2021-04-21T15:03:34","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=56763"},"modified":"2021-04-21T17:03:36","modified_gmt":"2021-04-21T15:03:36","slug":"alfa-romeo-apre-le-porte-del-nuovo-headquarter","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/","title":{"rendered":"Alfa Romeo apre le porte del nuovo headquarter"},"content":{"rendered":"\n<p>Alfa Romeo continua a lavorare con impegno e passione per il proprio futuro, in modo da cogliere tutte le opportunit\u00e0 generate dalla nascita di Stellantis, quarto produttore di auto a livello mondiale, accelerando nella transizione verso il futuro professionale delle donne e degli uomini che animano il brand.<br \/>Nell\u2019ultimo anno, lo scenario globale ha portato a ripensare le modalit\u00e0 di lavoro secondo canoni inediti, e il marchio ha dedicato le proprie energie all\u2019apertura di un nuovo quartier generale capace di accogliere i dipendenti secondo una nuova concezione di spazi condivisi e aperti, che sin dalla loro architettura agevolano il lavoro di squadra, la diffusione delle idee, il confronto.<\/p>\n<p>\u00a0<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&amp;href=https%3A%2F%2Fwww.facebook.com%2FABMnews%2Fvideos%2F471091311012964%2F&amp;show_text=false&amp;width=560\" width=\"560\" height=\"314\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong><em>Un luogo di storia e di ispirazione<\/em><\/strong><\/p>\n<p>Questo ambiente \u00e8 stato identificato nel Centro Stile di via Plava, un\u2019area riqualificata dello stabilimento di Mirafiori che occupa gli spazi delle storiche Officine 83. Si tratta di un luogo iconico, con forti legami alla tradizione: del resto, in centodieci anni, la bellezza e il dinamismo sono sempre stati tratti distintivi di ogni creazione Alfa Romeo. Oggi tutto il team del Biscione pu\u00f2 lavorare a stretto contatto con i designer che hanno creato, e creano, modelli entrati nella storia, cos\u00ec che la storia possa assumere ancor pi\u00f9 marcatamente un valore ispirazionale.<\/p>\n<p>\u00a0<\/p>\n<p><strong><em>Uno spazio in cui dall\u2019esperienza nasce il futuro <\/em><\/strong><\/p>\n<p>Come accennato, la sede, appena rimodernata, \u00e8 caratterizzata da ambienti ampi e luminosi, fortemente caratterizzati secondo i canoni stilistici del brand e postazioni di lavoro appositamente studiate per favorire al massimo l\u2019interazione e la cooperazione. Sono previsti, inoltre, spazi operativi all\u2019aperto.<br \/>La nuova squadra Alfa Romeo, poi, ha contribuito a personalizzare gli spazi portando con s\u00e9 oggetti legati alla storia del brand e alle proprie esperienze professionali, in un intreccio tra il passato, il coinvolgimento personale e le ambizioni future.<\/p>\n<figure id=\"attachment_56768\" aria-describedby=\"caption-attachment-56768\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-56768\" src=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo4-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo4-300x200.jpg 300w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo4-768x512.jpg 768w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo4-696x464.jpg 696w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo4-630x420.jpg 630w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo4.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-56768\" class=\"wp-caption-text\">Foto LaPresse &#8211; Fabio Ferrari<br \/>08 Aprile 2021 Torino, Italia<br \/>Centro Stile Alfa Romeo &#8211; Torino &#8211; Via Plava.<\/figcaption><\/figure>\n<figure id=\"attachment_56767\" aria-describedby=\"caption-attachment-56767\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-56767\" src=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo3-300x200.jpg 300w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo3-768x512.jpg 768w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo3-696x464.jpg 696w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo3-630x420.jpg 630w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo3.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-56767\" class=\"wp-caption-text\">Foto LaPresse &#8211; Fabio Ferrari<br \/>08 Aprile 2021 Torino, Italia<br \/>Centro Stile Alfa Romeo &#8211; Torino &#8211; Via Plava.<\/figcaption><\/figure>\n<figure id=\"attachment_56766\" aria-describedby=\"caption-attachment-56766\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-56766\" src=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo2-300x221.jpg\" alt=\"\" width=\"300\" height=\"221\" srcset=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo2-300x221.jpg 300w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo2-768x566.jpg 768w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo2-80x60.jpg 80w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo2-696x513.jpg 696w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo2-569x420.jpg 569w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo2.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-56766\" class=\"wp-caption-text\">Foto LaPresse &#8211; Fabio Ferrari<br \/>08 Aprile 2021 Torino, Italia<br \/>Centro Stile Alfa Romeo &#8211; Torino &#8211; Via Plava.<\/figcaption><\/figure>\n<figure id=\"attachment_56765\" aria-describedby=\"caption-attachment-56765\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-56765\" src=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo1-300x200.jpg 300w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo1-768x512.jpg 768w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo1-696x464.jpg 696w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo1-630x420.jpg 630w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-56765\" class=\"wp-caption-text\">Foto LaPresse &#8211; Fabio Ferrari<br \/>08 Aprile 2021 Torino, Italia<br \/>Centro Stile Alfa Romeo &#8211; Torino &#8211; Via Plava.<\/figcaption><\/figure>\n<figure id=\"attachment_56764\" aria-describedby=\"caption-attachment-56764\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-56764\" src=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo0-300x179.jpg\" alt=\"\" width=\"300\" height=\"179\" srcset=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo0-300x179.jpg 300w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo0-768x458.jpg 768w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo0-696x415.jpg 696w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo0-704x420.jpg 704w, http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo0.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-56764\" class=\"wp-caption-text\">Foto LaPresse &#8211; Fabio Ferrari<br \/>08 Aprile 2021 Torino, Italia<br \/>Centro Stile Alfa Romeo &#8211; Torino &#8211; Via Plava.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":56768,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[354,262,346],"tags":[],"class_list":["post-56763","post","type-post","status-publish","format-standard","has-post-thumbnail","category-alfa-romeo","category-novita","category-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alfa Romeo apre le porte del nuovo headquarter - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alfa Romeo apre le porte del nuovo headquarter - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-21T15:03:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-21T15:03:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Alfa Romeo apre le porte del nuovo headquarter\",\"datePublished\":\"2021-04-21T15:03:34+00:00\",\"dateModified\":\"2021-04-21T15:03:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\\\/\"},\"wordCount\":420,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/alfaromeo4.jpg\",\"articleSection\":[\"Alfa Romeo\",\"Novit\u00e0\",\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\\\/\",\"name\":\"Alfa Romeo apre le porte del nuovo headquarter - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/alfaromeo4.jpg\",\"datePublished\":\"2021-04-21T15:03:34+00:00\",\"dateModified\":\"2021-04-21T15:03:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/alfaromeo4.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/alfaromeo4.jpg\",\"width\":800,\"height\":533,\"caption\":\"Foto LaPresse - Fabio Ferrari 08 Aprile 2021 Torino, Italia Centro Stile Alfa Romeo - Torino - Via Plava.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alfa Romeo apre le porte del nuovo headquarter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alfa Romeo apre le porte del nuovo headquarter - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/","og_locale":"it_IT","og_type":"article","og_title":"Alfa Romeo apre le porte del nuovo headquarter - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2021-04-21T15:03:34+00:00","article_modified_time":"2021-04-21T15:03:36+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo4.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Alfa Romeo apre le porte del nuovo headquarter","datePublished":"2021-04-21T15:03:34+00:00","dateModified":"2021-04-21T15:03:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/"},"wordCount":420,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo4.jpg","articleSection":["Alfa Romeo","Novit\u00e0","Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/","url":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/","name":"Alfa Romeo apre le porte del nuovo headquarter - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo4.jpg","datePublished":"2021-04-21T15:03:34+00:00","dateModified":"2021-04-21T15:03:36+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo4.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/04\/alfaromeo4.jpg","width":800,"height":533,"caption":"Foto LaPresse - Fabio Ferrari 08 Aprile 2021 Torino, Italia Centro Stile Alfa Romeo - Torino - Via Plava."},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-apre-le-porte-del-nuovo-headquarter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Alfa Romeo apre le porte del nuovo headquarter"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/56763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=56763"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/56763\/revisions"}],"predecessor-version":[{"id":56769,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/56763\/revisions\/56769"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/56768"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=56763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=56763"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=56763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}