{"id":60442,"date":"2021-08-03T10:58:49","date_gmt":"2021-08-03T08:58:49","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=60442"},"modified":"2021-08-03T10:58:52","modified_gmt":"2021-08-03T08:58:52","slug":"eicma-kymco-alledizione-numero-78","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/","title":{"rendered":"EICMA, KYMCO ALL\u2019EDIZIONE NUMERO 78"},"content":{"rendered":"\n<p class=\"m_-6599195418718201234MsoNoSpacing\">Kymco sar\u00e0 ad EICMA 2021. L\u2019annuncio della presenza del costruttore taiwanese alla 78esima Edizione dell\u2019Esposizione Internazionale del Ciclo e Motociclo, in programma dal 23 al 28 novembre prossimi nei padiglioni di Fiera Milano a Rho, \u00e8 arrivata oggi attraverso una nota dell\u2019organizzatore. Tra i pi\u00f9 importanti produttori di scooter, motocicli e quad a livello mondiale e marchio molto apprezzato sul mercato italiano, la conferma di Kymco va cos\u00ec ad arricchire l\u2019ormai ragguardevole parterre di espositori che porteranno le loro novit\u00e0 sul pi\u00f9 importante palcoscenico per l\u2019industria della mobilit\u00e0 su due ruote.<u><\/u><u><\/u><\/p>\n<p class=\"m_-6599195418718201234MsoNoSpacing\">Stefano Gianotti, legale Rappresentante del Gruppo Padana Sviluppo, che tramite la societ\u00e0 KMI Italia S.r.l.\u00a0rappresenta e distribuisce i prodotti Kymco in Italia, ha dichiarato: \u201c\u00c8 per noi un piacere confermare la presenza di Kymco a EICMA anche in un anno cos\u00ec particolare e difficile: dopo lo stop forzato del 2020 \u00e8 importante dare un segnale di ripartenza e di ritorno alla normalit\u00e0 ed EICMA \u00e8 un evento simbolo non solo nel settore delle due ruote ma anche in tutto il mondo delle esposizioni e manifestazioni a livello internazionale. Quale strumento migliore, quindi, se non EICMA, per presentare al pubblico tutte le novit\u00e0 dei nostri scooter direttamente da Taiwan e dare il giusto riconoscimento a chi, come noi, non si \u00e8 mai fermato e crede nel futuro\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":60443,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[7938,293,312],"tags":[],"class_list":["post-60442","post","type-post","status-publish","format-standard","has-post-thumbnail","category-kymco","category-news","category-saloni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EICMA, KYMCO ALL\u2019EDIZIONE NUMERO 78 - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EICMA, KYMCO ALL\u2019EDIZIONE NUMERO 78 - AbmNews\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-03T08:58:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-03T08:58:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/08\/226435962_10159300071289800_2596338767874380312_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"798\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/eicma-kymco-alledizione-numero-78\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/eicma-kymco-alledizione-numero-78\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"EICMA, KYMCO ALL\u2019EDIZIONE NUMERO 78\",\"datePublished\":\"2021-08-03T08:58:49+00:00\",\"dateModified\":\"2021-08-03T08:58:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/eicma-kymco-alledizione-numero-78\\\/\"},\"wordCount\":221,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/eicma-kymco-alledizione-numero-78\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/226435962_10159300071289800_2596338767874380312_n.jpg\",\"articleSection\":[\"Kymco\",\"News\",\"Saloni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/eicma-kymco-alledizione-numero-78\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/eicma-kymco-alledizione-numero-78\\\/\",\"name\":\"EICMA, KYMCO ALL\u2019EDIZIONE NUMERO 78 - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/eicma-kymco-alledizione-numero-78\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/eicma-kymco-alledizione-numero-78\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/226435962_10159300071289800_2596338767874380312_n.jpg\",\"datePublished\":\"2021-08-03T08:58:49+00:00\",\"dateModified\":\"2021-08-03T08:58:52+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/eicma-kymco-alledizione-numero-78\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/eicma-kymco-alledizione-numero-78\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/eicma-kymco-alledizione-numero-78\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/226435962_10159300071289800_2596338767874380312_n.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/226435962_10159300071289800_2596338767874380312_n.jpg\",\"width\":1200,\"height\":798},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/eicma-kymco-alledizione-numero-78\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EICMA, KYMCO ALL\u2019EDIZIONE NUMERO 78\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EICMA, KYMCO ALL\u2019EDIZIONE NUMERO 78 - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/","og_locale":"it_IT","og_type":"article","og_title":"EICMA, KYMCO ALL\u2019EDIZIONE NUMERO 78 - AbmNews","og_url":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2021-08-03T08:58:49+00:00","article_modified_time":"2021-08-03T08:58:52+00:00","og_image":[{"width":1200,"height":798,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/08\/226435962_10159300071289800_2596338767874380312_n.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"EICMA, KYMCO ALL\u2019EDIZIONE NUMERO 78","datePublished":"2021-08-03T08:58:49+00:00","dateModified":"2021-08-03T08:58:52+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/"},"wordCount":221,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/08\/226435962_10159300071289800_2596338767874380312_n.jpg","articleSection":["Kymco","News","Saloni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/","url":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/","name":"EICMA, KYMCO ALL\u2019EDIZIONE NUMERO 78 - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/08\/226435962_10159300071289800_2596338767874380312_n.jpg","datePublished":"2021-08-03T08:58:49+00:00","dateModified":"2021-08-03T08:58:52+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/08\/226435962_10159300071289800_2596338767874380312_n.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/08\/226435962_10159300071289800_2596338767874380312_n.jpg","width":1200,"height":798},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/eicma-kymco-alledizione-numero-78\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"EICMA, KYMCO ALL\u2019EDIZIONE NUMERO 78"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/60442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=60442"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/60442\/revisions"}],"predecessor-version":[{"id":60444,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/60442\/revisions\/60444"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/60443"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=60442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=60442"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=60442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}