{"id":62770,"date":"2021-10-30T08:07:08","date_gmt":"2021-10-30T06:07:08","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=62770"},"modified":"2021-10-30T08:07:10","modified_gmt":"2021-10-30T06:07:10","slug":"lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/","title":{"rendered":"Lamborghini Super Trofeo: a Misano le World Finals incoronano i campioni Europa e Nord America"},"content":{"rendered":"\n<p>Il sesto e ultimo appuntamento della stagione ha laureato al Misano World Circuit tutti i campioni del Lamborghini Super Trofeo Europa e Nord America. Quindici differenti vincitori oggi nelle due serie continentali e grande spettacolo sul circuito romagnolo, in vista dell&#8217;ottava edizione delle Lamborghini World Finals che entreranno nel vivo domani con le qualifiche e le prime due gare riservate rispettivamente alle classi Pro\/Pro-Am e Am\/Lamborghini Cup, per concludersi nella giornata di domenica.<\/p>\n<p><strong>Lamborghini Super Trofeo Europa<\/strong><\/p>\n<p>Finale di stagione movimentato e ricco di emozioni quello che nella classe Pro ha incoronato Kevin Gilardoni e Leonardo Pulcini campioni del Lamborghini Super Trofeo Europa. Ad assegnare il titolo \u00e8 stata infatti l&#8217;ultima gara, dopo che nella prima Gilardoni era stato costretto al ritiro per un problema a una ruota. Una prima gara che ha visto Max Weering (alla vigilia di questo conclusivo round a soli otto punti dall&#8217;equipaggio Oregon Team), perdere la prima posizione a causa di una foratura, dopo che il suo compagno Loris Spinelli era riuscito a mantenere il comando durante tutto il suo primo stint, avviandosi dalla pole con la vettura della Johan Kraan Motorsport. In Gara 2 finale entusiasmante, con Pulcini in testa dalla pole e Spinelli che, dopo le soste, si \u00e8 ritrovato proprio davanti a Gilardoni. Quest&#8217;ultimo \u00e8 poi riuscito a sfilare primo, ma in seguito \u00e8 finito in testacoda a causa di un contatto con lo stesso Spinelli, poi penalizzato per\u00f2 di dieci secondi. Una penalizzazione che ha consentito a Gilardoni e Pulcini di chiudere sesti davanti a Spinelli e Weering, laureandosi in questo modo campioni. Non \u00e8 passata inosservata neppure la doppia vittoria dell&#8217;equipaggio del team Bonaldi Motorsport formato dai due olandesi Daan Pijl e Danny Kroes, primi in entrambe le gare. A laurearsi campione della Pro-Am \u00e8 stato il polacco Andrzej Lewandowski, due volte terzo assoluto e primo di classe con Karol Basz al volante della Hurac\u00e1n Super Trofeo Evo della VS Racing. Nella Am successi di Raffaele Giannoni (Automobile Tricolore) e Gabriel Rindone (Leipert Motorsport), anche se a conquistare il titolo \u00e8 stato Claude-Yves Gosselin con i colori del Boutsen Ginion. Hans Fabri, con Imperiale Racing, si \u00e8 laureato campione della Lamborghini Cup per il secondo anno consecutivo. Doppia vittoria a Misano nella stessa classe di Gerard Van der Horst.<\/p>\n<p><strong>Leonardo Pulcini (Oregon Team \/ campione Pro): <\/strong>\u201cIn Gara 2 sono partito molto bene, riuscendo a costruire un buon margine su tutti gli altri, anche se prima di effettuare il pit-stop sono stato rallentato da alcuni doppiati pi\u00f9 lenti. Questo titolo per me, Kevin ed il team \u00e8 un riconoscimento fantastico al lavoro che abbiamo fatto da inizio anno. Adesso vogliamo puntare ovviamente anche alle World Finals\u201d.<\/p>\n<p><strong>Kevin Gilardoni (Oregon Team \/ campione Pro): <\/strong>\u201cDopo avere concluso secondo lo scorso anno, l&#8217;unico modo di fare meglio in questa stagione era di vincere il titolo. In Gara 2, quando sono salito in macchina per il secondo stint ho iniziato subito a spingere, ma sfortunatamente \u00e8 entrata in pista la safety car. Ho cercato di mettere pressione a Spinelli e a un certo punto ho detto \u2018okay, passiamolo&#8230;&#8221;, ma lui mi ha toccato e cos\u00ec sono finito in testacoda. Poi lo hanno penalizzato e alla fine io e Leo ci siamo potuti laureare campioni. Penso che ce lo siamo davvero meritato e sono davvero felice per me, per l&#8217;Oregon Team e per chi mi ha supportato\u201d.<\/p>\n<p><strong>Lamborghini Super Trofeo Nord America <\/strong><\/p>\n<p>Sette vittorie e titolo Pro nel Lamborghini Super Trofeo Nord America per Richard Antinucci, che per la terza volta si \u00e8 laureato campione della serie continentale. Il pilota del team Dream Racing Motorsport ha chiuso i conti al termine di Gara 1, che ha dominato dall&#8217;inizio alla fine dopo essere partito in pole, finendo nell&#8217;ordine davanti a Steven Aghakhani e Jacob Eidson (US RaceTronics) e Max Weering (MCR Racing), centrando poi un altro successo in Gara 2. Stesso discorso per Brandon Gdovic e Bryan Ortiz, ai quali bastava conquistare solamente due punti per concludere il discorso nella Pro-Am. L&#8217;equipaggio della Precision Performance Motorsport ha fatto di pi\u00f9, conquistando sempre nella prima gara il secondo posto di classe alle spalle dell&#8217;altro binomio della MCR Racing composto da Claude Senhoreti e Loris Spinelli e andando a segno poi in Gara 2. Vittoria Am ancora in Gara 1 e titolo di classe per Luke Berkeley, che ha completato un weekend perfetto per il Dream Racing Motorsport, ottenendo una vittoria ed un secondo posto alle spalle di Ashton Harrison (Wayne Taylor Racing). Dopo il ritiro di Gara 1 a causa di un incidente, i suoi compagno di squadra Edoardo Liberati e Dario Capitanio, nella seconda gara sono partiti dai box compiendo una rimonta che li ha portati a chiudere quinti alle spalle di Gdovic e Ortiz, con Jeroen Mul e Stevan McAleer (Change Racing) secondi e Aghakhani-Eidson terzi. Doppio trionfo anche per la Precision Performance Motorsport, con Mark Kvamme e Terry Olson campioni della Lamborghini Cup, in cui a conquistare le ultime due vittorie \u00e8 stato John Hennessy (US RaceTronics).<\/p>\n<p><strong>Ricard Antinucci (Dream Racing Motorsport \/ campione Pro): <\/strong>&#8220;Questo \u00e8 il mio terzo titolo Pro nel Lamborghini Super Trofeo Nord America, il primo che conquisto in Italia che \u00e8 il mio paese d&#8217;origine. A Misano si \u00e8 conclusa una stagione straordinaria, che mi ha sempre visto protagonista. Voglio ringraziare per questo tutti i miei sponsor ed il Dream Racing Motorsport, che mi ha consentito di essere qui a festeggiare. Infine anche la squadra di Marco Antonelli, il cui supporto in questo conclusivo appuntamento \u00e8 stato certamente fondamentale&#8221;.<\/p>\n<p>Nella serie europea il titolo riservato alle squadre \u00e8 andato all&#8217;Oregon Team, mentre nel campionato nordamericano alla Dream Racing Motorsport.<\/p>\n<p><strong>Lamborghini World Finals<\/strong><\/p>\n<p>Domani le qualifiche delle Lamborghini World Finals inizieranno a mezzogiorno e verranno precedute dalle due sessioni di warm-up. Gara 1 della Am e Lamborghini Cup scatter\u00e0 alle 16.30. Quella delle classi Pro e Pro-Am, sempre della durata di 50 minuti, prender\u00e0 il via alle 17.55. Le ultime due gare si svolgeranno invece domenica con il semaforo verde alle 12.05 (Am e Lamborghini Cup) e alle 14.25 (Pro e Pro-Am).<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":62771,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[414,7853,293],"tags":[],"class_list":["post-62770","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lamborghini","category-motorsport","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lamborghini Super Trofeo: a Misano le World Finals incoronano i campioni Europa e Nord America - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lamborghini Super Trofeo: a Misano le World Finals incoronano i campioni Europa e Nord America - AbmNews\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-30T06:07:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-30T06:07:10+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/10\/597585.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Lamborghini Super Trofeo: a Misano le World Finals incoronano i campioni Europa e Nord America\",\"datePublished\":\"2021-10-30T06:07:08+00:00\",\"dateModified\":\"2021-10-30T06:07:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\\\/\"},\"wordCount\":1010,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/597585.jpg\",\"articleSection\":[\"Lamborghini\",\"Motorsport\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\\\/\",\"name\":\"Lamborghini Super Trofeo: a Misano le World Finals incoronano i campioni Europa e Nord America - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/597585.jpg\",\"datePublished\":\"2021-10-30T06:07:08+00:00\",\"dateModified\":\"2021-10-30T06:07:10+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/597585.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/597585.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lamborghini Super Trofeo: a Misano le World Finals incoronano i campioni Europa e Nord America\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lamborghini Super Trofeo: a Misano le World Finals incoronano i campioni Europa e Nord America - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/","og_locale":"it_IT","og_type":"article","og_title":"Lamborghini Super Trofeo: a Misano le World Finals incoronano i campioni Europa e Nord America - AbmNews","og_url":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2021-10-30T06:07:08+00:00","article_modified_time":"2021-10-30T06:07:10+00:00","og_image":[{"width":800,"height":533,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/10\/597585.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Lamborghini Super Trofeo: a Misano le World Finals incoronano i campioni Europa e Nord America","datePublished":"2021-10-30T06:07:08+00:00","dateModified":"2021-10-30T06:07:10+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/"},"wordCount":1010,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/10\/597585.jpg","articleSection":["Lamborghini","Motorsport","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/","url":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/","name":"Lamborghini Super Trofeo: a Misano le World Finals incoronano i campioni Europa e Nord America - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/10\/597585.jpg","datePublished":"2021-10-30T06:07:08+00:00","dateModified":"2021-10-30T06:07:10+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/10\/597585.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2021\/10\/597585.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/lamborghini-super-trofeo-a-misano-le-world-finals-incoronano-i-campioni-europa-e-nord-america\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Lamborghini Super Trofeo: a Misano le World Finals incoronano i campioni Europa e Nord America"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/62770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=62770"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/62770\/revisions"}],"predecessor-version":[{"id":62772,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/62770\/revisions\/62772"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/62771"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=62770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=62770"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=62770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}