{"id":64499,"date":"2022-01-07T10:33:05","date_gmt":"2022-01-07T09:33:05","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=64499"},"modified":"2022-01-07T10:33:06","modified_gmt":"2022-01-07T09:33:06","slug":"il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia","status":"publish","type":"post","link":"http:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/","title":{"rendered":"IL GRUPPO TOYOTA ANNUNCIA I RISULTATI DEL 2021 IN ITALIA"},"content":{"rendered":"\n<p>Un 2021 eccezionale, quello del Gruppo Toyota. In un contesto di mercato ancora estremamente difficile, il Gruppo ha saputo cogliere ogni opportunit\u00e0, realizzando quasi 90.000 immatricolazioni e una quota di mercato del 6,1%, in crescita di 0,7 punti percentuali rispetto al 2020 e di 1,1 punti percentuali rispetto al 2019 (pre-pandemia). Un risultato straordinario, grazie all\u2019ampia offerta di prodotti e servizi Toyota e Lexus, con soluzioni innovative di finanziamento, noleggio, assicurazione e connettivit\u00e0 proposte dal Gruppo e molto apprezzate dai clienti, come per esempio i programmi del mondo Wehybrid.\u00a0\u00a0 \u00a0<\/p>\n<p>Cresce anche la quota di veicoli elettrificati Toyota e Lexus sul totale delle vendite complessive del Gruppo, raggiungendo nel 2021 il 77,5% (+7,2 punti percentuali rispetto al 2020). Percentuale rappresentata quasi interamente dai modelli con motorizzazione Full Hybrid, sempre pi\u00f9 apprezzati dai clienti italiani per la loro accessibilit\u00e0 e facilit\u00e0 d\u2019utilizzo, la risposta pi\u00f9 efficace e immediata al contenimento delle emissioni (il Full Hybrid Toyota e Lexus garantisce bassissime emissioni non solo di CO<sub>2<\/sub>\u00a0ma anche di altri inquinanti, ad esempio, le emissioni di ossidi di azoto -NOx- sono inferiori di oltre il 90% rispetti ai limiti di legge).\u00a0\u00a0<\/p>\n<p>Un anno da record per il brand\u00a0<b><strong>Toyota<\/strong><\/b>, che si posiziona al terzo posto nella classifica dei marchi per l\u2019anno 2021.\u00a0<b><strong>Un risultato storico<\/strong><\/b>, con cui Toyota sancisce il suo percorso di crescita nel mercato italiano, realizzando una quota record di mercato del 5,8%, grazie alle oltre 85.000 immatricolazioni.\u00a0\u00a0<\/p>\n<p>Un importante contributo ai risultati del brand va riconosciuto alla <b><strong>nuova Yaris<\/strong><\/b>\u00a0che, grazie alle 32.633 vetture immatricolate nell\u2019anno, si classifica quinta tra le auto pi\u00f9 vendute in Italia nel 2021 e prima auto straniera nel segmento B. Numeri che confermano il grande successo della vettura, l\u2019ibrida pi\u00f9 venduta di sempre in Italia, con oltre 170.000 immatricolazioni dalla sua introduzione nel 2012.\u00a0\u00a0Importante anche il contributo che <b><strong>Yaris Cross<\/strong><\/b>, dalla sua introduzione, sta dando e che continuer\u00e0 a dare nel 2022, grazie all\u2019ottima accoglienza che sta avendo in termini di acquisizione di contratti.\u00a0<\/p>\n<p>Ma i primati di Toyota non finiscono qui! <b><strong>Corolla Touring Sports<\/strong><\/b> chiude l\u2019anno con 4.311 immatricolazioni e diventa la prima vettura straniera nel segmento C-SW, con il 20,1% di quota, e prima nel canale delle flotte. <b><strong>Proace City Verso<\/strong><\/b>, con 1.285 veicoli immatricolati nel 2021, diventa prima assoluta nel segmento LCV M1, con una quota del 19,8%.<\/p>\n<p><b><strong>Lexus<\/strong><\/b>\u00a0chiude un anno molto positivo con oltre 4.700 vetture immatricolate e una quota del 1,9% sul mercato premium, la pi\u00f9 alta raggiunta dal brand sul mercato italiano. Determinante per questo risultato \u00e8 stato il contributo di\u00a0<b><strong>Lexus UX<\/strong><\/b>, che ha pesato per oltre il 67% sul totale delle vendite del marchio, con 3.166 vetture immatricolate e una quota del 5% nel segmento C-SUV Premium.\u00a0<\/p>\n<p><i>\u201cIl 2021 \u00e8 stato un anno straordinario, coronato da tanti successi, per i quali ringrazio tutti i clienti che ci hanno scelto e dato fiducia. I risultati ottenuti sono il frutto dell\u2019incredibile lavoro di una squadra formidabile, composta da ogni singolo membro delle aziende del Gruppo Toyota in Italia e delle Concessionarie Toyota e Lexus, che hanno saputo valorizzare al meglio le nostre proposte e ai quali va il mio pi\u00f9 sincero ringraziamento. Sono orgoglioso di farne parte &#8211;<\/i>\u00a0dichiara\u00a0<b><strong>Luigi Ksawery Luca&#8217;<\/strong><\/b>, Amministratore Delegato di Toyota Motor Italia.\u00a0<i>Ci aspetta un 2022 altrettanto entusiasmante, nel quale avremo tante novit\u00e0 di prodotto, che sfrutteranno al massimo le potenzialit\u00e0 delle nostre tecnologie: quest\u2019anno inizieranno le consegne della Lexus NX, che ha gi\u00e0 ricevuto un\u2019accoglienza straordinaria dai clienti. Per Toyota introdurremo la nuova Aygo X (con emissioni particolarmente contenute), la Corolla Cross (con il nuovo sistema ibrido di quinta generazione), il nuovo Proace City Electric e il nuovo Toyota bZ4X, il primo modello della nuova famiglia Toyota bZ, sviluppata sulla nuova piattaforma e-TNGA, completamente dedicata alle auto elettriche a batteria, a conferma del nostro approccio multi-tecnologico per la riduzione delle emissioni.\u201d\u00a0<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":64500,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[417,6338,293,335],"tags":[],"class_list":["post-64499","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lexus","category-mercato-auto-italia","category-news","category-toyota"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL GRUPPO TOYOTA ANNUNCIA I RISULTATI DEL 2021 IN ITALIA - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL GRUPPO TOYOTA ANNUNCIA I RISULTATI DEL 2021 IN ITALIA - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-07T09:33:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-07T09:33:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2022\/01\/yaris-cross.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"IL GRUPPO TOYOTA ANNUNCIA I RISULTATI DEL 2021 IN ITALIA\",\"datePublished\":\"2022-01-07T09:33:05+00:00\",\"dateModified\":\"2022-01-07T09:33:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\\\/\"},\"wordCount\":627,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/yaris-cross.jpg\",\"articleSection\":[\"Lexus\",\"Mercato Auto Italia\",\"News\",\"Toyota\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\\\/\",\"name\":\"IL GRUPPO TOYOTA ANNUNCIA I RISULTATI DEL 2021 IN ITALIA - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/yaris-cross.jpg\",\"datePublished\":\"2022-01-07T09:33:05+00:00\",\"dateModified\":\"2022-01-07T09:33:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/yaris-cross.jpg\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/yaris-cross.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL GRUPPO TOYOTA ANNUNCIA I RISULTATI DEL 2021 IN ITALIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL GRUPPO TOYOTA ANNUNCIA I RISULTATI DEL 2021 IN ITALIA - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/","og_locale":"it_IT","og_type":"article","og_title":"IL GRUPPO TOYOTA ANNUNCIA I RISULTATI DEL 2021 IN ITALIA - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2022-01-07T09:33:05+00:00","article_modified_time":"2022-01-07T09:33:06+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2022\/01\/yaris-cross.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"IL GRUPPO TOYOTA ANNUNCIA I RISULTATI DEL 2021 IN ITALIA","datePublished":"2022-01-07T09:33:05+00:00","dateModified":"2022-01-07T09:33:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/"},"wordCount":627,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2022\/01\/yaris-cross.jpg","articleSection":["Lexus","Mercato Auto Italia","News","Toyota"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/","url":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/","name":"IL GRUPPO TOYOTA ANNUNCIA I RISULTATI DEL 2021 IN ITALIA - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/#primaryimage"},"thumbnailUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2022\/01\/yaris-cross.jpg","datePublished":"2022-01-07T09:33:05+00:00","dateModified":"2022-01-07T09:33:06+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/#primaryimage","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2022\/01\/yaris-cross.jpg","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2022\/01\/yaris-cross.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-toyota-annuncia-i-risultati-del-2021-in-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"IL GRUPPO TOYOTA ANNUNCIA I RISULTATI DEL 2021 IN ITALIA"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"http:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/64499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=64499"}],"version-history":[{"count":1,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/64499\/revisions"}],"predecessor-version":[{"id":64501,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/64499\/revisions\/64501"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/64500"}],"wp:attachment":[{"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=64499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=64499"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=64499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}