{"id":18861,"date":"2015-06-08T14:04:25","date_gmt":"2015-06-08T12:04:25","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=18861"},"modified":"2015-06-08T17:46:37","modified_gmt":"2015-06-08T15:46:37","slug":"alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/","title":{"rendered":"Alfa Romeo Giulietta Collezione, per continuare a giocare un ruolo da protagonista"},"content":{"rendered":"<p>Arriva in Italia la nuova Alfa Romeo Giulietta Collezione che si rivolge a una clientela particolarmente esigente, elegante, attenta ai dettagli e alla ricerca di elementi distintivi ma che al tempo stesso non rinuncia alla &#8220;sostanza&#8221; in termini di dotazioni di serie e motorizzazioni efficienti e prestazionali.<\/p>\n<p>All&#8217;esterno, la nuova Giulietta Collezione si contraddistingue dalle calotte nere degli specchi retrovisori e dai cerchi in lega da 18&#8243; a raggi con trattamento brunito). Per esaltare ulteriormente l&#8217;eleganza e la personalit\u00e0 distintiva, a richiesta, la Giulietta Collezione pu\u00f2 essere dotata del raffinato tetto nero a contrasto per un perfetto abbinamento cromatico con cerchi e calotte.<\/p>\n<p>La cura del dettaglio e l&#8217;alta qualit\u00e0 dei materiali scelti &#8211; espressione pi\u00f9 evoluta dello stile &#8220;Made in Italy&#8221; &#8211; sono ben visibili all&#8217;interno dove spicca l&#8217;elegante ambiente scuro, reso ancora pi\u00f9 suggestivo dai nuovi sedili rivestiti in pregiata pelle bicolore (nero\/grigio) con cuciture a contrasto, oltre che da alcuni inserti satinati di colore grigio su plancia, pannelli porta e tunnel centrale.<\/p>\n<p>La nuova Giulietta Collezione offre una ricca dotazione di serie che include 6 airbag, il dispositivo Alfa DNA (con differenziale elettronico Q2 e DST), l&#8217;innovativo ESC (include ASR e Hill Holder), fendinebbia e sensore di pressione degli pneumatici. Inoltre, per il massimo del comfort, sono sempre di serie climatizzatore automatico bi-zona, alzacristalli elettrici posteriori, volante in pelle con comandi radio, braccioli anteriore e posteriore, regolazione lombare dei sedili anteriori, specchietti retrovisori ripiegabili elettricamente, sensori di parcheggio posteriore, specchietto retrovisore interno elettrocromico e sensori di pioggia e crepuscolare.<\/p>\n<p>L&#8217;esclusiva versione Collezione propone il nuovo dispositivo multimediale Uconnect con touch-screen da 6,5&#8243; integrato in plancia che prevede interfaccia Bluetooth, connettore Aux-in, porta USB e comandi vocali. In pi\u00f9, il dispositivo \u00e8 dotato anche di navigazione satellitare con mappe dall&#8217;alto in 3D, indicazioni progressive sul percorso e funzione &#8216;One Step Voice entry Destination&#8217; per inserire l&#8217;indirizzo con i comandi vocali. Il sistema \u00e8 stato sviluppato in collaborazione con partner di eccellenza quali Harman e Here Auto<\/p>\n<p>Sull&#8217;allestimento Collezione debutta il nuovo motore turbodiesel Multijet di seconda generazione 1.6 JTDM 120 CV Euro 6, perfetta combinazione tra prestazioni, bassi consumi e rispetto per l&#8217;ambiente: 3,9 l\/100Km e soli 103 g\/km di CO2 nel ciclo combinato. Altre due le motorizzazioni disponibili: i turbodiesel Multijet di seconda generazione 2.0 JTDM 150 CV e 2.0 JTDM 175 CV Euro 6, quest&#8217;ultimo esclusivamente con cambio automatico a doppia frizione Alfa TCT e il TurboBenzina 1.4 MultiAir da 170 CV, anch&#8217;esso solo con cambio automatico Alfa TCT.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arriva in Italia la nuova Alfa Romeo Giulietta Collezione che si rivolge a una clientela particolarmente esigente, elegante, attenta ai dettagli e alla ricerca di elementi distintivi ma che al tempo stesso non rinuncia alla &#8220;sostanza&#8221; in termini di dotazioni di serie e motorizzazioni efficienti e prestazionali. All&#8217;esterno, la nuova Giulietta Collezione si contraddistingue dalle [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18862,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[354,346],"tags":[80],"class_list":["post-18861","post","type-post","status-publish","format-standard","has-post-thumbnail","category-alfa-romeo","category-video","tag-featured"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alfa Romeo Giulietta Collezione, per continuare a giocare un ruolo da protagonista - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alfa Romeo Giulietta Collezione, per continuare a giocare un ruolo da protagonista - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Arriva in Italia la nuova Alfa Romeo Giulietta Collezione che si rivolge a una clientela particolarmente esigente, elegante, attenta ai dettagli e alla ricerca di elementi distintivi ma che al tempo stesso non rinuncia alla &#8220;sostanza&#8221; in termini di dotazioni di serie e motorizzazioni efficienti e prestazionali. All&#8217;esterno, la nuova Giulietta Collezione si contraddistingue dalle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-08T12:04:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-08T15:46:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/150223_AR_Giulietta-Collezione_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Alfa Romeo Giulietta Collezione, per continuare a giocare un ruolo da protagonista\",\"datePublished\":\"2015-06-08T12:04:25+00:00\",\"dateModified\":\"2015-06-08T15:46:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\\\/\"},\"wordCount\":424,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/150223_AR_Giulietta-Collezione_01.jpg\",\"keywords\":[\"Featured\"],\"articleSection\":[\"Alfa Romeo\",\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\\\/\",\"name\":\"Alfa Romeo Giulietta Collezione, per continuare a giocare un ruolo da protagonista - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/150223_AR_Giulietta-Collezione_01.jpg\",\"datePublished\":\"2015-06-08T12:04:25+00:00\",\"dateModified\":\"2015-06-08T15:46:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/150223_AR_Giulietta-Collezione_01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/150223_AR_Giulietta-Collezione_01.jpg\",\"width\":1000,\"height\":290},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alfa Romeo Giulietta Collezione, per continuare a giocare un ruolo da protagonista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alfa Romeo Giulietta Collezione, per continuare a giocare un ruolo da protagonista - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/","og_locale":"it_IT","og_type":"article","og_title":"Alfa Romeo Giulietta Collezione, per continuare a giocare un ruolo da protagonista - AbmNews","og_description":"Arriva in Italia la nuova Alfa Romeo Giulietta Collezione che si rivolge a una clientela particolarmente esigente, elegante, attenta ai dettagli e alla ricerca di elementi distintivi ma che al tempo stesso non rinuncia alla &#8220;sostanza&#8221; in termini di dotazioni di serie e motorizzazioni efficienti e prestazionali. All&#8217;esterno, la nuova Giulietta Collezione si contraddistingue dalle [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2015-06-08T12:04:25+00:00","article_modified_time":"2015-06-08T15:46:37+00:00","og_image":[{"width":1000,"height":290,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/150223_AR_Giulietta-Collezione_01.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Alfa Romeo Giulietta Collezione, per continuare a giocare un ruolo da protagonista","datePublished":"2015-06-08T12:04:25+00:00","dateModified":"2015-06-08T15:46:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/"},"wordCount":424,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/150223_AR_Giulietta-Collezione_01.jpg","keywords":["Featured"],"articleSection":["Alfa Romeo","Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/","url":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/","name":"Alfa Romeo Giulietta Collezione, per continuare a giocare un ruolo da protagonista - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/150223_AR_Giulietta-Collezione_01.jpg","datePublished":"2015-06-08T12:04:25+00:00","dateModified":"2015-06-08T15:46:37+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/150223_AR_Giulietta-Collezione_01.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/150223_AR_Giulietta-Collezione_01.jpg","width":1000,"height":290},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-giulietta-collezione-per-continuare-a-giocare-un-ruolo-da-protagonista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Alfa Romeo Giulietta Collezione, per continuare a giocare un ruolo da protagonista"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/18861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=18861"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/18861\/revisions"}],"predecessor-version":[{"id":18863,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/18861\/revisions\/18863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/18862"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=18861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=18861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=18861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}