{"id":18997,"date":"2015-06-12T16:20:28","date_gmt":"2015-06-12T14:20:28","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=18997"},"modified":"2015-06-12T16:20:28","modified_gmt":"2015-06-12T14:20:28","slug":"smart-a-roma-incontra-il-mondo","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/","title":{"rendered":"smart a \u2018Roma Incontra il Mondo\u2019"},"content":{"rendered":"<p>La famiglia smart al gran completo si \u00e8 data appuntamento a Villa Ada, nel cuore della Capitale, per la 22\u00b0 edizione di \u2018Roma Incontra il Mondo\u2019, storico festival di musica internazionale che, dal 19 giugno al 29 luglio, animer\u00e0 le serate romane: un nuovo omaggio alla Capitale, smart city per eccellenza, con oltre 135.000 unit\u00e0 vendute dal lancio nel 1998. I visitatori di \u2018Roma Incontra il Mondo\u2019 potranno conoscere da vicino tutte le novit\u00e0 della nuova generazione e cercare la propria anima gemella grazie a smart matching, la speciale selezione di smart FirstHand, che mette sotto i riflettori le pi\u00f9 giovani e attraenti smart \u00a0\u2018single\u2019 del momento. Nel verde di Villa Ada saranno protagonisti i prodotti, ma anche le soluzioni di mobilit\u00e0 su misura per la citt\u00e0 come car2go, il rivoluzionario car sharing che ha gi\u00e0 conquistato Roma, Milano, Firenze e Torino, ed ebike, che estende alle due ruote il piacere della mobilit\u00e0 a zero emissioni.<\/p>\n<p>&nbsp;<\/p>\n<p>Dal 19 giugno al 29 luglio in occasione del Festival di musica internazionale \u2018Roma Incontra il Mondo\u2019, visitatori da tutto il mondo potranno conoscere da vicino e provare tutta la gamma smart, proprio nel suo habitat naturale, a Villa Ada nel cuore della Capitale. Nuova fortwo e forfour, ebike e soluzioni innovative per la mobilit\u00e0 urbana come car2go faranno da cornice ad un ricco calendario di concerti. Protagonista nell\u2019area espositiva della regina delle city car, la nuova generazione smart, completamente rinnovata nel design, con una gamma di motori nuovi, tre cilindri da 45 kW\/ 60 CV, 52 kW\/ 71 CV e 66 kW\/ 90 CV, abbinate ad un cambio manuale a cinque marce o all\u2019inedito automatico a doppia frizione twinamic.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel cuore verde della Capitale non potevano mancare ebike, la bicicletta a pedalata assistita firmata smart, che estende alle due ruote il piacere della mobili\u00e0 a zero emissioni.<\/p>\n<p>&nbsp;<\/p>\n<p>Per chi, invece, fosse alla ricerca di una smart usata e garantita, potr\u00e0 trovare la propria anima gemella a &#8216;Roma Incontra il Mondo\u2019, dove sar\u00e0 presente una selezione delle migliori smart tornate \u2018single\u2019 e disponibili nell\u2019offerta di usato certificato e garantito smart matching FirstHand.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La famiglia smart al gran completo si \u00e8 data appuntamento a Villa Ada, nel cuore della Capitale, per la 22\u00b0 edizione di \u2018Roma Incontra il Mondo\u2019, storico festival di musica internazionale che, dal 19 giugno al 29 luglio, animer\u00e0 le serate romane: un nuovo omaggio alla Capitale, smart city per eccellenza, con oltre 135.000 unit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18998,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[318],"tags":[],"class_list":["post-18997","post","type-post","status-publish","format-standard","has-post-thumbnail","category-smart"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>smart a \u2018Roma Incontra il Mondo\u2019 - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"smart a \u2018Roma Incontra il Mondo\u2019 - AbmNews\" \/>\n<meta property=\"og:description\" content=\"La famiglia smart al gran completo si \u00e8 data appuntamento a Villa Ada, nel cuore della Capitale, per la 22\u00b0 edizione di \u2018Roma Incontra il Mondo\u2019, storico festival di musica internazionale che, dal 19 giugno al 29 luglio, animer\u00e0 le serate romane: un nuovo omaggio alla Capitale, smart city per eccellenza, con oltre 135.000 unit\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-12T14:20:28+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/1129056_2301440_1024_682_smart_twinamic_35.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/smart-a-roma-incontra-il-mondo\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/smart-a-roma-incontra-il-mondo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"smart a \u2018Roma Incontra il Mondo\u2019\",\"datePublished\":\"2015-06-12T14:20:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/smart-a-roma-incontra-il-mondo\\\/\"},\"wordCount\":350,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/smart-a-roma-incontra-il-mondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/1129056_2301440_1024_682_smart_twinamic_35.jpg\",\"articleSection\":[\"Smart\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/smart-a-roma-incontra-il-mondo\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/smart-a-roma-incontra-il-mondo\\\/\",\"name\":\"smart a \u2018Roma Incontra il Mondo\u2019 - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/smart-a-roma-incontra-il-mondo\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/smart-a-roma-incontra-il-mondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/1129056_2301440_1024_682_smart_twinamic_35.jpg\",\"datePublished\":\"2015-06-12T14:20:28+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/smart-a-roma-incontra-il-mondo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/smart-a-roma-incontra-il-mondo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/smart-a-roma-incontra-il-mondo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/1129056_2301440_1024_682_smart_twinamic_35.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/1129056_2301440_1024_682_smart_twinamic_35.jpg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/smart-a-roma-incontra-il-mondo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"smart a \u2018Roma Incontra il Mondo\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"smart a \u2018Roma Incontra il Mondo\u2019 - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/","og_locale":"it_IT","og_type":"article","og_title":"smart a \u2018Roma Incontra il Mondo\u2019 - AbmNews","og_description":"La famiglia smart al gran completo si \u00e8 data appuntamento a Villa Ada, nel cuore della Capitale, per la 22\u00b0 edizione di \u2018Roma Incontra il Mondo\u2019, storico festival di musica internazionale che, dal 19 giugno al 29 luglio, animer\u00e0 le serate romane: un nuovo omaggio alla Capitale, smart city per eccellenza, con oltre 135.000 unit\u00e0 [&hellip;]","og_url":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2015-06-12T14:20:28+00:00","og_image":[{"width":1024,"height":682,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/1129056_2301440_1024_682_smart_twinamic_35.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"smart a \u2018Roma Incontra il Mondo\u2019","datePublished":"2015-06-12T14:20:28+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/"},"wordCount":350,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/1129056_2301440_1024_682_smart_twinamic_35.jpg","articleSection":["Smart"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/","url":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/","name":"smart a \u2018Roma Incontra il Mondo\u2019 - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/1129056_2301440_1024_682_smart_twinamic_35.jpg","datePublished":"2015-06-12T14:20:28+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/1129056_2301440_1024_682_smart_twinamic_35.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/06\/1129056_2301440_1024_682_smart_twinamic_35.jpg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/smart-a-roma-incontra-il-mondo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"smart a \u2018Roma Incontra il Mondo\u2019"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/18997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=18997"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/18997\/revisions"}],"predecessor-version":[{"id":18999,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/18997\/revisions\/18999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/18998"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=18997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=18997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=18997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}