{"id":19668,"date":"2015-07-11T08:11:52","date_gmt":"2015-07-11T06:11:52","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=19668"},"modified":"2015-07-11T08:11:52","modified_gmt":"2015-07-11T06:11:52","slug":"al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/","title":{"rendered":"Al Mugello quarto appuntamento dell&#8217;Italian F4 Championship powered by Abarth"},"content":{"rendered":"<p>Ancora un fine settimana agonistico all&#8217;insegna dello Scorpione quello che si vive da oggi a domenica sul circuito toscano del Mugello, dove si disputano il quarto appuntamento dell&#8217;Italian F4 Championship powered by Abarth, la seconda manche del Trofeo Abarth Selenia Europa e la terza del Trofeo Nazionale Acisport Abarth Selenia Italia.<\/p>\n<p>In tutto sono circa 50 i piloti impegnati nei due campionati con vetture Abarth: una trentina con le monoposto F4 e 20 con le Abarth 595 Assetto Corse Evoluzione e Abarth 500 Assetto Corse. In prevalenza si tratta di giovani o giovanissimi. L&#8217;Italian F4 Championship powered by Abarth \u00e8 infatti riservato ai piloti provenienti dal kart di et\u00e0 compresa tra i 15 e i 18 anni.<\/p>\n<p>Nell&#8217;Italian F4 Championship powered by Abarth l&#8217;agonismo non manca e dopo le prime tre manche, disputate sui circuiti di Vallelunga, Monza e Imola, la classifica generale di campionato vede al comando l&#8217;estone Ralf Aron (150 punti) davanti al cinese Guan Yu Zhou (135). Seguono in classifica generale il russo Robert Shwartzman (78), il tedesco David Beckmann (68), l&#8217;israeliano Bar Baruch a parimerito con il brasiliano Joao Vieira (60). Nel Woman Trophy al comando troviamo Julia Pankiewicz, con un solo punto di vantaggio sulla sorella gemella Wiktoria.<\/p>\n<p>Contemporaneamente il terzo appuntamento del Trofeo Nazionale Acisport Abarth Selenia Italia e la seconda manche del Trofeo Abarth Selenia Europa, vedono al via 20 piloti al volante delle performanti Abarth 695 Assetto Corse Evoluzione e Abarth 500 Assetto Corse.<\/p>\n<p>Dopo le prime due gare, nel Trofeo Nazionale Acisport Abarth Selenia Italia \u00e8 al comando l&#8217;italiano Luca Anselmi, balzato in testa grazie al successo ottenuto nell&#8217;ultima gara, corsa sul circuito di Vallelunga. Al secondo posto lo svedese Niklas Lilja, staccato di tre lunghezze, terzo un altro pilota scandinavo, il giovane finlandese Juuso Pajuranta.<\/p>\n<p>La classifica continentale vede sempre un italiano in testa: il giovane Eric Scalvini, che precede Maurizio Campani e Lilja.<\/p>\n<p>Tra le Abarth 500 Assetto Corse dominio scandinavo nella graduatoria europea, con gli svedesi Robin Appleqvist e Joakim Darbom rispettivamente primo e secondo davanti all&#8217;italiano Alfredo Di Cosmo. Nella stessa categoria, nel campionato italiano \u00e8 in testa Franco Cimarelli.<\/p>\n<p>Il programma dell&#8217;evento prevede oggi le prove di qualificazione della Formula 4 alle ore 17,40 e 18,05; domani le qualifiche dei trofei Abarth sono alle 12,10; nella stessa giornata si disputano la prima gara della Formula 4 alle 14,20 e dei trofei alle 19. Domenica la giornata conclusiva con due corse della Formula 4 (alle 9 e alle 17,05) e una dei trofei alle 16,10.<\/p>\n<p>Classifica Trofeo Abarth Selenia Europa: 1. Scalvini 32; 2. M.Campani 30; 3. Lilja 25; 4. Buffoli 25; 5. Anselmi 24.<\/p>\n<p>Classifica categoria Abarth 500 Assetto Corse Europa: 1. Appelqvist 46; 2. Darbom 33; 3. Di Cosmo 25; 4. Cimarelli 25; 5. Arrigosi 12.<\/p>\n<p>Classifica Trofeo Nazionale Acisport Abarth Selenia Italia: 1. Anselmi 69; 2. Lilja 66; 3. Pajuranta 50; 4. Scalvini 44; 5. Barberini 32.<\/p>\n<p>Classifica categoria Abarth 500 Assetto Corse Italia: 1. Cimarelli 78; 2. Appelqvist 73; 3. Darbom 63; 4. Arrigosi 45; 5. Di Cosmo 25.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ancora un fine settimana agonistico all&#8217;insegna dello Scorpione quello che si vive da oggi a domenica sul circuito toscano del Mugello, dove si disputano il quarto appuntamento dell&#8217;Italian F4 Championship powered by Abarth, la seconda manche del Trofeo Abarth Selenia Europa e la terza del Trofeo Nazionale Acisport Abarth Selenia Italia. In tutto sono circa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19669,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[227],"tags":[],"class_list":["post-19668","post","type-post","status-publish","format-standard","has-post-thumbnail","category-abarth"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Al Mugello quarto appuntamento dell&#039;Italian F4 Championship powered by Abarth - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al Mugello quarto appuntamento dell&#039;Italian F4 Championship powered by Abarth - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Ancora un fine settimana agonistico all&#8217;insegna dello Scorpione quello che si vive da oggi a domenica sul circuito toscano del Mugello, dove si disputano il quarto appuntamento dell&#8217;Italian F4 Championship powered by Abarth, la seconda manche del Trofeo Abarth Selenia Europa e la terza del Trofeo Nazionale Acisport Abarth Selenia Italia. In tutto sono circa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-11T06:11:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/07\/150710_Abarth_Mugello_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Al Mugello quarto appuntamento dell&#8217;Italian F4 Championship powered by Abarth\",\"datePublished\":\"2015-07-11T06:11:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\\\/\"},\"wordCount\":458,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/150710_Abarth_Mugello_01.jpg\",\"articleSection\":[\"Abarth\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\\\/\",\"name\":\"Al Mugello quarto appuntamento dell'Italian F4 Championship powered by Abarth - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/150710_Abarth_Mugello_01.jpg\",\"datePublished\":\"2015-07-11T06:11:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/150710_Abarth_Mugello_01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/150710_Abarth_Mugello_01.jpg\",\"width\":620,\"height\":415},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al Mugello quarto appuntamento dell&#8217;Italian F4 Championship powered by Abarth\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al Mugello quarto appuntamento dell'Italian F4 Championship powered by Abarth - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/","og_locale":"it_IT","og_type":"article","og_title":"Al Mugello quarto appuntamento dell'Italian F4 Championship powered by Abarth - AbmNews","og_description":"Ancora un fine settimana agonistico all&#8217;insegna dello Scorpione quello che si vive da oggi a domenica sul circuito toscano del Mugello, dove si disputano il quarto appuntamento dell&#8217;Italian F4 Championship powered by Abarth, la seconda manche del Trofeo Abarth Selenia Europa e la terza del Trofeo Nazionale Acisport Abarth Selenia Italia. In tutto sono circa [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2015-07-11T06:11:52+00:00","og_image":[{"width":620,"height":415,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/07\/150710_Abarth_Mugello_01.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Al Mugello quarto appuntamento dell&#8217;Italian F4 Championship powered by Abarth","datePublished":"2015-07-11T06:11:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/"},"wordCount":458,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/07\/150710_Abarth_Mugello_01.jpg","articleSection":["Abarth"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/","url":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/","name":"Al Mugello quarto appuntamento dell'Italian F4 Championship powered by Abarth - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/07\/150710_Abarth_Mugello_01.jpg","datePublished":"2015-07-11T06:11:52+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/07\/150710_Abarth_Mugello_01.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2015\/07\/150710_Abarth_Mugello_01.jpg","width":620,"height":415},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/al-mugello-quarto-appuntamento-dellitalian-f4-championship-powered-by-abarth\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Al Mugello quarto appuntamento dell&#8217;Italian F4 Championship powered by Abarth"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/19668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=19668"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/19668\/revisions"}],"predecessor-version":[{"id":19670,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/19668\/revisions\/19670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/19669"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=19668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=19668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=19668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}