{"id":24354,"date":"2016-04-06T18:46:36","date_gmt":"2016-04-06T16:46:36","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=24354"},"modified":"2016-04-06T18:46:36","modified_gmt":"2016-04-06T16:46:36","slug":"per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/","title":{"rendered":"Per il nono anno consecutivo PSA Groupe \u00e8 primo per brevetti depositati in Francia"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>PSA Groupe \u00e8 al primo posto nella classifica 2015 dell\u2019Institut National de la Propri\u00e9t\u00e9 Industrielle (INPI) con 1012 brevetti pubblicati e conserva la posizione di leader.<\/p>\n<p>Grazie alla performance dei team di PSA Groupe e all\u2019efficacia delle scelte interne di Ricerca e sviluppo effettuate, la pubblicazione di oltre un migliaio di brevetti, potenzia la strategia di innovazione del Gruppo in tre ambiti principali: le clean technologies, i veicoli autonomi e connessi, e l\u2019attrattiva specifica esercitata dai tre marchi Peugeot, Citro\u00ebn e DS.<\/p>\n<p>Il budget Ricerca e Sviluppo di PSA Groupe per il 2015 ammonta a 1,8 miliardi di euro. Tutte queste innovazioni dimostrano la volont\u00e0 del Gruppo di proporre soluzioni sostenibili in grado di affrontare le sfide della mobilit\u00e0 di domani.<\/p>\n<p>PSA Groupe, attore della nuova mobilit\u00e0<\/p>\n<p>Le innovative soluzioni in questo ambito hanno richiesto un importante lavoro di ricerca, che si traducono in oltre 250 brevetti.<\/p>\n<ul>\n<li>\uf0b7 \u00a0Per quanto riguarda i veicoli autonomi, il passaggio dalla modalit\u00e0 di guida standard a quella semiautonoma, o addirittura totalmente autonoma, \u00e8 stato oggetto di oltre 130 brevetti, e riguarda in particolare le IHM (Interface Human Machine), i sistemi ADAS (Advanced Driver Assistance Systems) e gli equipaggiamenti interni specifici. Diverse C4 Picasso dotate di funzioni di guida autonoma hanno percorso oltre 20.000 chilometri su strada, a dimostrazione del know how del Gruppo.<\/li>\n<li>\uf0b7 \u00a0PSA Groupe ha anche depositato oltre 60 brevetti che riguardano i veicoli connessi. In particolare ha sviluppato Car Easy Apps, una piattaforma software che servir\u00e0 da base a future applicazioni smartphone collegate all\u2019auto. In tema di servizi telematici, il Gruppo \u00e8 pioniere della chiamata d\u2019emergenza e assistenza automatizzata, che permette di allertare automaticamente i soccorsi in caso di incidente. Attualmente oltre 1,8 milioni di veicoli del Gruppo sono equipaggiati di questo sistema.\n<p>PSA Groupe al vertice della tecnologia per ridurre consumi ed emissioni<\/p>\n<p>Con una media di 104,4 g di CO2\/km nel 2015 sull\u2019intera gamma, PSA Groupe si impone come leader europeo nella riduzione delle emissioni di CO2. Moltissime innovazioni riguardano le motorizzazioni. Ad esempio:<\/li>\n<\/ul>\n<p>\uf0b7 il motore benzina tre cilindri EB PureTech turbocompresso \u00e8 stato eletto \u00abMotore dell\u2019anno 2015 \u00bb per la sua categoria. Vanta ben 120 brevetti, e permette una<\/p>\n<\/div>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>riduzione del 18% dei consumi e delle emissioni di CO2 rispetto alle versioni<\/p>\n<p>precedenti.<br \/>\n\uf0b7 PSA Groupe mira all\u2019eccellenza per le tecnologie che riguardano i sistemi<\/p>\n<p>antinquinamento e le motorizzazioni Diesel. La tecnologia BLUEHDI permette di eliminare il 99,9% del particolato, e di ridurre fino al 90% gli ossidi d\u2019azoto emessi dal motore. Questa tecnologia SCR*, abbinata al filtro antiparticolato additivato \u00e8 oggetto di oltre 100 brevetti che riguardano ad esempio la gestione dell\u2019iniezione di urea e la concezione del serbatoio.<\/p>\n<p>Alla luce di questo nuovo primato Gilles Le Borgne, Direttore R&amp;D di PSA Groupe dichiara:<\/p>\n<p>\u00abPer il nono anno consecutivo PSA Groupe \u00e8 al primo posto per brevetti depositati in Francia. Questo primato mostra il coinvolgimento e l\u2019efficienza dei team del gruppo, e il nostro impegno nel rispondere alle esigenze e alle aspettative dei nostri clienti\u00bb.<\/p>\n<p>*Selective Catalytic Reduction<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PSA Groupe \u00e8 al primo posto nella classifica 2015 dell\u2019Institut National de la Propri\u00e9t\u00e9 Industrielle (INPI) con 1012 brevetti pubblicati e conserva la posizione di leader. Grazie alla performance dei team di PSA Groupe e all\u2019efficacia delle scelte interne di Ricerca e sviluppo effettuate, la pubblicazione di oltre un migliaio di brevetti, potenzia la strategia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24355,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6257],"tags":[],"class_list":["post-24354","post","type-post","status-publish","format-standard","has-post-thumbnail","category-psa-peugeot-citroen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Per il nono anno consecutivo PSA Groupe \u00e8 primo per brevetti depositati in Francia - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Per il nono anno consecutivo PSA Groupe \u00e8 primo per brevetti depositati in Francia - AbmNews\" \/>\n<meta property=\"og:description\" content=\"PSA Groupe \u00e8 al primo posto nella classifica 2015 dell\u2019Institut National de la Propri\u00e9t\u00e9 Industrielle (INPI) con 1012 brevetti pubblicati e conserva la posizione di leader. Grazie alla performance dei team di PSA Groupe e all\u2019efficacia delle scelte interne di Ricerca e sviluppo effettuate, la pubblicazione di oltre un migliaio di brevetti, potenzia la strategia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-06T16:46:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/04\/M_e8cf15c6-cc33-441f-9d21-ceb2d92bd9e0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"797\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Per il nono anno consecutivo PSA Groupe \u00e8 primo per brevetti depositati in Francia\",\"datePublished\":\"2016-04-06T16:46:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\\\/\"},\"wordCount\":504,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/M_e8cf15c6-cc33-441f-9d21-ceb2d92bd9e0.jpg\",\"articleSection\":[\"PSA Peugeot Citroen\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\\\/\",\"name\":\"Per il nono anno consecutivo PSA Groupe \u00e8 primo per brevetti depositati in Francia - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/M_e8cf15c6-cc33-441f-9d21-ceb2d92bd9e0.jpg\",\"datePublished\":\"2016-04-06T16:46:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/M_e8cf15c6-cc33-441f-9d21-ceb2d92bd9e0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/M_e8cf15c6-cc33-441f-9d21-ceb2d92bd9e0.jpg\",\"width\":1200,\"height\":797},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Per il nono anno consecutivo PSA Groupe \u00e8 primo per brevetti depositati in Francia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Per il nono anno consecutivo PSA Groupe \u00e8 primo per brevetti depositati in Francia - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/","og_locale":"it_IT","og_type":"article","og_title":"Per il nono anno consecutivo PSA Groupe \u00e8 primo per brevetti depositati in Francia - AbmNews","og_description":"PSA Groupe \u00e8 al primo posto nella classifica 2015 dell\u2019Institut National de la Propri\u00e9t\u00e9 Industrielle (INPI) con 1012 brevetti pubblicati e conserva la posizione di leader. Grazie alla performance dei team di PSA Groupe e all\u2019efficacia delle scelte interne di Ricerca e sviluppo effettuate, la pubblicazione di oltre un migliaio di brevetti, potenzia la strategia [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2016-04-06T16:46:36+00:00","og_image":[{"width":1200,"height":797,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/04\/M_e8cf15c6-cc33-441f-9d21-ceb2d92bd9e0.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Per il nono anno consecutivo PSA Groupe \u00e8 primo per brevetti depositati in Francia","datePublished":"2016-04-06T16:46:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/"},"wordCount":504,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/04\/M_e8cf15c6-cc33-441f-9d21-ceb2d92bd9e0.jpg","articleSection":["PSA Peugeot Citroen"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/","url":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/","name":"Per il nono anno consecutivo PSA Groupe \u00e8 primo per brevetti depositati in Francia - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/04\/M_e8cf15c6-cc33-441f-9d21-ceb2d92bd9e0.jpg","datePublished":"2016-04-06T16:46:36+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/04\/M_e8cf15c6-cc33-441f-9d21-ceb2d92bd9e0.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/04\/M_e8cf15c6-cc33-441f-9d21-ceb2d92bd9e0.jpg","width":1200,"height":797},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/per-il-nono-anno-consecutivo-psa-groupe-e-primo-per-brevetti-depositati-in-francia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Per il nono anno consecutivo PSA Groupe \u00e8 primo per brevetti depositati in Francia"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/24354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=24354"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/24354\/revisions"}],"predecessor-version":[{"id":24356,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/24354\/revisions\/24356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/24355"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=24354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=24354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=24354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}