{"id":25502,"date":"2016-06-07T05:34:42","date_gmt":"2016-06-07T03:34:42","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=25502"},"modified":"2016-06-07T05:34:42","modified_gmt":"2016-06-07T03:34:42","slug":"i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/","title":{"rendered":"I giovani Matteo Fusi e Nicol\u00f2 Salgaro al volante di un&#8217;Abarth 500 R3T nel rally d&#8217;Italia-Sardegna dal 9 al 12 giugno"},"content":{"rendered":"<p>Un premio molto allettante, la partecipazione all&#8217;appuntamento italiano del Mondiale Rally 2016 al volante di un&#8217;Abarth 500 R3T, ha decretato il successo della terza edizione del Rally Italia Talent. Pi\u00f9 di 5000 aspiranti piloti e navigatori, affascinati da una specialit\u00e0 spettacolare come il rally, si sono cimentati in questa iniziativa, supportata da Aci Sport e Abarth, che ha permesso a questi appassionati di mettersi alla prova al volante delle performanti Abarth 595 Competizione, vetture con una potenza di 180 CV e grande tenuta di strada e maneggevolezza: un&#8217;auto che anche nella sua versione di serie presenta le caratteristiche di guida tipiche di un&#8217;auto da corsa.<\/p>\n<p>Selezione dopo selezione sono risultati vincitori assoluti il pilota Matteo Fusi &#8211; 20 anni, di Caslino d&#8217;Erba (CO) e studente di ingegneria meccanica &#8211; e il navigatore Nicol\u00f2 Salgaro, 24 anni, di Vestenanova (VR), studente di ingegneria del veicolo.<br \/>\nL&#8217;equipaggio si \u00e8 aggiudicato la partecipazione al Rally d&#8217;Italia Sardegna, unica gara italiana valida per il Campionato del Mondo Rally, in programma dal 9 al 12 giugno prossimi al volante dell&#8217;Abarth 500 R3T gestita da Rally Italia Talent.<\/p>\n<p>Non si tratta di un impegno facile, vista la difficolt\u00e0 del percorso, articolato su tre tappe con 19 prove speciali tutte su sterrato, per un totale di 325 km di velocit\u00e0 cronometrata. Un esordio quindi impegnativo, che vedr\u00e0 i due giovanissimi piloti al volante di una vettura performante e professionale come l&#8217;Abarth 500 R3T, con una potenza di 200 CV, cambio sequenziale, assetto specifico da sterrato e tutti i dispositivi necessari ad affrontare la gara.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un premio molto allettante, la partecipazione all&#8217;appuntamento italiano del Mondiale Rally 2016 al volante di un&#8217;Abarth 500 R3T, ha decretato il successo della terza edizione del Rally Italia Talent. Pi\u00f9 di 5000 aspiranti piloti e navigatori, affascinati da una specialit\u00e0 spettacolare come il rally, si sono cimentati in questa iniziativa, supportata da Aci Sport e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25503,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[227],"tags":[],"class_list":["post-25502","post","type-post","status-publish","format-standard","has-post-thumbnail","category-abarth"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I giovani Matteo Fusi e Nicol\u00f2 Salgaro al volante di un&#039;Abarth 500 R3T nel rally d&#039;Italia-Sardegna dal 9 al 12 giugno - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I giovani Matteo Fusi e Nicol\u00f2 Salgaro al volante di un&#039;Abarth 500 R3T nel rally d&#039;Italia-Sardegna dal 9 al 12 giugno - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Un premio molto allettante, la partecipazione all&#8217;appuntamento italiano del Mondiale Rally 2016 al volante di un&#8217;Abarth 500 R3T, ha decretato il successo della terza edizione del Rally Italia Talent. Pi\u00f9 di 5000 aspiranti piloti e navigatori, affascinati da una specialit\u00e0 spettacolare come il rally, si sono cimentati in questa iniziativa, supportata da Aci Sport e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-07T03:34:42+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/160606_Abarth_500-R3T_HP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"I giovani Matteo Fusi e Nicol\u00f2 Salgaro al volante di un&#8217;Abarth 500 R3T nel rally d&#8217;Italia-Sardegna dal 9 al 12 giugno\",\"datePublished\":\"2016-06-07T03:34:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\\\/\"},\"wordCount\":275,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/160606_Abarth_500-R3T_HP.jpg\",\"articleSection\":[\"Abarth\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\\\/\",\"name\":\"I giovani Matteo Fusi e Nicol\u00f2 Salgaro al volante di un'Abarth 500 R3T nel rally d'Italia-Sardegna dal 9 al 12 giugno - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/160606_Abarth_500-R3T_HP.jpg\",\"datePublished\":\"2016-06-07T03:34:42+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/160606_Abarth_500-R3T_HP.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/160606_Abarth_500-R3T_HP.jpg\",\"width\":620,\"height\":426},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I giovani Matteo Fusi e Nicol\u00f2 Salgaro al volante di un&#8217;Abarth 500 R3T nel rally d&#8217;Italia-Sardegna dal 9 al 12 giugno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I giovani Matteo Fusi e Nicol\u00f2 Salgaro al volante di un'Abarth 500 R3T nel rally d'Italia-Sardegna dal 9 al 12 giugno - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/","og_locale":"it_IT","og_type":"article","og_title":"I giovani Matteo Fusi e Nicol\u00f2 Salgaro al volante di un'Abarth 500 R3T nel rally d'Italia-Sardegna dal 9 al 12 giugno - AbmNews","og_description":"Un premio molto allettante, la partecipazione all&#8217;appuntamento italiano del Mondiale Rally 2016 al volante di un&#8217;Abarth 500 R3T, ha decretato il successo della terza edizione del Rally Italia Talent. Pi\u00f9 di 5000 aspiranti piloti e navigatori, affascinati da una specialit\u00e0 spettacolare come il rally, si sono cimentati in questa iniziativa, supportata da Aci Sport e [&hellip;]","og_url":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2016-06-07T03:34:42+00:00","og_image":[{"width":620,"height":426,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/160606_Abarth_500-R3T_HP.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"I giovani Matteo Fusi e Nicol\u00f2 Salgaro al volante di un&#8217;Abarth 500 R3T nel rally d&#8217;Italia-Sardegna dal 9 al 12 giugno","datePublished":"2016-06-07T03:34:42+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/"},"wordCount":275,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/160606_Abarth_500-R3T_HP.jpg","articleSection":["Abarth"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/","url":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/","name":"I giovani Matteo Fusi e Nicol\u00f2 Salgaro al volante di un'Abarth 500 R3T nel rally d'Italia-Sardegna dal 9 al 12 giugno - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/160606_Abarth_500-R3T_HP.jpg","datePublished":"2016-06-07T03:34:42+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/160606_Abarth_500-R3T_HP.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/160606_Abarth_500-R3T_HP.jpg","width":620,"height":426},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/i-giovani-matteo-fusi-e-nicolo-salgaro-al-volante-di-unabarth-500-r3t-nel-rally-ditalia-sardegna-dal-9-al-12-giugno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"I giovani Matteo Fusi e Nicol\u00f2 Salgaro al volante di un&#8217;Abarth 500 R3T nel rally d&#8217;Italia-Sardegna dal 9 al 12 giugno"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=25502"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25502\/revisions"}],"predecessor-version":[{"id":25504,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25502\/revisions\/25504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/25503"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=25502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=25502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=25502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}