{"id":25832,"date":"2016-06-23T01:05:37","date_gmt":"2016-06-22T23:05:37","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=25832"},"modified":"2016-06-23T01:05:37","modified_gmt":"2016-06-22T23:05:37","slug":"nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/","title":{"rendered":"NUOVO NISSAN MURANO PER IL 10O ANNIVERSARIO   DELLO STABILIMENTO DI SAN PIETROBURGO"},"content":{"rendered":"<p>Nissan ha celebrato il 10o anniversario dello stabilimento in Russia con l\u2019inizio della produzione del nuovo crossover Murano.<\/p>\n<p>Riaffermando l\u2019impegno nei confronti della Russia, il Murano di terza generazione rappresenta il completamento di un investimento di 167 milioni di Euro in nuovi modelli crossover e infrastrutture che hanno raddoppiato le capacit\u00e0 di produzione a San Pietroburgo.<\/p>\n<p>Alla cerimonia nello stabilimento erano presenti i dipendenti che sono stati raggiunti dal Senior Vice President, Responsabile produzione acquisti e gestione della Supply Chain in Europa, Colin Lawther, dal Vice Presidente Produzione russo Dmitry Mikhailov, e dal Vice Presidente di Nissan Est, Philippe Saillard, oltre alle autorit\u00e0 governative: il Vice Ministro dell\u2019Industria e Commercio della Federazione Russa, Alexander Morozov e il Vice Governatore di San Pietroburgo Sergey Movchan.<\/p>\n<p>Lawther ha dichiarato: \u201cCongratulazioni a tutti i miei colleghi qui a San Pietroburgo, il cui impegno ed esemplare livello di rendimento sono risultati fondamentali nella strategia Nissan di rafforzamento della nostra posizione in Russia.<\/p>\n<p>\u201cOggi festeggiamo 10 anni di amicizia con la citt\u00e0 di San Pietroburgo presentando il nuovo Murano e completando cos\u00ec la nostra offerta di modelli costruiti sul posto per i clienti russi. Confermiamo la nostra posizione leader nel settore dei crossover.\u201d<\/p>\n<p>Per ricordare l\u2019evento \u00e8 stato realizzato un murale Murano utilizzando le foto dei dipendenti dello stabilimento per rappresentare l\u2019impegno di tutto il personale nel realizzare in ogni vettura la promessa Nissan di innovazione ed emozione.<\/p>\n<p>Philippe Saillard, Vice Presidente di Nissan Est, ha a sua volta dichiarato: &#8220;Nissan \u00e8 lieta di presentare agli automobilisti russi e agli appassionati del marchio il nuovo Nissan Murano, l\u2019ultimo arrivato nella nostra gamma crossover e SUV prodotti in Russia per la Russia.<\/p>\n<p>\u201cIl nuovo Murano sar\u00e0 al centro della nostra gamma crossover e sar\u00e0 presente sulle strade e autostrade russe, grazia al design audace e futuristico e a tutta una serie di tecnologie innovative che rispettano quello che i clienti si aspettano da Nissan.\u201d<\/p>\n<p>Il nuovo Murano \u00e8 offerto con un motore serie VQ, 3,5 lt DOHC V6 da 249 CV e 325 Nm di coppia, con un avanzato CVT\u00ae Xtronic che offre un\u2019esperienza di guida sportiva e fluida. La seconda opzione sar\u00e0 un veicolo ibrido benzina-elettrico con un motore a benzina da 2,5 lt sovralimentato e un motore elettrico da 15 kW (254 CV\/368 Nm).<\/p>\n<p>Il nuovo Murano sar\u00e0 il primo prodotto Nissan dotato dell\u2019ERA-GLONASS, un sistema di chiamata di emergenza che in caso di incidente invia automaticamente informazioni ai servizi di emergenza. Sar\u00e0 reso disponibile, insieme ad altri prodotti di San Pietroburgo, per altri membri della Unione Doganale, Bielorussia e Kazakistan.<\/p>\n<p>Il progetto Nissan a San Pietroburgo \u00e8 stato avviato nel giugno 2006 con la firma di un Memorandum of Understanding tra il Governo di San Pietroburgo e Nissan Motor Co Ltd., che prevedeva l\u2019impiego di 750 persone nello stabilimento con una capacit\u00e0 di produzione fino a 50.000 unit\u00e0 l\u2019anno.<\/p>\n<p>La produzione \u00e8 iniziata nel giugno 2009 e da allora dalla linea di produzione sono usciti oltre 230.000 veicoli, con un investimento totale in due fasi che ha raggiunto adesso i 312 milioni di euro. In questo periodo sono stati utilizzati 400 milioni di componenti e circa 2.000 tonnellate di pittura e gli impianti hanno funzionato per un totale di 28.290 ore lavorative.<\/p>\n<p>Il Vice Ministro dell\u2019Industria e del Commercio della Federazione Russa, Alexander Morozov, ha dichiarato: \u201cMi congratulo con Nissan per questo 10o anniversario. L\u2019azienda \u00e8 diventata un importante componente dell\u2019industria automobilistica russa e continua a migliorare la produzione locale. Il lancio odierno di Nissan Murano ne \u00e8 la prova.<\/p>\n<p>\u201cDesidero sottolineare che Murano sar\u00e0 il primo modello Nissan dotato del Sistema di emergenza ERA-GLONASS e sono sicuro che Murano otterr\u00e0 la posizione che merita nel mercato russo.\u201d<\/p>\n<p>La Russia rimane un mercato strategico per Nissan, dato il suo elevato potenziale di diventare il suo pi\u00f9 grande mercato in Europa. Fin dal 2014 la gamma dei modelli russi \u00e8 stata aggiornata per riflettere la posizione di Nissan come leader nel mercato dei crossover e SUV. La diffusione di modelli quali Terrano, X-Trail, Pathfinder, Murano e Qashqai nel mercato russo ha visto l\u2019azienda conquistare nel 2015 il 6o posto tra tutti i costruttori di auto in vendita in Russia.<\/p>\n<p>La produzione locale, a San Pietroburgo, ha giocato un ruolo chiave; lo stabilimento produce attualmente Nissan X-Trail, Pathfinder, Qashqai e ora anche Murano, specificamente adattato alle esigenze derivanti dalle condizioni delle strade russe.<\/p>\n<p>Dmitry Mikhailov, Vice Presidente per la Produzione in Russia, ha aggiunto: \u201cLo stabilimento Nissan a San Pietroburgo \u00e8 il pi\u00f9 recente di tutti gli stabilimenti Nissan in Europa ma oggi abbiamo gi\u00e0 10 anni di esperienza e costruiamo in Russia il 95% dei veicoli Nissan venduti in Russia.<\/p>\n<p>\u201cCon oltre 230.000 veicoli prodotti, due premi mondiali per la qualit\u00e0 e la capacit\u00e0 degli impianti raddoppiata, lo stabilimento di San Pietroburgo si trova nella situazione giusta per giocare un ruolo chiave nella crescita di Nissan in Russia nei prossimi 10 anni.\u201d<\/p>\n<p>Lo stabilimento opera nel pieno rispetto del sistema APW (Alliance Production Way) e nel 2012 e 2014 \u00e8 stato designato quale &#8220;Migliore Fabbrica per qualit\u00e0 del prodotto&#8221; tra tutti gli impianti di produzione Nissan nel mondo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nissan ha celebrato il 10o anniversario dello stabilimento in Russia con l\u2019inizio della produzione del nuovo crossover Murano. Riaffermando l\u2019impegno nei confronti della Russia, il Murano di terza generazione rappresenta il completamento di un investimento di 167 milioni di Euro in nuovi modelli crossover e infrastrutture che hanno raddoppiato le capacit\u00e0 di produzione a San [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25833,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[294],"tags":[],"class_list":["post-25832","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nissan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NUOVO NISSAN MURANO PER IL 10O ANNIVERSARIO  DELLO STABILIMENTO DI SAN PIETROBURGO - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUOVO NISSAN MURANO PER IL 10O ANNIVERSARIO  DELLO STABILIMENTO DI SAN PIETROBURGO - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Nissan ha celebrato il 10o anniversario dello stabilimento in Russia con l\u2019inizio della produzione del nuovo crossover Murano. Riaffermando l\u2019impegno nei confronti della Russia, il Murano di terza generazione rappresenta il completamento di un investimento di 167 milioni di Euro in nuovi modelli crossover e infrastrutture che hanno raddoppiato le capacit\u00e0 di produzione a San [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-22T23:05:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/unnamed53.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"824\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"NUOVO NISSAN MURANO PER IL 10O ANNIVERSARIO DELLO STABILIMENTO DI SAN PIETROBURGO\",\"datePublished\":\"2016-06-22T23:05:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\\\/\"},\"wordCount\":845,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/unnamed53.jpg\",\"articleSection\":[\"Nissan\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\\\/\",\"name\":\"NUOVO NISSAN MURANO PER IL 10O ANNIVERSARIO DELLO STABILIMENTO DI SAN PIETROBURGO - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/unnamed53.jpg\",\"datePublished\":\"2016-06-22T23:05:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/unnamed53.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/unnamed53.jpg\",\"width\":824,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUOVO NISSAN MURANO PER IL 10O ANNIVERSARIO DELLO STABILIMENTO DI SAN PIETROBURGO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUOVO NISSAN MURANO PER IL 10O ANNIVERSARIO  DELLO STABILIMENTO DI SAN PIETROBURGO - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/","og_locale":"it_IT","og_type":"article","og_title":"NUOVO NISSAN MURANO PER IL 10O ANNIVERSARIO  DELLO STABILIMENTO DI SAN PIETROBURGO - AbmNews","og_description":"Nissan ha celebrato il 10o anniversario dello stabilimento in Russia con l\u2019inizio della produzione del nuovo crossover Murano. Riaffermando l\u2019impegno nei confronti della Russia, il Murano di terza generazione rappresenta il completamento di un investimento di 167 milioni di Euro in nuovi modelli crossover e infrastrutture che hanno raddoppiato le capacit\u00e0 di produzione a San [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2016-06-22T23:05:37+00:00","og_image":[{"width":824,"height":550,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/unnamed53.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"NUOVO NISSAN MURANO PER IL 10O ANNIVERSARIO DELLO STABILIMENTO DI SAN PIETROBURGO","datePublished":"2016-06-22T23:05:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/"},"wordCount":845,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/unnamed53.jpg","articleSection":["Nissan"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/","url":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/","name":"NUOVO NISSAN MURANO PER IL 10O ANNIVERSARIO DELLO STABILIMENTO DI SAN PIETROBURGO - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/unnamed53.jpg","datePublished":"2016-06-22T23:05:37+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/unnamed53.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2016\/06\/unnamed53.jpg","width":824,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/nuovo-nissan-murano-per-il-10o-anniversario-dello-stabilimento-di-san-pietroburgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"NUOVO NISSAN MURANO PER IL 10O ANNIVERSARIO DELLO STABILIMENTO DI SAN PIETROBURGO"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=25832"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25832\/revisions"}],"predecessor-version":[{"id":25834,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/25832\/revisions\/25834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/25833"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=25832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=25832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=25832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}