{"id":28688,"date":"2017-01-07T13:29:58","date_gmt":"2017-01-07T12:29:58","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=28688"},"modified":"2017-01-11T13:49:08","modified_gmt":"2017-01-11T12:49:08","slug":"dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/","title":{"rendered":"Dakar 2017. Il Maltempo annulla la Tappa, e i leoni del  team Peugeot affilano gli artigli"},"content":{"rendered":"<p>Le avverse condizioni meteo costringono gli Organizzatori ad annullare la quinta frazione. I piloti avranno a disposizione due giorni per riposarsi, in vista del rush finale verso Buenos Aires. Con Peugeot che si avvicina sempre pi\u00f9 alla meta\u2026<\/p>\n<p>Oruro, Bolivia, 7 gennaio 2017. Gli annullamenti di tappa causati dal maltempo non sono una novit\u00e0, in questa veste sudamericana della Dakar. Come comunicato ufficialmente dall\u2019organizzazione, quando in Bolivia era notte fonda, \u201cci sono piloti che si trovano nella speciale del giorno; considerando che \u00e8 impossibile far tornare tutti i partecipanti al bivacco e preparare la prova nelle condizioni migliori e tenendo conto che alcune persone incaricate di fare la ricognizione del tracciato della Tappa 7 hanno affermato che il percorso \u00e8 impraticabile, la tappa che va da Oruro a La Paz \u00e8 stata annullata\u201d.<\/p>\n<p>Ci\u00f2 fa sorridere i tre moschettieri di Peugeot, che potranno tenere le loro \u201clame\u201d; le 3008 DKR, nel fodero per tutta la durata del fine settimana, pronti tuttavia a sguainarle ancora una volta luned\u00ec, quando saranno chiamati ad affrontare la settima frazione, da La Paz a Uyuni, con 322 km contro il tempo da vivere tutti d\u2019un fiato. Buenos Aires si avvicina!<\/p>\n<p>cronaca rally<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le avverse condizioni meteo costringono gli Organizzatori ad annullare la quinta frazione. I piloti avranno a disposizione due giorni per riposarsi, in vista del rush finale verso Buenos Aires. Con Peugeot che si avvicina sempre pi\u00f9 alla meta\u2026 Oruro, Bolivia, 7 gennaio 2017. Gli annullamenti di tappa causati dal maltempo non sono una novit\u00e0, in [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":28691,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6459,300,346],"tags":[80],"class_list":["post-28688","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dakar-2017","category-peugeot","category-video","tag-featured"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dakar 2017. Il Maltempo annulla la Tappa, e i leoni del team Peugeot affilano gli artigli - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dakar 2017. Il Maltempo annulla la Tappa, e i leoni del team Peugeot affilano gli artigli - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Le avverse condizioni meteo costringono gli Organizzatori ad annullare la quinta frazione. I piloti avranno a disposizione due giorni per riposarsi, in vista del rush finale verso Buenos Aires. Con Peugeot che si avvicina sempre pi\u00f9 alla meta\u2026 Oruro, Bolivia, 7 gennaio 2017. Gli annullamenti di tappa causati dal maltempo non sono una novit\u00e0, in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-07T12:29:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-11T12:49:08+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/01\/dakar_2017-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Dakar 2017. Il Maltempo annulla la Tappa, e i leoni del team Peugeot affilano gli artigli\",\"datePublished\":\"2017-01-07T12:29:58+00:00\",\"dateModified\":\"2017-01-11T12:49:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\\\/\"},\"wordCount\":206,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/dakar_2017-4.jpg\",\"keywords\":[\"Featured\"],\"articleSection\":[\"DAKAR 2017\",\"Peugeot\",\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\\\/\",\"name\":\"Dakar 2017. Il Maltempo annulla la Tappa, e i leoni del team Peugeot affilano gli artigli - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/dakar_2017-4.jpg\",\"datePublished\":\"2017-01-07T12:29:58+00:00\",\"dateModified\":\"2017-01-11T12:49:08+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/dakar_2017-4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/dakar_2017-4.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dakar 2017. Il Maltempo annulla la Tappa, e i leoni del team Peugeot affilano gli artigli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dakar 2017. Il Maltempo annulla la Tappa, e i leoni del team Peugeot affilano gli artigli - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/","og_locale":"it_IT","og_type":"article","og_title":"Dakar 2017. Il Maltempo annulla la Tappa, e i leoni del team Peugeot affilano gli artigli - AbmNews","og_description":"Le avverse condizioni meteo costringono gli Organizzatori ad annullare la quinta frazione. I piloti avranno a disposizione due giorni per riposarsi, in vista del rush finale verso Buenos Aires. Con Peugeot che si avvicina sempre pi\u00f9 alla meta\u2026 Oruro, Bolivia, 7 gennaio 2017. Gli annullamenti di tappa causati dal maltempo non sono una novit\u00e0, in [&hellip;]","og_url":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2017-01-07T12:29:58+00:00","article_modified_time":"2017-01-11T12:49:08+00:00","og_image":[{"width":1024,"height":683,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/01\/dakar_2017-4.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Dakar 2017. Il Maltempo annulla la Tappa, e i leoni del team Peugeot affilano gli artigli","datePublished":"2017-01-07T12:29:58+00:00","dateModified":"2017-01-11T12:49:08+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/"},"wordCount":206,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/01\/dakar_2017-4.jpg","keywords":["Featured"],"articleSection":["DAKAR 2017","Peugeot","Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/","url":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/","name":"Dakar 2017. Il Maltempo annulla la Tappa, e i leoni del team Peugeot affilano gli artigli - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/01\/dakar_2017-4.jpg","datePublished":"2017-01-07T12:29:58+00:00","dateModified":"2017-01-11T12:49:08+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/01\/dakar_2017-4.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2017\/01\/dakar_2017-4.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/dakar-2017-il-maltempo-annulla-la-tappa-e-i-leoni-del-team-peugeot-affilano-gli-artigli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Dakar 2017. Il Maltempo annulla la Tappa, e i leoni del team Peugeot affilano gli artigli"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/28688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=28688"}],"version-history":[{"count":3,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/28688\/revisions"}],"predecessor-version":[{"id":28694,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/28688\/revisions\/28694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/28691"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=28688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=28688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=28688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}