{"id":35214,"date":"2019-04-09T15:42:01","date_gmt":"2019-04-09T13:42:01","guid":{"rendered":"http:\/\/abmnews.com\/blog\/?p=35214"},"modified":"2019-04-09T15:42:01","modified_gmt":"2019-04-09T13:42:01","slug":"europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/","title":{"rendered":"EUROPCAR LANCIA IN ITALIA SMART WAY, PER UNA CUSTOMER EXPERIENCE SEMPRE PIU\u2019 DIGITAL"},"content":{"rendered":"<p><strong>Europcar<\/strong>\u2013 brand leader dell\u2019autonoleggio in Europa e parte di Europcar Mobility Group, uno dei principali player nel settore della mobilit\u00e0 \u2013 e <strong>Manet Mobile Solutions<\/strong>\u2013 azienda innovativa che opera con soluzioni digitali in ambito travel e turismo\u2013 lanciano in Italia <strong>Smart Way, uno smartphone che offre ai Clienti la possibilit\u00e0 di accedere a numerosi servizi che rendono pi\u00f9 facile viaggiare<\/strong>a bordo di un\u2019auto Europcar.<\/p>\n<p>&nbsp;<\/p>\n<p>Smart Way \u00e8 un device che i Clienti Europcar, italiani e stranieri, possono prenotare insieme all\u2019auto oppure richiedere direttamente al banco Europcar al momento del ritiro della vettura.<\/p>\n<p>Utilizzare Smart Way \u00e8 facile. Basta registrarsi in pochi facili step, scegliere la lingua tra le 10 disponibili e poi accedere ai diversi servizi tramite un semplice tap sulle relative icone:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Chiamate nazionali e internazionali illimitate<\/li>\n<li>Internet 4G illimitato<\/li>\n<li>Connessione in Hotspot di 6 dispositivi<\/li>\n<li>Audioguide gratuite delle citt\u00e0 e dei luoghi d\u2019interesse<\/li>\n<li>Geo-localizzazione dei luoghi d\u2019interesse con descrizioni, contatti, orari di apertura, indicazioni stradali<\/li>\n<li>Traduttore, convertitore di valuta, numeri di emergenza, Info su deposito bagagli e parcheggi<\/li>\n<li>Acquisto biglietti per musei, luoghi di interesse, teatri, concerti ed eventi<\/li>\n<li>Sezione Europcar dedicata attraverso la quale \u00e8 possibile accedere ai numeri utili per il proprio noleggio e trovare in ogni momento l\u2019ufficio Europcar pi\u00f9 vicino<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Smart Way \u00e8 stato lanciato nel mese di marzo e al momento \u00e8 disponibile negli uffici di noleggio presenti negli Aeroporti di Bergamo, Catania, Fiumicino, Malpensa, Napoli, Pisa e Venezia ad un prezzo di lancio particolarmente vantaggioso. Inoltre per tutte le vetture Top di Gamma il dispositivo \u00e8 incluso nel noleggio.<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201cManet nasce con l\u2019obiettivo di fornire un upgrade dell\u2019esperienza di viaggio<\/em><em>consentendo una connettivit\u00e0 gratuita e illimitata e l\u2019accesso diretto ad una serie di servizi. <\/em>-racconta <strong>Antonio Calia, CEO Manet Mobile Solutions<\/strong>&#8211; <em>L&#8217;approccio di Europcar focalizzato sull&#8217;esperienza del cliente con una forte vocazione alla digitalizzazione ha guidato una naturale partnership e la nascita di Smart Way\u201d<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201c<em>Per Europcar Mobility Group la digitalizzazione e l\u2019innovazione sono parole chiave<\/em>&#8211; dichiara <strong>Riccardo Mastrovincenzo, Sales &amp; Marketing Director Europcar Mobility Group in Italia<\/strong>.<em>Il lancio di Smart Way in Italia, in collaborazione con un brand leader come Manet, \u00e8 in linea con l\u2019approccio Customer Centric del Gruppo che mira ad offrire servizi di mobilit\u00e0 innovativi e su misura per le esigenze dei diversi segmenti di clientela ottimizzando, al contempo, il loro Customer Journey. Lo stesso approccio ci caratterizza sempre pi\u00f9 come \u201cMobility Service Company\u201d, con un ampio portfolio di servizi in grado di offrire una valida alternativa all\u2019auto di propriet\u00e0.\u201d<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><strong>Europcar Mobility Group in Italia<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Europcar Mobility Group in Italia fa parte di Europcar Mobility Group e opera sul territorio con i brand <strong>Europcar, Interrent, Goldcar e Ubeeqo.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Nell\u2019ambito del <strong>car rental<\/strong><strong>Europcar <\/strong>offreil noleggio di auto e veicoli commerciali a breve termine a clienti privati e business; per il target business ci sono ora anche soluzioni a medio termine. Con<strong>Goldcar e Interrent<\/strong>viene presidiata la fascia low cost.<\/li>\n<\/ul>\n<p>La flotta di picco in Italia ammonta a 50.000 veicoli e sono circa 1milione i turisti nazionali ed internazionali che noleggiano veicoli in Italia ogni anno.<\/p>\n<ul>\n<li><strong>Ubeeqo<\/strong>\u00e8 invece il brand di <strong>car sharing<\/strong>del Gruppo e in italia \u00e8 presente dal 2017 come soluzione di open car sharing a postazioni fisse nella citt\u00e0 di Milano (con 150 veicoli) ma anche di corporate car sharing su tutto il territorio, offrendo alle aziende la possibilit\u00e0 di ottimizzare la gestione delle flotte ed i relativi costi.<\/li>\n<\/ul>\n<p>Per ulteriori informazioni:<\/p>\n<p><a href=\"http:\/\/www.europcar.it\/\">www.europcar.it<\/a><\/p>\n<p><a href=\"http:\/\/www.ubeeqo.com\/\">www.ubeeqo.com<\/a><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><strong>Manet Mobile Solutions<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Manet Mobile Solutions \u00e8 un\u2019azienda nata a Roma con il supporto di LVenture Group, holding di partecipazioni quotata sul MTA di Borsa Italiana e del suo acceleratore LUISS EnLabs, originato da una joint venture con l\u2019Universit\u00e0 LUISS.<\/p>\n<p>Manet Mobile Solutions propone una soluzione tecnologica innovativa, composta di uno smartphone e una dashboard web, che si rivolge agli operatori del settore del turismo, in Italia e all\u2019estero, con l\u2019obiettivo di fare un upgrade dell\u2019esperienza di viaggio dei loro clienti.<\/p>\n<ul>\n<li>Lo smartphone \u00e8 completamente personalizzabile per includere specifiche informazioni o servizi e offre al turista chiamate e connettivit\u00e0 illimitate oltre a consigli di viaggio, guide e altri strumenti utili al viaggiatore.<\/li>\n<li>La dashboard \u00e8 uno strumento di Customer Relationship Management al servizio degli operatori del settore turistico per monitorare e comunicare con i propri clienti, promuovere i servizi.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.manetmobile.com\/\">www.manetmobile.com<\/a><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Europcar\u2013 brand leader dell\u2019autonoleggio in Europa e parte di Europcar Mobility Group, uno dei principali player nel settore della mobilit\u00e0 \u2013 e Manet Mobile Solutions\u2013 azienda innovativa che opera con soluzioni digitali in ambito travel e turismo\u2013 lanciano in Italia Smart Way, uno smartphone che offre ai Clienti la possibilit\u00e0 di accedere a numerosi servizi [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":35215,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6345],"tags":[],"class_list":["post-35214","post","type-post","status-publish","format-standard","has-post-thumbnail","category-europcar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EUROPCAR LANCIA IN ITALIA SMART WAY, PER UNA CUSTOMER EXPERIENCE SEMPRE PIU\u2019 DIGITAL - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EUROPCAR LANCIA IN ITALIA SMART WAY, PER UNA CUSTOMER EXPERIENCE SEMPRE PIU\u2019 DIGITAL - AbmNews\" \/>\n<meta property=\"og:description\" content=\"Europcar\u2013 brand leader dell\u2019autonoleggio in Europa e parte di Europcar Mobility Group, uno dei principali player nel settore della mobilit\u00e0 \u2013 e Manet Mobile Solutions\u2013 azienda innovativa che opera con soluzioni digitali in ambito travel e turismo\u2013 lanciano in Italia Smart Way, uno smartphone che offre ai Clienti la possibilit\u00e0 di accedere a numerosi servizi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-09T13:42:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/04\/Home-ITA-Def.png\" \/>\n\t<meta property=\"og:image:width\" content=\"413\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"EUROPCAR LANCIA IN ITALIA SMART WAY, PER UNA CUSTOMER EXPERIENCE SEMPRE PIU\u2019 DIGITAL\",\"datePublished\":\"2019-04-09T13:42:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\\\/\"},\"wordCount\":739,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Home-ITA-Def.png\",\"articleSection\":[\"Europcar\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\\\/\",\"name\":\"EUROPCAR LANCIA IN ITALIA SMART WAY, PER UNA CUSTOMER EXPERIENCE SEMPRE PIU\u2019 DIGITAL - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Home-ITA-Def.png\",\"datePublished\":\"2019-04-09T13:42:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Home-ITA-Def.png\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Home-ITA-Def.png\",\"width\":413,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EUROPCAR LANCIA IN ITALIA SMART WAY, PER UNA CUSTOMER EXPERIENCE SEMPRE PIU\u2019 DIGITAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EUROPCAR LANCIA IN ITALIA SMART WAY, PER UNA CUSTOMER EXPERIENCE SEMPRE PIU\u2019 DIGITAL - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/","og_locale":"it_IT","og_type":"article","og_title":"EUROPCAR LANCIA IN ITALIA SMART WAY, PER UNA CUSTOMER EXPERIENCE SEMPRE PIU\u2019 DIGITAL - AbmNews","og_description":"Europcar\u2013 brand leader dell\u2019autonoleggio in Europa e parte di Europcar Mobility Group, uno dei principali player nel settore della mobilit\u00e0 \u2013 e Manet Mobile Solutions\u2013 azienda innovativa che opera con soluzioni digitali in ambito travel e turismo\u2013 lanciano in Italia Smart Way, uno smartphone che offre ai Clienti la possibilit\u00e0 di accedere a numerosi servizi [&hellip;]","og_url":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2019-04-09T13:42:01+00:00","og_image":[{"width":413,"height":800,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/04\/Home-ITA-Def.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"EUROPCAR LANCIA IN ITALIA SMART WAY, PER UNA CUSTOMER EXPERIENCE SEMPRE PIU\u2019 DIGITAL","datePublished":"2019-04-09T13:42:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/"},"wordCount":739,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/04\/Home-ITA-Def.png","articleSection":["Europcar"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/","url":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/","name":"EUROPCAR LANCIA IN ITALIA SMART WAY, PER UNA CUSTOMER EXPERIENCE SEMPRE PIU\u2019 DIGITAL - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/04\/Home-ITA-Def.png","datePublished":"2019-04-09T13:42:01+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/04\/Home-ITA-Def.png","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/04\/Home-ITA-Def.png","width":413,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/europcar-lancia-in-italia-smart-way-per-una-customer-experience-sempre-piu-digital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"EUROPCAR LANCIA IN ITALIA SMART WAY, PER UNA CUSTOMER EXPERIENCE SEMPRE PIU\u2019 DIGITAL"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/35214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=35214"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/35214\/revisions"}],"predecessor-version":[{"id":35216,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/35214\/revisions\/35216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/35215"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=35214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=35214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=35214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}