{"id":35955,"date":"2019-09-07T18:48:03","date_gmt":"2019-09-07T16:48:03","guid":{"rendered":"http:\/\/new.abmnews.com\/blog\/?p=35955"},"modified":"2019-09-07T18:49:34","modified_gmt":"2019-09-07T16:49:34","slug":"la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/","title":{"rendered":"La produzione della ID.3 inizier\u00e0 a novembre nella fabbrica di Zwickau"},"content":{"rendered":"\n<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Il conto alla rovescia procede: a novembre, la produzione di serie della ID.3 inizier\u00e0 nella fabbrica di Zwickau. In questi giorni, vengono installati gli ultimi robot e avviata la linea di assemblaggio. La ID.3 \u00e8 il primo modello di una generazione completamente nuova di auto elettriche basate sulla piattaforma modulare elettrica della Volkswagen (MEB). La ID.3 debutter\u00e0 in anteprima mondiale il 9 settembre al Salone di Francoforte. Le prime vetture verranno consegnate ai Clienti la prossima estate. Con la ID.3, la Volkswagen lancia la pi\u00f9 grande offensiva elettrica dell\u2019industria automobilistica a livello globale. Solo nei prossimi tre anni, \u00e8 previsto l\u2019avvio dellaproduzione di 33 modelli MEB delle Marche di grande serie del Gruppo Volkswagen.<\/p>\n<\/div>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>La conversione dello stabilimento di Zwickau<\/p>\n<p>A Zwickau, per la prima volta la Volkswagen sta convertendo l\u2019interostabilimento dal 100% della produzione di auto a combustione interna al 100% di auto elettriche.<\/p>\n<\/div>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\u00a0<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Il passaggio all\u2019elettrico \u00e8 stato avviato a inizio 2018 e sar\u00e0 completato a fine 2020, un totale di circa tre anni. I reparti carrozzeria e verniciatura sono gi\u00e0 stati in buona parte preparati per la produzione della ID.3. Una delle due linee di assemblaggio \u00e8 gi\u00e0 stata completata. Qui, a novembre la produzione della ID.3 inizier\u00e0 per andare a regime progressivamente. Un totale di 12 nuovi edifici o parti di edifici sono attualmente in costruzione nello stabilimento. Il precedente reparto presse \u00e8 stato gi\u00e0 ampliato e preparato per la nuova era con un investimento totale di 75 milioni di Euro. Questo permetter\u00e0 allo stabilimento di Zwickau di produrre internamente tutti gli elementi principali dei veicoli MEB dal 2021.<\/p>\n<p>La seconda linea di assemblaggio di Zwickau verr\u00e0 modificata a partiredall\u2019estate 2020 ed entrer\u00e0 in funzione lo stesso anno. Al termine dei lavori, dal 2021 sei modelli basati sulla MEB di tre Marche del Gruppo saranno prodotti a Zwickau. La capacit\u00e0 produttiva aumenter\u00e0 da300.000 a 330.000 veicoli l\u2019anno. Ci\u00f2 render\u00e0 Zwickau la fabbrica di auto elettriche pi\u00f9 grande e pi\u00f9 efficiente in Europa. In totale, la Volkswagen sta investendo circa 1,2 miliardi di Euro nella trasformazione di questo stabilimento. A oggi, gli investimenti gi\u00e0 effettuati ammontano a circa 800 milioni di Euro.<\/p>\n<p>Verso una fabbrica ad alta tecnologia<\/p>\n<p>Negli scorsi mesi, oltre 1.600 avanzatissimi robot di produzione sono statiinstallati. In particolare nell\u2019assemblaggio finale, verranno utilizzatetecnologie completamente nuove, come l\u2019installazione automatizzata delrivestimento interno del tetto. In futuro, Zwickau sar\u00e0 in grado di produrre circa 150 auto al giorno in pi\u00f9 (1.500 invece di 1.350) rispetto a prima della trasformazione, grazie alla maggiore automazione. I numero di lavoratori impiegati, invece, rimarr\u00e0 pressoch\u00e9 stabile.<\/p>\n<p>A Zwickau, in totale 8.000 lavoratori si stanno preparando per l\u2019inizio dell\u2019era elettrica. Grazie a una formazione specifica per l\u2019alto voltaggio,stanno imparando come maneggiare correttamente e in sicurezza i moderni sistemi di batterie e i cablaggi elettrici. A oggi, circa 8.000 dei 13.000 giorni totali di formazione sono gi\u00e0 stati fatti. Oltre 2.500 lavoratori sono gi\u00e0 qualificati per la mobilit\u00e0 elettrica.<\/p>\n<\/div>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\u00a0<\/div>\n<\/div>\n<\/div>\n<div title=\"Page 3\">\u00a0<\/div>\n<div class=\"page\" title=\"Page 3\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Anteprima mondiale della ID.3 al Salone di Francoforte<\/p>\n<p>La ID.3 verr\u00e0 mostrata al pubblico di tutto il mondo per la prima volta al Salone di Francoforte. La consegna dei primi esemplari \u00e8 prevista perl\u2019estate 2020. All\u2019inizio, le vetture verranno consegnate ai Clienti che hanno gi\u00e0 ottenuto la possibilit\u00e0 di ordinare uno degli esemplari della edizione di lancio ID.3 1ST con la campagna di pre-booking (www.volkswagen.it\/app\/prebooking\/vw-it\/it). In Europa, sono gi\u00e0 state effettuate oltre 30.000 prenotazioni.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":35956,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[232,262,312,347],"tags":[],"class_list":["post-35955","post","type-post","status-publish","format-standard","has-post-thumbnail","category-auto","category-novita","category-saloni","category-volkswagen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La produzione della ID.3 inizier\u00e0 a novembre nella fabbrica di Zwickau - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La produzione della ID.3 inizier\u00e0 a novembre nella fabbrica di Zwickau - AbmNews\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-07T16:48:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-07T16:49:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/09\/ShowPhoto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1790\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"La produzione della ID.3 inizier\u00e0 a novembre nella fabbrica di Zwickau\",\"datePublished\":\"2019-09-07T16:48:03+00:00\",\"dateModified\":\"2019-09-07T16:49:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\\\/\"},\"wordCount\":560,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ShowPhoto.jpg\",\"articleSection\":[\"AUTO\",\"Novit\u00e0\",\"Saloni\",\"Volkswagen\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\\\/\",\"name\":\"La produzione della ID.3 inizier\u00e0 a novembre nella fabbrica di Zwickau - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ShowPhoto.jpg\",\"datePublished\":\"2019-09-07T16:48:03+00:00\",\"dateModified\":\"2019-09-07T16:49:34+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ShowPhoto.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ShowPhoto.jpg\",\"width\":1790,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La produzione della ID.3 inizier\u00e0 a novembre nella fabbrica di Zwickau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La produzione della ID.3 inizier\u00e0 a novembre nella fabbrica di Zwickau - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/","og_locale":"it_IT","og_type":"article","og_title":"La produzione della ID.3 inizier\u00e0 a novembre nella fabbrica di Zwickau - AbmNews","og_url":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2019-09-07T16:48:03+00:00","article_modified_time":"2019-09-07T16:49:34+00:00","og_image":[{"width":1790,"height":1024,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/09\/ShowPhoto.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"La produzione della ID.3 inizier\u00e0 a novembre nella fabbrica di Zwickau","datePublished":"2019-09-07T16:48:03+00:00","dateModified":"2019-09-07T16:49:34+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/"},"wordCount":560,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/09\/ShowPhoto.jpg","articleSection":["AUTO","Novit\u00e0","Saloni","Volkswagen"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/","url":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/","name":"La produzione della ID.3 inizier\u00e0 a novembre nella fabbrica di Zwickau - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/09\/ShowPhoto.jpg","datePublished":"2019-09-07T16:48:03+00:00","dateModified":"2019-09-07T16:49:34+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/09\/ShowPhoto.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/09\/ShowPhoto.jpg","width":1790,"height":1024},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/la-produzione-della-id-3-iniziera-a-novembre-nella-fabbrica-di-zwickau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La produzione della ID.3 inizier\u00e0 a novembre nella fabbrica di Zwickau"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/35955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=35955"}],"version-history":[{"count":2,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/35955\/revisions"}],"predecessor-version":[{"id":35958,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/35955\/revisions\/35958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/35956"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=35955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=35955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=35955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}