{"id":41583,"date":"2019-12-15T06:20:14","date_gmt":"2019-12-15T05:20:14","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=41583"},"modified":"2019-12-15T06:20:16","modified_gmt":"2019-12-15T05:20:16","slug":"il-senegal-completa-le-tappe-della-extreme-e","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/","title":{"rendered":"IL SENEGAL COMPLETA LE TAPPE DELLA EXTREME E"},"content":{"rendered":"\n<div>\n<p>Lac Rose in Senegal, sulla costa occidentale dell&#8217;Africa, \u00e8 stata svelata oggi come location della gara oceanica per la stagione inaugurale dell&#8217;Extreme E, la nuova e pionieristica serie di corse elettriche off-road che utilizza lo sport per sensibilizzare l&#8217;opinione pubblica sui problemi climatici globali.<\/p>\n<p>Alejandro Agag, fondatore e CEO di Extreme E, si \u00e8 unito ad Abdou Thiam, Presidente della Federazione Senegalese di Motorsport, per l&#8217;annuncio durante la pulizia comunitaria di una spiaggia nel sito di gara proposto a Lac Rose &#8211; noto anche come Lago Retba &#8211; a circa 30 chilometri dalla capitale senegalese Dakar.<\/p>\n<p>Alejandro ha dichiarato: &#8220;Sono entusiasta di confermare il Senegal come location della nostra gara oceanica. Si tratta di un&#8217;area di straordinaria bellezza naturale, ma purtroppo, come molte delle zone costiere del mondo, \u00e8 seriamente minacciata da una serie di problemi climatici\u201d.<\/p>\n<p>&#8220;Questo litorale sta attualmente perdendo dai tre ai quattro metri all&#8217;anno e una delle cause principali \u00e8 lo scioglimento della calotta glaciale della Groenlandia, anche se si trova a pi\u00f9 di 6.500 km di distanza dal Circolo Polare Artico. Con il 30% delle emissioni di CO2 provenienti dai trasporti, che contribuiscono al riscaldamento del pianeta, Extreme E mostrer\u00e0 le prestazioni dei veicoli elettrici, utilizzando un potente mix di azione sportiva, educazione scientifica e storytelling, per accelerare l\u2019adozione della mobilit\u00e0 elettrica in modo da aiutare a rendere il mondo pi\u00f9 sostenibile in maniera pi\u00f9 veloce. Speriamo che Extreme E sia di ispirazione agli appassionati cos\u00ec come alle comunit\u00e0 ed ai governi sia nei luoghi dove gareggeremo sia altrove, per far s\u00ec che le ambizioni climatiche vengano aumentate in uno sforzo unico per limitare il riscaldamento globale a 1.5\u00b0c. Questa \u00e8 una sfida che possiamo &#8211; e dobbiamo &#8211; vincere per evitare di peggiorare significativamente il rischio di temperature estreme, scioglimento dei ghiacciai, innalzamento del livello del mare, siccit\u00e0, inondazioni e tanto altro ancora, per centinaia di milioni di persone, comprese quelle che vivono qui in Senegal\u201d.<\/p>\n<p>Alejandro ha poi aggiunto: &#8220;Oggi, per celebrare il nostro annuncio, siamo lieti di iniziare a lavorare con to.Org, un&#8217;organizzazione locale, per organizzare una pulizia comunitaria della spiaggia della location di gara qui a Lac Rose. La plastica raccolta sar\u00e0 utilizzata per realizzare mattoni ecologici per aiutare a costruire bagni per oltre 300 scolari che attualmente ne hanno a disposizione soltanto due. Questo \u00e8 un primo passo per costruire un rapporto positivo e duraturo con la comunit\u00e0 locale in vista della nostra gara del 2021&#8221;.<\/p>\n<p>Abdou Thiam, Presidente della Federazione Senegalese di Motorsport, ha detto: &#8220;Siamo molto felici di ospitare Extreme E, che \u00e8 sicuramente il futuro del motorsport. Lo sport ha una grande responsabilit\u00e0 nell&#8217;aiutare le persone a comprendere la questione del cambiamento climatico e siamo orgogliosi di far parte di questa avventura&#8221;.<\/p>\n<p>Extreme E \u00e8 un nuovo ed estremo campionato automobilistico che vedr\u00e0 gli E-SUV testa a testa in alcuni degli ambienti pi\u00f9 remoti del mondo. L&#8217;obiettivo \u00e8 quello di evidenziare l&#8217;impatto che i cambiamenti climatici e le interferenze umane stanno gi\u00e0 avendo su questi ecosistemi, promuovendo al contempo l&#8217;adozione di veicoli elettrici per contribuire a preservare l&#8217;ambiente e \u00a0proteggere il pianeta.<\/p>\n<p>Il Senegal \u00e8 la quinta e ultima location ad essere svelata per la Stagione 1, unendosi a Kangerlussuaq in Groenlandia, alla Foresta Amazzonica in Brasile, all&#8217;Arabia Saudita e all&#8217;Himalaya in Nepal.<\/p>\n<p>To.Org \u00e8 un propulsore per le iniziative pi\u00f9 importanti della terra. La sua presenza a Dakar mira a riunire i partner per affrontare le questioni sociali e ambientali pi\u00f9 critiche della regione &#8211; aumento del livello del mare, degrado dell&#8217;ecosistema marino e desertificazione &#8211; colpita dalla pesca eccessiva, da una gestione inadeguata dei rifiuti e dai cambiamenti climatici. Extreme E ha utilizzato la conoscenza unica di To.Org del Senegal per identificare il Lac Rose come location di gara.<\/p>\n<\/div>\n<p>Nachson Mimran, co-fondatore e CEO di to.Org, ha detto: \u201cSono cresciuto in Senegal, ho vissuto in prima persona le sfide che la regione del Sahel deve affrontare a causa dei cambiamenti climatici. Queste sfide rendono il Senegal una scelta vincente per il debutto della Extreme E.<\/p>\n<p>Extreme E \u00e8 una serie moderna ed ecologica, con la mission offrire un lascito positivo e che lavorer\u00e0 con le istituzioni locali aiutandole ad affrontare i problemi del Senegal. \u00c8 stimolante accogliere un campionato come questo nel nostro Paese\u201d.<\/p>\n<p>Oltre a lavorare con le comunit\u00e0 locali, Extreme E si avvarr\u00e0 anche di scienziati di fama mondiale per fornire consulenza sulle iniziative di ricerca e sui programmi educativi in ogni localit\u00e0. La dottoressa Lucy Woodall \u00e8 una delle principali scienziate della Nekton Foundation, specializzata nella comprensione dell\u2019impatto dell&#8217;uomo sull&#8217;ambiente marino.<\/p>\n<p>Lucy Woodall ha commentato: &#8220;Per avere un pianeta sano, dobbiamo avere un oceano sano. Le attivit\u00e0 umane hanno avuto un impatto sull&#8217;oceano per decenni e recentemente gli effetti sono diventati pi\u00f9 visibili. Il pi\u00f9 evidente di questi \u00e8 l&#8217;innalzamento del livello del mare. Il rapido innalzamento del livello del mare \u00e8 una conseguenza del cambiamento climatico indotto dall\u2019uomo. Ci\u00f2 comporta una minore stabilit\u00e0 degli ecosistemi costieri e una diminuzione della biodiversit\u00e0. Inoltre, l&#8217;innalzamento del livello del mare aumenta il rischio per le comunit\u00e0 costiere poich\u00e9 perdono la loro protezione biologica &#8211; mangrovie, foreste e barriere coralline &#8211; dalle tempeste. L&#8217;innalzamento del livello del mare \u00e8 quindi un disastro per la biodiversit\u00e0 marina e per l\u2019uomo, da cui ne dipende la sopravvivenza. Extreme E offre una nuova ed eccitante piattaforma per mettere in evidenza questi importanti temi e sono interessata a vedere lo sport usato in questo modo per sensibilizzare l&#8217;opinione pubblica&#8221;.<\/p>\n<p>Le gare in Senegal si svolgeranno in tre giorni, all&#8217;interno di un&#8217;area non superiore a 10 kmq. Agli ideatori della pista \u00e8 stato affidato il compito di selezionare attentamente le opzioni di percorso che possono offrire una gara pi\u00f9 competitiva ed emozionante.<\/p>\n<p>In Senegal banchi di sabbia, sale, ghiaia, rocce e ondulazioni offriranno ai piloti della serie, ai team e alla vettura prototipo ODYSSEY 21 E-SUV una vera e propria sfida, mentre percorreranno le strette piste di sabbia off-road nel suggestivo paesaggio del Lac Rose con l\u2019Oceano Atlantico sullo sfondo.<\/p>\n<p>I percorsi saranno strutturati per unire gli ostacoli e gli elementi esistenti a cambiamenti di quota e salti, al fine di ridurre al minimo l&#8217;impatto ambientale. La serie ci porter\u00e0 sui sentieri gi\u00e0 esistenti che circondano il lago, rinomato per il suo suggestivo colore rosa causato dalle alghe che crescono nelle sue acque altamente salmastre.<\/p>\n<p>Ulteriori notizie su team, partner e piloti saranno rivelate nelle prossime settimane, con la campagna inaugurale che prender\u00e0 il via a febbraio 2021. Il calendario completo della Stagione 1 sar\u00e0 annunciato il 17 dicembre.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":41584,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[7853,293],"tags":[],"class_list":["post-41583","post","type-post","status-publish","format-standard","has-post-thumbnail","category-motorsport","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL SENEGAL COMPLETA LE TAPPE DELLA EXTREME E - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL SENEGAL COMPLETA LE TAPPE DELLA EXTREME E - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-15T05:20:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-15T05:20:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/m1081_crop169014_1024x576_proportional_15742472333375.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"864\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-senegal-completa-le-tappe-della-extreme-e\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-senegal-completa-le-tappe-della-extreme-e\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"IL SENEGAL COMPLETA LE TAPPE DELLA EXTREME E\",\"datePublished\":\"2019-12-15T05:20:14+00:00\",\"dateModified\":\"2019-12-15T05:20:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-senegal-completa-le-tappe-della-extreme-e\\\/\"},\"wordCount\":1102,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-senegal-completa-le-tappe-della-extreme-e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/m1081_crop169014_1024x576_proportional_15742472333375.jpg\",\"articleSection\":[\"Motorsport\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-senegal-completa-le-tappe-della-extreme-e\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-senegal-completa-le-tappe-della-extreme-e\\\/\",\"name\":\"IL SENEGAL COMPLETA LE TAPPE DELLA EXTREME E - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-senegal-completa-le-tappe-della-extreme-e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-senegal-completa-le-tappe-della-extreme-e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/m1081_crop169014_1024x576_proportional_15742472333375.jpg\",\"datePublished\":\"2019-12-15T05:20:14+00:00\",\"dateModified\":\"2019-12-15T05:20:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-senegal-completa-le-tappe-della-extreme-e\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-senegal-completa-le-tappe-della-extreme-e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-senegal-completa-le-tappe-della-extreme-e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/m1081_crop169014_1024x576_proportional_15742472333375.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/m1081_crop169014_1024x576_proportional_15742472333375.jpg\",\"width\":864,\"height\":576,\"caption\":\"| Driver: Kevin Hansen| Car: Odyssey 21|| Photographer: Shivraj Gohil| Event: Extreme E Testing October 2019| Location: Chateau De Lastours| Series: Extreme E| Country: France |\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-senegal-completa-le-tappe-della-extreme-e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL SENEGAL COMPLETA LE TAPPE DELLA EXTREME E\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL SENEGAL COMPLETA LE TAPPE DELLA EXTREME E - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/","og_locale":"it_IT","og_type":"article","og_title":"IL SENEGAL COMPLETA LE TAPPE DELLA EXTREME E - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2019-12-15T05:20:14+00:00","article_modified_time":"2019-12-15T05:20:16+00:00","og_image":[{"width":864,"height":576,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/m1081_crop169014_1024x576_proportional_15742472333375.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"IL SENEGAL COMPLETA LE TAPPE DELLA EXTREME E","datePublished":"2019-12-15T05:20:14+00:00","dateModified":"2019-12-15T05:20:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/"},"wordCount":1102,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/m1081_crop169014_1024x576_proportional_15742472333375.jpg","articleSection":["Motorsport","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/","url":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/","name":"IL SENEGAL COMPLETA LE TAPPE DELLA EXTREME E - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/m1081_crop169014_1024x576_proportional_15742472333375.jpg","datePublished":"2019-12-15T05:20:14+00:00","dateModified":"2019-12-15T05:20:16+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/m1081_crop169014_1024x576_proportional_15742472333375.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/m1081_crop169014_1024x576_proportional_15742472333375.jpg","width":864,"height":576,"caption":"| Driver: Kevin Hansen| Car: Odyssey 21|| Photographer: Shivraj Gohil| Event: Extreme E Testing October 2019| Location: Chateau De Lastours| Series: Extreme E| Country: France |"},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/il-senegal-completa-le-tappe-della-extreme-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"IL SENEGAL COMPLETA LE TAPPE DELLA EXTREME E"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/41583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=41583"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/41583\/revisions"}],"predecessor-version":[{"id":41585,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/41583\/revisions\/41585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/41584"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=41583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=41583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=41583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}