{"id":41595,"date":"2019-12-15T14:28:18","date_gmt":"2019-12-15T13:28:18","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=41595"},"modified":"2019-12-15T14:28:21","modified_gmt":"2019-12-15T13:28:21","slug":"nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/","title":{"rendered":"NUOVI SPAZI DEDICATI AL REFITTING E AL BROKERAGE,  LA GALLERY DEL LUSSO E IL MATCHING B2B"},"content":{"rendered":"\n<p>\u00a0Una piattaforma di matching b2b sempre pi\u00f9 profilata, un\u2019area dedicata al lusso che accoglie il <em>bello e ben fatto<\/em>tipicamente italiano, e nuovi spazi pronti a ospitare le aziende del mondo del refitting e brokerage. Sono solo alcune novit\u00e0 della quarta edizione di <strong>Versilia Yachting Rendez-vous<\/strong>, l\u2019appuntamento dedicato alla nautica d\u2019eccellenza in programma dal 28 al 31 maggio 2020 a Viareggio.<\/p>\n<p>Il prossimo anno l\u2019evento si svolger\u00e0 per la prima volta alla fine di maggio e all\u2019interno della darsena Viareggio: un momento dell\u2019anno ritenuto molto favorevole dagli operatori del settore, in una darsena pi\u00f9 strutturata per accogliere imbarcazioni di grandi dimensioni.<\/p>\n<p><strong>I NUOVI SPAZI<\/strong> \u2013 La nuova area \u201cGallery\u201d, un\u2019accogliente tensostruttura all\u2019ingresso della manifestazione, ospiter\u00e0 le maison del lusso, dell\u2019artigianato e gli interior designer per far scoprire al visitatore le nuove tendenze del settore.\u00a0Spazio in acqua dedicato al brokerage e ai charter, dove i migliori professionisti del settore assisteranno i visitatori durante il processo di acquisto o di vendita di un\u2019imbarcazione. I Broker presenti accompagneranno i visitatori nella scelta, nella strategia per la vendita dell\u2019usato e nelle pratiche finanziarie. La banchina ospiter\u00e0 tutte le aziende specializzate in servizi dedicati ai futuri armatori: finanziamenti e leasing, perizie commerciali e tecniche, pratiche nautiche, consulenza assicurativa, restyling imbarcazioni. Non mancheranno i Tender &amp; Toys, irrinunciabili accessori per il divertimento in navigazione, la componentistica e i motori. \u00a0<\/p>\n<p><strong>MATCHING B2B<\/strong> \u2013 Favorire il dialogo B2B e promuovere l\u2019incontro tra domanda e offerta, attraverso opportunit\u00e0 di business concrete. Questo l\u2019obiettivo del sistema My Matching (a cura di Fiera Milano) che Versilia Yachting Rendez-vous metter\u00e0 a disposizione degli espositori e operatori. Attraverso l\u2019utilizzo di questa piattaforma, sar\u00e0 possibile ricercare gli operatori e i produttori di proprio interesse e fissare appuntamenti per i giorni di manifestazione prima che l\u2019evento abbia inizio. Grazie a My Matching l\u2019espositore potr\u00e0 conoscere e contattare prima della manifestazione i buyer selezionati da Fiera Milano e fissare gli appuntamenti in largo anticipo, ottimizzando cos\u00ec il tempo dedicato al business durante l\u2019evento espositivo.<\/p>\n<p><strong>HOSPITALITY <\/strong>\u2013 Anche per l\u2019edizione 2020 di Versilia Yachting Rendez-vous sar\u00e0 attivo il servizio \u201cHospitality\u201d a cura di MiCodmc (societ\u00e0 del Gruppo Fiera Milano) per assistere i clienti nell\u2019organizzazione del loro viaggio a Viareggio offrendo soluzioni innovative e personalizzate con servizi di accomodation, intrattenimento e proposte di tour ed escursioni personalizzate su misura del cliente.<\/p>\n<p>Ti aspettiamo a Viareggio dal 28 al 31 maggio al Versilia Yachting Rendez-vous\u2026 <em>the wonder is coming!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":41596,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[7880,293],"tags":[],"class_list":["post-41595","post","type-post","status-publish","format-standard","has-post-thumbnail","category-barche","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NUOVI SPAZI DEDICATI AL REFITTING E AL BROKERAGE, LA GALLERY DEL LUSSO E IL MATCHING B2B - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUOVI SPAZI DEDICATI AL REFITTING E AL BROKERAGE, LA GALLERY DEL LUSSO E IL MATCHING B2B - AbmNews\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-15T13:28:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-15T13:28:21+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/2.-VYR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"NUOVI SPAZI DEDICATI AL REFITTING E AL BROKERAGE, LA GALLERY DEL LUSSO E IL MATCHING B2B\",\"datePublished\":\"2019-12-15T13:28:18+00:00\",\"dateModified\":\"2019-12-15T13:28:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\\\/\"},\"wordCount\":430,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/2.-VYR.jpg\",\"articleSection\":[\"Barche\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\\\/\",\"name\":\"NUOVI SPAZI DEDICATI AL REFITTING E AL BROKERAGE, LA GALLERY DEL LUSSO E IL MATCHING B2B - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/2.-VYR.jpg\",\"datePublished\":\"2019-12-15T13:28:18+00:00\",\"dateModified\":\"2019-12-15T13:28:21+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/2.-VYR.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/2.-VYR.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUOVI SPAZI DEDICATI AL REFITTING E AL BROKERAGE, LA GALLERY DEL LUSSO E IL MATCHING B2B\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUOVI SPAZI DEDICATI AL REFITTING E AL BROKERAGE, LA GALLERY DEL LUSSO E IL MATCHING B2B - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/","og_locale":"it_IT","og_type":"article","og_title":"NUOVI SPAZI DEDICATI AL REFITTING E AL BROKERAGE, LA GALLERY DEL LUSSO E IL MATCHING B2B - AbmNews","og_url":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2019-12-15T13:28:18+00:00","article_modified_time":"2019-12-15T13:28:21+00:00","og_image":[{"width":1024,"height":683,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/2.-VYR.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"NUOVI SPAZI DEDICATI AL REFITTING E AL BROKERAGE, LA GALLERY DEL LUSSO E IL MATCHING B2B","datePublished":"2019-12-15T13:28:18+00:00","dateModified":"2019-12-15T13:28:21+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/"},"wordCount":430,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/2.-VYR.jpg","articleSection":["Barche","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/","url":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/","name":"NUOVI SPAZI DEDICATI AL REFITTING E AL BROKERAGE, LA GALLERY DEL LUSSO E IL MATCHING B2B - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/2.-VYR.jpg","datePublished":"2019-12-15T13:28:18+00:00","dateModified":"2019-12-15T13:28:21+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/2.-VYR.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/2.-VYR.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/nuovi-spazi-dedicati-al-refitting-e-al-brokerage-la-gallery-del-lusso-e-il-matching-b2b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"NUOVI SPAZI DEDICATI AL REFITTING E AL BROKERAGE, LA GALLERY DEL LUSSO E IL MATCHING B2B"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/41595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=41595"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/41595\/revisions"}],"predecessor-version":[{"id":41597,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/41595\/revisions\/41597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/41596"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=41595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=41595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=41595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}