{"id":41604,"date":"2019-12-16T15:50:30","date_gmt":"2019-12-16T14:50:30","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=41604"},"modified":"2019-12-16T15:50:32","modified_gmt":"2019-12-16T14:50:32","slug":"una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/","title":{"rendered":"UNA NUOVA ERA DI COLLABORAZIONE RENAULT, PUBLICIS, OMD: IN UNA PAROLA, VOIL\u00c0."},"content":{"rendered":"\n<p class=\"introduction\">Il Gruppo Renault lancia un progetto pi\u00f9 unico che raro con i suoi partner di lunga data, Publicis e OMD: riunire i team di marketing dei tre gruppi in una stessa piattaforma nel cuore di Parigi per sviluppare, con un approccio collaborativo, le campagne delle Marche Renault e Dacia.<\/p>\n<p>\u00a0<strong>La piattaforma comune <\/strong><em>Voil\u00e0<\/em><strong> \u00e8 la soluzione per un modello di collaborazione <i>agile.<\/i><\/strong><\/p>\n<p>Questa piattaforma riunir\u00e0 inizialmente <strong>200 talenti e pi\u00f9 di 20 professionalit\u00e0 per ideare e produrre tutte le campagne di marketing mondiali ed europee Renault e Dacia<\/strong>. Organizzati in team di progetto interfunzionali che riuniscono esperti di marketing di Renault, Publicis e OMD \u2013 piuttosto che in silos di competenze a livello di contenuti, mass media e pubblicit\u00e0 \u2013 avranno l\u2019obiettivo di sviluppare i piani di comunicazione di marca e prodotto rispecchiando i percorsi dei clienti, in un perimetro che va dal reveal del modello fino al lancio sul mercato.<\/p>\n<p>Questo nuovo modello di collaborazione, in linea con la metodologia \u201c<i>agile\u201d<\/i>, risponde all\u2019<b>evoluzione della strategia di marketing mondiale del Gruppo Renault<\/b>, che fa della transizione dal marketing di massa a quello individualizzato il motore della propria trasformazione. <em>Voil\u00e0<\/em> incarna, pertanto, l\u2019obiettivo ambizioso di trasformare tutta la catena del marketing del Gruppo Renault, in tutto il mondo, ponendo il cliente al centro della riflessione, con una costante attenzione all\u2019agilit\u00e0, all\u2019efficacia creativa e alla pertinenza dei media.<\/p>\n<p class=\"Citazione1\"><em>\u00abCreare il coinvolgimento del cliente e marche forti \u00e8 al centro delle sfide di marketing del Gruppo Renault. Con Voil\u00e0, la nuova piattaforma collaborativa, potremo far emergere e crescere le nostre marche presso un pubblico frammentato, contestualizzare e individualizzare i nostri contenuti, adattarli in tempo reale ai percorsi dei clienti, rimanendo quanto pi\u00f9 possibile vicino alle attese dei consumatori\u00bb, <\/em><strong>ha dichiarato Xavier Martinet, Direttore Marketing Mondo del Gruppo Renault.<\/strong><\/p>\n<p class=\"Citazione1\"><em>\u00abAgilit\u00e0 ed efficacia sono le due parole chiave di questa collaborazione. Unendo i nostri rispettivi team su una stessa piattaforma e mettendo in comune i nostri processi e strumenti, lavoreremo in modo molto pi\u00f9 fluido e complementare\u00bb,<\/em>\u00a0<strong>ha commentato Jean-Guy Saulou, Global Client Leader del Gruppo Publicis. \u00a0\u00a0<\/strong><\/p>\n<p class=\"Citazione1\"><em>\u00abPer coinvolgere meglio il consumatore in un mondo caratterizzato dalla sovrabbondanza di contenuti e in costante mutamento, abbiamo pi\u00f9 che mai bisogno di porlo al centro delle nostre riflessioni e azioni, e ci\u00f2 pensando al percorso del consumatore senza soluzione di continuit\u00e0, con coerenza e pertinenza. Desideriamo, pertanto, un modo di lavorare e una struttura pi\u00f9 fluida e interdisciplinare, per prendere decisioni migliori e farlo pi\u00f9 velocemente\u00bb, <\/em><strong>ha affermato Neith Jauregui, Global Client Leader di OMD.<\/strong><\/p>\n<p><strong>\u00a0Un\u2019identit\u00e0 comune per un progetto unico nel suo genere<\/strong><\/p>\n<p>Per sintetizzare questo concept inedito e andar oltre le differenze culturali tra agenzie e inserzionisti, i tre partner hanno costruito un\u2019identit\u00e0 comune fondata sullo stesso spirito che funziona come un mantra e si riassume in una parola: <em>Voil\u00e0.<\/em><\/p>\n<p><em>\u00a0\u00ab\u201cVoil\u00e0\u201d, che parola buffa &#8230; e talmente francese, vero?\u00bb\u00a0 <\/em><i><\/i><\/p>\n<p><em>\u00abVoil\u00e0\u201d \u00e8 complessa e diretta quanto noi.\u00bb\u00a0<\/em><\/p>\n<p><em>\u00abSiamo orgogliosi, creativi e appassionati, a volte brontoloni, siamo franchi e spesso non siamo d\u2019accordo. Ma siamo fatti cos\u00ec\u00bb\u00a0<\/em><\/p>\n<p><em>\u00abQuesto \u201cVoil\u00e0\u201d ci assomiglia (\u2026)\u00bb\u00a0<\/em><\/p>\n<p><em>\u00abAl di l\u00e0 del nome, \u201cVoil\u00e0\u201d \u00e8 una promessa.\u00bb <\/em><\/p>\n<p><em>\u00abUno stato d\u2019animo che ci porter\u00e0 a lavorare in modo semplice, umano e intelligente senza deviazioni, ad avanzare insieme con ci\u00f2 che abbiamo di meglio e con i migliori che abbiamo, per costruire la nuova era della nostra collaborazione.\u00bb<\/em><\/p>\n<p>\u2026 precisa il manifesto della piattaforma.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":41605,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[293,307],"tags":[],"class_list":["post-41604","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news","category-renault"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UNA NUOVA ERA DI COLLABORAZIONE RENAULT, PUBLICIS, OMD: IN UNA PAROLA, VOIL\u00c0. - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNA NUOVA ERA DI COLLABORAZIONE RENAULT, PUBLICIS, OMD: IN UNA PAROLA, VOIL\u00c0. - AbmNews\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-16T14:50:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-16T14:50:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/Renault_logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"224\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"UNA NUOVA ERA DI COLLABORAZIONE RENAULT, PUBLICIS, OMD: IN UNA PAROLA, VOIL\u00c0.\",\"datePublished\":\"2019-12-16T14:50:30+00:00\",\"dateModified\":\"2019-12-16T14:50:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\\\/\"},\"wordCount\":569,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Renault_logo.jpg\",\"articleSection\":[\"News\",\"Renault\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\\\/\",\"name\":\"UNA NUOVA ERA DI COLLABORAZIONE RENAULT, PUBLICIS, OMD: IN UNA PAROLA, VOIL\u00c0. - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Renault_logo.jpg\",\"datePublished\":\"2019-12-16T14:50:30+00:00\",\"dateModified\":\"2019-12-16T14:50:32+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Renault_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Renault_logo.jpg\",\"width\":224,\"height\":224},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UNA NUOVA ERA DI COLLABORAZIONE RENAULT, PUBLICIS, OMD: IN UNA PAROLA, VOIL\u00c0.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UNA NUOVA ERA DI COLLABORAZIONE RENAULT, PUBLICIS, OMD: IN UNA PAROLA, VOIL\u00c0. - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/","og_locale":"it_IT","og_type":"article","og_title":"UNA NUOVA ERA DI COLLABORAZIONE RENAULT, PUBLICIS, OMD: IN UNA PAROLA, VOIL\u00c0. - AbmNews","og_url":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2019-12-16T14:50:30+00:00","article_modified_time":"2019-12-16T14:50:32+00:00","og_image":[{"width":224,"height":224,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/Renault_logo.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"UNA NUOVA ERA DI COLLABORAZIONE RENAULT, PUBLICIS, OMD: IN UNA PAROLA, VOIL\u00c0.","datePublished":"2019-12-16T14:50:30+00:00","dateModified":"2019-12-16T14:50:32+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/"},"wordCount":569,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/Renault_logo.jpg","articleSection":["News","Renault"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/","url":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/","name":"UNA NUOVA ERA DI COLLABORAZIONE RENAULT, PUBLICIS, OMD: IN UNA PAROLA, VOIL\u00c0. - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/Renault_logo.jpg","datePublished":"2019-12-16T14:50:30+00:00","dateModified":"2019-12-16T14:50:32+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/Renault_logo.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2019\/12\/Renault_logo.jpg","width":224,"height":224},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/una-nuova-era-di-collaborazione-renault-publicis-omd-in-una-parola-voila\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"UNA NUOVA ERA DI COLLABORAZIONE RENAULT, PUBLICIS, OMD: IN UNA PAROLA, VOIL\u00c0."}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/41604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=41604"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/41604\/revisions"}],"predecessor-version":[{"id":41606,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/41604\/revisions\/41606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/41605"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=41604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=41604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=41604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}