{"id":42756,"date":"2020-01-24T08:03:20","date_gmt":"2020-01-24T07:03:20","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=42756"},"modified":"2020-01-24T08:03:21","modified_gmt":"2020-01-24T07:03:21","slug":"gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/","title":{"rendered":"GIMS Discovery: una pista Indoor  e 48 veicoli con motore alternativo da provare"},"content":{"rendered":"\n<p><strong>La 90<\/strong> <sup>a<\/sup> <strong>edizione del \u00a0Geneva International Motor Show (GIMS), aperta al pubblico dal 5 al 15 marzo 2020,\u00a0 offre al visitatore la possibilit\u00e0 di un\u2019esperienza molto particolare: chi verr\u00e0 al GIMS potr\u00e0 provare tutti i tipi di motori alternativi su una pista lunga 456 metri. E tutto questo con emissioni quasi zero. Si potranno scegliere auto con vari tipi di alimentazione: elettrici, ibridi, a idrogeno e gas naturale. GIMS Discovery \u00e8 a disposizione di tutti i visitatori del GIMS, i quali, per\u00f2, per poter effettuare il test, devono precedentemente partecipare all\u2019estrazione,\u00a0 attraverso l\u2019App del GIMS.<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>Il GIMS lancia <a href=\"https:\/\/www.gims.swiss\/gims-discovery\">GIMS Discovery<\/a>, per promuovere la diffusione e la conoscenza di veicoli con motori e carburanti alternativi: \u00abBench\u00e9 \u00a0il consenso per questi tipi di veicoli stia via via aumentando &#8211; afferma Maurice Turrettini, Presidente del Consiglio della Fondazione GIMS &#8211; secondo la nostra esperienza la maggior parte degli automobilisti non ha mai guidato un\u2019auto con motore alternativo. In quanto attori nel campo della mobilit\u00e0 individuale, vogliamo rivestire un ruolo importante per quanto riguarda la diffusione di questo tipo di mobilit\u00e0 ed aiutare cos\u00ec i consumatori a scoprire i vantaggi di questi veicoli nella loro vita quotidiana e, forse \u2013 aspetto questo ancor pi\u00f9 importante -, a meglio comprenderne gli effetti sul nostro ambiente. Il Salone ginevrino, con oltre mezzo milione di visitatori, offre la piattafoma ideale per conoscere l\u2019interessante futuro della mobilit\u00e0\u00a0\u00bb.<\/p>\n<p>\u00a0<\/p>\n<p>A disposizione dei visitatori vi saranno 48 diverse autovetture di <strong>Aiways, Audi, BMW, DS Automobiles, Honda, Hyundai, Kia, Mercedes Benz, \u00a0Porsche, Renault, Seat, Skoda, Smart, Toyota e Volkswagen. <\/strong><\/p>\n<p>\u00a0<\/p>\n<p>I partecipanti potranno scoprire le qualit\u00e0 delle auto lungo un percorso di prova della durata di dieci minuti, sotto il controllo del team dei Commissari del Touring Club Svizzero (TCS). \u00a0Un circuito unico nel padiglione 7, che replica il mondo reale, con curve strette e larghe e lunghi rettilinei, che permetteranno di vivere, durante una prova\u00a0 \u00a0di due giri,\u00a0 una vera e propria esperienza di guida. Ogni partecipante sar\u00e0 accompagnato \u00a0da un esperto della Casa. \u00a0La pista \u00e8 costituita da rivestimenti riciclabili del pavimentazione.\u00a0 I partecipanti al GIMS Discovery potranno rendersi conto con stupore quanto silenziosi e puliti\u00a0 possano essere i veicoli con motori alternativi, quali sono\u00a0 gi\u00e0 oggi i veicoli elettrici, \u00a0e quanto semplici siano le loro ricariche.\u00a0 \u00a0La loro conoscenza contribuir\u00e0 a dissipare le idee preconcette ed a \u00a0spiegare con quale facilit\u00e0 la mobilit\u00e0 elettrica possa\u00a0 essere integrata nella \u00a0vita quotidiana.\u00a0Al centro del Salone, il padiglione \u00a07, dove hanno sede i test drive, \u00a0diventer\u00e0 un luogo d&#8217;incontro ideale. Oltre alla pista di prova, la mostra Discovery presenter\u00e0 stand interattivi, simulatori e mostre fotografiche. Il partner di GIMS, SwissEnergy, offrir\u00e0 consulenza sui veicoli a basso consumo energetico attraverso il programma CO<sub>2<\/sub> Ribassato, mentre il Touring Club Svizzero sar\u00e0 il partner pi\u00f9 autorevole per le informazioni sulla sicurezza del traffico. Inoltre ci saranno collegamenti in diretta con quattro stazioni radio del gruppo MediaOne che racconteranno la fasi salienti dello dello spettacolo da uno studio situato nella sala GIMS Discovery.\u00a0<\/p>\n<p>Al GIMS si susseguiranno circa 11.000 Discovery Drives nelle giornate del Salone. Per gestire l&#8217;elevata richiesta di test drive tra i 600.000 visitatori previsti, le prenotazioni verranno effettuate esclusivamente con un sorteggio tramite l&#8217;app mobile GIMS. Discovery Drives \u00e8 aperta a tutti i visitatori e i partecipanti devono possedere un biglietto GIMS valido per il giorno richiesto. L&#8217;app mobile GIMS \u00e8 disponibile per dispositivi iOS e Android e pu\u00f2 essere scaricata dall&#8217;App Store e dal Google Play Store.<\/p>\n<p>I partner di GIMS Discovery sono il TCS, ABB Schweiz, il MediaOne Group e 20Minuten.<\/p>\n<p>\u00a0<\/p>\n<p><strong>GIMS VIP Day <\/strong><\/p>\n<p>Il 4 marzo 2020 sar\u00e0 il giorno esclusivo di GIMS, il VIP Day! I pi\u00f9 importanti personaggi del mondo automobilistico e tecnologico s\u2019incontreranno, \u00a0per discutere e far conoscere i temi che daranno forma al futuro della mobilit\u00e0, dall&#8217;elettrificazione alla guida autonoma, dalla trasformazione digitale alle innovazioni nel mondo degli sport motoristici. I partecipanti al VIP Day avranno anche accesso al sorteggio per Discovery Drives nella giornata del 4 marzo.<\/p>\n<p>\u00a0<\/p>\n<p>Tra i primi relatori che hanno confemato la loro partecipazione al VIP Day, segnaliamo:<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>Alejandro Agag, fondatore e CEO di Extreme E e Presidente della Formula E<\/li>\n<li>Roger Atkins, fondatore e Direttore, Electric Vehicles Outlook<\/li>\n<li>S\u00e9bastien Buemi, pilota Nissan della Formula E<\/li>\n<li>Rajeev Chand, partner e Head of Research, Wing Capital<\/li>\n<li>Shaun Collins, fondatore e CEO, CCS Insight<\/li>\n<li>Simona De Silvestro, pilota Team TAG Heuer Porsche Formula E<\/li>\n<li>Neel Jani, pilota Team TAG Heuer Porsche Formula E<\/li>\n<li>John Krafcik, CEO Waymo<\/li>\n<li>William Li, fondatore, presidente e CEO, NIO<\/li>\n<li>Nico M\u00fcller, pilota Formula E<\/li>\n<li>Marco Parroni, Head of Global Sponsoring, Bank Julius B\u00e4r &amp; Co. Ltd.<\/li>\n<li>Michael Perschke, CEO, Automobili Pininfarina<\/li>\n<li>Nico Rosberg, fondatore Greentech Festival e Campione del Mondo Formula 1 2016<\/li>\n<li>Mate Rimac, fondatore e CEO, Rimac Automobili<\/li>\n<li>Claire Ritchie-Tomkins, fondatore e CEO, Sine Qua No<\/li>\n<li>Jean-\u00c9ric Vergne, due volte Campione del Mondo Formula E, Team DS Techeetah<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>Il Salone Internazionale dell\u2019Auto di Ginevra <\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Circa 150 Espositori si sono gi\u00e0 registrati a GIMS 2020 in rappresentanza delle pi\u00f9 grandi Case automobilistiche e delle pi\u00f9 avanzate start-up nel settore tecnologico. Il visitatore potr\u00e0 conoscere il mondo dell\u2019auto attraverso la pi\u00f9 ampia variet\u00e0 di espositori. La 90<sup>a<\/sup> edizione del GIMS sar\u00e0 aperta al pubblico dal 5 al 15 marzo 2020. L\u2019assegnazione del Premio \u00abCar of the Year\u00bb avverr\u00e0 il 2 marzo 2020, mentre il GIMS Media Day e il VIP Day si terranno rispettivamente il 3 e il 4 marzo 2020.<\/p>\n<p>Il GIMS \u00e8 uno dei cinque Saloni dell\u2019Auto pi\u00f9 importanti al mondo, riconosciuto dall\u2019Organizzazione Internazionale dei Costruttori di Automobili (OICA) ed \u00e8 anche l\u2019unico in Europa con cadenza annuale. Per ulteriori informazioni sul GIMS, consultare la nostra pagina <a href=\"http:\/\/www.gims.swiss\/\">Web GIMS<\/a>.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":42758,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[293,262,312],"tags":[],"class_list":["post-42756","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news","category-novita","category-saloni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GIMS Discovery: una pista Indoor e 48 veicoli con motore alternativo da provare - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GIMS Discovery: una pista Indoor e 48 veicoli con motore alternativo da provare - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-24T07:03:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-24T07:03:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/01\/GIMS20180306__PPE4023_HD.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1150\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"GIMS Discovery: una pista Indoor e 48 veicoli con motore alternativo da provare\",\"datePublished\":\"2020-01-24T07:03:20+00:00\",\"dateModified\":\"2020-01-24T07:03:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\\\/\"},\"wordCount\":945,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/GIMS20180306__PPE4023_HD.jpg\",\"articleSection\":[\"News\",\"Novit\u00e0\",\"Saloni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\\\/\",\"name\":\"GIMS Discovery: una pista Indoor e 48 veicoli con motore alternativo da provare - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/GIMS20180306__PPE4023_HD.jpg\",\"datePublished\":\"2020-01-24T07:03:20+00:00\",\"dateModified\":\"2020-01-24T07:03:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/GIMS20180306__PPE4023_HD.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/GIMS20180306__PPE4023_HD.jpg\",\"width\":1150,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GIMS Discovery: una pista Indoor e 48 veicoli con motore alternativo da provare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GIMS Discovery: una pista Indoor e 48 veicoli con motore alternativo da provare - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/","og_locale":"it_IT","og_type":"article","og_title":"GIMS Discovery: una pista Indoor e 48 veicoli con motore alternativo da provare - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-01-24T07:03:20+00:00","article_modified_time":"2020-01-24T07:03:21+00:00","og_image":[{"width":1150,"height":525,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/01\/GIMS20180306__PPE4023_HD.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"GIMS Discovery: una pista Indoor e 48 veicoli con motore alternativo da provare","datePublished":"2020-01-24T07:03:20+00:00","dateModified":"2020-01-24T07:03:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/"},"wordCount":945,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/01\/GIMS20180306__PPE4023_HD.jpg","articleSection":["News","Novit\u00e0","Saloni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/","url":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/","name":"GIMS Discovery: una pista Indoor e 48 veicoli con motore alternativo da provare - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/01\/GIMS20180306__PPE4023_HD.jpg","datePublished":"2020-01-24T07:03:20+00:00","dateModified":"2020-01-24T07:03:21+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/01\/GIMS20180306__PPE4023_HD.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/01\/GIMS20180306__PPE4023_HD.jpg","width":1150,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/gims-discovery-una-pista-indoor-e-48-veicoli-con-motore-alternativo-da-provare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"GIMS Discovery: una pista Indoor e 48 veicoli con motore alternativo da provare"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/42756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=42756"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/42756\/revisions"}],"predecessor-version":[{"id":42759,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/42756\/revisions\/42759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/42758"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=42756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=42756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=42756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}