{"id":47032,"date":"2020-06-06T03:33:45","date_gmt":"2020-06-06T01:33:45","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=47032"},"modified":"2020-06-06T03:33:47","modified_gmt":"2020-06-06T01:33:47","slug":"il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/","title":{"rendered":"Il Gruppo Volkswagen avvia lo sviluppo di progetti climatici per la compensazione della CO2"},"content":{"rendered":"\n<p><strong>\u2013 Il Gruppo Volkswagen e Permian Global hanno firmato un accordo di sviluppo congiunto (Joint Development Agreement) per la realizzazione di progetti a protezione del clima. Con il supporto di Permian Global, il Gruppo avvier\u00e0 le proprie attivit\u00e0 a tutela delle foreste tropicali nella seconda met\u00e0 del 2020. Evitare la deforestazione e rimboschire le foreste in pericolo permetter\u00e0 di trattenere il carbonio e, dopo la relativa certificazione, di ottenere carbon credits (crediti di carbonio). Questi saranno utilizzati per compensare le emissioni di CO<sub>2<\/sub> generate dalla catena di approvvigionamento, dalla produzione e dalla logistica dei veicoli, fintanto che non sar\u00e0 possibile evitarle e non si utilizzeranno energie rinnovabili<\/strong><\/p>\n<p>\u201cAggiungiamo un ulteriore elemento alla strategia di protezione del clima del Gruppo Volkswagen insieme a Permian Global, azienda che sviluppa progetti di successo a tutela dell\u2019ambiente. Le attivit\u00e0 previste si concentrano sulla protezione delle foreste tropicali e subtropicali in pericolo. Tutelare e ampliare questi efficacissimi pozzi di assorbimento del carbonio naturali \u00e8 un compito importante, come pi\u00f9 volte sottolineato dal Gruppo Intergovernativo sul Cambiamento Climatico\u201d ha affermato Ralf Pfitzner, Responsabile per la Sostenibilit\u00e0 del Gruppo Volkswagen.<\/p>\n<p>Stephen Rumsey, Presidente di Permian Global, ha aggiunto: \u201cForeste naturali in salute portano una miriade di benefici alle persone e all\u2019ambiente in generale, inclusa la capacit\u00e0 di assorbire e trattenere quantit\u00e0 enormi di carbonio. Data l\u2019urgenza e le dimensioni della crisi climatica \u00e8 fondamentale che i leader industriali diventino le forze trainanti di un cambiamento positivo. E siamo felici di aver trovato nel Gruppo Volkswagen un partner che comprende la sfida che abbiamo davanti e che si impegna a giocare un ruolo chiave nel trovare una soluzione\u201d.\u00a0<\/p>\n<p><strong>Portata dei progetti a protezione del clima<\/strong><\/p>\n<p>Secondo i termini dell\u2019accordo, inizialmente le due aziende svilupperanno progetti su un\u2019area totale di un milione di ettari &#8211; dieci volte la superficie di Berlino &#8211; in Sudamerica e in Asia. I progetti avranno molteplici benefici: la protezione e il rimboschimento di foreste tropicali in pericolo; alternative sostenibili alla deforestazione, che gioveranno alle comunit\u00e0 locali nel lungo termine; la biodiversit\u00e0 sar\u00e0 preservata e allo stesso tempo si contribuir\u00e0 a superare la crisi climatica. Il programma contribuir\u00e0 anche al raggiungimento degli Obiettivi di Sviluppo Sostenibile (Sustainable Development Goals, SDG) delle Nazioni Unite. Tutti i progetti saranno verificati in modo indipendente e certificati secondo i pi\u00f9 elevati standard, in particolare il \u201cVerified Carbon Standard\u201d (VCS) e il \u201cClimate Community and Biodiversity Standard\u201d (CCB) o il \u201cGold Standard\u201d.\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":47033,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[293,347],"tags":[],"class_list":["post-47032","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news","category-volkswagen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Gruppo Volkswagen avvia lo sviluppo di progetti climatici per la compensazione della CO2 - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Gruppo Volkswagen avvia lo sviluppo di progetti climatici per la compensazione della CO2 - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-06T01:33:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-06T01:33:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/unnamed-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Il Gruppo Volkswagen avvia lo sviluppo di progetti climatici per la compensazione della CO2\",\"datePublished\":\"2020-06-06T01:33:45+00:00\",\"dateModified\":\"2020-06-06T01:33:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\\\/\"},\"wordCount\":417,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/unnamed-2-1.jpg\",\"articleSection\":[\"News\",\"Volkswagen\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\\\/\",\"name\":\"Il Gruppo Volkswagen avvia lo sviluppo di progetti climatici per la compensazione della CO2 - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/unnamed-2-1.jpg\",\"datePublished\":\"2020-06-06T01:33:45+00:00\",\"dateModified\":\"2020-06-06T01:33:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/unnamed-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/unnamed-2-1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Gruppo Volkswagen avvia lo sviluppo di progetti climatici per la compensazione della CO2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Gruppo Volkswagen avvia lo sviluppo di progetti climatici per la compensazione della CO2 - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/","og_locale":"it_IT","og_type":"article","og_title":"Il Gruppo Volkswagen avvia lo sviluppo di progetti climatici per la compensazione della CO2 - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-06-06T01:33:45+00:00","article_modified_time":"2020-06-06T01:33:47+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/unnamed-2-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Il Gruppo Volkswagen avvia lo sviluppo di progetti climatici per la compensazione della CO2","datePublished":"2020-06-06T01:33:45+00:00","dateModified":"2020-06-06T01:33:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/"},"wordCount":417,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/unnamed-2-1.jpg","articleSection":["News","Volkswagen"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/","url":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/","name":"Il Gruppo Volkswagen avvia lo sviluppo di progetti climatici per la compensazione della CO2 - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/unnamed-2-1.jpg","datePublished":"2020-06-06T01:33:45+00:00","dateModified":"2020-06-06T01:33:47+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/unnamed-2-1.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/06\/unnamed-2-1.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/il-gruppo-volkswagen-avvia-lo-sviluppo-di-progetti-climatici-per-la-compensazione-della-co2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Il Gruppo Volkswagen avvia lo sviluppo di progetti climatici per la compensazione della CO2"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/47032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=47032"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/47032\/revisions"}],"predecessor-version":[{"id":47034,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/47032\/revisions\/47034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/47033"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=47032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=47032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=47032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}