{"id":50441,"date":"2020-10-13T10:18:05","date_gmt":"2020-10-13T08:18:05","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=50441"},"modified":"2020-10-13T10:18:08","modified_gmt":"2020-10-13T08:18:08","slug":"le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/","title":{"rendered":"LE BEST SELLER RANGE ROVER EVOQUE E DISCOVERY SPORT IN VERSIONE LIMITATA PER UNA MOBILITA\u2019 URBANA INTEGRATA"},"content":{"rendered":"\n<p>La micro-mobilit\u00e0 elettrica \u00e8 uno dei trend in crescita in Italia, soprattutto dopo l\u2019emergenza sanitaria Covid-19, ed \u00e8 diventata parte integrante del panorama quotidiano nelle citt\u00e0 italiane.<\/p>\n<p>Il successo dei monopattini elettrici \u00e8 sempre pi\u00f9 tangibile: rappresentano un\u2019alternativa semplice e a zero emissioni per gli spostamenti a corto raggio ed un mezzo complementare all\u2019automobile, magari per percorrere velocemente l\u2019ultimo chilometro o per entrare nelle aree a traffico limitato.<\/p>\n<p>Questo \u00e8 quanto emerso anche dall\u2019indagine che Jaguar Land Rover Italia ha condotto lo scorso giugno tra i suoi Clienti; i risultati della ricerca hanno confermato il trend della micro-mobilit\u00e0 in sensibile crescita.<\/p>\n<p>Per questo, nascono le edizioni limitate <strong>Range Rover Evoque e Discovery Sport Urban View<\/strong> <strong>Segway<\/strong>&#8211;<strong>Ninebot<\/strong>come risultato della partnership di Jaguar Land Rover Italia con Segway-Ninebot, produttore leader di monopattini elettrici.<\/p>\n<p>Range Rover Evoque e Discovery Sport con il tetto panoramico, saranno vendute in serie limitata, in abbinamento ad un monopattino Segway-Ninebot MAX G30. Con le loro ampie superfici vetrate diventeranno le vetture ideali per esplorare e godere la citt\u00e0, con comfort ed elegante dinamicit\u00e0, consentendo di percorrere gli ultimi chilometri con il monopattino Segway-Ninebot per arrivare a destinazione, diventando quindi un vero manifesto di mobilit\u00e0 urbana integrata.<\/p>\n<p>Si tratta di un\u2019edizione limitata di 200 unit\u00e0 che riguarderanno le vendite da ottobre a dicembre 2020 e che sar\u00e0 sostenuta da una campagna di comunicazione nazionale sui canali stampa, digital e affissioni nel periodo ottobre &#8211; novembre 2020.<\/p>\n<p>Range Rover Evoque e Discovery Sport sono due vetture di grande successo in Italia, entrambe con un innegabile carattere: perfetta sintesi di eleganza e minimalismo la prima, di versatilit\u00e0 e performance sportiva, la seconda.<\/p>\n<p><em>\u201cIn un momento di grandi cambiamenti nella mobilit\u00e0 in generale ed in particolare di quella urbana\u201d <\/em><strong>dichiara Daniele Maver, Presidente di Jaguar Land Rover Italia<\/strong><em>. \u201cla soluzione migliore consiste in un modello integrato che prevede l\u2019uso della vettura per la parte principale del percorso per poi passare\u00a0\u00a0 a mezzi pi\u00f9\u2019 piccoli e versatili con cui \u00a0arrivare a destinazione, spostandosi dal parcheggio, alla sede di lavoro, ad esempio, senza incidere sul traffico e sull\u2019inquinamento ambientale. La partnership con Segway-Ninebot ci permette di avere un monopattino tecnologicamente avanzato, da ripiegare e riporre all\u2019interno del bagagliaio, per spostamenti sempre pi\u00f9\u2019 sostenibili\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":50442,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[416,7797,293],"tags":[],"class_list":["post-50441","post","type-post","status-publish","format-standard","has-post-thumbnail","category-land-rover","category-mobilita","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LE BEST SELLER RANGE ROVER EVOQUE E DISCOVERY SPORT IN VERSIONE LIMITATA PER UNA MOBILITA\u2019 URBANA INTEGRATA - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LE BEST SELLER RANGE ROVER EVOQUE E DISCOVERY SPORT IN VERSIONE LIMITATA PER UNA MOBILITA\u2019 URBANA INTEGRATA - AbmNews\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-13T08:18:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-13T08:18:08+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/landrover1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1587\" \/>\n\t<meta property=\"og:image:height\" content=\"1058\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"LE BEST SELLER RANGE ROVER EVOQUE E DISCOVERY SPORT IN VERSIONE LIMITATA PER UNA MOBILITA\u2019 URBANA INTEGRATA\",\"datePublished\":\"2020-10-13T08:18:05+00:00\",\"dateModified\":\"2020-10-13T08:18:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\\\/\"},\"wordCount\":388,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/landrover1.jpg\",\"articleSection\":[\"Land Rover\",\"Mobilit\u00e0\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\\\/\",\"name\":\"LE BEST SELLER RANGE ROVER EVOQUE E DISCOVERY SPORT IN VERSIONE LIMITATA PER UNA MOBILITA\u2019 URBANA INTEGRATA - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/landrover1.jpg\",\"datePublished\":\"2020-10-13T08:18:05+00:00\",\"dateModified\":\"2020-10-13T08:18:08+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/landrover1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/landrover1.jpg\",\"width\":1587,\"height\":1058},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LE BEST SELLER RANGE ROVER EVOQUE E DISCOVERY SPORT IN VERSIONE LIMITATA PER UNA MOBILITA\u2019 URBANA INTEGRATA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LE BEST SELLER RANGE ROVER EVOQUE E DISCOVERY SPORT IN VERSIONE LIMITATA PER UNA MOBILITA\u2019 URBANA INTEGRATA - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/","og_locale":"it_IT","og_type":"article","og_title":"LE BEST SELLER RANGE ROVER EVOQUE E DISCOVERY SPORT IN VERSIONE LIMITATA PER UNA MOBILITA\u2019 URBANA INTEGRATA - AbmNews","og_url":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-10-13T08:18:05+00:00","article_modified_time":"2020-10-13T08:18:08+00:00","og_image":[{"width":1587,"height":1058,"url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/landrover1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/#article","isPartOf":{"@id":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"LE BEST SELLER RANGE ROVER EVOQUE E DISCOVERY SPORT IN VERSIONE LIMITATA PER UNA MOBILITA\u2019 URBANA INTEGRATA","datePublished":"2020-10-13T08:18:05+00:00","dateModified":"2020-10-13T08:18:08+00:00","mainEntityOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/"},"wordCount":388,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/landrover1.jpg","articleSection":["Land Rover","Mobilit\u00e0","News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/","url":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/","name":"LE BEST SELLER RANGE ROVER EVOQUE E DISCOVERY SPORT IN VERSIONE LIMITATA PER UNA MOBILITA\u2019 URBANA INTEGRATA - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/#primaryimage"},"image":{"@id":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/landrover1.jpg","datePublished":"2020-10-13T08:18:05+00:00","dateModified":"2020-10-13T08:18:08+00:00","breadcrumb":{"@id":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/landrover1.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/landrover1.jpg","width":1587,"height":1058},{"@type":"BreadcrumbList","@id":"http:\/\/www.abmnews.com\/blog\/le-best-seller-range-rover-evoque-e-discovery-sport-in-versione-limitata-per-una-mobilita-urbana-integrata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"LE BEST SELLER RANGE ROVER EVOQUE E DISCOVERY SPORT IN VERSIONE LIMITATA PER UNA MOBILITA\u2019 URBANA INTEGRATA"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/50441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=50441"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/50441\/revisions"}],"predecessor-version":[{"id":50443,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/50441\/revisions\/50443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/50442"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=50441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=50441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=50441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}