{"id":50850,"date":"2020-10-29T09:44:17","date_gmt":"2020-10-29T08:44:17","guid":{"rendered":"http:\/\/www.abmnews.com\/blog\/?p=50850"},"modified":"2020-10-29T09:44:19","modified_gmt":"2020-10-29T08:44:19","slug":"alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1","status":"publish","type":"post","link":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/","title":{"rendered":"Alfa Romeo rinnova la partnership con Sauber Motorsport per la stagione 2021 di Formula 1"},"content":{"rendered":"\n<p>Alfa Romeo e Sauber Motorsport riconfermano la loro collaborazione per il Campionato del mondo di Formula 1 del 2021. I due brand, fra i pi\u00f9 iconici nell\u2019ambito del motorsport, hanno avviato la partnership nel 2018, con Alfa Romeo in qualit\u00e0 di Title Sponsor. Negli ultimi tre anni di collaborazione, il Team ha raggiunto risultati importanti conquistando l\u2019ottavo posto nelle due passate stagioni e con l\u2019ambizione di confermare questo risultato anche nel campionato in corso. Fedele allo spirito competitivo che la contraddistingue da sempre, Alfa Romeo rilancia la sfida.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Fr\u00e9d\u00e9ric Vasseur, Team Principal Alfa Romeo Racing ORLEN e CEO di Sauber Motorsport AG: <\/strong><\/p>\n<p>\u201cIl rinnovo della nostra collaborazione con Alfa Romeo rappresenta una vera e propria dichiarazione di intenti da parte di entrambi i brand. In Sauber, Alfa Romeo ha trovato un partner fortemente focalizzato sulle performances a cui affidarsi e noi siamo onorati di accogliere nel nostro nome l\u2019eredit\u00e0 e i successi di Alfa Romeo. I due brand condividono fin dall\u2019inizio l\u2019obiettivo di portare avanti una partnership che sia fruttuosa nel lungo periodo: nelle ultime tre stagioni abbiamo costruito delle solide basi e puntiamo a raccogliere i frutti di questo lavoro nel 2021 e oltre\u201d.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Mike Manley, CEO FCA:<\/strong><\/p>\n<p>\u201cLe competizioni sportive e le performance rappresentano l\u2019essenza di Alfa Romeo. Il brand \u00e8 praticamente nato sui circuiti e oggi continuiamo a competere al livello pi\u00f9 alto del motorsport. Grazie alla partnership con Sauber, i nostri clienti possono beneficiare di un know-how esclusivo nell\u2019ambito dell\u2019automobilismo sportivo, come dimostrano le nuove Giulia GTA e GTAm, sviluppate con il contributo tecnico di Sauber Engineering, soprattutto per quanto riguarda le soluzioni aerodinamiche specifiche\u201d.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>Una speciale livrea per un evento importante<\/strong><\/p>\n<p>In occasione del Gran Premio di Imola, un luogo simbolico sia per Alfa Romeo sia per il mondo del motorsport italiano, il brand celebra questo annuncio e rende omaggio a tutti i suoi appassionati mostrando la monoposto C39 con una livrea esclusiva realizzata dal Centro Stile Alfa Romeo. La speciale livrea esibir\u00e0 il tricolore italiano in un lampo rettilineo sulla parte superiore del cofano motore e sulla piastra terminale dell\u2019ala posteriore, che sfuma nel tema che contraddistingue la nuova livrea 2020, denominato \u201cspeed pixel\u201d e caratterizzato da un trattamento grafico lineare e dinamico.<\/p>\n<p>\u00a0<\/p>\n<p>Sempre sul cofano motore, in posizione di rilievo, compare il logo esclusivo per il 110\u00b0 anniversario Alfa Romeo, affiancato dalla scritta \u201cWelcome back, Imola\u201d che sottolinea l\u2019iconicit\u00e0 del circuito, fra i pi\u00f9 importanti in Italia. Imola \u00e8 stata teatro di memorabili vittorie Alfa Romeo nelle tre categorie Touring, Sport e Formula 1.<\/p>\n<p>\u00a0<\/p>\n<p><strong><em>Alfa Romeo e Gruppo Sauber: una partnership tecnico-commerciale<\/em><\/strong><\/p>\n<p>La partnership tra Alfa Romeo e il Gruppo Sauber non si limita all\u2019ambito sportivo: la collaborazione consente di trasferire le competenze tecniche di Sauber Engineering anche su vetture Alfa Romeo, sfruttando il know-how dei dipartimenti di ingegneria e aerodinamica di Sauber, nonch\u00e9 la sua competenza nella produzione additiva e di materiali compositi.<\/p>\n<p>Inoltre, Alfa Romeo affida a Sauber Engineering la produzione del maggior numero di componenti in carbonio della Giulia GTA e della GTAm, in particolare di quelli che influiscono sull\u2019aerodinamica. Fra questi si annoverano il nuovo paraurti anteriore e lo splitter anteriore regolabile, le minigonne laterali, l\u2019estrattore, lo spoiler GTA e l\u2019aerowing GTAm. Grazie alle ali anteriori e posteriori regolabili manualmente, Giulia GTAm \u00e8 in grado di adattare il carico aerodinamico a qualsiasi tipo di pista o strada, rispondendo perfettamente alle richieste e alle preferenze del pilota. Lo sviluppo aerodinamico in galleria del vento non \u00e8 stato limitato all\u2019ala ma \u00e8 stato testato anche il sottoscocca che, come su Giulia Quadrifoglio, \u00e8 interamente carenato. GTA e GTAm sono dotate inoltre di un nuovo estrattore dedicato in grado di aumentare l\u2019effetto suolo della vettura e di garantire in tal modo un\u2019ottima tenuta di strada ad alte velocit\u00e0. In particolare, sulla Giulia GTAm la configurazione aerodinamica implementata \u00e8 in grado di sviluppare il doppio del carico rispetto alla Giulia GTA, e il triplo rispetto alla Giulia Quadrifoglio, che gi\u00e0 in precedenza rappresentava il riferimento nel suo segmento.<\/p>\n<p>\u00a0<\/p>\n<p><strong><em>110 anni di storia sui circuiti di tutto il mondo<\/em><\/strong><\/p>\n<p>Un anno dopo la sua fondazione, avvenuta il 24 giugno 1910, il brand Alfa Romeo debutta ufficialmente nel mondo dell\u2019automobilismo vincendo la prima gara di regolarit\u00e0 a Modena. Da allora, il suo patrimonio sportivo si \u00e8 arricchito ulteriormente di vittorie e podi in svariati campionati internazionali. Il legame tra Alfa Romeo e la Formula 1 ha scritto la storia dell\u2019automobilismo sportivo: vince il primo Gran Premio e l\u2019edizione inaugurale della massima categoria dell\u2019automobilismo nel 1950, con Nino Farina a bordo di un\u2019Alfa Romeo Gran Premio Tipo 158 \u201cAlfetta\u201d, trionfo ripetuto nel 1951 da Juan Manuel Fangio sull\u2019Alfetta 159.<\/p>\n<p>Il rinnovo di questo impegno rappresenta anche il modo migliore per continuare a celebrare il 110\u00b0 anniversario del Brand.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":50851,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[354,7853,262],"tags":[],"class_list":["post-50850","post","type-post","status-publish","format-standard","has-post-thumbnail","category-alfa-romeo","category-motorsport","category-novita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alfa Romeo rinnova la partnership con Sauber Motorsport per la stagione 2021 di Formula 1 - AbmNews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alfa Romeo rinnova la partnership con Sauber Motorsport per la stagione 2021 di Formula 1 - AbmNews\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/\" \/>\n<meta property=\"og:site_name\" content=\"AbmNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ABMnews\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-29T08:44:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-29T08:44:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/Carzoom.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"566\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:site\" content=\"@ABMnewscom\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\"},\"headline\":\"Alfa Romeo rinnova la partnership con Sauber Motorsport per la stagione 2021 di Formula 1\",\"datePublished\":\"2020-10-29T08:44:17+00:00\",\"dateModified\":\"2020-10-29T08:44:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\\\/\"},\"wordCount\":807,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Carzoom.jpg\",\"articleSection\":[\"Alfa Romeo\",\"Motorsport\",\"Novit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\\\/\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\\\/\",\"name\":\"Alfa Romeo rinnova la partnership con Sauber Motorsport per la stagione 2021 di Formula 1 - AbmNews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Carzoom.jpg\",\"datePublished\":\"2020-10-29T08:44:17+00:00\",\"dateModified\":\"2020-10-29T08:44:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Carzoom.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Carzoom.jpg\",\"width\":800,\"height\":566},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alfa Romeo rinnova la partnership con Sauber Motorsport per la stagione 2021 di Formula 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"name\":\"AbmNews\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#organization\",\"name\":\"AbmNews\",\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"contentUrl\":\"http:\\\/\\\/www.abmnews.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logoabmnews544x180.png\",\"width\":544,\"height\":180,\"caption\":\"AbmNews\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ABMnews\",\"https:\\\/\\\/x.com\\\/ABMnewscom\",\"https:\\\/\\\/www.instagram.com\\\/abmnewsblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/#\\\/schema\\\/person\\\/2da21c254d26591b7993648c954826a2\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.abmnews.com\\\/blog\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alfa Romeo rinnova la partnership con Sauber Motorsport per la stagione 2021 di Formula 1 - AbmNews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/","og_locale":"it_IT","og_type":"article","og_title":"Alfa Romeo rinnova la partnership con Sauber Motorsport per la stagione 2021 di Formula 1 - AbmNews","og_url":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/","og_site_name":"AbmNews","article_publisher":"https:\/\/www.facebook.com\/ABMnews","article_published_time":"2020-10-29T08:44:17+00:00","article_modified_time":"2020-10-29T08:44:19+00:00","og_image":[{"width":800,"height":566,"url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/Carzoom.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@ABMnewscom","twitter_site":"@ABMnewscom","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/#article","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/"},"author":{"name":"Redazione","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2"},"headline":"Alfa Romeo rinnova la partnership con Sauber Motorsport per la stagione 2021 di Formula 1","datePublished":"2020-10-29T08:44:17+00:00","dateModified":"2020-10-29T08:44:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/"},"wordCount":807,"publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/Carzoom.jpg","articleSection":["Alfa Romeo","Motorsport","Novit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/","url":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/","name":"Alfa Romeo rinnova la partnership con Sauber Motorsport per la stagione 2021 di Formula 1 - AbmNews","isPartOf":{"@id":"https:\/\/www.abmnews.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/#primaryimage"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/Carzoom.jpg","datePublished":"2020-10-29T08:44:17+00:00","dateModified":"2020-10-29T08:44:19+00:00","breadcrumb":{"@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/#primaryimage","url":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/Carzoom.jpg","contentUrl":"https:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2020\/10\/Carzoom.jpg","width":800,"height":566},{"@type":"BreadcrumbList","@id":"https:\/\/www.abmnews.com\/blog\/alfa-romeo-rinnova-la-partnership-con-sauber-motorsport-per-la-stagione-2021-di-formula-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abmnews.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Alfa Romeo rinnova la partnership con Sauber Motorsport per la stagione 2021 di Formula 1"}]},{"@type":"WebSite","@id":"https:\/\/www.abmnews.com\/blog\/#website","url":"https:\/\/www.abmnews.com\/blog\/","name":"AbmNews","description":"","publisher":{"@id":"https:\/\/www.abmnews.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abmnews.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.abmnews.com\/blog\/#organization","name":"AbmNews","url":"https:\/\/www.abmnews.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","contentUrl":"http:\/\/www.abmnews.com\/blog\/wp-content\/uploads\/2026\/01\/logoabmnews544x180.png","width":544,"height":180,"caption":"AbmNews"},"image":{"@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ABMnews","https:\/\/x.com\/ABMnewscom","https:\/\/www.instagram.com\/abmnewsblog"]},{"@type":"Person","@id":"https:\/\/www.abmnews.com\/blog\/#\/schema\/person\/2da21c254d26591b7993648c954826a2","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/888b71ec1a1241930daa72f4c66b40f2390ac7ac3003b2cea4bbb235380b9dc2?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.abmnews.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/50850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/comments?post=50850"}],"version-history":[{"count":1,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/50850\/revisions"}],"predecessor-version":[{"id":50852,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/posts\/50850\/revisions\/50852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media\/50851"}],"wp:attachment":[{"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/media?parent=50850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/categories?post=50850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abmnews.com\/blog\/wp-json\/wp\/v2\/tags?post=50850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}